{"id":100550,"date":"2025-06-08T21:56:44","date_gmt":"2025-06-09T01:56:44","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=100550"},"modified":"2025-06-08T21:56:46","modified_gmt":"2025-06-09T01:56:46","slug":"sistema-911-coordina-respuesta-a-incendio-en-instalaciones-del-merca-santo-domingo","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/06\/08\/sistema-911-coordina-respuesta-a-incendio-en-instalaciones-del-merca-santo-domingo\/","title":{"rendered":"Sistema 911 coordina respuesta a incendio en instalaciones del MERCA Santo Domingo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>21 unidades de Bomberos de diferentes municipios se encuentran sofocando el siniestro. El evento se encuentra en desarrollo.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 911 coordin\u00f3 la respuesta ante un incendio registrado en una de las naves del MERCA Santo Domingo, ubicado en el municipio Pedro Brand, provincia Santo Domingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras recibir la alerta a trav\u00e9s de la l\u00ednea \u00fanica de emergencias, el Sistema 911 activ\u00f3 los protocolos correspondientes y moviliz\u00f3 unidades de respuesta de distintas instituciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la escena se encuentran desplegadas 21 unidades de Bomberos pertenecientes al Distrito Nacional, Santo Domigo Oeste, Santo Domingo Norte, Santo Domingo Este, La Guayiga, Cuaba, Los Alcarrizos, Haina y de la provincia San Crist\u00f3bal, quienes dirigen y ejecutan las labores del combate del fuego; dos equipos de drones del Sistema 911; cuatro unidades de ambulancias de la Direcci\u00f3n de Servicios de Atenci\u00f3n a Emergencias Extrahospitalarias (DAEH), cuatro unidades de Polic\u00eda Nacional, una de DIGESETT.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se coordin\u00f3 el apoyo de tres camiones cisterna de la Corporaci\u00f3n del Acueducto y Alcantarillado de Santo Domingo (CAASD) reforzando el suministro de agua para el control del siniestro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta el momento, no se reportan personas heridas ni afectadas. Sin embargo, se ha confirmado que varios establecimientos dentro del MERCA resultaron incendiados. El caso se encuentra en desarrollo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Sistema 911 contin\u00faa el seguimiento activo del evento y destaca el trabajo incansable de los cuerpos de bomberos para sofocar el incendio que afecta al referido establecimiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>21 unidades de Bomberos de diferentes municipios se encuentran sofocando el siniestro. El evento se encuentra en desarrollo. El Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 911 coordin\u00f3 la&hellip;<\/p>\n","protected":false},"author":2,"featured_media":100551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35],"tags":[1399,840,20357,806,13177],"class_list":["post-100550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-incendio","tag-instalaciones","tag-merca","tag-santo-domingo","tag-sistema-911"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/FUEGO-1.jpg","jetpack-related-posts":[{"id":86787,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/07\/31\/sistema-911-coordina-asistencia-en-incendio-de-tienda-en-bajos-de-haina\/","url_meta":{"origin":100550,"position":0},"title":"Sistema 911 coordina asistencia en incendio de tienda en Bajos de Haina","author":"Nelson Feliz","date":"31 de julio de 2024","format":false,"excerpt":"Las autoridades han desplegado m\u00faltiples unidades para controlar el incendio y asistir a los afectados en el lugar. El evento contin\u00faa en desarrollo. El Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 911 coordin\u00f3 la asistencia de los Cuerpos de Bomberos de San Crist\u00f3bal, Haina, Distrito Nacional, Yaguate, Santo Domingo\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/incendio-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/incendio-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/incendio-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/incendio-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":83913,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/05\/27\/sistema-911-coordina-asistencia-en-incendio-de-tienda-ubicada-en-mejoramiento-social\/","url_meta":{"origin":100550,"position":1},"title":"Sistema 911 coordina asistencia en incendio de tienda ubicada en Mejoramiento Social","author":"Nelson Feliz","date":"27 de mayo de 2024","format":false,"excerpt":"Hasta el momento no se han reportado afectados. El caso contin\u00faa en desarrollo. El Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 911 coordin\u00f3 la asistencia a un incendio que se origin\u00f3 la ma\u00f1ana de este lunes, en una tienda ubicada en el sector Mejoramiento Social, Distrito Nacional.\u00a0 De inmediato,\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Bomberos-del-Distrito-Nacional-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Bomberos-del-Distrito-Nacional-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Bomberos-del-Distrito-Nacional-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Bomberos-del-Distrito-Nacional-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":85233,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/06\/25\/incendio-en-nave-ubicada-en-autopista-duarte-es-asistido-por-el-911\/","url_meta":{"origin":100550,"position":2},"title":"Incendio en\u00a0 nave ubicada en autopista Duarte es asistido por el 911","author":"Nelson Feliz","date":"25 de junio de 2024","format":false,"excerpt":"Personal en la escena no ha reportado ning\u00fan afectado, hasta el momento. El caso contin\u00faa en desarrollo. El Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 911 inform\u00f3 que, bajo su coordinaci\u00f3n, unidades del Cuerpo de Bomberos del Distrito Nacional (DN) asiste el incendio que se origin\u00f3 este martes, en\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Incendio-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Incendio-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Incendio-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Incendio-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":87212,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/08\/08\/sistema-911-coordina-asistencia-de-incendio-en-zona-franca-de-rafey\/","url_meta":{"origin":100550,"position":3},"title":"Sistema 911 coordina asistencia de incendio en zona franca de Rafey","author":"Nelson Feliz","date":"8 de agosto de 2024","format":false,"excerpt":"Seg\u00fan informes, se trat\u00f3 de una nave incendiada en la referida zona franca, sin reportes de personas afectadas. El Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 911 inform\u00f3 que coordin\u00f3 la asistencia de un incendio en la zona industrial Rafey, Santiago, el cual fue visualizado por las c\u00e1maras de\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Zona Industrial Rafey","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Zona-Industrial-Rafey.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Zona-Industrial-Rafey.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Zona-Industrial-Rafey.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":89730,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/10\/03\/911-sofoca-incendio-de-fabrica-en-zona-industrial-de-santiago\/","url_meta":{"origin":100550,"position":4},"title":"911 sofoca incendio de f\u00e1brica en zona industrial de Santiago","author":"Nelson Feliz","date":"3 de octubre de 2024","format":false,"excerpt":"El Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 911 coordina la respuesta ante un incendio que se desat\u00f3 en una f\u00e1brica de pl\u00e1stico y papel, ubicada en el sector Pontezuela Arriba, municipio Santiago, la tarde de este jueves. El siniestro afect\u00f3 una nave industrial de dos niveles en la\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/incendio-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/incendio-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/incendio-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/incendio-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":85210,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/06\/25\/se-incendia-nave-industrial-en-la-autopista-duarte\/","url_meta":{"origin":100550,"position":5},"title":"Se incendia nave industrial en la Autopista Duarte","author":"Nelson Feliz","date":"25 de junio de 2024","format":false,"excerpt":"Una nave industrial, ubicada en el kil\u00f3metro 11 de la Autopista Duarte, se incendi\u00f3 la ma\u00f1ana de este martes sin que se reporten afectados hasta el momento. De acuerdo al reporte del Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 911, varias unidades del Cuerpo de Bomberos del Distrito Nacional\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Incendio","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Incendio-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Incendio-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Incendio-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Incendio-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=100550"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100550\/revisions"}],"predecessor-version":[{"id":100552,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/100550\/revisions\/100552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/100551"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=100550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=100550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=100550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}