{"id":104194,"date":"2025-07-22T12:33:40","date_gmt":"2025-07-22T16:33:40","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=104194"},"modified":"2025-07-22T12:33:41","modified_gmt":"2025-07-22T16:33:41","slug":"abinader-sale-la-manana-de-este-miercoles-a-guyana-y-regresa-en-horas-de-la-tarde","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/22\/abinader-sale-la-manana-de-este-miercoles-a-guyana-y-regresa-en-horas-de-la-tarde\/","title":{"rendered":"Abinader sale la ma\u00f1ana de este mi\u00e9rcoles a Guyana y regresa en horas de la tarde"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Mandatario viaja para asistir a la fundaci\u00f3n de la Alianza Global por la Biodiversidad de la cual es fundador.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente Luis Abinader partir\u00e1 la ma\u00f1ana de este mi\u00e9rcoles hacia Guyana y regresar\u00e1 en horas de la tarde, para participar en el acto inaugural de la Alianza Global por la Biodiversidad, una iniciativa internacional destinada a enfrentar la crisis ambiental y clim\u00e1tica a trav\u00e9s de la cooperaci\u00f3n global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acto constituci\u00f3n a donde han sido invitados jefes de Estado, gobiernos, organismos multilaterales, sector privado, academias, comunidades ind\u00edgenas y sociedad civil, tendr\u00e1 lugar en Georgetown, Guyana, del 23 al 25 de este mes, es una iniciativa que marcar\u00e1 un nuevo hito en la acci\u00f3n internacional frente a la crisis ambiental y clim\u00e1tica actual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este evento, la Rep\u00fablica Dominicana, a trav\u00e9s del presidente Luis Abinader, proyectar\u00e1 su liderazgo regional y global en la defensa de la biodiversidad como activo estrat\u00e9gico para el bienestar, la resiliencia y crecimiento econ\u00f3mico sostenible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Alianza estar\u00e1 conformada por l\u00edderes de gobiernos, organismos multilaterales, entidades del sector privado, centros acad\u00e9micos, organizaciones cient\u00edficas, comunidades locales e ind\u00edgenas y actores de la sociedad civil, quienes trabajar\u00e1n de manera articulada para impulsar soluciones concretas y medibles que promuevan la conservaci\u00f3n y el uso sostenible de la biodiversidad como pilar de desarrollo global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente Abinader tendr\u00e1 una intervenci\u00f3n durante el acto de lanzamiento de la Alianza Global por la Biodiversidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mandatario viaja para asistir a la fundaci\u00f3n de la Alianza Global por la Biodiversidad de la cual es fundador. El presidente Luis Abinader partir\u00e1 la ma\u00f1ana de este mi\u00e9rcoles hacia&hellip;<\/p>\n","protected":false},"author":10,"featured_media":54873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35,25],"tags":[50,3539,22041,8408,4334,2744,67,826,22040],"class_list":["post-104194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada","tag-alianza","tag-biodiversidad","tag-en-la-tarde","tag-este-miercoles","tag-global","tag-guyana","tag-luis-abinader","tag-regresa","tag-sale"],"jetpack-related-posts":[{"id":104283,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/23\/abinader-viaja-a-guyana-para-participar-en-la-fundacion-de-la-alianza-global-por-la-biodiversidad\/","url_meta":{"origin":104194,"position":0},"title":"Abinader viaja a Guyana para participar en la fundaci\u00f3n de la Alianza Global por la Biodiversidad","author":"Nelson Feliz","date":"23 de julio de 2025","format":false,"excerpt":"En estos momentos, el presidente Luis Abinader viaja hacia la Rep\u00fablica Cooperativa de Guyana para participar en el acto inaugural de la Alianza Global por la Biodiversidad. El mandatario sali\u00f3 a las 7:29 de la ma\u00f1ana desde la Base A\u00e9rea de San Isidro, donde fue despedido por el ministro de\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/LA-viaja.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/LA-viaja.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/LA-viaja.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/LA-viaja.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":104088,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/21\/crearan-la-alianza-global-por-la-biodiversidad-durante-evento-en-guyana-esta-semana\/","url_meta":{"origin":104194,"position":1},"title":"Crear\u00e1n la Alianza Global por la Biodiversidad durante evento en Guyana esta semana","author":"Nelson Feliz","date":"21 de julio de 2025","format":false,"excerpt":"Presidente Abinader ser\u00e1 fundador. Estar\u00e1 presente en el acto inaugural La Alianza Global por la Biodiversidad, de la que el presidente dominicano Luis Abinader ser\u00e1 fundador, quedar\u00e1 constituida esta semana durante un acto en Guyana, a donde han sido invitados jefes de Estado, gobiernos, organismos multilaterales, sector privado, academias, comunidades\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Alianza-Global.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Alianza-Global.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Alianza-Global.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Alianza-Global.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":104356,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/23\/presidente-abinader-propone-se-declare-sargazo-una-prioridad-regional\/","url_meta":{"origin":104194,"position":2},"title":"Presidente Abinader propone se declare sargazo una prioridad regional","author":"Nelson Feliz","date":"23 de julio de 2025","format":false,"excerpt":"GUYANA.- El presidente dominicano Luis Abinader destac\u00f3 este mi\u00e9rcoles que la biodiversidad no es un lujo ni un concepto abstracto, sino la base de la seguridad alimentaria, la salud y el bienestar econ\u00f3mico de los pueblos y afirm\u00f3 que defenderla es un imperativo \u00e9tico y una condici\u00f3n para la paz\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/abinader.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/abinader.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/abinader.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":130460,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/13\/presidente-abinader-llega-a-guyana-en-cuarta-visita-oficial\/","url_meta":{"origin":104194,"position":3},"title":"Presidente Abinader llega a Guyana en cuarta visita oficial","author":"Nelson Feliz","date":"13 de mayo de 2026","format":false,"excerpt":"Ambos mandatarios dar\u00e1n seguimiento a los m\u00faltiples acuerdos firmados desde 2023 en temas de energ\u00eda, seguridad alimentaria y cooperaci\u00f3n comercial Georgetown, Guyana. - El presidente Luis Abinader arrib\u00f3 a Guyana a las 6:05 de la tarde de este mi\u00e9rcoles, donde tiene agendado la firma de acuerdos de cooperaci\u00f3n con el\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Luis-Abinader-7-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Luis-Abinader-7-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Luis-Abinader-7-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Luis-Abinader-7-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":130490,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/14\/abinader-llega-a-casa-de-gobierno-en-guyana-sostendra-reunion-bilateral-con-su-homologo-mohamed-irfaan-ali\/","url_meta":{"origin":104194,"position":4},"title":"Abinader llega a Casa de Gobierno en Guyana; sostendr\u00e1 reuni\u00f3n bilateral con su hom\u00f3logo Mohamed Irfaan Al\u00ed","author":"Nelson Feliz","date":"14 de mayo de 2026","format":false,"excerpt":"_Tambi\u00e9n se lleva a cabo desayuno oficial y se firmar\u00e1 nuevo acuerdo de cooperaci\u00f3n_ Georgetown. - El presidente Luis Abinader inici\u00f3 las actividades oficiales de este jueves en la ciudad de Georgetown, Guyana, con un desayuno en la Casa de Gobierno, invitado por su hom\u00f3logo Mohamed Irfaan Al\u00ed. El jefe\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0301.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0301.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0301.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0301.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/IMG-20260514-WA0301.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":130455,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/13\/presidente-abinader-viaja-hoy-miercoles-a-guyana\/","url_meta":{"origin":104194,"position":5},"title":"Presidente Abinader viaja hoy mi\u00e9rcoles a Guyana","author":"Nelson Feliz","date":"13 de mayo de 2026","format":false,"excerpt":"Ambos mandatarios dar\u00e1n seguimiento a los m\u00faltiples acuerdos firmados desde 2023 en materia de energ\u00eda, seguridad alimentaria y cooperaci\u00f3n comercial Georgetown, Guyana. - El presidente Luis Abinader viajar\u00e1 este mi\u00e9rcoles en horas de la noche a Guyana, donde tiene programada una reuni\u00f3n bilateral y la firma de acuerdos de cooperaci\u00f3n\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Luis Abinader","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Luis-Abinader-viaja.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Luis-Abinader-viaja.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Luis-Abinader-viaja.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Luis-Abinader-viaja.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Luis-Abinader-viaja.jpg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/104194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=104194"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/104194\/revisions"}],"predecessor-version":[{"id":104195,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/104194\/revisions\/104195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/54873"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=104194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=104194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=104194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}