{"id":105507,"date":"2025-08-04T13:10:34","date_gmt":"2025-08-04T17:10:34","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=105507"},"modified":"2025-08-04T13:10:36","modified_gmt":"2025-08-04T17:10:36","slug":"card-saluda-acto-de-valentia-la-promulgacion-del-nuevo-codigo-penal","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/08\/04\/card-saluda-acto-de-valentia-la-promulgacion-del-nuevo-codigo-penal\/","title":{"rendered":"CARD saluda acto de valent\u00eda la promulgaci\u00f3n del nuevo C\u00f3digo Penal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>-Trajano Potentini resalta avances logrados y asegura que con esta decisi\u00f3n se pone fin a una legislaci\u00f3n obsoleta.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-Colegio de Abogados anuncia jornada de socializaci\u00f3n y conocimiento de la nueva normativa para garantizar su exitosa implementaci\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente del Colegio de Abogados de la Rep\u00fablica Dominicana (CARD), Trajano Potentini, salud\u00f3 y calific\u00f3 como un acto de valent\u00eda y responsabilidad pol\u00edtica la promulgaci\u00f3n del nuevo C\u00f3digo Penal (Ley No. 74-25), por parte del presidente de la Rep\u00fablica, Luis Abinader.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 que con esta medida se cierra un cap\u00edtulo marcado por una legislaci\u00f3n desfasada y obsoleta, heredada de los franceses, con los denominados c\u00f3digos napole\u00f3nicos de inicio del pasado siglo XIX, con ello se abre el camino a un marco jur\u00eddico penal m\u00e1s moderno, justo y adaptado a los retos actuales de la sociedad dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La promulgaci\u00f3n de la Ley No. 74-25, nuevo C\u00f3digo Penal, marca el final de una legislaci\u00f3n obsoleta que, durante d\u00e9cadas, ha representado un freno significativo para el desarrollo de un sistema de justicia moderno, \u00e1gil y eficaz en la Rep\u00fablica Dominicana&#8221;, acot\u00f3 Potentini.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl viejo C\u00f3digo Penal, vigente desde 1884, ya no reflejaba las complejidades del crimen moderno ni garantizaba una respuesta oportuna del sistema de justicia ante nuevas formas de criminalidad. Con esta promulgaci\u00f3n, se pone fin a una legislaci\u00f3n obsoleta y se inaugura un nuevo paradigma de justicia penal\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Colegio de Abogados valor\u00f3 los m\u00faltiples avances introducidos en el nuevo cuerpo normativo, destacando la tipificaci\u00f3n de nuevos delitos y modernizaci\u00f3n de existentes, como el feminicidio, sicariato, el acoso laboral, el cibercrimen, los delitos contra la integridad sexual, el c\u00famulo de penas, el notorio avance en el abordaje de la violencia de g\u00e9nero y protecci\u00f3n a v\u00edctimas, entre otros flagelos que afectan a la sociedad dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se destac\u00f3 el fortalecimiento de las garant\u00edas procesales, el enfoque en los derechos humanos, y la adaptaci\u00f3n del c\u00f3digo a los compromisos internacionales asumidos por la Rep\u00fablica Dominicana en materia de derecho penal y derechos fundamentales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las deficiencias m\u00e1s notorias del c\u00f3digo anterior era su incapacidad para abordar las nuevas modalidades delictivas surgidas con la globalizaci\u00f3n y el avance tecnol\u00f3gico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nuevo C\u00f3digo Penal subsana esta carencia al incorporar de manera expl\u00edcita y detallada delitos como el cibercrimen en todas sus vertientes (desde el fraude inform\u00e1tico hasta la pornograf\u00eda infantil en l\u00ednea), la trata de personas, la explotaci\u00f3n sexual comercial, el lavado de activos con una definici\u00f3n m\u00e1s amplia y adaptada a los est\u00e1ndares internacionales, diversas formas de corrupci\u00f3n administrativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trajano Potentini tambi\u00e9n anunci\u00f3 que el CARD, fiel a su rol de garante de la pr\u00e1ctica profesional y defensor de la justicia, reitera su disposici\u00f3n inquebrantable a colaborar activamente con el Poder Judicial, el Ministerio P\u00fablico, la Defensa P\u00fablica y todas las instituciones relacionadas con la administraci\u00f3n de justicia para asegurar una implementaci\u00f3n exitosa y efectiva del nuevo C\u00f3digo, (Ley No. 74-25) Penal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, el CARD pondr\u00e1 en marcha un plan nacional de formaci\u00f3n y difusi\u00f3n del nuevo c\u00f3digo, a fin de garantizar que todos los profesionales del derecho y sectores vinculados est\u00e9n debidamente capacitados para su correcta interpretaci\u00f3n y aplicaci\u00f3n, incluyendo, adem\u00e1s un levantamiento de aquellas disposiciones contenidas en los 393 art\u00edculos del c\u00f3digo que pudieran ser mejoradas en el a\u00f1o de vacaciones judiciales previsto para su entrada en vigencia, verificando y planteando algunas posibles correcciones, en lo relativo a aspectos propios de la libertad de expresi\u00f3n, los delitos de alta tecnolog\u00eda y redes sociales, revisando tambi\u00e9n, como planteara a t\u00edtulo de preocupaci\u00f3n el magistrado Alejandro Vargas, sobre la inflaci\u00f3n punitiva del m\u00ednimum de las penas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl pueblo dominicano ha dado un paso trascendental. Saludamos esta decisi\u00f3n del presidente Luis Abinader como un acto de madurez democr\u00e1tica y compromiso institucional que ser\u00e1 recordado por generaciones\u201d, concluy\u00f3 Potentini.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"CARD saluda la promulgaci\u00f3n del nuevo C\u00f3digo Penal\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/5H0Ddz7dF3g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>-Trajano Potentini resalta avances logrados y asegura que con esta decisi\u00f3n se pone fin a una legislaci\u00f3n obsoleta. -Colegio de Abogados anuncia jornada de socializaci\u00f3n y conocimiento de la nueva&hellip;<\/p>\n","protected":false},"author":10,"featured_media":75689,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35,25],"tags":[22686,5847,13808,5085],"class_list":["post-105507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada","tag-acto-de-valentia","tag-card","tag-codigo-penal","tag-promulgacion"],"jetpack-related-posts":[{"id":115053,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/11\/18\/colegio-abogados-rechaza-prorroga-conocer-codigo-penal\/","url_meta":{"origin":105507,"position":0},"title":"Colegio Abogados rechaza pr\u00f3rroga conocer C\u00f3digo Penal","author":"Nelson Feliz","date":"18 de noviembre de 2025","format":false,"excerpt":"El Colegio de Abogados de la Rep\u00fablica Dominicana (CARD) rechaz\u00f3 que el Tribunal Constitucional (TC) otorgue una nueva pr\u00f3rroga al Congreso para continuar con la revisi\u00f3n del C\u00f3digo Procesal Penal. Trajano Potentini, presidente del gremio, advirti\u00f3 que permitir una extensi\u00f3n del plazo implicar\u00eda que el TC volver\u00eda sobre sus propios\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Trajano Potentini","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Trajano-Potentini.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Trajano-Potentini.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Trajano-Potentini.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":135675,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/07\/26\/presidente-del-cardel-articulo-310-del-codigo-penal-criminaliza-el-derecho-de-defensa\/","url_meta":{"origin":105507,"position":1},"title":"Presidente del CARD:El art\u00edculo 310 del C\u00f3digo Penal criminaliza el derecho de defensa","author":"Nelson Feliz","date":"26 de julio de 2026","format":false,"excerpt":"Potentini convoca a la clase jur\u00eddica a respaldar acci\u00f3n de inconstitucionalidad contra el C\u00f3digo Penal Santo Domingo, RD.\u2013 El presidente del Colegio de Abogados de la Rep\u00fablica Dominicana (CARD), convoc\u00f3 a la comunidad jur\u00eddica del pa\u00eds a concentrarse este lunes frente Tribunal Constitucional, en la Plaza de la Bandera, para\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Trajano Potentini","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/07\/Trajano-Potentini.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/07\/Trajano-Potentini.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/07\/Trajano-Potentini.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/07\/Trajano-Potentini.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":109902,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/09\/23\/expresidentes-del-colegio-de-abogados-la-gestion-de-potentini-no-ha-alcanzado-los-resultados-esperados\/","url_meta":{"origin":105507,"position":2},"title":"Expresidentes del Colegio de Abogados: La gesti\u00f3n de Potentini no ha alcanzado los resultados esperados","author":"Nelson Feliz","date":"23 de septiembre de 2025","format":false,"excerpt":"El Consejo Nacional de Expresidentes del Colegio de Abogados de la Rep\u00fablica Dominicana (CNEXPCARD), inform\u00f3 a la opini\u00f3n p\u00fablica que, tras m\u00faltiples esfuerzos orientados a lograr un entendimiento entre los candidatos Johan L\u00f3pez y Trajano Vidal Potentini, quienes se declararon ganadores de las elecciones celebradas en diciembre de 2023, dichas\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Expresidentes-del-Colegio-de-Abogados-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Expresidentes-del-Colegio-de-Abogados-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Expresidentes-del-Colegio-de-Abogados-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Expresidentes-del-Colegio-de-Abogados-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":115292,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/11\/20\/trajano-vidal-potentini-califica-de-desafortunada-e-innecesaria-sentencia-del-tc\/","url_meta":{"origin":105507,"position":3},"title":"Trajano Vidal Potentini califica de desafortunada e innecesaria sentencia del TC","author":"Nelson Feliz","date":"20 de noviembre de 2025","format":false,"excerpt":"El Colegio de Abogados de la Rep\u00fablica Dominicana calific\u00f3 como \u00abdesafortunada e innecesaria\u00bb la reciente sentencia del Tribunal Constitucional que despenaliza las relaciones homosexuales entre miembros de la Polic\u00eda Nacional y las Fuerzas Armadas, la cual ha generado un amplio debate jur\u00eddico, social e institucional en el pa\u00eds. El presidente\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Trajano Vidal Potentini","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Trajano-Vidal-Potentini.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Trajano-Vidal-Potentini.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Trajano-Vidal-Potentini.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Trajano-Vidal-Potentini.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":104999,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/29\/fedomu-y-colegio-de-abogados-capacitaran-juristas-de-los-ayuntamientos\/","url_meta":{"origin":105507,"position":4},"title":"Fedomu y Colegio de Abogados capacitar\u00e1n juristas de los ayuntamientos","author":"Nelson Feliz","date":"29 de julio de 2025","format":false,"excerpt":"Ambas entidades firman acuerdo de colaboraci\u00f3n. La Federaci\u00f3n Dominicana de Municipios (Fedomu) y el Colegio de Abogados de la Rep\u00fablica Dominicana (CARD) desarrollar\u00e1n talleres de capacitaci\u00f3n t\u00e9cnica jur\u00eddica en las 10 regionales de municipios para los abogados de los ayuntamientos que sean previamente seleccionados por los alcaldes. Durante la firma\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/fedomu-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/fedomu-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/fedomu-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/fedomu-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":113731,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/11\/05\/card-califico-prudente-posposicion-de-la-cumbre-de-las-americas\/","url_meta":{"origin":105507,"position":5},"title":"CARD calific\u00f3 prudente posposici\u00f3n de la Cumbre de las Am\u00e9ricas","author":"Nelson Feliz","date":"5 de noviembre de 2025","format":false,"excerpt":"El Colegio de Abogados de la Rep\u00fablica Dominicana (CARD), que preside el jurista Trajano Potentini, calific\u00f3 como atinada, prudente y responsable la decisi\u00f3n del Gobierno dominicano de posponer para el pr\u00f3ximo a\u00f1o 2026, la X Cumbre de las Am\u00e9ricas prevista a celebrarse en el mes de diciembre del presente a\u00f1o\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Trajano Potentini","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Trajano-Potentini.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Trajano-Potentini.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Trajano-Potentini.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/02\/Trajano-Vidal-Potentini.jpg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/105507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=105507"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/105507\/revisions"}],"predecessor-version":[{"id":105508,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/105507\/revisions\/105508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/75689"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=105507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=105507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=105507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}