{"id":114156,"date":"2025-11-11T09:33:18","date_gmt":"2025-11-11T13:33:18","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=114156"},"modified":"2025-11-11T09:33:19","modified_gmt":"2025-11-11T13:33:19","slug":"dominicanos-perderan-trabajos-por-cierre-300-restaurant-wendys-en-usa","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/11\/11\/dominicanos-perderan-trabajos-por-cierre-300-restaurant-wendys-en-usa\/","title":{"rendered":"Dominicanos perder\u00e1n trabajos por cierre 300 restaurant Wendy\u2019s en USA"},"content":{"rendered":"\n<p>Por Ram\u00f3n Mercedes<\/p>\n\n\n\n<p>NUEVA YORK.- Decenas de dominicanos, entre los cientos que laboran en la cadena de restaurantes Wendy\u2019s en los Estados Unidos, perder\u00e1n sus trabajos por el cierre a final del presente a\u00f1o de 300 de estos establecimientos, una de las mayores reducciones operativas de su historia reciente.<\/p>\n\n\n\n<p>En territorio estadounidense operan cerca de seis mil de estos negocios, entre ellos decenas en NYC.<\/p>\n\n\n\n<p>A nivel internacional, Wendy&#8217;s es la tercera cadena de hamburguesas m\u00e1s grande de USA, con m\u00e1s de 13.817 establecimientos, por detr\u00e1s de McDonald&#8217;s y Burger King.<\/p>\n\n\n\n<p>La noticia llega apenas un a\u00f1o despu\u00e9s de que la compa\u00f1\u00eda clausurara 140 locales, en un intento por reestructurar su red de franquicias y mejorar su rentabilidad.<\/p>\n\n\n\n<p>El anuncio fue realizado por el director ejecutivo interino, Ken Cook, durante la presentaci\u00f3n de resultados trimestrales celebrada el pasado fin de semana.<\/p>\n\n\n\n<p>Wendy&#8217;s es una empresa multinacional de restaurantes de comida r\u00e1pida con sede en Dublin, Ohio-USA. Su men\u00fa est\u00e1 compuesto por hamburguesas, s\u00e1ndwiches, batidos, papas fritas, ensalada, desayuno, postre helado, bebidas gaseosas, entre otros productos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Ram\u00f3n Mercedes NUEVA YORK.- Decenas de dominicanos, entre los cientos que laboran en la cadena de restaurantes Wendy\u2019s en los Estados Unidos, perder\u00e1n sus trabajos por el cierre a&hellip;<\/p>\n","protected":false},"author":10,"featured_media":114157,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[25580],"tags":[26988],"class_list":["post-114156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-voz-de-la-diaspora","tag-dominicanos-perderan-trabajos-por-cierre-300-restaurant-wendys-en-usa"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-11-at-6.12.29-AM.jpeg","jetpack-related-posts":[{"id":95831,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/19\/cientos-de-dominicanos-en-eua-perderan-sus-trabajos-por-cierre-350-tiendas-forever-21\/","url_meta":{"origin":114156,"position":0},"title":"Cientos de dominicanos en EUA perder\u00e1n sus trabajos por cierre 350 tiendas Forever 21","author":"Nelson Feliz","date":"19 de marzo de 2025","format":false,"excerpt":"Por Ram\u00f3n Mercedes NUEVA YORK.- Cientos de dominicanos residentes en los Estados Unidos perder\u00e1n sus trabajos debido al cierre de 350 tiendas de la reconocida y multinacional tienda minorista de moda r\u00e1pida, Forever 21. El cierre ocurre tras declararse en bancarrota. Forever 21, con m\u00e1s de cuatro d\u00e9cadas y oficinas\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"Cientos de dominicanos en EUA perder\u00e1n sus trabajos por cierre 350 tiendas Forever 21","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.35.00-AM-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.35.00-AM-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.35.00-AM-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-19-at-5.35.00-AM-1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":108985,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/09\/12\/recortes-del-medicaid-por-el-gobierno-usa-afectara-neoyorquinos-en-sector-salud-y-snap\/","url_meta":{"origin":114156,"position":1},"title":"Recortes del Medicaid por el gobierno USA afectar\u00e1 neoyorquinos en sector salud y SNAP","author":"Nelson Feliz","date":"12 de septiembre de 2025","format":false,"excerpt":"Por Ram\u00f3n Mercedes NUEVA YORK.- Los recortes a Medicaid podr\u00edan reducir los ingresos de los proveedores de atenci\u00f3n m\u00e9dica de NY en hasta $10 mil millones a nivel estatal, lo que podr\u00eda costar al estado 78,000 empleos en el sector salud y 136,000 empleos adicionales como consecuencia de las repercusiones\u2026","rel":"","context":"En \u00abSALUD\u00bb","block_context":{"text":"SALUD","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/salud\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-12-at-7.26.41-AM-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-12-at-7.26.41-AM-2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-12-at-7.26.41-AM-2.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":118042,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/12\/19\/fiesta-navidena-de-los-300-con-leonel-en-nyc-supera-las-de-varias-instituciones-en-conjunto\/","url_meta":{"origin":114156,"position":2},"title":"Fiesta navide\u00f1a de los \u00ab300 con Leonel\u00bb en NYC supera las de varias instituciones en conjunto","author":"Nelson Feliz","date":"19 de diciembre de 2025","format":false,"excerpt":"https:\/\/www.youtube.com\/watch?v=dWmWACdWH6Y Por Ram\u00f3n Mercedes NUEVA YORK.- La tradicional fiesta navide\u00f1a del Proyecto \u00ab300 con Leonel\u00bb, que dirige Geraldo Rosario, celebrada el pasado d\u00eda 7 en esta ciudad, ha superado en conjunto la asistencia de varias festividades de reconocidas instituciones. Observadores pol\u00edticos quisqueyanos en el Alto Manhattan y El Bronx, condados\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/Fiesta-navidena-de-los-300-con-Leonel-en-NYC-supera-las-de-varias-instituciones-en-conjunto.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/Fiesta-navidena-de-los-300-con-Leonel-en-NYC-supera-las-de-varias-instituciones-en-conjunto.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/Fiesta-navidena-de-los-300-con-Leonel-en-NYC-supera-las-de-varias-instituciones-en-conjunto.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":111757,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/10\/13\/300-con-leonel-finaliza-con-exito-asamblea-2025-amplian-directiva-en-usa\/","url_meta":{"origin":114156,"position":3},"title":"300 con Leonel finaliza con \u00e9xito asamblea 2025; ampl\u00edan directiva en USA","author":"Nelson Feliz","date":"13 de octubre de 2025","format":false,"excerpt":"Por Ram\u00f3n Mercedes NUEVA YORK.- El proyecto pol\u00edtico en esta ciudad \u00ab300 con Leonel\u00bb (los multiplicadores de NY), que preside Geraldo Rosario, finaliz\u00f3 la semana pasada con \u00e9xito su asamblea 2025, aprobando la reestructuraci\u00f3n y ampliaci\u00f3n de la entidad en los estados de la circunscripci\u00f3n 1-USA. La ampliaci\u00f3n de la\u2026","rel":"","context":"En \u00abLA VOZ DE LA DIASPORA\u00bb","block_context":{"text":"LA VOZ DE LA DIASPORA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/la-voz-de-la-diaspora\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-13-at-7.06.42-AM-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-13-at-7.06.42-AM-2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-13-at-7.06.42-AM-2.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":61909,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/01\/abel-gobierno-perdio-el-norte-tambien-perdera-las-elecciones\/","url_meta":{"origin":114156,"position":4},"title":"Abel: &#8220;Gobierno perdi\u00f3 el norte; tambi\u00e9n perder\u00e1 las elecciones&#8221;","author":"Nelson Feliz","date":"1 de octubre de 2023","format":false,"excerpt":"El candidato presidencial del Partido de la Liberaci\u00f3n Dominicana (PLD), Abel Mart\u00ednez, declar\u00f3 ante una multitud de dominicanos que lo esper\u00f3 en New Jersey, que el Gobierno del PRM perdi\u00f3 el rumbo y el norte. El l\u00edder de la oposici\u00f3n a\u00f1adi\u00f3 que, a consecuencia de esa realidad, perder\u00e1 tambi\u00e9n las\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Abel-Martinez.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Abel-Martinez.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Abel-Martinez.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Abel-Martinez.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":107275,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/08\/25\/movimientos-externos-en-torno-a-leonel-en-usa-trazan-linea-de-accion\/","url_meta":{"origin":114156,"position":5},"title":"Movimientos externos en torno a Leonel en USA trazan l\u00ednea de acci\u00f3n","author":"Nelson Feliz","date":"25 de agosto de 2025","format":false,"excerpt":"Por Ram\u00f3n Mercedes NUEVA YORK.- Varios movimientos externos en torno al l\u00edder del Partido Fuerza del Pueblo (FP), Leonel Fern\u00e1ndez, iniciaron acciones puntuales de sus trabajos pol\u00edticos de afiliaci\u00f3n de nuevos miembros, promoci\u00f3n y juramentaciones en los Estados Unidos, para nuclearlo hacia el presidente de la organizaci\u00f3n. Geraldo Rosario, representante\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-25-at-6.20.09-AM-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/114156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=114156"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/114156\/revisions"}],"predecessor-version":[{"id":114158,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/114156\/revisions\/114158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/114157"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=114156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=114156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=114156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}