{"id":117722,"date":"2025-12-14T23:35:28","date_gmt":"2025-12-15T03:35:28","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=117722"},"modified":"2025-12-14T23:35:30","modified_gmt":"2025-12-15T03:35:30","slug":"padre-e-hijo-armados-matan-al-menos-a-15-personas-en-un-evento-de-hanukkah-en-bondi-beach-sidney","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/12\/14\/padre-e-hijo-armados-matan-al-menos-a-15-personas-en-un-evento-de-hanukkah-en-bondi-beach-sidney\/","title":{"rendered":"Padre e hijo armados matan al menos a 15 personas en un evento de Hanukkah en Bondi Beach, S\u00eddney"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por KRISTEN GELINEAU , CHARLOTTE GRAHAM-MCLAY y ROD MCGUIRK<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00cdDNEY (AP) \u2014 Dos hombres armados abrieron fuego durante una celebraci\u00f3n de Januc\u00e1 en la playa Bondi de S\u00eddney, matando a 15 personas, incluido un ni\u00f1o, informaron las autoridades el lunes, en lo que el primer ministro Anthony Albanese calific\u00f3 como un acto de terrorismo antisemita que golpe\u00f3 el coraz\u00f3n de la naci\u00f3n. Los tiradores eran padre e hijo, informaron las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La masacre en una de las playas m\u00e1s populares de Australia se produjo tras una ola de ataques antisemitas que han sacudido al pa\u00eds durante el \u00faltimo a\u00f1o, aunque las autoridades no insinuaron que estos y el tiroteo del domingo estuvieran relacionados. Fue el tiroteo m\u00e1s mort\u00edfero en casi tres d\u00e9cadas en un pa\u00eds con estrictas leyes de control de armas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un pistolero, un hombre de 50 a\u00f1os, fue asesinado a tiros por la polic\u00eda. El otro tirador, su hijo de 24 a\u00f1os, result\u00f3 herido y estaba siendo atendido en un hospital, seg\u00fan inform\u00f3 Mal Lanyon, comisionado de polic\u00eda de Nueva Gales del Sur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La polic\u00eda dijo que los servicios de seguridad conoc\u00edan a un hombre armado, pero Lanyon dijo que las autoridades no ten\u00edan indicios de un ataque planeado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las personas fallecidas ten\u00edan entre 10 y 87 a\u00f1os, seg\u00fan inform\u00f3 a la prensa el primer ministro de Nueva Gales del Sur, Chris Minns. Al menos otras 42 personas estaban siendo atendidas en hospitales el lunes por la ma\u00f1ana, varias de ellas en estado cr\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo que vimos ayer fue un acto de pura maldad, un acto de antisemitismo, un acto de terrorismo en nuestras costas, en un lugar ic\u00f3nico de Australia, Bondi Beach, que est\u00e1 asociado con la alegr\u00eda, asociado con la reuni\u00f3n de familias, asociado con las celebraciones\u201d, dijo el lunes el primer ministro australiano, Anthony Albanese.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQuedar\u00e1 manchado para siempre por lo ocurrido\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tiroteo tuvo como objetivo una celebraci\u00f3n jud\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La violencia estall\u00f3 al final de un d\u00eda de verano, cuando miles de personas acudieron a Bondi Beach, un icono de la vida cultural australiana. Cientos de ellas se reunieron para el evento de Januc\u00e1 junto al Mar, que celebraba el inicio de los ocho d\u00edas de la festividad de Januc\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las festividades incluyeron pintacaritas y un zool\u00f3gico interactivo. Entonces se desat\u00f3 el caos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jabad, un movimiento jud\u00edo ortodoxo que realiza actividades de extensi\u00f3n mundial y patrocina eventos durante las principales festividades jud\u00edas, identific\u00f3 a uno de los muertos como el rabino Eli Schlanger, rabino asistente de Jabad de Bondi y organizador del evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio de Asuntos Exteriores de Israel confirm\u00f3 la muerte de un ciudadano israel\u00ed, pero no ofreci\u00f3 m\u00e1s detalles. El presidente franc\u00e9s, Emmanuel Macron, anunci\u00f3 que un ciudadano franc\u00e9s, identificado como Dan Elkayam, se encontraba entre los fallecidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades australianas no han revelado p\u00fablicamente el nombre de ninguna de las v\u00edctimas. Los pistoleros tampoco han sido identificados oficialmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero las historias de las v\u00edctimas comenzaron a aparecer en los medios locales el lunes. Larisa Kleytman declar\u00f3 a los periodistas a las afueras del Hospital St. Vincent que su esposo, Alexander Kleytman, se encontraba entre los fallecidos, seg\u00fan el peri\u00f3dico The Australian.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pareja era sobreviviente del Holocausto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La polic\u00eda inform\u00f3 que se llam\u00f3 a los servicios de emergencia alrededor de las 18:45, respondiendo a reportes de disparos. Un video tomado por testigos mostr\u00f3 a personas en traje de ba\u00f1o huyendo del agua mientras se o\u00edan los disparos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im\u00e1genes separadas mostraron a dos hombres con camisas negras disparando con armas largas desde una pasarela que conduc\u00eda a la playa. Un dram\u00e1tico clip transmitido por la televisi\u00f3n australiana mostr\u00f3 a un hombre que aparentemente derribaba y desarmaba a un pistolero, antes de apuntarle con el arma y luego dejarla en el suelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Minns calific\u00f3 al hombre, identificado por sus familiares a los medios australianos como el due\u00f1o de una fruter\u00eda, Ahmed al Ahmed, como un &#8220;aut\u00e9ntico h\u00e9roe&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los testigos huyeron y se escondieron cuando se oyeron los disparos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arsen Ostrovsky, un abogado que asist\u00eda a la ceremonia de Januc\u00e1 con su esposa e hijas, recibi\u00f3 un roce de bala en la cabeza. Ostrovsky cont\u00f3 que se mud\u00f3 de Israel a Australia hace dos semanas para trabajar en un grupo de defensa de los derechos jud\u00edos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo que vi hoy fue pura maldad, un ba\u00f1o de sangre. Cad\u00e1veres esparcidos por todas partes\u201d, declar\u00f3 a The Associated Press en un correo electr\u00f3nico desde el hospital. \u201cNunca pens\u00e9 que ser\u00eda posible aqu\u00ed en Australia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lachlan Moran, de 32 a\u00f1os, de Melbourne, dijo a la AP que estaba esperando a su familia cuando escuch\u00f3 disparos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Corr\u00ed tan r\u00e1pido como pude&#8221;, dijo Moran. Dijo que escuch\u00f3 disparos intermitentes durante unos cinco minutos. &#8220;Todos dejaron caer sus pertenencias y todo, y corrieron, y la gente lloraba; fue horrible&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ataques antisemitas han sacudido a Australia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Albanese prometi\u00f3 que la violencia se enfrentar\u00eda a &#8220;un momento de unidad nacional en el que los australianos, en general, acoger\u00edan a sus compatriotas de fe jud\u00eda&#8221;. Algunos de sus oponentes pol\u00edticos y el gobierno de Israel lo acusaron de no haber hecho lo suficiente para evitar semejante horror.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Australia, un pa\u00eds de 28 millones de habitantes, alberga a unos 117.000 jud\u00edos, seg\u00fan cifras oficiales. Los incidentes antisemitas, como agresiones, vandalismo, amenazas e intimidaci\u00f3n, se triplicaron en el pa\u00eds durante el a\u00f1o posterior al ataque de Ham\u00e1s a Israel el 7 de octubre de 2023, y tras el inicio de una guerra israel\u00ed contra Ham\u00e1s en Gaza como respuesta, seg\u00fan inform\u00f3 en julio la enviada especial del gobierno para combatir el antisemitismo, Jillian Segal .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El a\u00f1o pasado, el pa\u00eds se vio sacudido por ataques antisemitas en S\u00eddney y Melbourne. Sinagogas y coches fueron incendiados, negocios y viviendas fueron objeto de grafitis y jud\u00edos fueron atacados en esas ciudades, donde vive el 85% de la poblaci\u00f3n jud\u00eda del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En agosto, Albanese culp\u00f3 a Ir\u00e1n por dos de los ataques y cort\u00f3 las relaciones diplom\u00e1ticas con Teher\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Israel inst\u00f3 al gobierno australiano a abordar los cr\u00edmenes contra los jud\u00edos. El primer ministro, Benjamin Netanyahu, afirm\u00f3 haber advertido a los l\u00edderes australianos hace meses sobre los peligros de no tomar medidas contra el antisemitismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que la decisi\u00f3n de Australia, al igual que la de muchos otros pa\u00edses, de reconocer un Estado palestino &#8220;echa le\u00f1a al fuego del antisemitismo&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSu gobierno no hizo nada para detener la propagaci\u00f3n del antisemitismo en Australia\u2026 y el resultado son los horribles ataques contra los jud\u00edos que vimos hoy\u201d, dijo Netanyahu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La polic\u00eda investigar\u00e1 lo sucedido<br>Las autoridades no buscaban a nadie m\u00e1s en relaci\u00f3n con la masacre, afirm\u00f3 Lanyon. La polic\u00eda prometi\u00f3 una investigaci\u00f3n exhaustiva, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es probable que se anuncien m\u00e1s investigaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se encontraron dos artefactos explosivos improvisados \u200b\u200ben el lugar. Expertos en desactivaci\u00f3n de bombas los desactivaron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lanyon los describi\u00f3 como dispositivos \u201crudimentarios\u201d que habr\u00edan sido detonados por una mecha en lugar de un tel\u00e9fono o electr\u00f3nicamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estado de Minnesota afirm\u00f3 que &#8220;casi con toda seguridad&#8221; habr\u00eda cambios en la ley de armas tras la masacre. El pistolero de 50 a\u00f1os, abatido a tiros, ten\u00eda seis armas de fuego cuando las fuerzas del orden allanaron la propiedad donde se alojaba, seg\u00fan inform\u00f3 la polic\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las preguntas sobre c\u00f3mo pudo adquirirlas cobraron fuerza el lunes, en parte porque los tiroteos masivos en Australia son extremadamente raros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una masacre en 1996 en la ciudad de Port Arthur, en Tasmania, donde un pistolero solitario mat\u00f3 a 35 personas, impuls\u00f3 al gobierno a endurecer dr\u00e1sticamente las leyes de armas, dificultando considerablemente su adquisici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los tiroteos masivos m\u00e1s importantes de este siglo se incluyen dos asesinatos-suicidios con un saldo de cinco muertos en 2014 y siete en 2018, en los que hombres armados mataron a sus propias familias y a s\u00ed mismos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2022, seis personas murieron en un tiroteo entre la polic\u00eda y extremistas cristianos en una propiedad rural en el estado de Queensland.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los l\u00edderes mundiales expresan conmoci\u00f3n y dolor<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la masacre, comenzaron a llegar mensajes de l\u00edderes de todo el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El rey Carlos III declar\u00f3 que \u00e9l y la reina Camila estaban &#8220;horrorizados y entristecidos por el atroz ataque terrorista antisemita&#8221;. El secretario general de las Naciones Unidas, Ant\u00f3nio Guterres, declar\u00f3 en X que estaba horrorizado y que su &#8220;coraz\u00f3n est\u00e1 con la comunidad jud\u00eda mundial&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El secretario de Estado estadounidense, Marco Rubio, declar\u00f3 en una publicaci\u00f3n en X: \u00abEstados Unidos condena en\u00e9rgicamente el ataque terrorista en Australia contra una celebraci\u00f3n jud\u00eda. El antisemitismo no tiene cabida en este mundo\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por KRISTEN GELINEAU , CHARLOTTE GRAHAM-MCLAY y ROD MCGUIRK S\u00cdDNEY (AP) \u2014 Dos hombres armados abrieron fuego durante una celebraci\u00f3n de Januc\u00e1 en la playa Bondi de S\u00eddney, matando a&hellip;<\/p>\n","protected":false},"author":10,"featured_media":117723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16289],"tags":[28558,1122,1601,28559,6440,28557,2823,20197,28560],"class_list":["post-117722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","tag-15-personas","tag-armados","tag-ataque","tag-bondi-beach","tag-evento","tag-hanukkah","tag-matan","tag-padre-e-hijo","tag-sidney"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/15-personas.jpg","jetpack-related-posts":[{"id":117661,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/12\/14\/a-menos-11-muertos-en-ataque-durante-evento-judio-en-australia\/","url_meta":{"origin":117722,"position":0},"title":"A menos 11 muertos en ataque durante evento jud\u00edo en Australia","author":"Nelson Feliz","date":"14 de diciembre de 2025","format":false,"excerpt":"POR KRISTEN GELINEAU, CHARLOTTE GRAHAM-MCLAY and ROD MCGUIRK SYDNEY (AP) \u2014 Dos hombres armados mataron al menos a 11 personas el domingo durante una celebraci\u00f3n de una festividad jud\u00eda en la playa de Bondi de Sydney, informaron las autoridades australianas, que calificaron el suceso como ataque terrorista. Un hombre armado\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/muertos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/muertos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/muertos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/muertos.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":99477,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/05\/22\/asesinan-a-2-empleados-de-la-embajada-israeli-en-tiroteo-cerca-de-museo-judio-en-washington\/","url_meta":{"origin":117722,"position":1},"title":"Asesinan a 2 empleados de la embajada israel\u00ed en tiroteo cerca de museo jud\u00edo en Washington","author":"Nelson Feliz","date":"22 de mayo de 2025","format":false,"excerpt":"POR MAYA SWEEDLER WASHINGTON (AP) \u2014 Dos miembros del personal de la embajada de Israel en Washington fueron asesinados a balazos el mi\u00e9rcoles por la noche al salir de un evento en un museo jud\u00edo, y el sospechoso grit\u00f3: \"\u00a1Liberen, liberen Palestina!\u201d despu\u00e9s de ser arrestado, inform\u00f3 la polic\u00eda. El\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Asesinan.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Asesinan.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Asesinan.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Asesinan.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":52555,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/06\/11\/al-menos-diez-muertos-y-once-heridos-tras-volcar-un-autobus-en-australia\/","url_meta":{"origin":117722,"position":2},"title":"Al menos diez muertos y once heridos tras volcar un autob\u00fas en Australia","author":"prenxa100","date":"11 de junio de 2023","format":false,"excerpt":"Al menos diez personas han muerto y once resultaron heridas al volcar el autob\u00fas en el que viajaban en la localidad de Greta, a unos 180 kil\u00f3metros al norte de la ciudad de S\u00eddney, informaron este lunes fuentes policiales. La Polic\u00eda de la regi\u00f3n de Nueva Gales del Sur explic\u00f3\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":48757,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/05\/03\/menor-mata-a-nueve-personas-en-un-colegio-serbio\/","url_meta":{"origin":117722,"position":3},"title":"Menor mata a nueve personas en un colegio serbio","author":"prenxa100","date":"3 de mayo de 2023","format":false,"excerpt":"Serbia.-. Ocho estudiantes y el guardi\u00e1n de una\u00a0escuela primaria de\u00a0Belgrado\u00a0murieron a tiros y otros seis estudiantes y su profesora resultaron heridos por un alumno que fue detenido, informaron las autoridades de\u00a0Serbia,\u00a0donde en d\u00e9cadas no se hab\u00eda presentado un tiroteo de esta magnitud en un colegio. Poco despu\u00e9s de lo ocurrido,\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":49958,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/05\/15\/mueren-seis-personas-incluidos-tres-ninos-en-ataque-armado-en-campo-de-futbol\/","url_meta":{"origin":117722,"position":4},"title":"Mueren seis personas, incluidos tres ni\u00f1os, en ataque armado en campo de f\u00fatbol","author":"prenxa100","date":"15 de mayo de 2023","format":false,"excerpt":"M\u00e9xico, AP.-.Seis personas, entre ellas tres ni\u00f1os, fallecieron en un ataque armado que se registr\u00f3 en un campo de f\u00fatbol en el centro de M\u00e9xico, anunciaron el lunes autoridades estatales. El ataque ocurri\u00f3 la noche del domingo en el municipio central de Atotonilco de Tula, estado de Hidalgo, donde varios\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":53893,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/07\/03\/hombre-mata-su-hija-de-15-anos-y-luego-se-suicida-en-san-juan\/","url_meta":{"origin":117722,"position":5},"title":"Hombre mata su hija de 15 a\u00f1os y luego se suicida en San Juan","author":"Nelson Feliz","date":"3 de julio de 2023","format":false,"excerpt":"Una tragedia desgarradora sacude a la comunidad de Juan de Herrera, provincia de San Juan, donde un hombre identificado como \u00abGringo Arena\u00bb ha sido se\u00f1alado como el presunto autor de un lamentable suceso. Seg\u00fan informes, el individuo habr\u00eda acabado con la vida de su propia hija de 15 a\u00f1os para\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Gringo Arena","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Gringo-Arena.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Gringo-Arena.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Gringo-Arena.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/117722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=117722"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/117722\/revisions"}],"predecessor-version":[{"id":117724,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/117722\/revisions\/117724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/117723"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=117722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=117722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=117722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}