{"id":117774,"date":"2025-12-15T17:38:29","date_gmt":"2025-12-15T21:38:29","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=117774"},"modified":"2025-12-15T17:38:30","modified_gmt":"2025-12-15T21:38:30","slug":"mamdani-nombra-congresista-espaillat-y-otros-para-conectar-con-diversas-comunidades","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/12\/15\/mamdani-nombra-congresista-espaillat-y-otros-para-conectar-con-diversas-comunidades\/","title":{"rendered":"Mamdani nombra congresista Espaillat y otros para conectar con diversas comunidades"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por Ram\u00f3n Mercedes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">NUEVA YORK.- El alcalde electo en esta ciudad, Zohran Mamdani, quien asumir\u00e1 el cargo el pr\u00f3ximo 1 de enero, nombr\u00f3 al congresista Adriano Espaillat (D-13) en su Comit\u00e9 Asesor, con el objetivo de servir de enlace entre la nueva Alcald\u00eda y las diversas comunidades, as\u00ed como para colaborar en la implementaci\u00f3n de la agenda de gobierno municipal prometida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este nombramiento se realiz\u00f3 en reconocimiento al s\u00f3lido y amplio liderazgo pol\u00edtico del congresista Espaillat, quien goza de un alto prestigio entre las comunidades que representa en el Distrito Congresual 13-NY, tanto por su labor legislativa como por su firme defensa de la vivienda asequible, la seguridad p\u00fablica y el acceso al seguro de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se destaca su trabajo a favor de la extensi\u00f3n del Metro de la Segunda Avenida y de la remodelaci\u00f3n del Kingsbridge Armory, proyectos que generar\u00e1n miles de empleos locales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, fueron designados la congresista Nydia Vel\u00e1zquez (D-12); el senador estatal Gustavo Rivera (D-33); los asamble\u00edstas George \u00c1lvarez (D-78), Amanda Septimo (D-84) y Karine Reyes (D-87); el presidente del condado de Brooklyn, Antonio Reynoso; la l\u00edder comunitaria Elida Almonte; los concejales Christopher Marte (D-1); y Radham\u00e9s Rodr\u00edguez, presidente de la Asociaci\u00f3n de Bodegueros Unidos de Am\u00e9rica (UBA), en el Comit\u00e9 de Transici\u00f3n, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la agenda del nuevo alcalde figuran iniciativas como la implementaci\u00f3n de autobuses gratuitos; la reducci\u00f3n de los crecientes costos del cuidado infantil; el acceso equitativo al transporte; el impulso al desarrollo empresarial; la preparaci\u00f3n ante emergencias; y el congelamiento de los alquileres para m\u00e1s de dos millones de neoyorquinos, entre ellos decenas de miles de dominicanos, junto a otras etnias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLograr una ciudad asequible requerir\u00e1 la colaboraci\u00f3n con l\u00edderes de todos los niveles de gobierno, incluidos aquellos que formaron parte de la hist\u00f3rica victoria que obtuvimos en noviembre\u00bb, expres\u00f3 Mamdani.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El alcalde electo indic\u00f3 adem\u00e1s que el Comit\u00e9 Asesor permitir\u00e1 a su nueva administraci\u00f3n \u00abconstruir un gobierno que refleje la diversidad de nuestra ciudad, se centre en las necesidades de los trabajadores y est\u00e9 preparado para implementar la agenda de asequibilidad\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la campa\u00f1a, el congresista respald\u00f3 sin reservas la candidatura dem\u00f3crata de Mamdani. En ese contexto, el diario The New York Times, considerado el m\u00e1s influyente del mundo, destac\u00f3 que Espaillat, primer y \u00fanico congresista dominicano en Estados Unidos, es hoy \u00abel l\u00edder latino m\u00e1s poderoso de NY\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El peri\u00f3dico a\u00f1adi\u00f3 que su respaldo al entonces candidato dem\u00f3crata a la Alcald\u00eda era significativo tanto por razones simb\u00f3licas como pr\u00e1cticas, al Espaillat representar al norte de Manhattan y parte de El Bronx.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese mismo momento, el congresista por El Bronx (D-15), Ritchie Torres, afirm\u00f3 que \u00abEspaillat goza de una merecida reputaci\u00f3n como alguien capaz de impulsar a los votantes a acudir a las urnas en su distrito\u00bb, calific\u00e1ndolo incluso como una \u00abm\u00e1quina de participaci\u00f3n electoral\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mamdani decidi\u00f3 conformar su Comit\u00e9 Asesor con pol\u00edticos y l\u00edderes comunitarios \u00aben un momento en que la coordinaci\u00f3n temprana entre las distintas ramas y niveles de gobierno puede resultar clave para enfrentar los desaf\u00edos m\u00e1s urgentes de la ciudad\u00bb, se inform\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Ram\u00f3n Mercedes NUEVA YORK.- El alcalde electo en esta ciudad, Zohran Mamdani, quien asumir\u00e1 el cargo el pr\u00f3ximo 1 de enero, nombr\u00f3 al congresista Adriano Espaillat (D-13) en su&hellip;<\/p>\n","protected":false},"author":10,"featured_media":117775,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16289],"tags":[11654,2880,28589,11655,28590,20876],"class_list":["post-117774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","tag-adriano-espaillat","tag-comunidades","tag-conectar","tag-congresista","tag-diversas","tag-zohran-mamdani"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/Zohran-Mamdani-2.jpeg","jetpack-related-posts":[{"id":112635,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/10\/23\/ydanis-rodriguez-se-une-a-congresista-espaillat-y-otros-oficiales-electos-apoyan-a-mamdani\/","url_meta":{"origin":117774,"position":0},"title":"Ydanis Rodr\u00edguez se une a congresista Espaillat y otros oficiales electos apoyan a Mamdani","author":"Nelson Feliz","date":"23 de octubre de 2025","format":false,"excerpt":"https:\/\/www.youtube.com\/watch?v=sFsUncTssI4 Por Ram\u00f3n Mercedes NUEVA YORK.- El exconcejal dominicano por el Alto Manhattan, Ydanis Rodr\u00edguez, promotor de la \u00abAgenda Latina\u00bb en esta ciudad se uni\u00f3 al congresista Adriano Espaillat y otros oficiales electos hispanos para impulsar el voto latino de forma masiva a favor del candidato dem\u00f3crata a la alcald\u00eda\u2026","rel":"","context":"En \u00abLA VOZ DE LA DIASPORA\u00bb","block_context":{"text":"LA VOZ DE LA DIASPORA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/la-voz-de-la-diaspora\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-23-at-6.11.10-AM.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-23-at-6.11.10-AM.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-23-at-6.11.10-AM.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":103526,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/16\/tras-espaillat-respaldar-a-mamdani-new-york-times-lo-reconoce-como-el-lider-latino-mas-poderoso-de-nyc\/","url_meta":{"origin":117774,"position":1},"title":"Tras Espaillat respaldar a Mamdani, New York Times lo reconoce como el l\u00edder latino m\u00e1s poderoso de NYC","author":"Nelson Feliz","date":"16 de julio de 2025","format":false,"excerpt":"Por Ram\u00f3n Mercedes NUEVA YORK.- Luego de que el congresista Adriano Espaillat (D-13) expresara su respaldo al dem\u00f3crata Zohran Mamdani para la Alcald\u00eda en esta ciudad, el influyente peri\u00f3dico The New York Times lo calific\u00f3 como \u201cel l\u00edder latino m\u00e1s poderoso de NYC\u201d, en un art\u00edculo firmado por Emma G.\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-15-at-6.06.14-AM.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-15-at-6.06.14-AM.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-15-at-6.06.14-AM.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-15-at-6.06.14-AM.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":112653,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/10\/24\/valoran-ydanis-se-uniera-a-espaillat-septimo-y-de-la-rosa-en-apoyo-a-mamdani-alcaldia-nyc\/","url_meta":{"origin":117774,"position":2},"title":"Valoran Ydanis se uniera a Espaillat, S\u00e9ptimo y De la Rosa en apoyo a Mamdani alcald\u00eda NYC","author":"Nelson Feliz","date":"24 de octubre de 2025","format":false,"excerpt":"Por Ram\u00f3n Mercedes NUEVA YORK.- Dominicanos en esta ciudad valoraron de positivo que el exconcejal por el Alto Manhattan, Ydanis Rodr\u00edguez, se uniera al congresista Adriano Espaillat, a la asamble\u00edsta Amada S\u00e9ptimo y a la concejal Carmen de la Rosa, junto a otros oficiales latinos para apoyar al candidato dem\u00f3crata\u2026","rel":"","context":"En \u00abLA VOZ DE LA DIASPORA\u00bb","block_context":{"text":"LA VOZ DE LA DIASPORA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/la-voz-de-la-diaspora\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":112760,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/10\/27\/ydanis-rodriguez-anuncia-su-apoyo-oficial-a-mamdani-para-alcaldia-nyc\/","url_meta":{"origin":117774,"position":3},"title":"Ydanis Rodr\u00edguez anuncia su apoyo oficial a Mamdani para alcald\u00eda NYC","author":"Nelson Feliz","date":"27 de octubre de 2025","format":false,"excerpt":"https:\/\/www.youtube.com\/watch?v=GcOmJFlttr8 Por Ram\u00f3n Mercedes NUEVA YORK.- El l\u00edder comunitario y actual comisionado del Departamento de Transporte de la Ciudad de Nueva York, Ydanis Rodr\u00edguez, anunci\u00f3 oficialmente este domingo su respaldo al candidato dem\u00f3crata Zohran Mamdani en su aspiraci\u00f3n a la alcald\u00eda de NYC, durante un encuentro celebrado en \u00abLa Casa\u2026","rel":"","context":"En \u00abLA VOZ DE LA DIASPORA\u00bb","block_context":{"text":"LA VOZ DE LA DIASPORA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/la-voz-de-la-diaspora\/"},"img":{"alt_text":"Ydanis Rodr\u00edguez anuncia durante masivo acto su apoyo oficial a Mamdani para alcald\u00eda NYC","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Ydanis-Rodriguez.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Ydanis-Rodriguez.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Ydanis-Rodriguez.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Ydanis-Rodriguez.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":111864,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/10\/14\/mamdani-llena-a-toda-capacidad-teatro-united-palace-en-el-alto-manhattan\/","url_meta":{"origin":117774,"position":4},"title":"Mamdani llena a toda capacidad Teatro United Palace en el Alto Manhattan","author":"Nelson Feliz","date":"14 de octubre de 2025","format":false,"excerpt":"https:\/\/www.youtube.com\/shorts\/a7iF5n5ULQA Por Ram\u00f3n Mercedes NUEVA YORK.- El legendario Teatro United Palace, ubicado en el Alto Manhattan, con capacidad para 3,350 personas fue abarrotado por dominicanos la noche de este lunes durante un acto pol\u00edtico en apoyo al candidato dem\u00f3crata a la alcald\u00eda de esta ciudad, Zohran Mamdani. Bajo el lema\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-5.20.15-AM-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-5.20.15-AM-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-5.20.15-AM-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-14-at-5.20.15-AM-1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":111313,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/10\/07\/espaillat-dice-democratas-son-abanderados-derechos-inmigrantes-pide-regresen-los-que-se-han-ido\/","url_meta":{"origin":117774,"position":5},"title":"Espaillat dice dem\u00f3cratas son abanderados derechos inmigrantes; pide regresen los que se han ido","author":"Nelson Feliz","date":"7 de octubre de 2025","format":false,"excerpt":"https:\/\/www.youtube.com\/watch?v=EZnbf7PFRio Por Ram\u00f3n Mercedes NUEVA YORK.- El congresista dominicano (D-13) en esta ciudad, Adriano Espaillat, declar\u00f3 que es un dem\u00f3crata a carta cabal porque cree en los valores de ese partido: Defender el derecho de las mujeres, de los trabajadores, brindar vivienda asequible, asegurar la educaci\u00f3n de mejor calidad para\u2026","rel":"","context":"En \u00abLA VOZ DE LA DIASPORA\u00bb","block_context":{"text":"LA VOZ DE LA DIASPORA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/la-voz-de-la-diaspora\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Espaillat-dice-democratas-son-abanderados-derechos-inmigrantes.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Espaillat-dice-democratas-son-abanderados-derechos-inmigrantes.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Espaillat-dice-democratas-son-abanderados-derechos-inmigrantes.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Espaillat-dice-democratas-son-abanderados-derechos-inmigrantes.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/117774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=117774"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/117774\/revisions"}],"predecessor-version":[{"id":117776,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/117774\/revisions\/117776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/117775"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=117774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=117774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=117774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}