{"id":119253,"date":"2026-01-09T09:10:00","date_gmt":"2026-01-09T13:10:00","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=119253"},"modified":"2026-01-09T09:10:02","modified_gmt":"2026-01-09T13:10:02","slug":"nelson-cruz-y-fundacion-boomstick23-anuncian-jornada-social-en-las-matas-de-santa-cruz","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2026\/01\/09\/nelson-cruz-y-fundacion-boomstick23-anuncian-jornada-social-en-las-matas-de-santa-cruz\/","title":{"rendered":"Nelson Cruz y Fundaci\u00f3n Boomstick23 anuncian jornada social en Las Matas de Santa Cruz"},"content":{"rendered":"\n<p>Expelotero honra el legado de servicio de Nelsy Milagros Cruz.<\/p>\n\n\n\n<p>El exjugador de Grandes Ligas y presidente de la Fundaci\u00f3n Boomstick23, Nelson Cruz anunci\u00f3 la realizaci\u00f3n de una amplia jornada de actividades sociales, educativas, deportivas y culturales en Las Matas de Santa Cruz, como un homenaje al legado de servicio p\u00fablico, compromiso comunitario y vocaci\u00f3n social de su extinta hermana y exgobernadora de Montecristi, Nelsy Milagros Cruz.<\/p>\n\n\n\n<p>La iniciativa, que se desarrollar\u00e1 los d\u00edas viernes 9 y s\u00e1bado 10 de enero de 2026, contempla reconocimientos a estudiantes sobresalientes y a figuras hist\u00f3ricas de la comunidad, una conferencia motivacional, un concierto art\u00edstico, un operativo m\u00e9dico, evaluaciones deportivas para j\u00f3venes peloteros, cl\u00ednicas deportivas con jugadores de Grandes Ligas y la entrega de un cami\u00f3n de bomberos al municipio, entre otras acciones de alto impacto social.<\/p>\n\n\n\n<p>Nelson Cruz expres\u00f3 que esta jornada nace del profundo compromiso de continuar el legado de servicio de Nelsy, quien siempre procur\u00f3 que sus acciones generan un impacto positivo en la gente.<\/p>\n\n\n\n<p>\u201cNelsy vivi\u00f3 siempre pensando en su gente, en c\u00f3mo abrir oportunidades y en c\u00f3mo servir con humildad. Esta jornada no es solo un homenaje a su memoria, es una manera de continuar su misi\u00f3n, de seguir sembrando esperanza donde ella tanto luch\u00f3\u201d, expres\u00f3 Nelson Cruz.<\/p>\n\n\n\n<p>Se recuerda que Nelsy Milagros Cruz fue una de las v\u00edctimas que falleci\u00f3 en la tragedia del Jet Set ocurrida el 8 de abril de 2025.<\/p>\n\n\n\n<p>El destacado exjugador de Grandes Ligas a\u00f1adi\u00f3 que su motivaci\u00f3n principal es mantener vivo el ejemplo de su hermana a trav\u00e9s de iniciativas que impacten positivamente a la sociedad.<\/p>\n\n\n\n<p>\u201cSu legado se refleja en el impacto que dej\u00f3 en su comunidad y en las oportunidades que ayud\u00f3 a construir. Nuestro compromiso es que su ejemplo siga guiando acciones concretas en favor de la educaci\u00f3n, la salud y el desarrollo de nuestra gente\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Boomstick23 es una organizaci\u00f3n sin fines de lucro comprometida con generar impacto social, empoderando a ni\u00f1os y j\u00f3venes en situaci\u00f3n de vulnerabilidad social, as\u00ed como desarrollando habilidades y destrezas a trav\u00e9s de la educaci\u00f3n y el deporte para mejorar su entorno y calidad de vida.<\/p>\n\n\n\n<p>Con esta jornada en memoria de Nelsy Milagros Cruz, la fundaci\u00f3n reafirma su convicci\u00f3n de que el verdadero homenaje se construye a trav\u00e9s del servicio, la acci\u00f3n social y el compromiso con las comunidades que m\u00e1s lo necesitan, manteniendo vivo el legado de una mujer cuya huella permanece en la memoria y el coraz\u00f3n de su pueblo.<\/p>\n\n\n\n<p>Adem\u00e1s, reafirma su misi\u00f3n de contribuir al desarrollo integral de Las Matas de Santa Cruz y de toda la provincia de Montecristi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nelson Cruz<\/p>\n","protected":false},"author":10,"featured_media":119254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[630],"tags":[7914,18684],"class_list":["post-119253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-nelson-cruz","tag-nelsy-cruz"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260109-WA0122.jpg","jetpack-related-posts":[{"id":96897,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/10\/presidente-abinader-asiste-a-honras-funebres-de-la-gobernadora-de-montecristi-nelsy-cruz\/","url_meta":{"origin":119253,"position":0},"title":"Presidente Abinader asiste a honras f\u00fanebres de la gobernadora de Montecristi, Nelsy Cruz","author":"Nelson Feliz","date":"10 de abril de 2025","format":false,"excerpt":"Mandatario destaca cualidades humanas, profesionales, honestidad y eficiencia de la gobernadora fallecida. El presidente Luis Abinader, acompa\u00f1ado de la primera dama, Raquel Arbaje, asisti\u00f3 este mi\u00e9rcoles a las honras f\u00fanebres de la gobernadora de Montecristi, Nelsy Cruz, quien falleci\u00f3 tras el colapso del techo de la discoteca Jet Set en\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Luis Abinader","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Luis-Abinader-m-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Luis-Abinader-m-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Luis-Abinader-m-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":96861,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/09\/deporte-se-enlutece-con-muertes-de-octavio-dotel-y-tony-blanco\/","url_meta":{"origin":119253,"position":1},"title":"Deporte se enlutece con muertes de Octavio Dotel y Tony Blanco","author":"Nelson Feliz","date":"9 de abril de 2025","format":false,"excerpt":"Fallece un exfutbolista y una hermana del expelotero Nelson Cruz Carlos S\u00e1nchez G.Carlos S\u00e1nchez G. La tragedia del Jet Set enlutece al pa\u00eds a tan alta escala, que llev\u00f3 tristeza a la familia deportiva. El imprevisto derrumbe del techo de la discoteca seg\u00f3 la vida de los expeloteros Octavio Dotel\u2026","rel":"","context":"En \u00abDEPORTES\u00bb","block_context":{"text":"DEPORTES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/deportes\/"},"img":{"alt_text":"Octavio Dotel y Tony Blanco fallecieron en la tragedia de la Discoteca Jet Set de la madrugada del martes 8 de abril del 2025.","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Octavio-Dotel-y-Tony-Blanco.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Octavio-Dotel-y-Tony-Blanco.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Octavio-Dotel-y-Tony-Blanco.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Octavio-Dotel-y-Tony-Blanco.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":96785,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/08\/abinader-confirma-la-muerte-de-gobernadora-de-montecristi-nelsy-cruz-en-la-discoteca-jet-set\/","url_meta":{"origin":119253,"position":2},"title":"Abinader confirma la muerte de gobernadora de Montecristi Nelsy Cruz en la discoteca Jet Set","author":"Nelson Feliz","date":"8 de abril de 2025","format":false,"excerpt":"\"Nos llamaron y se confirm\u00f3 que muri\u00f3 en la Plaza de la Salud\", expres\u00f3 el mandatario. El presidente de la Rep\u00fablica, Luis Abinader, confirm\u00f3 este martes el fallecimiento de la gobernadora de la provincia Montecristi, Nelsy Cruz, tras resultar herida en el colapso parcial del techo de la discoteca Jet\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Luis-Abinader-JS.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":105465,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/08\/04\/cesac-y-fundacion-cruz-jiminian-ejecutan-jornada-integral-de-asistencia-medica-en-barahona\/","url_meta":{"origin":119253,"position":3},"title":"CESAC y Fundaci\u00f3n Cruz Jimini\u00e1n ejecutan jornada integral de asistencia m\u00e9dica en Barahona","author":"Nelson Feliz","date":"4 de agosto de 2025","format":false,"excerpt":"El Cuerpo Especializado en Seguridad Aeroportuaria y de la Aviaci\u00f3n Civil (CESAC), en colaboraci\u00f3n con la Fundaci\u00f3n Cruz Jimini\u00e1n, llev\u00f3 a cabo una jornada de acci\u00f3n c\u00edvica y asistencia m\u00e9dica comunitaria en la Escuela B\u00e1sica Aura Therma Suero F\u00e9liz-Habanero, provincia Barahona. La actividad cont\u00f3 con la participaci\u00f3n de un equipo\u2026","rel":"","context":"En \u00abSALUD\u00bb","block_context":{"text":"SALUD","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/salud\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/jornada-medica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/jornada-medica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/jornada-medica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/jornada-medica.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":90106,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/10\/13\/academia-nelsy-brito-bayahibe-pasa-a-final-bpl-beisbol-del-torneo-crazy-cup\/","url_meta":{"origin":119253,"position":4},"title":"Academia Nelsy Brito (Bayahibe) pasa a final BPL- B\u00c9ISBOL del Torneo Crazy Cup","author":"Nelson Feliz","date":"13 de octubre de 2024","format":false,"excerpt":"Espera el Ganador de Ray y Los Bautys Tras La Corona y Premio Met\u00e1lico. Las academia de Nelsy Brito (El S\u00edndico) desde Bayahibe la zona este derroto con score de 7 carreras por 6 a la academia de banana para avanzar a La final del torneo organizado por Big Prospect\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"Los entrenadores Miguel Caceres y Jose de la Cruz junto a los jugadores de la academia Nelsy Brito.","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/MIguel-Caceres-y-Jose-de-La-Cruz-junto-a-los-Jugadores-Academia-Nelsy-Brito.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/MIguel-Caceres-y-Jose-de-La-Cruz-junto-a-los-Jugadores-Academia-Nelsy-Brito.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/MIguel-Caceres-y-Jose-de-La-Cruz-junto-a-los-Jugadores-Academia-Nelsy-Brito.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/MIguel-Caceres-y-Jose-de-La-Cruz-junto-a-los-Jugadores-Academia-Nelsy-Brito.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":61941,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/02\/teatro-nacional-inaugura-memorabilia-de-salsera-celia-cruz\/","url_meta":{"origin":119253,"position":5},"title":"Teatro Nacional inaugura memorabilia de salsera Celia Cruz","author":"BIMARY DE JES\u00daS Matos","date":"2 de octubre de 2023","format":false,"excerpt":"SANTO DOMINGO.- El Teatro Nacional Eduardo Brito, la Fundaci\u00f3n Legado de Celia Cruz y el Congreso de Salsa de la Rep\u00fablica Dominicana inauguraron la memorabilia del vestido usado por Celia Cruz al recibir el Premio Casandra en el 1996, durante un emotivo encuentro en la Mezzanine del Teatro Nacional. Celia\u2026","rel":"","context":"En \u00abENTRETENIMIENTO\u00bb","block_context":{"text":"ENTRETENIMIENTO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/entretenimiento\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-09-28-at-11.50.30-PM-1-4.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-09-28-at-11.50.30-PM-1-4.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-09-28-at-11.50.30-PM-1-4.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-09-28-at-11.50.30-PM-1-4.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/119253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=119253"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/119253\/revisions"}],"predecessor-version":[{"id":119255,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/119253\/revisions\/119255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/119254"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=119253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=119253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=119253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}