{"id":130417,"date":"2026-05-13T17:21:54","date_gmt":"2026-05-13T21:21:54","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=130417"},"modified":"2026-05-13T17:21:55","modified_gmt":"2026-05-13T21:21:55","slug":"rusia-lanza-unos-800-drones-a-ucrania-pese-a-reciente-comentarios-de-putin-y-trump-sobre-posible-paz","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/13\/rusia-lanza-unos-800-drones-a-ucrania-pese-a-reciente-comentarios-de-putin-y-trump-sobre-posible-paz\/","title":{"rendered":"Rusia lanza unos 800 drones a Ucrania pese a reciente comentarios de Putin y Trump sobre posible paz"},"content":{"rendered":"\n<p>POR HANNA ARHIROVA and BARRY HATTON<\/p>\n\n\n\n<p>KIEV, Ucrania (AP) \u2014 Rusia dispar\u00f3 al menos 800 drones en una enorme andanada diurna contra unas 20 regiones de Ucrania el mi\u00e9rcoles, matando al menos a seis personas e hiriendo a decenas, incluidos ni\u00f1os, en uno de los ataques m\u00e1s prolongados de Mosc\u00fa en la guerra de cuatro a\u00f1os, afirm\u00f3 el presidente ucraniano Volodymyr Zelenskyy.<\/p>\n\n\n\n<p>El ataque comenz\u00f3 a media ma\u00f1ana y dur\u00f3 horas en la capital, Kiev, la ciudad occidental de Le\u00f3polis cerca de Polonia, y el puerto de Odesa en el mar Negro, entre otros centros de poblaci\u00f3n, dijo Zelenskyy en la aplicaci\u00f3n de mensajer\u00eda Telegram.<\/p>\n\n\n\n<p>\u201cNuestros soldados est\u00e1n defendiendo a Ucrania, pero el objetivo evidente de Rusia es sobrecargar las defensas a\u00e9reas\u201d, dijo Zelenskyy, cuando el bombardeo se prolongaba hasta \u00faltima hora de la tarde.<\/p>\n\n\n\n<p>Advirti\u00f3 que una ofensiva con misiles de crucero y bal\u00edsticos podr\u00eda seguir a la andanada de drones.<\/p>\n\n\n\n<p>Fue \u201cuno de los ataques rusos m\u00e1s prolongados y masivos contra Ucrania\u201d, escribi\u00f3 en redes sociales.<\/p>\n\n\n\n<p>Tambi\u00e9n sacudi\u00f3 a los vecinos. El primer ministro h\u00fangaro P\u00e9ter Magyar dijo que su nuevo gobierno ha convocado al embajador ruso por un ataque con drones cerca de la frontera de Hungr\u00eda, en un cambio significativo respecto a las relaciones amistosas con Mosc\u00fa de su predecesor Viktor Orb\u00e1n.<\/p>\n\n\n\n<p>\u201cEl gobierno h\u00fangaro condena en\u00e9rgicamente el ataque ruso contra Transcarpatia\u201d, subray\u00f3 Magyar a los periodistas, y a\u00f1adi\u00f3 que la ministra de Relaciones Exteriores, Anita Orb\u00e1n, hablar\u00e1 con el embajador el jueves por la ma\u00f1ana.<\/p>\n\n\n\n<p>La ministra de Relaciones Exteriores preguntar\u00e1 \u201ccu\u00e1ndo Rusia y Vlad\u00edmir Putin planean finalmente poner fin a esta sangrienta guerra\u201d, a\u00f1adi\u00f3 Magyar.<\/p>\n\n\n\n<p>\u201c\u00a1Gracias por su compasi\u00f3n y su firme postura!\u201d, dijo Zelenskyy en X tras los comentarios de Magyar.<\/p>\n\n\n\n<p>Mueren 3 personas en ataques en regi\u00f3n cerca de Kiev<\/p>\n\n\n\n<p>Restos de drones cayeron en un \u00e1rea abierta del distrito Obolonskyi de Kiev sin causar v\u00edctimas, indicaron autoridades de la ciudad, al tiempo que los sistemas de defensa a\u00e9rea enfrentaban drones rusos sobre la capital.<\/p>\n\n\n\n<p>El alcalde Vitali Klitschko dijo que los servicios de emergencia acudieron al lugar. Se escucharon explosiones en toda la ciudad a primera hora del mi\u00e9rcoles.<\/p>\n\n\n\n<p>Tres personas murieron en un ataque con drones en la regi\u00f3n de Rivne al oeste de Kiev, seg\u00fan Oleksandr Koval, jefe de la administraci\u00f3n militar regional.<\/p>\n\n\n\n<p>Los ataques de Mosc\u00fa contra su vecino no dan tregua, incluso cuando Ucrania se ve alentada por sus recientes logros militares y el presidente estadounidense Donald Trump y Putin sostienen \u2014sin aportar pruebas\u2014 que la guerra podr\u00eda estar acerc\u00e1ndose a su fin.<\/p>\n\n\n\n<p>El martes, dijo Zelenskyy, 14 regiones ucranianas fueron atacadas, seguidas de ataques nocturnos contra la infraestructura residencial, energ\u00e9tica y ferroviaria de Ucrania.<\/p>\n\n\n\n<p>\u201cEs importante apoyar a Ucrania y no guardar silencio sobre la guerra de Rusia. Cada vez que la guerra desaparece de los principales titulares, anima a Rusia a volverse a\u00fan m\u00e1s salvaje\u201d, subray\u00f3 Zelenskyy en una aparente referencia a que la atenci\u00f3n mundial est\u00e1 centrada en la guerra con Ir\u00e1n.<\/p>\n\n\n\n<p>Trump y Putin hablan de un posible fin de la guerra<\/p>\n\n\n\n<p>Trump dijo el martes que cree que Mosc\u00fa y Kiev pronto alcanzar\u00e1n un acuerdo para poner fin a los combates.<\/p>\n\n\n\n<p>\u201cEl fin de la guerra en Ucrania de verdad creo que est\u00e1 muy cerca. Lo crean o no, se est\u00e1 acercando\u201d, declar\u00f3 Trump a los periodistas al salir de la Casa Blanca rumbo a una cumbre en Beijing.<\/p>\n\n\n\n<p>Putin dijo en un discurso el fin de semana pasado que su invasi\u00f3n de Ucrania posiblemente \u201cest\u00e1 llegando a su fin\u201d.<\/p>\n\n\n\n<p>Ninguno de los dos presidentes explic\u00f3 qu\u00e9 los convenci\u00f3 sobre la posibilidad de paz en el conflicto m\u00e1s prolongado de Europa desde la Segunda Guerra Mundial.<\/p>\n\n\n\n<p>Durante el \u00faltimo a\u00f1o, los esfuerzos diplom\u00e1ticos encabezados por Estados Unidos para terminar la guerra se han venido abajo tras no lograr avances en asuntos clave, como si Rusia puede quedarse con territorio ucraniano que ha tomado y qu\u00e9 se puede hacer para disuadir a Mosc\u00fa de invadir de nuevo.<\/p>\n\n\n\n<p>El portavoz del Kremlin, Dmitry Peskov, indic\u00f3 el mi\u00e9rcoles que las condiciones fundamentales de Mosc\u00fa no han cambiado, y afirm\u00f3 Putin insiste en que Ucrania retire sus tropas de las cuatro regiones \u2014Donetsk, Luhansk, Jers\u00f3n y Zaporiyia\u2014 que Rusia anexion\u00f3 ilegalmente en septiembre de 2022 pero que no ha capturado por completo.<\/p>\n\n\n\n<p>\u201cEn ese momento, se establecer\u00e1 un alto el fuego y las partes podr\u00e1n entablar negociaciones con calma, que, por cierto, inevitablemente ser\u00e1n muy complejas e incluir\u00e1n muchos detalles importantes\u201d, asever\u00f3 Peskov.<\/p>\n\n\n\n<p>Zelenskyy prometi\u00f3 mantener la presi\u00f3n sobre Mosc\u00fa para que haga concesiones en el di\u00e1logo.<\/p>\n\n\n\n<p>\u201cNo renunciamos a los esfuerzos diplom\u00e1ticos, y esperamos que la presi\u00f3n sobre Rusia, junto con negociaciones en diferentes formatos, ayude a traer la paz\u201d, dijo en un discurso el mi\u00e9rcoles en Bucarest, Rumania, a representantes de pa\u00edses del flanco oriental de la OTAN.<\/p>\n\n\n\n<p>\u201cLas sanciones est\u00e1n funcionando, nuestras capacidades de largo alcance (drones y misiles) est\u00e1n funcionando, y toda forma de presi\u00f3n est\u00e1 funcionando\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Por otra parte, los gobiernos europeos est\u00e1n evaluando la posibilidad de iniciar conversaciones con Putin. Europa ha intentado durante a\u00f1os aislar al presidente ruso y castig\u00f3 a su pa\u00eds con sanciones internacionales.<\/p>\n\n\n\n<p>La guerra parece inclinarse a favor de Ucrania<\/p>\n\n\n\n<p>La correlaci\u00f3n de fuerzas en la guerra ha cambiado en los \u00faltimos meses. Ucrania pas\u00f3 de suplicar ayuda internacional para su defensa a ofrecer a otras naciones conocimientos sobre c\u00f3mo contrarrestar ataques, gracias a su tecnolog\u00eda de drones desarrollada en el pa\u00eds.<\/p>\n\n\n\n<p>Los ataques ucranianos de largo alcance con drones y misiles han afectado instalaciones energ\u00e9ticas y manufactura en el interior de Rusia, y tres regiones rusas reportaron ataques el mi\u00e9rcoles.<\/p>\n\n\n\n<p>El Ministerio ruso de Defensa indic\u00f3 que sus defensas a\u00e9reas interceptaron y destruyeron 286 drones ucranianos sobre regiones rusas, la pen\u00ednsula de Crimea anexionada ilegalmente, el mar de Azov y el mar Negro.<\/p>\n\n\n\n<p>En la l\u00ednea del frente de 1.250 kil\u00f3metros (780 millas), el avance del ej\u00e9rcito ruso, m\u00e1s grande y mejor equipado, se ha ido ralentizando cada mes desde octubre pasado, seg\u00fan el Instituto para el Estudio de la Guerra.<\/p>\n\n\n\n<p>La ofensiva de primavera de Rusia se ha estancado, y las fuerzas rusas registraron una p\u00e9rdida neta de territorio el mes pasado por primera vez desde 2024, de acuerdo con el centro de estudios con sede en Washington.<\/p>\n\n\n\n<p>\u201cNo s\u00f3lo las l\u00edneas defensivas ucranianas se mantienen, sino que las fuerzas ucranianas han logrado disputar la iniciativa t\u00e1ctica en varias zonas de la l\u00ednea del frente, incluso cuando Rusia contin\u00faa perdiendo cantidades desproporcionadas de personal para lograr avances m\u00ednimos\u201d, indic\u00f3 el martes el centro de estudios.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Hatton report\u00f3 desde Lisboa, Portugal. Sam McNeil en Bruselas y Bela Szandelzsky en Budapest, Hungr\u00eda, contribuyeron a este despacho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POR HANNA ARHIROVA and BARRY HATTON KIEV, Ucrania (AP) \u2014 Rusia dispar\u00f3 al menos 800 drones en una enorme andanada diurna contra unas 20 regiones de Ucrania el mi\u00e9rcoles, matando&hellip;<\/p>\n","protected":false},"author":2,"featured_media":130418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16289],"tags":[33364,33363,33362],"class_list":["post-130417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","tag-posible-paz","tag-putin-y-trump","tag-rusia-lanza-unos-800-drones-a-ucrania"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/drones.jpg","jetpack-related-posts":[{"id":72449,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/12\/29\/rusia-lanza-uno-de-los-mayores-ataques-aereos-contra-ucrania\/","url_meta":{"origin":130417,"position":0},"title":"Rusia lanza uno de los mayores ataques a\u00e9reos contra Ucrania","author":"BIMARY DE JES\u00daS Matos","date":"29 de diciembre de 2023","format":false,"excerpt":"KIEV, Ucrania.- Rusia dispar\u00f3 alrededor de 110 misiles durante la noche, adem\u00e1s de aviones no tripulados, contra objetivos ucranianos en uno de los mayores ataques del a\u00f1o, dijo el presidente de Ucrania, Volodymyr Zelenskyy, el viernes. La mayor\u00eda de los misiles y drones fueron derribados pero al menos siete civiles\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Noticias-de-energia-2023-12-29T121341.489.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Noticias-de-energia-2023-12-29T121341.489.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Noticias-de-energia-2023-12-29T121341.489.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":95773,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/19\/zelenskyy-la-promesa-de-putin-de-no-atacar-la-red-energetica-de-ucrania-dista-de-la-realidad\/","url_meta":{"origin":130417,"position":1},"title":"Zelenskyy: la promesa de Putin de no atacar la red energ\u00e9tica de Ucrania \u201cdista de la realidad\u201d","author":"Nelson Feliz","date":"19 de marzo de 2025","format":false,"excerpt":"POR HANNA ARHIROVA KIEV, Ucrania (AP) \u2014 El presidente de Ucrania, Volodymyr Zelenskyy, dijo el mi\u00e9rcoles que la promesa de su hom\u00f3logo ruso, Vlad\u00edmir Putin, de no atacar la infraestructura energ\u00e9tica \u201cdista mucho de la realidad\u201d tras una serie de ataques nocturnos con drones en todo el pa\u00eds. Zelenskyy dijo\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Volodymyr-Zelenskyy.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Volodymyr-Zelenskyy.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Volodymyr-Zelenskyy.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Volodymyr-Zelenskyy.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":94935,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/07\/rusia-bombardea-red-electrica-de-ucrania-tras-anuncio-de-zelenskyy-de-conversaciones-con-eeuu\/","url_meta":{"origin":130417,"position":2},"title":"Rusia bombardea red el\u00e9ctrica de Ucrania tras anuncio de Zelenskyy de conversaciones con EEUU","author":"Nelson Feliz","date":"7 de marzo de 2025","format":false,"excerpt":"POR ILLIA NOVIKOV KIEV, Ucrania (AP) \u2014 Rusia atac\u00f3 la infraestructura energ\u00e9tica de Ucrania con un bombardeo a gran escala con misiles y aviones no tripulados durante la noche, informaron autoridades el viernes, horas despu\u00e9s que el presidente Volodymyr Zelenskyy anunci\u00f3 que la pr\u00f3xima semana tendr\u00e1 conversaciones con Estados Unidos\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/INCENDIO.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/INCENDIO.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/INCENDIO.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/INCENDIO.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":96173,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/26\/zelenskyy-dice-que-ucrania-esta-lista-para-un-alto-el-fuego-parcial-tras-acuerdo-mediado-por-eeuu\/","url_meta":{"origin":130417,"position":3},"title":"Zelenskyy dice que Ucrania est\u00e1 lista para un alto el fuego parcial tras acuerdo mediado por EEUU","author":"Nelson Feliz","date":"26 de marzo de 2025","format":false,"excerpt":"POR ILLIA NOVIKOV KIEV, Ucrania (AP) \u2014 Ucrania est\u00e1 lista para proceder con un alto el fuego que proh\u00edbe los ataques a la infraestructura energ\u00e9tica, afirm\u00f3 el presidente, Volodymyr Zelenskyy, en l\u00ednea con un acuerdo mediado por Estados Unidos durante tres d\u00edas de negociaciones con funcionarios ucranianos y rusos en\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"Volodymyr Zelenskyy","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Volodymyr-Zelenskyy-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Volodymyr-Zelenskyy-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Volodymyr-Zelenskyy-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Volodymyr-Zelenskyy-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":82613,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/05\/06\/ucrania-celebra-su-tercera-semana-santa-en-guerra-mientras-es-atacada-por-drones-y-tropas-rusas\/","url_meta":{"origin":130417,"position":4},"title":"Ucrania celebra su tercera Semana Santa en guerra mientras es atacada por drones y tropas rusas","author":"Esteffany Vargas","date":"6 de mayo de 2024","format":false,"excerpt":"POR SUSIE BLANN Y ELISE MORTON KIEV, Ucrania (AP) \u2014 Mientras Ucrania celebraba su tercera Semana Santa en guerra, Rusia lanz\u00f3 el domingo una andanada de drones concentrados en el este de Ucrania, hiriendo a m\u00e1s de una docena de personas, y afirm\u00f3 que sus tropas tomaron el control de\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/guerra.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/guerra.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/guerra.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/guerra.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":97649,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/25\/ucrania-reporta-3-muertos-en-otro-ataque-ruso-con-drones-tras-las-criticas-de-trump-a-putin\/","url_meta":{"origin":130417,"position":5},"title":"Ucrania reporta 3 muertos en otro ataque ruso con drones tras las cr\u00edticas de Trump a Putin","author":"Nelson Feliz","date":"25 de abril de 2025","format":false,"excerpt":"POR ILLIA NOVIKOV KIEV, Ucrania (AP) \u2014 Un dron ruso alcanz\u00f3 un edificio de apartamentos en una ciudad del sureste de Ucrania y caus\u00f3 tres muertos y 10 heridos, dijeron funcionarios el viernes, un d\u00eda despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, reprendi\u00f3 a su hom\u00f3logo en\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/muertos-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/muertos-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/muertos-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/muertos-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/130417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=130417"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/130417\/revisions"}],"predecessor-version":[{"id":130419,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/130417\/revisions\/130419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/130418"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=130417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=130417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=130417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}