{"id":131793,"date":"2026-05-25T18:12:14","date_gmt":"2026-05-25T22:12:14","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=131793"},"modified":"2026-05-25T18:13:29","modified_gmt":"2026-05-25T22:13:29","slug":"presunto-implicado-en-rapto-y-muerte-de-el-gordo-se-entrega-ante-la-policia-nacional","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/25\/presunto-implicado-en-rapto-y-muerte-de-el-gordo-se-entrega-ante-la-policia-nacional\/","title":{"rendered":"Presunto implicado en rapto y muerte de \u201cEl Gordo\u201d se entrega ante la Polic\u00eda Nacional"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Polic\u00eda Nacional inform\u00f3 que se entreg\u00f3 este lunes un presunto delincuente que era buscado por su presunta vinculaci\u00f3n en el rapto y muerte de Jes\u00fas Rodr\u00edguez, alias \u201cEl Gordo\u201d, cuyo cad\u00e1ver fue encontrado calcinado en el interior de un veh\u00edculo en Juan Dolio, provincia San Pedro de Macor\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de Maicol Miguel Pantale\u00f3n, alias \u201cLa Fuga\u201d, de 30 a\u00f1os, quien fue entregado por Virgilio Almanzar, presidente del Comit\u00e9 Dominicano de los Derechos Humanos, junto a familiares del investigado y otros integrantes de la referida entidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa Fuga\u201d fue recibido en la sede policial por el coronel Diego Pesqueira, vocero de la Polic\u00eda Nacional, quien garantiz\u00f3 el respeto al debido proceso y a los derechos fundamentales del detenido durante el curso de las investigaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La instituci\u00f3n del orden, precis\u00f3 que, con relaci\u00f3n a este mismo caso, el pasado s\u00e1bado tambi\u00e9n se entreg\u00f3 el nombrado Wander Erickson Soriano, alias \u201cCampe\u201d, quien igualmente era requerido por los organismos investigativos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Polic\u00eda Nacional indic\u00f3 que las investigaciones contin\u00faan avanzando para esclarecer completamente el hecho y determinar posibles responsabilidades adicionales.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"576\" style=\"aspect-ratio: 1024 \/ 576;\" width=\"1024\" autoplay controls muted src=\"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Video-2026-05-25-at-5.16.34-PM.mp4\" playsinline><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda Nacional inform\u00f3 que se entreg\u00f3 este lunes un presunto delincuente que era buscado por su presunta vinculaci\u00f3n en el rapto y muerte de Jes\u00fas Rodr\u00edguez, alias \u201cEl Gordo\u201d,&hellip;<\/p>\n","protected":false},"author":10,"featured_media":131794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3057],"tags":[33960,3329,1157,33959,33961,1129],"class_list":["post-131793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-militares","tag-el-gordo","tag-implicado","tag-policia-nacional","tag-presunto","tag-rapto-y-muerte","tag-se-entrega"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/La-Fuga.jpg","jetpack-related-posts":[{"id":126740,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/04\/04\/policia-investiga-rapto-y-muerte-de-joven-en-puerto-plata-cuerpo-fue-hallado-en-la-vega\/","url_meta":{"origin":131793,"position":0},"title":"Polic\u00eda investiga rapto y muerte de joven en Puerto Plata; cuerpo fue hallado en La Vega","author":"Nelson Feliz","date":"4 de abril de 2026","format":false,"excerpt":"La Polic\u00eda Nacional, a trav\u00e9s de la Direcci\u00f3n Central de Investigaci\u00f3n (DICRIM), mantiene una activa investigaci\u00f3n en torno al rapto y posterior hallazgo sin vida de un joven, en un hecho ocurrido entre las provincias Puerto Plata y La Vega. La v\u00edctima fue identificada como Anser Stephan Almonte, alias \u201cEl\u2026","rel":"","context":"En \u00abMILITARES\u00bb","block_context":{"text":"MILITARES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/militares\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/muerto.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/muerto.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/muerto.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/muerto.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":129751,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/06\/encapuchados-raptan-joven-en-el-sector-alma-rosa-ii\/","url_meta":{"origin":131793,"position":1},"title":"Encapuchados raptan joven en el sector Alma Rosa II","author":"Nelson Feliz","date":"6 de mayo de 2026","format":false,"excerpt":"Los raptores exigieron dinero a cambio de la liberaci\u00f3n de la joven Edyleni Mercedes Mart\u00ednez Liriano fue sorprendida por la violencia cuando sal\u00eda de su residencia la madrugada del martes 5 de mayo, en el sector Alma Rosa II, en el municipio Santo Domingo Este. Las c\u00e1maras de video vigilancia\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/encapuchados.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/encapuchados.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/encapuchados.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":99274,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/05\/19\/se-entrega-uno-de-los-tres-sospechosos-de-matar-a-cinco-hombres-en-dajabon\/","url_meta":{"origin":131793,"position":2},"title":"Se entrega uno de los tres sospechosos de matar a cinco hombres en Dajab\u00f3n","author":"Nelson Feliz","date":"19 de mayo de 2025","format":false,"excerpt":"Se trata de H\u00e9ctor Alejandro Acevedo Est\u00e9vez, alias \"Chico\", a quien la Polic\u00eda hab\u00eda se\u00f1alado como el principal responsable del crimen. El hecho ocurri\u00f3 en un punto de venta de drogas en Loma de Cabrera. De manera voluntaria, se entreg\u00f3 este lunes uno de los tres acusados por la Polic\u00eda\u2026","rel":"","context":"En \u00abMILITARES\u00bb","block_context":{"text":"MILITARES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/militares\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Hector-Alejandro-Acevedo-Estevez.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Hector-Alejandro-Acevedo-Estevez.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Hector-Alejandro-Acevedo-Estevez.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Hector-Alejandro-Acevedo-Estevez.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":116633,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/12\/02\/pn-identifica-a-responsables-del-rapto-y-asesinato-de-hombre-desaparecido-en-san-cristobal\/","url_meta":{"origin":131793,"position":3},"title":"PN identifica a &#8220;responsables&#8221; del rapto y asesinato de hombre desaparecido en San Crist\u00f3bal","author":"Nelson Feliz","date":"2 de diciembre de 2025","format":false,"excerpt":"La Polic\u00eda Nacional inform\u00f3 este martes que identific\u00f3 a los \"responsables\" del rapto y posterior asesinato de Jos\u00e9 Ignacio Mel\u00e9ndez Medrano, alias \"Satan\u00e1s\", cuyo cuerpo fue encontrado con heridas de arma de fuego en la comunidad Los Novas, provincia San Crist\u00f3bal, tras ser reportado como desaparecido el 19 de noviembre.\u2026","rel":"","context":"En \u00abMILITARES\u00bb","block_context":{"text":"MILITARES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/militares\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/PN-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/PN-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/PN-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/PN-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84165,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/06\/03\/pn-acribilla-dos-supuestos-delincuentes-en-spm\/","url_meta":{"origin":131793,"position":4},"title":"PN acribilla dos supuestos delincuentes en SPM","author":"Nelson Feliz","date":"3 de junio de 2024","format":false,"excerpt":"Miembros de la Polic\u00eda Nacional acribillaron a dos supuestos delincuentes, este domingo a quienes presuntamente enfrentaron a tiros en el municipio de Quisqueya, San Pedro de Macor\u00eds. Se trata de Ramfis Theophile (alias El Se\u00f1or de los Cielos), de 32 a\u00f1os; y Junior Ram\u00edrez (alias Junior Kepua), quienes murieron \u00abmientras\u2026","rel":"","context":"En \u00abMILITARES\u00bb","block_context":{"text":"MILITARES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/militares\/"},"img":{"alt_text":"armas y cel","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/armas-y-cel.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/armas-y-cel.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/armas-y-cel.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/armas-y-cel.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":88040,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/08\/21\/capturan-en-el-dn-a-presunto-implicado-en-asalto-a-joyeria-de-santiago\/","url_meta":{"origin":131793,"position":5},"title":"Capturan en el DN a presunto implicado en asalto a joyer\u00eda de Santiago","author":"Nelson Feliz","date":"21 de agosto de 2024","format":false,"excerpt":"-Recuperan m\u00e1s de mil gramos de prendas en oro y plata, as\u00ed como tambi\u00e9n 201 mil pesos en efectivo. Agentes policiales adscritos a la Direcci\u00f3n Central de Investigaci\u00f3n (DICRIM) en Santiago capturaron a uno de los dos implicados en el asalto a mano armada a una joyer\u00eda ubicada en la\u2026","rel":"","context":"En \u00abMILITARES\u00bb","block_context":{"text":"MILITARES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/militares\/"},"img":{"alt_text":"Evidencias","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/evidencias-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/evidencias-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/evidencias-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/evidencias-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/131793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=131793"}],"version-history":[{"count":2,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/131793\/revisions"}],"predecessor-version":[{"id":131797,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/131793\/revisions\/131797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/131794"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=131793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=131793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=131793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}