{"id":132120,"date":"2026-05-28T23:59:34","date_gmt":"2026-05-29T03:59:34","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=132120"},"modified":"2026-05-28T23:59:37","modified_gmt":"2026-05-29T03:59:37","slug":"presidente-guatemalteco-rechaza-informe-de-acuerdo-con-ee-uu","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/28\/presidente-guatemalteco-rechaza-informe-de-acuerdo-con-ee-uu\/","title":{"rendered":"Presidente guatemalteco rechaza informe de acuerdo con EE. UU."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">CIUDAD DE GUATEMALA (AP) \u2014 El presidente guatemalteco, Bernardo Ar\u00e9valo, neg\u00f3 el jueves la existencia de un acuerdo con Estados Unidos para llevar a cabo operaciones contra el narcotr\u00e1fico en territorio guatemalteco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas declaraciones se producen despu\u00e9s de que The New York Times informara de que la naci\u00f3n centroamericana acord\u00f3 llevar a cabo ataques conjuntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este caso es el m\u00e1s reciente de una serie de tensiones entre la administraci\u00f3n Trump y los gobiernos latinoamericanos que buscan lograr un equilibrio entre la cooperaci\u00f3n bilateral para combatir el narcotr\u00e1fico y el mantenimiento de la soberan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo existe ning\u00fan acuerdo. Se trata de una solicitud que se enmarca dentro de los acuerdos vigentes en varios pa\u00edses\u201d, declar\u00f3 Ar\u00e9valo en una rueda de prensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo que estamos firmando son tipos de colaboraci\u00f3n que ya se ven\u00edan dando en el pasado. Llevamos a cabo interceptaciones mar\u00edtimas en las que Estados Unidos ha colaborado con capacitaci\u00f3n, desarrollo de capacidades y equipamiento\u201d, dijo Ar\u00e9valo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que las acciones del gobierno est\u00e1n en conformidad con la ley guatemalteca y la Constituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl \u00fanico organismo que puede autorizar operaciones con soldados en territorio guatemalteco es el Congreso de la Rep\u00fablica. El gobierno guatemalteco no solicita esta cooperaci\u00f3n ni tiene planes de hacerlo\u201d, declar\u00f3 el presidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ser preguntado sobre el supuesto acuerdo, el secretario de prensa interino del Pent\u00e1gono, Joel Valdez, dijo que no pod\u00eda &#8220;especular sobre operaciones futuras ni hablar de asuntos de seguridad operativa&#8221;, pero enfatiz\u00f3 que el Departamento de Guerra trabaja con socios en la regi\u00f3n para combatir el narcotr\u00e1fico y otras amenazas transnacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno guatemalteco tambi\u00e9n public\u00f3 un comunicado de prensa y dos cartas en las que su ministro de Defensa analiza las operaciones militares conjuntas en virtud de acuerdos preexistentes con el secretario de Guerra de Estados Unidos, Pete Hegseth.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La muerte en abril de dos agentes de la CIA en el norte de M\u00e9xico, tras una operaci\u00f3n para destruir un laboratorio de drogas, puso de manifiesto la presencia de agentes estadounidenses en Latinoam\u00e9rica y suscit\u00f3 interrogantes sobre la creciente implicaci\u00f3n de Estados Unidos en la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los d\u00edas posteriores, las autoridades mexicanas ofrecieron versiones contradictorias sobre la cantidad de informaci\u00f3n que el pa\u00eds pose\u00eda respecto a la participaci\u00f3n de los agentes de la CIA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno mexicano reconoce la presencia de agencias estadounidenses en territorio mexicano, pero afirma que no pueden participar en operaciones sobre el terreno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CIUDAD DE GUATEMALA (AP) \u2014 El presidente guatemalteco, Bernardo Ar\u00e9valo, neg\u00f3 el jueves la existencia de un acuerdo con Estados Unidos para llevar a cabo operaciones contra el narcotr\u00e1fico en&hellip;<\/p>\n","protected":false},"author":10,"featured_media":132121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16289],"tags":[521,5605,6473,98,587,34068,935],"class_list":["post-132120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","tag-acuerdo","tag-ataques","tag-bernardo-arevalo","tag-estados-unidos","tag-guatemala","tag-guatemalteco","tag-presidente"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Bernardo-Arevalo.jpg","jetpack-related-posts":[{"id":58847,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/08\/28\/tribunal-electoral-de-guatemala-proclama-presidente-electo-a-bernardo-arevalo\/","url_meta":{"origin":132120,"position":0},"title":"Tribunal Electoral de Guatemala proclama presidente electo a Bernardo Ar\u00e9valo","author":"Nelson Feliz","date":"28 de agosto de 2023","format":false,"excerpt":"El Tribunal Electoral de Guatemala proclama presidente electo a Ar\u00e9valo, poco despu\u00e9s de que suspendieran a su partido, el Movimiento Semilla. Ar\u00e9valo gan\u00f3 las elecciones en segunda vuelta. Ar\u00e9valo se enfrent\u00f3 en el balotaje a la ex primera dama Sandra Torres. Seg\u00fan el conteo oficial el progresista obtuvo 58.01 %\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"Bernardo Ar\u00e9valo y Karin Herrera","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Bernardo-Arevalo-y-Karin-Herrera.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Bernardo-Arevalo-y-Karin-Herrera.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Bernardo-Arevalo-y-Karin-Herrera.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Bernardo-Arevalo-y-Karin-Herrera.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":71128,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/12\/17\/presidente-electo-de-guatemala-bernardo-arevalo-visitara-republica-dominicana-este-lunes-18\/","url_meta":{"origin":132120,"position":1},"title":"Presidente electo de Guatemala Bernardo Ar\u00e9valo visitar\u00e1 Rep\u00fablica Dominicana este lunes 18","author":"Nelson Feliz","date":"17 de diciembre de 2023","format":false,"excerpt":"El presidente elector de Guatemala, C\u00e9sar Bernardo Ar\u00e9valo de Le\u00f3n, realizar\u00e1 una visita a la Rep\u00fablica Dominicana este lunes 18 de diciembre, para sostener un encuentro con el mandatario dominicano, Luis Abinader. La llegada del presidente electo del pa\u00eds centroamericano y su delegaci\u00f3n est\u00e1 programada para la 1:00 de la\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Bernardo Ar\u00e9valo","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Bernardo-Arevalo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Bernardo-Arevalo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Bernardo-Arevalo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Bernardo-Arevalo.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":73691,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/01\/15\/bernardo-arevalo-se-juramenta-como-presidente-de-guatemala\/","url_meta":{"origin":132120,"position":2},"title":"Bernardo Ar\u00e9valo se juramenta como presidente de Guatemala","author":"Nelson Feliz","date":"15 de enero de 2024","format":false,"excerpt":"\u201cS\u00ed, juro\u201d, dijo Bernardo Ar\u00e9valo con la mano izquierda sobre la Constituci\u00f3n y la derecha alzada pasada ya la medianoche. Se pon\u00eda fin as\u00ed a la incertidumbre tras una jornada ca\u00f3tica en la que la investidura fue retrasada casi diez horas por las maniobras del Congreso saliente que declar\u00f3 independientes\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"Bernardo Ar\u00e9valo","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/01\/Bernardo-Arevalo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/01\/Bernardo-Arevalo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/01\/Bernardo-Arevalo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":88315,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/08\/26\/guatemala-y-belice-dialogan-sobre-seguridad-turismo-sostenible-y-desarrollo-economico\/","url_meta":{"origin":132120,"position":3},"title":"Guatemala y Belice dialogan sobre seguridad, turismo sostenible y desarrollo econ\u00f3mico","author":"Nelson Feliz","date":"26 de agosto de 2024","format":false,"excerpt":"Ciudad de Guatemala, (EFE).- El presidente de Guatemala, Bernardo Ar\u00e9valo de Le\u00f3n, y el primer ministro de Belice, John Brice\u00f1o, sostuvieron este lunes un encuentro para dialogar sobre migraci\u00f3n, comercio, turismo sostenible y tambi\u00e9n la interconexi\u00f3n el\u00e9ctrica entre los dos pa\u00edses vecinos. Ar\u00e9valo recibi\u00f3 al primer ministro belice\u00f1o en el\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"Guatemala y Belice","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Guatemala-y-Belice.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Guatemala-y-Belice.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Guatemala-y-Belice.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":71264,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/12\/18\/abinader-apoya-lucha-por-la-democracia-del-presidente-guatemala-bernardo-arevalo\/","url_meta":{"origin":132120,"position":4},"title":"Abinader apoya lucha por la democracia del presidente Guatemala, Bernardo Ar\u00e9valo","author":"Nelson Feliz","date":"18 de diciembre de 2023","format":false,"excerpt":"Abinader dice esta visita simboliza el comienzo de una relaci\u00f3n bilateral m\u00e1s estrecha y fruct\u00edfera que permita adem\u00e1s alzar la voz en foros globales donde se deciden importantes temas como el comercio internacional, el cambio clim\u00e1tico o los Objetivos de Desarrollo Sostenible. El presidente Luis Abinader, tras recibir este lunes\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"La Semanal","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/La-Semanal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/La-Semanal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/La-Semanal.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/La-Semanal.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":86523,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/07\/26\/presidente-de-mexico-minimiza-violencia-que-hizo-que-casi-600-mexicanos-se-refugiaran-en-guatemala\/","url_meta":{"origin":132120,"position":5},"title":"Presidente de M\u00e9xico minimiza violencia que hizo que casi 600 mexicanos se refugiaran en Guatemala","author":"Nelson Feliz","date":"26 de julio de 2024","format":false,"excerpt":"CIUDAD DE M\u00c9XICO (AP) \u2014 El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, agradeci\u00f3 el viernes a Guatemala la ayuda prestada a los cerca de 600 mexicanos que han cruzado a su pa\u00eds para huir de la violencia de los c\u00e1rteles de la droga, pero tambi\u00e9n minimiz\u00f3 la violencia que\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/07\/mexicanos.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/07\/mexicanos.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/07\/mexicanos.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/07\/mexicanos.png?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=132120"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132120\/revisions"}],"predecessor-version":[{"id":132122,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132120\/revisions\/132122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/132121"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=132120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=132120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=132120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}