{"id":132239,"date":"2026-05-30T22:17:28","date_gmt":"2026-05-31T02:17:28","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=132239"},"modified":"2026-05-30T22:17:30","modified_gmt":"2026-05-31T02:17:30","slug":"eeuu-detiene-a-otro-buque-comercial-que-intentaba-llegar-a-iran","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/30\/eeuu-detiene-a-otro-buque-comercial-que-intentaba-llegar-a-iran\/","title":{"rendered":"EEUU detiene a otro buque comercial que intentaba llegar a Ir\u00e1n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">POR KONSTANTIN TOROPIN<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">WASHINGTON (AP) \u2014 Fuerzas estadounidenses han detenido otro buque mercante que intentaba romper el bloqueo de los puertos iran\u00edes al disparar un misil a su sala de m\u00e1quinas, inform\u00f3 el s\u00e1bado el Comando Central de Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El granelero Lian Star, con bandera de Gambia, ignor\u00f3 m\u00e1s de 20 advertencias durante la noche mientras intentaba entrar en un puerto iran\u00ed, manifest\u00f3 el ej\u00e9rcito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El barco permanece a la deriva en el golfo de Om\u00e1n y las fuerzas norteamericanas no han abordado la embarcaci\u00f3n, indic\u00f3 un funcionario de Washington con conocimiento de la situaci\u00f3n, que habl\u00f3 bajo condici\u00f3n de anonimato para tratar operaciones militares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la acci\u00f3n m\u00e1s reciente, las fuerzas armadas de Estados Unidos han detenido seis barcos que intentaban violar el bloqueo. A uno se le permiti\u00f3 continuar. Otros 116 barcos han sido redirigidos, indic\u00f3 el ej\u00e9rcito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos lanz\u00f3 el bloqueo el 17 de abril en respuesta a que Ir\u00e1n efectivamente cerr\u00f3 el estrecho despu\u00e9s de que la guerra comenz\u00f3 con ataques de Estados Unidos e Israel el 28 de febrero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un fr\u00e1gil alto al fuego se ha mantenido desde el 7 de abril. Ahora la regi\u00f3n espera noticias sobre si se est\u00e1 alcanzando un acuerdo para ampliarlo por 60 d\u00edas mientras se celebrar\u00edan nuevas conversaciones sobre el programa nuclear de Ir\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los acontecimientos en el estrecho de Ormuz han sacudido la econom\u00eda mundial.<br>Muchos env\u00edos de petr\u00f3leo, gas natural y suministros relacionados como fertilizante est\u00e1n varados, lo que aumenta la presi\u00f3n sobre los consumidores y los productores de alimentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El bloqueo estadounidense busca limitar la actividad comercial de Ir\u00e1n y su acceso a dinero en efectivo, creando m\u00e1s dolor para su econom\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente estadounidense Donald Trump se reuni\u00f3 con asesores el viernes, pero a\u00fan no ha decidido si seguir adelante con un acuerdo para ampliar la tregua y reabrir el estrecho. Ir\u00e1n ha dicho que el acuerdo no se hab\u00eda finalizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tr\u00e1fico comercial ha seguido fluyendo discretamente a trav\u00e9s del estrecho, pese a las afirmaciones de Ir\u00e1n de que debe aprobar cualquier tr\u00e1nsito, aunque a un volumen mucho menor que antes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCualquier violaci\u00f3n de estas regulaciones pondr\u00e1 su paso en grave riesgo\u201d, declar\u00f3 el mando militar iran\u00ed el s\u00e1bado en un comunicado difundido por la televisi\u00f3n estatal, advirtiendo que cualquier buque militar que intentara interferir con eso ser\u00eda atacado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ir\u00e1n incluso ha cobrado peajes por el tr\u00e1nsito de hasta 2 millones de d\u00f3lares, lo que expertos han calificado como una violaci\u00f3n de un principio del comercio mar\u00edtimo internacional: la libertad de navegaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El viceprimer ministro de Qatar, el jeque Saoud bin Abdulrahman bin Hassan bin Ali Al Thani, indic\u00f3 el s\u00e1bado que la naci\u00f3n se opone a cobrar tarifas por el tr\u00e1nsito, \u201cpero por ciertos momentos cuando dicen que lo van a usar para despeje de minas o alg\u00fan uso de las tarifas por un tiempo temporal, esto es algo negociable, y podr\u00eda ser algo que ayude a que el tr\u00e1nsito del estrecho de Ormuz vuelva a una etapa normal\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario estadounidense previamente dijo a The Associated Press que Estados Unidos no ha encontrado ni destruido ninguna mina en el estrecho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POR KONSTANTIN TOROPIN WASHINGTON (AP) \u2014 Fuerzas estadounidenses han detenido otro buque mercante que intentaba romper el bloqueo de los puertos iran\u00edes al disparar un misil a su sala de&hellip;<\/p>\n","protected":false},"author":10,"featured_media":132240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16289],"tags":[34109],"class_list":["post-132239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","tag-eeuu-detiene-a-otro-buque-comercial"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/iran.jpg","jetpack-related-posts":[{"id":133484,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/06\/14\/buque-ignoro-advertencias-antes-de-ser-atacado-dice-funcionario-de-eeuu\/","url_meta":{"origin":132239,"position":0},"title":"Buque ignor\u00f3 advertencias antes de ser atacado, dice funcionario de EEUU","author":"Nelson Feliz","date":"14 de junio de 2026","format":false,"excerpt":"POR KONSTANTIN TOROPIN WASHINGTON (AP) \u2014 Un buque petrolero inutilizado por el ej\u00e9rcito estadounidense mientras intentaba burlar el bloqueo a Ir\u00e1n hab\u00eda desestimado casi 60 advertencias verbales, as\u00ed como otras demostraciones de fuerza, antes de que le dispararan, inform\u00f3 a The Associated Press un funcionario de Washington. El funcionario, que\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"Marco Rubio","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/Marco-Rubio-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/Marco-Rubio-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/Marco-Rubio-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/Marco-Rubio-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":69558,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/12\/04\/atacan-en-mar-rojo-un-buque-guerra-eu-y-barcos-comerciales\/","url_meta":{"origin":132239,"position":1},"title":"Atacan en mar Rojo un buque guerra EU y barcos comerciales","author":"BIMARY DE JES\u00daS Matos","date":"4 de diciembre de 2023","format":false,"excerpt":"WASHINGTON.- Un buque de guerra estadounidense y varios buques comerciales fueron atacados este domingo en el mar Rojo, inform\u00f3 el Pent\u00e1gono. El incidente se produjo en medio del aumento de las tensiones en la zona. \u00abTenemos conocimiento de informes relativos a ataques contra el [destructor de misiles guiados] USS Carney\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Nuestro-Mundo-8-9.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Nuestro-Mundo-8-9.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Nuestro-Mundo-8-9.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":129986,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/08\/eeuu-dispara-contra-buques-petroleros-iranies-en-medio-de-tensiones-en-el-estrecho-de-ormuz\/","url_meta":{"origin":132239,"position":2},"title":"EEUU dispara contra buques petroleros iran\u00edes en medio de tensiones en el estrecho de Ormuz","author":"Nelson Feliz","date":"8 de mayo de 2026","format":false,"excerpt":"POR ADAM SCHRECK, BEN FINLEY and RUSS BYNUM DUB\u00c1I, Emiratos \u00c1rabes Unidos (AP) \u2014 El ej\u00e9rcito de Estados Unidos atac\u00f3 y dej\u00f3 fuera de servicio a dos buques petroleros iran\u00edes el viernes tras intercambiar fuego con fuerzas armadas de Ir\u00e1n en el estrecho de Ormuz. Por su parte, Emiratos \u00c1rabes\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Estrecho-de-Ormuz-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Estrecho-de-Ormuz-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Estrecho-de-Ormuz-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Estrecho-de-Ormuz-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":127669,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/04\/14\/diplomaticos-intentan-organizar-2da-ronda-de-conversaciones-eeuu-iran\/","url_meta":{"origin":132239,"position":3},"title":"Diplom\u00e1ticos intentan organizar 2da ronda de conversaciones EEUU-Ir\u00e1n","author":"Nelson Feliz","date":"14 de abril de 2026","format":false,"excerpt":"POR MUNIR AHMED and SAM METZ ISLAMABAD, Pakist\u00e1n (AP) \u2014 Los diplom\u00e1ticos trabajaron el martes a trav\u00e9s de canales indirectos para organizar una nueva ronda de conversaciones entre Estados Unidos e Ir\u00e1n despu\u00e9s de que Washington puso en marcha su bloqueo a los puertos iran\u00edes, mientras Teher\u00e1n amenazaba con atacar\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/ataques-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/ataques-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/ataques-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/ataques-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84734,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/06\/14\/submarino-estadounidense-llega-a-la-bahia-de-guantanamo-un-dia-despues-de-la-llegada-de-buques-de-guerra-rusos-a-cuba\/","url_meta":{"origin":132239,"position":4},"title":"Submarino estadounidense llega a la Bah\u00eda de Guant\u00e1namo un d\u00eda despu\u00e9s de la llegada de buques de guerra rusos a Cuba","author":"Nelson Feliz","date":"14 de junio de 2024","format":false,"excerpt":"POR LOLITA C. BALDOR WASHINGTON (AP) \u2014 Un submarino de la Armada de Estados Unidos lleg\u00f3 a la Bah\u00eda de Guant\u00e1namo, Cuba, en una demostraci\u00f3n de fuerza mientras una flota de buques de guerra rusos se re\u00fane para realizar ejercicios militares planeados en el Caribe. El Comando Sur de Estados\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Busque-Guerra.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Busque-Guerra.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Busque-Guerra.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Busque-Guerra.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":72191,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/12\/27\/kiev-afirma-que-destruyo-buque-ruso-novocherkassk-en-crimea\/","url_meta":{"origin":132239,"position":5},"title":"Kiev afirma que destruy\u00f3 buque ruso \u2018Novocherkassk\u2019 en Crimea","author":"BIMARY DE JES\u00daS Matos","date":"27 de diciembre de 2023","format":false,"excerpt":"KIEV.- Un sorpresivo ataque de Ucrania alert\u00f3 a los residentes de Feodosia, una ciudad portuaria de la pen\u00ednsula de Crimea, territorio anexado por Rusia. Misiles guiados lanzados desde aviones causaron la destrucci\u00f3n del gran buque de desembarco ruso \u2018Novocherkassk\u2019, aseguraron las tropas del pa\u00eds invadido. Al menos una persona muri\u00f3\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Noticias-de-energia-58-7.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Noticias-de-energia-58-7.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Noticias-de-energia-58-7.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=132239"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132239\/revisions"}],"predecessor-version":[{"id":132241,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132239\/revisions\/132241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/132240"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=132239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=132239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=132239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}