{"id":132264,"date":"2026-05-30T23:43:04","date_gmt":"2026-05-31T03:43:04","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=132264"},"modified":"2026-05-30T23:43:06","modified_gmt":"2026-05-31T03:43:06","slug":"jovenes-participan-en-calentamiento-del-primer-mun-sde-2026","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/30\/jovenes-participan-en-calentamiento-del-primer-mun-sde-2026\/","title":{"rendered":"J\u00f3venes participan en calentamiento del primer MUN-SDE 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Santo Domingo Este.\u2013 Una ma\u00f1ana de di\u00e1logos e intercambio de ideas reuni\u00f3 a decenas de j\u00f3venes en el Palacio Municipal, como parte del calentamiento del primer Modelo de Naciones Unidas de Santo Domingo Este (MUN-SDE 2026), que se celebrar\u00e1 del 5 al 7 de junio en la sede del cabildo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El encuentro cont\u00f3 con la presencia de Hegel K. Mart\u00ednez, presidente y fundador de la Fundaci\u00f3n de Acci\u00f3n Juvenil, Justicia, Institucionalidad y Transparencia (FUNAJIT), y del director de Juventud del ASDE, Gabriel Est\u00e9vez, quienes destacaron la importancia de abrir espacios de participaci\u00f3n para la juventud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, Giancarlos Rodr\u00edguez, secretario general de FUNAJIT, subray\u00f3 que la organizaci\u00f3n ha tenido representaci\u00f3n en m\u00e1s de 33 conferencias internacionales, consolidando su experiencia en modelos de simulaci\u00f3n y diplomacia juvenil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la jornada participaron ni\u00f1os y adolescentes desde los diez a\u00f1os de edad, lo que reafirma la apertura de FUNAJIT a los m\u00e1s peque\u00f1os que deseen integrarse a este proyecto formativo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"722\" src=\"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-30-at-4.00.59-PM-1024x722.jpeg\" alt=\"\" class=\"wp-image-132266\" srcset=\"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-30-at-4.00.59-PM-1024x722.jpeg 1024w, https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-30-at-4.00.59-PM-300x211.jpeg 300w, https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-30-at-4.00.59-PM-768x541.jpeg 768w, https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-30-at-4.00.59-PM.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El MUN-SDE 2026 es una iniciativa institucional y pedag\u00f3gica impulsada por FUNAJIT a trav\u00e9s de su programa MUN Revolution, en alianza con el Ayuntamiento de Santo Domingo Este y su Direcci\u00f3n de Juventud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata del primer modelo de simulaci\u00f3n parlamentaria celebrado a nivel municipal en la Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad se desarrollar\u00e1 durante tres d\u00edas en los espacios del Palacio Municipal, con cobertura simult\u00e1nea de once cuerpos deliberativos y un cuerpo de prensa itinerante, distribuidos en distintos grupos de trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El calentamiento de este viernes inici\u00f3 a las 9:00 de la ma\u00f1ana en el Palacio Municipal Costa del Faro, marcando el inicio de una experiencia que busca fortalecer el liderazgo, la institucionalidad y la participaci\u00f3n juvenil en el municipio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo Este.\u2013 Una ma\u00f1ana de di\u00e1logos e intercambio de ideas reuni\u00f3 a decenas de j\u00f3venes en el Palacio Municipal, como parte del calentamiento del primer Modelo de Naciones Unidas&hellip;<\/p>\n","protected":false},"author":10,"featured_media":132265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35],"tags":[4549,3899,25618,34125],"class_list":["post-132264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-calentamiento","tag-jovenes","tag-participan","tag-primer-mun-sde-2026"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-30-at-4.01.00-PM.jpeg","jetpack-related-posts":[{"id":52055,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/06\/06\/candidatos-de-la-fuerza-del-pueblo-apoyan-actividades-deportivas-en-sde\/","url_meta":{"origin":132264,"position":0},"title":"Candidatos de la Fuerza del Pueblo apoyan actividades deportivas en SDE","author":"prenxa100","date":"6 de junio de 2023","format":false,"excerpt":"Santo Domingo, Este.-. La precandidata a la Alcald\u00eda de Santo Domingo Este, Leandra Acosta\u00a0 y el aspirante a regidor por el Partido Fuerza del Pueblo (FP), Francisco Terrero (Miguel), participaron en la apertura del Torneo A\u00f1ejo Interbarrial del sector el Tamarindo. En dicho torneo participar\u00e1n cuatro equipos del municipio que\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/atento.com.do\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-05-at-9.19.15-PM-768x1024.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/atento.com.do\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-05-at-9.19.15-PM-768x1024.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/atento.com.do\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-05-at-9.19.15-PM-768x1024.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/atento.com.do\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-05-at-9.19.15-PM-768x1024.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":89574,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/09\/28\/alcaldia-sde-reconoce-al-director-de-la-pn-por-su-apoyo-al-deporte-y-la-juventud\/","url_meta":{"origin":132264,"position":1},"title":"Alcald\u00eda SDE reconoce al director de la PN por su apoyo al deporte y la juventud","author":"Nelson Feliz","date":"28 de septiembre de 2024","format":false,"excerpt":"El director general de la Polic\u00eda Nacional, mayor general Ram\u00f3n Antonio Guzm\u00e1n Peralta, fue reconocido por la Alcald\u00eda de Santo Domingo Este y su alcalde Dio Astacio, por su invaluable apoyo al desarrollo del deporte y su compromiso con el bienestar de la juventud en la comunidad. La distinci\u00f3n al\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":114419,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/11\/13\/ministro-kelvin-cruz-inicia-construccion-de-11-techados-multiusos-en-sde\/","url_meta":{"origin":132264,"position":2},"title":"Ministro Kelvin Cruz inicia construcci\u00f3n de 11 techados multiusos en SDE","author":"Nelson Feliz","date":"13 de noviembre de 2025","format":false,"excerpt":"El ministro de Deportes, Kelvin Cruz, inici\u00f3 este mi\u00e9rcoles los trabajos para la construcci\u00f3n y remozamiento de techados en 11 clubes del municipio Santo Domingo Este, con una inversi\u00f3n total superior a los 300 millones de pesos. La masiva mejora de la infraestructura deportiva del municipio m\u00e1s poblado del pa\u00eds\u2026","rel":"","context":"En \u00abDEPORTES\u00bb","block_context":{"text":"DEPORTES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/deportes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Kelvin-Cruz-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Kelvin-Cruz-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Kelvin-Cruz-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Kelvin-Cruz-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":127654,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/04\/14\/se-entrega-el-burro-presunto-responsable-de-multiples-atracos-en-sde\/","url_meta":{"origin":132264,"position":3},"title":"Se entrega \u201cEl Burro\u201d presunto responsable de m\u00faltiples atracos en SDE","author":"Nelson Feliz","date":"14 de abril de 2026","format":false,"excerpt":"La Polic\u00eda Nacional inform\u00f3 este martes que se entreg\u00f3 ayer un reconocido delincuente, quien era activamente buscado por su presunta vinculaci\u00f3n a varios asaltos registrados en distintos sectores del municipio. Se trata de Alex Reyes Jim\u00e9nez, alias \u201cEl Burro\u201d, de 22 a\u00f1os, quien, seg\u00fan informes preliminares, es se\u00f1alado como supuesto\u2026","rel":"","context":"En \u00abMILITARES\u00bb","block_context":{"text":"MILITARES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/militares\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/11\/POLICIAS.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/11\/POLICIAS.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/11\/POLICIAS.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/11\/POLICIAS.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":56966,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/08\/07\/lanzan-tres-candidaturas-a-regidores-en-sde-por-alianza-pais\/","url_meta":{"origin":132264,"position":4},"title":"Lanzan tres candidaturas a regidores en SDE por Alianza Pa\u00eds","author":"Nelson Feliz","date":"7 de agosto de 2023","format":false,"excerpt":"Por Mart\u00edn Restituyo El presidente del Partido Alianza Pa\u00eds (AlPais), doctor Guillermo Moreno, encabez\u00f3 este fin de semana los actos de lanzamiento oficial de tres candidaturas a regidores por distintas demarcaciones en Santo Domingo Este. Durante las actividades desarrolladas por separado este domingo, Alianza Pa\u00eds present\u00f3 en un primer acto\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"Guillermo Moreno","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Guillermo-Moreno.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Guillermo-Moreno.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Guillermo-Moreno.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Guillermo-Moreno.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":50036,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/05\/16\/reconocen-a-leonel-fernandez-como-propulsor-de-los-modelos-de-las-naciones-unidas-en-rd\/","url_meta":{"origin":132264,"position":5},"title":"Reconocen a Leonel Fern\u00e1ndez como propulsor de los modelos de las Naciones Unidas en RD","author":"prenxa100","date":"16 de mayo de 2023","format":false,"excerpt":"L\u00edder pol\u00edtico afirma modelos de las Naciones Unidas han sido una revoluci\u00f3n del conocimiento en el pa\u00eds SANTO DOMINGO ESTE.- El expresidente de la Rep\u00fablica, Leonel Fern\u00e1ndez, afirm\u00f3 este martes que los modelos de las Naciones Unidas han contribuido a crear un mecanismo extracurricular de aprendizaje que se ha convertido\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=132264"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132264\/revisions"}],"predecessor-version":[{"id":132267,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/132264\/revisions\/132267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/132265"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=132264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=132264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=132264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}