{"id":134654,"date":"2026-07-14T08:07:14","date_gmt":"2026-07-14T12:07:14","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=134654"},"modified":"2026-07-14T08:07:17","modified_gmt":"2026-07-14T12:07:17","slug":"senado-firma-alianza-con-unapec","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2026\/07\/14\/senado-firma-alianza-con-unapec\/","title":{"rendered":"Senado firma alianza con UNAPEC"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por: Israel Figueroa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO. \u2013 El Senado de la Rep\u00fablica suscribi\u00f3 este lunes un Acuerdo Marco de Colaboraci\u00f3n con la Universidad APEC (UNAPEC), con el objetivo de desarrollar de manera conjunta programas formativos de posgrado y de educaci\u00f3n continua para el fortalecimiento del personal legislativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acuerdo contempla, tambi\u00e9n programas de ingl\u00e9s, autorizar el acceso y uso rec\u00edproco de sus respectivas bibliotecas, la realizaci\u00f3n de programa de pasant\u00edas, entre otros aspectos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acuerdo, suscrito por el presidente del Senado, Ricardo de los Santos, y el rector de UNAPEC, Erik P\u00e9rez Vega establece las bases de cooperaci\u00f3n interinstitucional en los \u00e1mbitos acad\u00e9mico, cient\u00edfico, tecnol\u00f3gico, cultural y de extensi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa firma de este acuerdo es una muestra de que las instituciones deben trabajar unidas y un acuerdo como este fortalece la mayor riqueza de un ser humano: el conocimiento\u201d afirm\u00f3 el presidente del Senado, Ricardo de los Santos, al destacar la importancia de la formaci\u00f3n permanente en la profesionalizaci\u00f3n del personal de una instituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acuerdo contempla, adem\u00e1s, el acceso rec\u00edproco a bibliotecas, el intercambio de personal, la realizaci\u00f3n de pasant\u00edas, congresos, seminarios y talleres conjunto, garantizando en todo momento la autonom\u00eda constitucional, administrativa y funcional del Senado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas universidades del siglo XXI est\u00e1n llamadas a desempe\u00f1ar un papel cada vez m\u00e1s activo como articuladoras del conocimiento, la innovaci\u00f3n y el desarrollo institucional. La academia debe ser un puente permanente entre la investigaci\u00f3n, las pol\u00edticas p\u00fablicas, el sector productivo y las necesidades de la ciudadan\u00eda\u201d, indic\u00f3 el rector de UNAPEC, Erik P\u00e9rez Vega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El convenio viabiliza la interoperabilidad entre la Biblioteca del Congreso Nacional y la Biblioteca de UNAPEC mediante el protocolo internacional Z39.50.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de este instrumento, ambas bibliotecas intercambiar\u00e1n registros bibliogr\u00e1ficos, lo que permitir\u00e1 fortalecer la normalizaci\u00f3n de los cat\u00e1logos y ampliar el acceso a la informaci\u00f3n para la investigaci\u00f3n acad\u00e9mica y legislativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acuerdo tendr\u00e1 una vigencia de dos a\u00f1os, renovables de forma autom\u00e1tica.<br>Con la firma de estos instrumentos, el Senado de la Rep\u00fablica reafirma su compromiso con la formaci\u00f3n continua de sus colaboradores y con la modernizaci\u00f3n de su gesti\u00f3n documental, consolidando una alianza estrat\u00e9gica con una de las principales instituciones de educaci\u00f3n superior del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el Senado acompa\u00f1aron al presidente Ricardo de los Santos, el secretario general legislativo, Jos\u00e9 Carrasco; la directora de Gesti\u00f3n Humana, Sonya Uribe; el secretario general administrativo, Ram\u00f3n Novo; el encargado de Gabinete, Nelson Guzman Dipl\u00e1n; entre otros funcionarios de la C\u00e1mara Alta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por UNAPEC estuvieron presentes la vicerrectora acad\u00e9mica Elsa Mar\u00eda Moquete; Milc\u00edades Wilmore, vicerrector de Estrategia, Investigaci\u00f3n y Desarrollo; Massiel Cohen, decana de Investigaci\u00f3n Aplicada; Jos\u00e9 Antonio Gil, decano de Vinculaci\u00f3n y Emprendimiento; Amarilis Beltr\u00e9, directora de Biblioteca; Andy Crespo, director de Relaciones Nacionales y Alejandro Moscoso Segarra, decano de la Facultad de Humanidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Israel Figueroa SANTO DOMINGO. \u2013 El Senado de la Rep\u00fablica suscribi\u00f3 este lunes un Acuerdo Marco de Colaboraci\u00f3n con la Universidad APEC (UNAPEC), con el objetivo de desarrollar de&hellip;<\/p>\n","protected":false},"author":10,"featured_media":134655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35,25],"tags":[50,413,5402],"class_list":["post-134654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada","tag-alianza","tag-senado","tag-unapec"],"jetpack-related-posts":[{"id":123484,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/03\/01\/prodominicana-y-unapec-nueva-alianza-por-el-comercio-exterior\/","url_meta":{"origin":134654,"position":0},"title":"ProDominicana y Unapec: Nueva alianza por el comercio exterior","author":"Nelson Feliz","date":"1 de marzo de 2026","format":false,"excerpt":"El Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana (ProDominicana) y la Universidad Unapec, firmaron un acuerdo de colaboraci\u00f3n interinstitucional con el objetivo de continuar fortaleciendo la cooperaci\u00f3n acad\u00e9mica, la formaci\u00f3n de talento humano y el desarrollo de iniciativas conjuntas que contribuyan a la competitividad del pa\u00eds en los\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"\u00c1lvaro Sousa Sevilla, presidennte del Junta de Directores_ Biviana Riveiro Directora Ejecutiva de ProDominicana....","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/Alvaro-Sousa-Sevilla-presidennte-del-Junta-de-Directores_-Biviana-Riveiro-Directora-Ejecutiva-de-ProDominicana.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/Alvaro-Sousa-Sevilla-presidennte-del-Junta-de-Directores_-Biviana-Riveiro-Directora-Ejecutiva-de-ProDominicana.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/Alvaro-Sousa-Sevilla-presidennte-del-Junta-de-Directores_-Biviana-Riveiro-Directora-Ejecutiva-de-ProDominicana.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/Alvaro-Sousa-Sevilla-presidennte-del-Junta-de-Directores_-Biviana-Riveiro-Directora-Ejecutiva-de-ProDominicana.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":131978,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/27\/unapec-y-prodominicana-lanzaran-nueva-maestria-en-gestion-estrategica-de-negocios-internacionales\/","url_meta":{"origin":134654,"position":1},"title":"UNAPEC y ProDominicana lanzar\u00e1n nueva &#8220;Maestr\u00eda en Gesti\u00f3n Estrat\u00e9gica de Negocios Internacionales&#8221;","author":"Nelson Feliz","date":"27 de mayo de 2026","format":false,"excerpt":"La Universidad APEC (UNAPEC) y el Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana (ProDominicana) anunciaron el lanzamiento oficial de la nueva Maestr\u00eda en Gesti\u00f3n Estrat\u00e9gica de Negocios Internacionales. Este programa acad\u00e9mico conjunto busca fortalecer las competencias del talento humano nacional ante las demandas de los mercados globales contempor\u00e1neos.\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/lanza.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/lanza.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/lanza.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/lanza.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":130874,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/17\/santos-badia-impulsa-educacion-de-calidad-en-unapec\/","url_meta":{"origin":134654,"position":2},"title":"Santos Bad\u00eda impulsa educaci\u00f3n de calidad en Unapec","author":"Nelson Feliz","date":"17 de mayo de 2026","format":false,"excerpt":"Santos Bad\u00eda impulsa una transformaci\u00f3n educativa de calidad orientada al siglo XXI durante graduaci\u00f3n extraordinaria de Unapec El ministro de Educaci\u00f3n Superior, Ciencia y Tecnolog\u00eda (MESCyT), Rafael Santos Bad\u00eda, reafirm\u00f3 su visi\u00f3n de impulsar una transformaci\u00f3n educativa de calidad, adaptada a los desaf\u00edos del siglo XXI, durante la Graduaci\u00f3n Extraordinaria\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Rafael Santos Bad\u00eda","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Rafael-Santos-Badia-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Rafael-Santos-Badia-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Rafael-Santos-Badia-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/Rafael-Santos-Badia-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":61620,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/28\/mescyt-firma-convenio-con-mepyd-gsa-y-unapec-para-promover-uso-de-tecnologias-en-recurso-agua-de-rd\/","url_meta":{"origin":134654,"position":3},"title":"MESCYT firma convenio con MEPyD, GSA y UNAPEC para promover uso de tecnolog\u00edas en recurso agua de RD","author":"Nelson Feliz","date":"28 de septiembre de 2023","format":false,"excerpt":"Por Martin Restituyo Los ministerios de Educaci\u00f3n Superior, Ciencia y Tecnolog\u00eda (MESCyT), Econom\u00eda, Planificaci\u00f3n y Desarrollo, el Gabinete del Sector Agua (GSA) y la Universidad APEC (UNAPEC), suscribieron un convenio de colaboraci\u00f3n interinstitucional sobre el uso de las \u201cTecnolog\u00edas Innovadoras para la gesti\u00f3n Sostenible del Recurso Agua en la Rep\u00fablica\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Acuerdo-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Acuerdo-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Acuerdo-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Acuerdo-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":132078,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/28\/prodominicana-y-universidad-apec-lanzan-maestria-en-gestion-estrategica-de-negocios-internacionales\/","url_meta":{"origin":134654,"position":4},"title":"ProDominicana y Universidad APEC lanzan maestr\u00eda en gesti\u00f3n estrat\u00e9gica de negocios internacionales","author":"Nelson Feliz","date":"28 de mayo de 2026","format":false,"excerpt":"La iniciativa acad\u00e9mica busca fortalecer las capacidades profesionales en comercio, inversi\u00f3n y negocios globales Santo Domingo. El Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana (ProDominicana) y la Universidad APEC (UNAPEC) realizaron el lanzamiento oficial de la \u201cMaestr\u00eda en Gesti\u00f3n Estrat\u00e9gica de Negocios Internacionales\u201d, una propuesta acad\u00e9mica orientada a\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/maestria-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/maestria-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/maestria-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/maestria-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":72782,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/01\/03\/universidad-apec-desarrolla-modelo-de-ia-que-definiria-vias-de-evacuacion-rapidas\/","url_meta":{"origin":134654,"position":5},"title":"Universidad APEC desarrolla modelo de IA que definir\u00eda v\u00edas de evacuaci\u00f3n r\u00e1pidas","author":"Nelson Feliz","date":"3 de enero de 2024","format":false,"excerpt":"El proyecto fue aprobado por el Mescyt evidenciando que, para predecir el potencial de actuaci\u00f3n, hay que desarrollar un gemelo digital de la metr\u00f3poli de Santo Domingo que propicie simular el comportamiento poblacional y poder prever diferentes escenarios ante diversas situaciones. La Universidad APEC, a trav\u00e9s de su Direcci\u00f3n de\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"inteligencia artificial","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/01\/inteligencia-artificial.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/01\/inteligencia-artificial.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/01\/inteligencia-artificial.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/07\/IMG-20260713-WA0431-scaled.jpg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/134654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=134654"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/134654\/revisions"}],"predecessor-version":[{"id":134656,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/134654\/revisions\/134656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/134655"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=134654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=134654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=134654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}