{"id":134712,"date":"2026-07-15T08:56:44","date_gmt":"2026-07-15T12:56:44","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=134712"},"modified":"2026-07-15T08:56:46","modified_gmt":"2026-07-15T12:56:46","slug":"adriano-sanchez-roa-el-verdadero-record-del-2025-fue-de-importaciones-no-de-produccion","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2026\/07\/15\/adriano-sanchez-roa-el-verdadero-record-del-2025-fue-de-importaciones-no-de-produccion\/","title":{"rendered":"Adriano S\u00e1nchez Roa: \u201cEl verdadero r\u00e9cord del 2025 fue de importaciones, no de producci\u00f3n\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Santo Domingo &#8211; El secretario de Asuntos Agropecuarios del Partido de la Liberaci\u00f3n Dominicana (PLD), exsenador Adriano S\u00e1nchez Roa, rechaz\u00f3 las afirmaciones del ministro de Agricultura, Francisco Oliverio Espaillat, de que en el a\u00f1o 2025 se alcanzaron r\u00e9cords de producci\u00f3n agropecuaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asegura que los datos oficiales demuestran que el verdadero r\u00e9cord fue el de las importaciones de alimentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl ministro Oliverio pretende desconocer una realidad incuestionable: en 2025 las importaciones de alimentos alcanzaron los 114.5 millones de quintales, un volumen 30.9 millones de quintales superior al registrado en 2024. Estos datos evidencian que el verdadero r\u00e9cord del a\u00f1o no fue de producci\u00f3n agropecuaria, sino de compras de alimentos en el exterior\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e1nchez Roa explic\u00f3 que en 2025 la Rep\u00fablica Dominicana import\u00f3 alimentos por US$5,594.8 millones, el mayor monto registrado en la historia del pa\u00eds, situaci\u00f3n que atribuy\u00f3 al descenso de la producci\u00f3n nacional y a la falta de pol\u00edticas eficaces de respaldo al sector agropecuario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El exsenador dijo que el gobierno import\u00f3 el 29.6% de los alimentos consumidos por la poblaci\u00f3n dominicana, equivalente a RD$352,472.4 millones, seg\u00fan afirm\u00f3, afect\u00f3 la rentabilidad de los productores nacionales sin lograr reducir el costo de la canasta alimentaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precis\u00f3 que entre los principales productos importados durante 2025 figuran US$125.5 millones en carne de pollo; US$278.2 millones en carne de cerdo; US$170.1 millones en leche; US$146.1 millones en carne de res; US$123 millones en caf\u00e9; US$87.8 millones en habichuelas y US$69.6 millones en papa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, S\u00e1nchez Roa revel\u00f3 la importaci\u00f3n de US$395.4 millones en ma\u00edz; US$20.5 millones en ajo; US$20.1 millones en arroz; US$20.2 millones en coco; US$16.9 millones en guandules; US$15.9 millones en cebolla y US$14.7 millones en limones y naranjas, entre otros alimentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando un pa\u00eds establece un r\u00e9cord de importaciones de alimentos es porque disminuye su producci\u00f3n, no puede hablarse de un \u00e9xito agropecuario. Es la evidencia de una creciente dependencia del mercado internacional y del debilitamiento del campo dominicano\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Advierte que el desempe\u00f1o del sector contin\u00faa deterior\u00e1ndose en 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e1nchez Roa afirm\u00f3 que durante el primer semestre de 2026 la situaci\u00f3n se ha agravado, indicando que el crecimiento del Producto Interno Bruto (PIB) agropecuario cay\u00f3 de 4.8 % a 2.9%, una penosa reducci\u00f3n cercana al 40%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se\u00f1al\u00f3 que entre 2023 y 2026 la producci\u00f3n nacional registra disminuciones de 51.2% en la producci\u00f3n porcina, 21.8% en arroz, 8.5% en cacao y 0.7% en pollo, lo que, a su juicio, confirma el deterioro del aparato productivo nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo &#8211; El secretario de Asuntos Agropecuarios del Partido de la Liberaci\u00f3n Dominicana (PLD), exsenador Adriano S\u00e1nchez Roa, rechaz\u00f3 las afirmaciones del ministro de Agricultura, Francisco Oliverio Espaillat, de&hellip;<\/p>\n","protected":false},"author":10,"featured_media":134713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16559,25],"tags":[3923],"class_list":["post-134712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-portada","tag-adriano-sanchez-roa"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/07\/S.-Roa.jpg","jetpack-related-posts":[{"id":92208,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/01\/01\/rd-importa-782-millones-de-pesos-diariamente-por-la-caida-en-la-produccion-de-alimentos\/","url_meta":{"origin":134712,"position":0},"title":"RD importa 782 millones de pesos diariamente por la ca\u00edda en la producci\u00f3n de alimentos","author":"Nelson Feliz","date":"1 de enero de 2025","format":false,"excerpt":"Adriano S\u00e1nchez Roa describe el 2024 como el a\u00f1o de la quiebra de productores y del m\u00e1s alto costo de la canasta alimenticia. La reducci\u00f3n dr\u00e1stica de la producci\u00f3n de alimentos en el pa\u00eds ha conllevado a la importaci\u00f3n de 19 mil 400 millones de d\u00f3lares en los 52 meses\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"Adriano S\u00e1nchez Roa","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/01\/Adriano-Sanchez-Roa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/01\/Adriano-Sanchez-Roa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/01\/Adriano-Sanchez-Roa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/01\/Adriano-Sanchez-Roa.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":104450,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/24\/sanchez-roa-la-preocupacion-de-los-productores-de-arroz\/","url_meta":{"origin":134712,"position":1},"title":"S\u00e1nchez Roa: La preocupaci\u00f3n de los productores de arr\u00f3z","author":"Nelson Feliz","date":"24 de julio de 2025","format":false,"excerpt":"S\u00e1nchez Roa acusa al ministro de Agricultura de mentir sobre la existencia de 2.7 millones de quintales de arr\u00f3z, sobrante del importado en el 2024 El titular de la Secretar\u00eda de Asuntos Agropecuarios del Partido de la Liberaci\u00f3n Dominicana (PLD), Adriano S\u00e1nchez Roa, acus\u00f3 al ministro de Agricultura, Limber Cruz,\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/adriano.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/adriano.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/adriano.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":93364,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/02\/08\/sanchez-roa-disminucion-de-la-autosuficiencia-alimentaria\/","url_meta":{"origin":134712,"position":2},"title":"S\u00e1nchez Roa: Disminuci\u00f3n de la autosuficiencia alimentaria","author":"Nelson Feliz","date":"8 de febrero de 2025","format":false,"excerpt":"\u201cSector agropecuario no anda bien y por eso el alza en los productos de la canasta b\u00e1sica\u201d. El titular de la Secretar\u00eda de Asuntos Agropecuarios del Partido de la Liberaci\u00f3n Dominicana (PLD), Adriano S\u00e1nchez Roa, afirm\u00f3 que \u201cla autosuficiencia alimentaria, (capacidad de producir los alimentos que necesita una poblaci\u00f3n, sin\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/Adriano-Sanchez-Roa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/Adriano-Sanchez-Roa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/Adriano-Sanchez-Roa.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":92653,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/01\/10\/adriano-sanchez-roa-gobierno-deja-caer-proyecto-guineero-la-cruz-de-manzanillo\/","url_meta":{"origin":134712,"position":3},"title":"Adriano S\u00e1nchez Roa: \u201cGobierno deja caer proyecto Guineero la Cruz de Manzanillo\u201d","author":"Nelson Feliz","date":"10 de enero de 2025","format":false,"excerpt":"El titular de la Secretar\u00eda de Asuntos Agropecuarios del Partido de la Liberaci\u00f3n Dominicana (PLD), Adriano S\u00e1nchez Roa, denunci\u00f3 las autoridades del sector Agropecuario dejaron caer el Proyecto Guineero La Cruz en Manzanillo, a tal extremo que apenas sembraron 1,093 tareas de una superficie total de 34,000 tareas. En un\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"Adriano S\u00e1nchez Roa","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/01\/Sanchez-Roa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/01\/Sanchez-Roa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/01\/Sanchez-Roa.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":119196,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/01\/08\/sanchez-roa-propone-reincorporar-agronomos-para-bajar-precios\/","url_meta":{"origin":134712,"position":4},"title":"S\u00e1nchez Roa propone reincorporar agr\u00f3nomos para bajar precios","author":"Nelson Feliz","date":"8 de enero de 2026","format":false,"excerpt":"Adriano S\u00e1nchez Roa propone al nuevo Ministro de Agricultura rescatar la rentabilidad del campo, reducir las importaciones y reponer agr\u00f3nomos cancelados. El titular de la Secretar\u00eda de Asuntos Agropecuarios del Partido de la Liberaci\u00f3n Dominicana (PLD), Adriano S\u00e1nchez Roa, plantea al reci\u00e9n juramentado ministro de Agricultura, Francisco Oliverio Espaillat Bencomo\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"Adriano S\u00e1nchez Roa","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Adriano-Sanchez-Roa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Adriano-Sanchez-Roa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Adriano-Sanchez-Roa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Adriano-Sanchez-Roa.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":94568,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/02\/sanchez-roa-carestia-de-los-alimentos-y-grandes-importaciones-demuestran-que-abinader-fue-mal-informado\/","url_meta":{"origin":134712,"position":5},"title":"S\u00e1nchez Roa: \u201cCarest\u00eda de los alimentos y grandes importaciones demuestran que Abinader fue mal informado\u201d","author":"Nelson Feliz","date":"2 de marzo de 2025","format":false,"excerpt":"El titular de la Secretaria de Asuntos Agropecuarios del Partido de la Liberaci\u00f3n Dominicana (PLD), Adriano S\u00e1nchez Roa, afirm\u00f3 que el presidente Luis Abinader fue mal informado, ya que la realidad, contraria a sus palabras en la rendici\u00f3n de cuentas, queda en evidencia con el aumento de la canasta familiar\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Sanchez-Roa-Photoroom.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Sanchez-Roa-Photoroom.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Sanchez-Roa-Photoroom.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Sanchez-Roa-Photoroom.png?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/134712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=134712"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/134712\/revisions"}],"predecessor-version":[{"id":134714,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/134712\/revisions\/134714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/134713"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=134712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=134712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=134712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}