{"id":134715,"date":"2026-07-15T09:50:16","date_gmt":"2026-07-15T13:50:16","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=134715"},"modified":"2026-07-15T09:50:17","modified_gmt":"2026-07-15T13:50:17","slug":"senador-franklin-romero-asegura-que-yayo-no-ha-declinado-a-sus-aspiraciones","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2026\/07\/15\/senador-franklin-romero-asegura-que-yayo-no-ha-declinado-a-sus-aspiraciones\/","title":{"rendered":"Senador Franklin Romero asegura que Yayo no ha declinado a sus aspiraciones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Santo Domingo &#8211; El senador de la provincia Duarte, Franklin Romero confirm\u00f3 este mi\u00e9rcoles que Eduardo Sanz Lovaton no ha declinado a sus aspiraciones presidenciales del Partido Revolucionario Moderno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ser entrevistado en el programa A Diario, Romero confirm\u00f3 que el es quien coordina el proyecto presidencial de Yayo en las 14 provincias de la regi\u00f3n del Cibao.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que las elecciones internas del PRM fueran hoy a Yayo Sanz Lovaton hay que contarles los votos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1ala que si Yayo decide apoyar a otro aspirante el c\u00f3mo dirigente del PRM respalda su decisi\u00f3n y se ir\u00e1 con qui\u00e9n se vaya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vaticin\u00f3 que cu\u00e1nto a la elecci\u00f3n del candidato del PRM lo decidir\u00e1 un tercero, lo mismo manifest\u00f3 en las elecciones generales entre PRM, PLD y Fuerza del Pueblo habr\u00e1 uno de los tres que tendr\u00e1 que decidir en una segunda vuelta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El legislador perremeista, revel\u00f3 que el Ministro de Industria y Comercio Eduardo &#8211; Yayo- Sanz Lovaton tiene un v\u00ednculo cercano con la aspirante presidencial Carolina Mej\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que entre los aspirantes presidenciales oficialistas, David Collado y Carolina Mej\u00eda, si Sanz Lovaton se inclina apoyar por uno de ellos, el tambi\u00e9n apoyar\u00e1 su decisi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo &#8211; El senador de la provincia Duarte, Franklin Romero confirm\u00f3 este mi\u00e9rcoles que Eduardo Sanz Lovaton no ha declinado a sus aspiraciones presidenciales del Partido Revolucionario Moderno. Al&hellip;<\/p>\n","protected":false},"author":10,"featured_media":134716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16559,25],"tags":[21150,31,19913],"class_list":["post-134715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-portada","tag-franklin-romero","tag-prm","tag-yayo-sanz-lovaton"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2026\/07\/IMG_20260715_091806-scaled.jpg","jetpack-related-posts":[{"id":119050,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/01\/06\/abinader-designa-a-eduardo-yayo-sanz-lovaton-como-ministro-de-industria-comercio-y-mipymes\/","url_meta":{"origin":134715,"position":0},"title":"Abinader designa a Eduardo \u201cYayo\u201d Sanz Lovat\u00f3n como ministro de Industria, Comercio y Mipymes","author":"Nelson Feliz","date":"6 de enero de 2026","format":false,"excerpt":"\u201cYayo\u201d Sanz Lovat\u00f3n, quien desde el a\u00f1o 2020 fung\u00eda como director de la Direcci\u00f3n General de Aduanas, fue designado mediante el decreto n\u00famero 3-26. El presidente Luis Abinader design\u00f3 este martes a Eduardo \u201cYayo\u201d Sanz Lovat\u00f3n como nuevo ministro de Industria, Comercio y Mipymes en sustituci\u00f3n de V\u00edctor \u201cIto\u201d Bison\u00f3,\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Eduardo \u201cYayo\u201d Sanz Lovat\u00f3n","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/Eduardo-Sanz-Lovaton.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/Eduardo-Sanz-Lovaton.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/Eduardo-Sanz-Lovaton.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":77796,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/02\/25\/yayo-sanz-lovaton-asegura-que-triunfo-del-prm-es-refrendacion-a-abinader\/","url_meta":{"origin":134715,"position":1},"title":"Yayo Sanz Lovat\u00f3n asegura que triunfo del PRM es refrendaci\u00f3n a Abinader","author":"Nelson Feliz","date":"25 de febrero de 2024","format":false,"excerpt":"El dirigente del Partido Revolucionario Moderno (PRM), Eduardo Sanz Lovat\u00f3n, consider\u00f3 que el resultado de las elecciones constituye una \u201crefrendaci\u00f3n plebiscitaria de las ejecutorias del presidente Luis Abinader en m\u00e1s de tres a\u00f1os de gobierno\u201d. Sanz Lovat\u00f3n , dijo que la sociedad dominicana ha entendido el esfuerzo de Abinader para\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"Eduardo Sanz Lovat\u00f3n","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/02\/Eduardo-Sanz-Lovaton.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/02\/Eduardo-Sanz-Lovaton.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/02\/Eduardo-Sanz-Lovaton.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/02\/Eduardo-Sanz-Lovaton.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":102917,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/10\/yayo-sanz-lovaton-apoya-advertencia-de-abinader-de-cancelar-funcionarios-que-hagan-politica\/","url_meta":{"origin":134715,"position":2},"title":"Yayo Sanz Lovat\u00f3n apoya advertencia de Abinader de cancelar funcionarios que hagan pol\u00edtica","author":"Nelson Feliz","date":"10 de julio de 2025","format":false,"excerpt":"El director general de Aduanas, Eduardo Sanz Lovat\u00f3n, respald\u00f3 la advertencia del presidente Luis Abinader a sus funcionarios de que no podr\u00e1n realizar proselitismo o campa\u00f1a pol\u00edtica desde cargos p\u00fablicos, \u00f3 ser\u00e1n cancelados. \u201cNuestra lucha fue para lograr los cambios en marcha. As\u00ed fundamos un partido de la nada cuando\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"Yayo Sanz Lovat\u00f3n","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Yayo-Sanz-Lovaton.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Yayo-Sanz-Lovaton.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Yayo-Sanz-Lovaton.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":99331,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/05\/20\/juventud-de-yayo-se-potencia-con-liderazgo-y-creatividad\/","url_meta":{"origin":134715,"position":3},"title":"Juventud de Yayo se potencia con liderazgo y creatividad","author":"Nelson Feliz","date":"20 de mayo de 2025","format":false,"excerpt":"El publicista Rafael V\u00e1squez asume la Direcci\u00f3n Nacional de Comunicaciones de la Juventud de Yayo y reafirma compromiso con el mensaje \u201cYa yo estoy Ready\u201d. La estructura juvenil que respalda las aspiraciones presidenciales de Eduardo Sanz Lovat\u00f3n (Yayo) contin\u00faa consolid\u00e1ndose con la incorporaci\u00f3n de j\u00f3venes l\u00edderes comprometidos con el presente\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Rafael V\u00e1squez","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Rafael-Vasquez-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Rafael-Vasquez-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Rafael-Vasquez-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Rafael-Vasquez-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":113842,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/11\/06\/empresarios-lideres-comunitarios-y-religiosos-respaldan-aspiraciones-presidencial-de-raquel-pena\/","url_meta":{"origin":134715,"position":4},"title":"Empresarios, l\u00edderes comunitarios y religiosos respaldan aspiraciones presidencial de Raquel Pe\u00f1a","author":"Nelson Feliz","date":"6 de noviembre de 2025","format":false,"excerpt":"Raquel Pe\u00f1a concita respaldo nacional de empresarios, l\u00edderes comunitarios y religiosos que llaman a la unidad del PRM\u201d Un amplio grupo de empresarios, dirigentes comunitarios y Religiosos, representantes de diversos sectores productivos anunciaron este jueves su respaldo oficial a la candidatura presidencial de la vicepresidenta Raquel Pe\u00f1a, destacando su liderazgo,\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Samuel-Abreu-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Samuel-Abreu-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Samuel-Abreu-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Samuel-Abreu-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":106319,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/08\/13\/abinader-y-yayo-sanz-lovaton-inauguran-en-el-aila-nueva-terminal-courier\/","url_meta":{"origin":134715,"position":5},"title":"Abinader y Yayo Sanz Lovat\u00f3n inauguran en el AILA nueva terminal Courier","author":"Nelson Feliz","date":"13 de agosto de 2025","format":false,"excerpt":"Con una inversi\u00f3n de US$10 millones, la nueva infraestructura permitir\u00e1 procesar m\u00e1s de 4 millones de paquetes adicionales al a\u00f1o, con mayor agilidad y seguridad. El presidente Luis Abinader y el director general de Aduanas, Yayo Sanz Lovat\u00f3n, inauguraron este mi\u00e9rcoles una moderna terminal courier para el manejo y almacenaje\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"Luis Abinader vs Yayo Sanz Lovat\u00f3n","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/Luis-Abinader-vs-Yayo-Sanz-Lovaton-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/Luis-Abinader-vs-Yayo-Sanz-Lovaton-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/Luis-Abinader-vs-Yayo-Sanz-Lovaton-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/Luis-Abinader-vs-Yayo-Sanz-Lovaton-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/134715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=134715"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/134715\/revisions"}],"predecessor-version":[{"id":134717,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/134715\/revisions\/134717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/134716"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=134715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=134715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=134715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}