{"id":49300,"date":"2023-05-10T06:32:44","date_gmt":"2023-05-10T10:32:44","guid":{"rendered":"https:\/\/atento.com.do\/?p=49300"},"modified":"2023-05-10T06:32:44","modified_gmt":"2023-05-10T10:32:44","slug":"bosch-quemo-las-naves-en-el-prd","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2023\/05\/10\/bosch-quemo-las-naves-en-el-prd\/","title":{"rendered":"Bosch quem\u00f3 las naves en el PRD"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">VISI\u00d3N GLOBAL<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por Nelson Encarnaci\u00f3n<br>Nelsonencar10@gmail.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquel 18 de noviembre de 1973, el profesor Juan Bosch encabez\u00f3 la que ser\u00eda su \u00faltima reuni\u00f3n como presidente del Partido Revolucionario Dominicano, tras la cual abandonar\u00eda para siempre todo v\u00ednculo con la organizaci\u00f3n pol\u00edtica en cuya formaci\u00f3n tuvo una destacada participaci\u00f3n en 1939.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue una decisi\u00f3n tajante, radical, si nos atenemos a hechos posteriores\u2014espec\u00edficamente en 1990\u2014cuando Bosch estuvo realmente a las puertas de volver al Gobierno del que hab\u00eda sido despojado en 1963 mediante un madrugonazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hablo de que, en 1990, con las elecciones casi en el bolsillo, Bosch rechaz\u00f3 llevar al doctor Jos\u00e9 Francisco Pe\u00f1a G\u00f3mez como candidato vicepresidencial mediante un acuerdo con el PRD, y m\u00e1s intransigente todav\u00eda fue su renuencia a aceptar el apoyo, sin condiciones, del expresidente Jacobo Majluta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos meses previos al vencimiento del plazo para registrar candidaturas, un importante miembro del Comit\u00e9 Pol\u00edtico del Partido de la Liberaci\u00f3n Dominicana me contact\u00f3, s\u00e1bado en la tarde, para ponerme al tanto de que varios de ellos gestaban una corriente interna para convencer a Bosch de la conveniencia t\u00e1ctica de pactar con Pe\u00f1a G\u00f3mez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto fue publicado como principal informaci\u00f3n de la edici\u00f3n dominical de El Nacional, lo que gener\u00f3 en Bosch una airada reacci\u00f3n, y ese mismo domingo compareci\u00f3 en un programa de televisi\u00f3n donde, no solo neg\u00f3 la versi\u00f3n, sino que lanz\u00f3 incendiarios ep\u00edtetos contra el director del diario, Radham\u00e9s G\u00f3mez Pep\u00edn, y este servidor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">All\u00ed mismo terminaron las gestiones. Bosch, Pe\u00f1a G\u00f3mez y Majluta acudieron a las elecciones de ese a\u00f1o de forma separada, obteniendo, en conjunto, 64%, pero el presidente Joaqu\u00edn Balaguer logr\u00f3 su en\u00e9sima reelecci\u00f3n con apenas poco m\u00e1s de un tercio de los votos v\u00e1lidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfA qu\u00e9 viene esta referencia hist\u00f3rica? Tiene su fundamento en el af\u00e1n que se observa en algunos dirigentes de la Fuerza del Pueblo, un laborantismo encaminado hacia un acuerdo con el PLD, muy a pesar de que, como Bosch en su momento, el expresidente Leonel Fern\u00e1ndez abandon\u00f3 la formaci\u00f3n morada por situaciones de mucho m\u00e1s peso que las invocadas por don Juan 46 a\u00f1os atr\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El profesor Bosch no recibi\u00f3 en el PRD ni un tercio de los agravios infligidos a Fern\u00e1ndez desde el comienzo del Gobierno de Danilo Medina y parte de la c\u00fapula actual del PLD, inclusive en el plano de la integridad personal, al vincul\u00e1rsele con un notorio narcotraficante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cierto que la pol\u00edtica se practica con el cerebro y no con el coraz\u00f3n, y que esta es el arte de lo conveniente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, a veces resulta preferible perder con dignidad y no ganar sobre el lodazal de la ignominia. El presidente Fern\u00e1ndez sabr\u00e1 qu\u00e9 es preferible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VISI\u00d3N GLOBAL Por Nelson Encarnaci\u00f3nNelsonencar10@gmail.com Aquel 18 de noviembre de 1973, el profesor Juan Bosch encabez\u00f3 la que ser\u00eda su \u00faltima reuni\u00f3n como presidente del Partido Revolucionario Dominicano, tras la&hellip;<\/p>\n","protected":false},"author":1,"featured_media":47349,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[95],"tags":[985],"class_list":["post-49300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","tag-bosch-quemo-las-naves-en-el-prd"],"jetpack-related-posts":[{"id":110093,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/09\/25\/25-de-septiembre-el-dia-que-tumban-a-bosch\/","url_meta":{"origin":49300,"position":0},"title":"25 de septiembre: El d\u00eda que tumban a Bosch","author":"Nelson Feliz","date":"25 de septiembre de 2025","format":false,"excerpt":"Los errores lo sacaron del poder. Por: Roberto Valenzuela Todo el mundo sab\u00eda que iban a derrocar al presidente. Hace 62 a\u00f1os. Entre el 24 de septiembre \u2014d\u00eda de Nuestra Se\u00f1ora de las Mercedes\u2014 y el 25 de ese mes, se consum\u00f3 el golpe de Estado a Juan Bosch. Hab\u00eda\u2026","rel":"","context":"En \u00abOPINI\u00d3N\u00bb","block_context":{"text":"OPINI\u00d3N","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/opinion\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":102352,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/03\/se-hace-necesario-seguir-el-ejemplo-del-profesor-juan-bosch\/","url_meta":{"origin":49300,"position":1},"title":"Se hace necesario seguir el ejemplo del Profesor Juan Bosch","author":"Nelson Feliz","date":"3 de julio de 2025","format":false,"excerpt":"La exvicepresidenta Margarita Cede\u00f1o exhorta honrar al Profesor Juan Bosch, ejerciendo la pol\u00edtica como un sacerdocio, no como un mercado. En medio de una democracia asediada por la desinformaci\u00f3n, la polarizaci\u00f3n y el oportunismo, el ejemplo de Juan Bosch es m\u00e1s necesario que nunca. La opini\u00f3n es de la exvicepresidenta\u2026","rel":"","context":"En \u00abOPINI\u00d3N\u00bb","block_context":{"text":"OPINI\u00d3N","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/opinion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Margarita-Cedeno.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Margarita-Cedeno.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Margarita-Cedeno.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Margarita-Cedeno.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":125947,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/03\/27\/jaime-david-acusa-a-la-fp-de-sonsacar-a-dirigentes-del-pld\/","url_meta":{"origin":49300,"position":2},"title":"Jaime David acusa a la FP de sonsacar a dirigentes del PLD","author":"Nelson Feliz","date":"27 de marzo de 2026","format":false,"excerpt":"El ex vicepresidente de la Rep\u00fablica y miembro del Comit\u00e9 Pol\u00edtico del Partido de la Liberaci\u00f3n Dominicana (PLD), Jaime David Fern\u00e1ndez Mirabal, calific\u00f3 \u201cactitud de aves de carro\u00f1a\u201d de dirigentes del partido Fuerza del Pueblo de insistir en sonsacar a dirigentes del PLD para llevarlos a sus filas. \u201cEso no\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"Jaime David Fern\u00e1ndez Mirabal","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/Jaime-Sanchez-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/Jaime-Sanchez-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/Jaime-Sanchez-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/Jaime-Sanchez-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":60210,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/11\/miguel-vargas-llama-a-no-ofender-la-memoria-de-pena-gomez-ni-de-juan-bosch\/","url_meta":{"origin":49300,"position":3},"title":"Miguel Vargas llama a no ofender la memoria de Pe\u00f1a G\u00f3mez ni de Juan Bosch","author":"Nelson Feliz","date":"11 de septiembre de 2023","format":false,"excerpt":"El presidente del Partido Revolucionario Dominicano (PRD), Miguel Vargas Maldonado, consider\u00f3 como una ofensa a la memoria del doctor Jos\u00e9 Francisco Pe\u00f1a G\u00f3mez y un intento fallido de utilizar los principios de honestidad y transparencia del profesor Juan Bosch y del referido l\u00edder hist\u00f3rico de los perrede\u00edstas el debate iniciado\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"Miguel Vargas Maldonado","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/06\/Miguel-Vargas-Maldonado.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/06\/Miguel-Vargas-Maldonado.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/06\/Miguel-Vargas-Maldonado.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/06\/Miguel-Vargas-Maldonado.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":95475,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/14\/hace-52-anos-juan-bosch-llama-a-la-lucha-en-las-calles-contra-el-gobierno-de-balaguer\/","url_meta":{"origin":49300,"position":4},"title":"Hace 52 a\u00f1os Juan Bosch llama a la lucha en las calles contra el gobierno de Balaguer","author":"Nelson Feliz","date":"14 de marzo de 2025","format":false,"excerpt":"Por Tom\u00e1s Vidal Rodr\u00edguez El 14 de marzo de 1973, el expresidente Juan Bosch anunci\u00f3 su determinaci\u00f3n de emprender una lucha sin tregua en las calles contra el gobierno de Joaqu\u00edn Balaguer. Su objetivo era frenar las arbitrariedades de las fuerzas policiales y militares, exigir el respeto a las leyes\u2026","rel":"","context":"En \u00abHISTORIA\u00bb","block_context":{"text":"HISTORIA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/historia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/jb.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/jb.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/jb.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/jb.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":95672,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/17\/jaime-david-fernandez-estimular-el-transfuguismo-es-una-de-las-peores-formas-de-corrupcion\/","url_meta":{"origin":49300,"position":5},"title":"Jaime David Fern\u00e1ndez: \u201cEstimular el transfuguismo es una de las peores formas de corrupci\u00f3n\u201d","author":"Nelson Feliz","date":"17 de marzo de 2025","format":false,"excerpt":"El ex vicepresidente de la Rep\u00fablica y miembro del Comit\u00e9 Pol\u00edtico del Partido de la Liberaci\u00f3n Dominicana (PLD), Jaime David Fern\u00e1ndez Mirabal, reiter\u00f3 sobre el da\u00f1o a la democracia y al sistema de partidos de la pr\u00e1ctica del transfuguismo. La legislaci\u00f3n local ubica al tr\u00e1nsfuga como la persona que, traicionando\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"Jaime David Fern\u00e1ndez Mirabal","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/jaime.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/jaime.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/jaime.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/jaime.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/49300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=49300"}],"version-history":[{"count":0,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/49300\/revisions"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=49300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=49300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=49300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}