{"id":53526,"date":"2023-06-27T21:42:15","date_gmt":"2023-06-28T01:42:15","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=53526"},"modified":"2023-06-27T21:42:16","modified_gmt":"2023-06-28T01:42:16","slug":"los-vecinos-de-arriba-llegan-al-gran-teatro-del-cibao","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2023\/06\/27\/los-vecinos-de-arriba-llegan-al-gran-teatro-del-cibao\/","title":{"rendered":"\u201cLos vecinos de arriba\u201d llegan al Gran Teatro del Cibao"},"content":{"rendered":"\n<p>En su quinta temporada de presentaci\u00f3n, la afamada comedia de Cesc Gay \u201cLos vecinos de arriba\u201d, llegar\u00e1 a Santiago de los Caballeros, por primera vez en la sala de la Restauraci\u00f3n del Gran Teatro del Cibao.<\/p>\n\n\n\n<p>La \u201cCiudad Coraz\u00f3n\u201d recibir\u00e1 la comedia los d\u00edas jueves 10 y viernes 11 de agosto, como un regalo de risas y carcajadas para todo el Cibao.<\/p>\n\n\n\n<p>Pamela Sued, Nashla Bogaert, Jos\u00e9 Guillermo Cortines y Luis Jos\u00e9 Germ\u00e1n interpretan las distintas y complejas personalidades de esta divertida puesta en escena.<\/p>\n\n\n\n<p>Todo transcurre dentro del marco de una p\u00edcara e interesante trama, con di\u00e1logos inteligentes, sarc\u00e1sticos y llenos de gracia que logran dejar al espectador con mucho que pensar y sobre todo con una sonrisa en sus rostros.<\/p>\n\n\n\n<p>Con esta pieza teatral, la compa\u00f1\u00eda de teatro Nin\u00ed Germ\u00e1n a cargo de Luly Rocha y Luis Jos\u00e9 Germ\u00e1n, abren el tel\u00f3n de Santiago y el Cibao, garantizando una puesta en escena de calidad, como siempre han caracterizado sus producciones.<\/p>\n\n\n\n<p>\u201cSe trata de una pareja de esposos quienes reciben la visita de sus vecinos del piso de arriba para una cena y compartir por primera vez juntos. La personalidad de esta pareja y su filosof\u00eda de vida chocan constantemente con el estilo de vida de los due\u00f1os de la casa, llevando a desencadenar muchos sentimientos reprimidos y dejando al espectador bastante que pensar sobre el comportamiento humano y de pareja\u201d, explicaron los productores.<\/p>\n\n\n\n<p>Las boletas para las funciones de Santiago, los d\u00edas 10 y 11 de agosto, se encuentran disponibles en Uepa Tickets, Supermercados Nacional y Jumbo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su quinta temporada de presentaci\u00f3n, la afamada comedia de Cesc Gay \u201cLos vecinos de arriba\u201d, llegar\u00e1 a Santiago de los Caballeros, por primera vez en la sala de la&hellip;<\/p>\n","protected":false},"author":2,"featured_media":53527,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[4003],"class_list":["post-53526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-los-vecinos-de-arriba"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/06\/Los-actores-Jose-Guillermo-Cortines-Nashla-Bogaert-Luis-Jose-German-y-Pamela-Sued.jpg","jetpack-related-posts":[{"id":57384,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/08\/11\/festival-internacional-de-teatro-2023-pondra-en-escena-35-producciones-colombia-sera-pais-invitado-de-honor\/","url_meta":{"origin":53526,"position":0},"title":"Festival Internacional de Teatro 2023 pondr\u00e1 en escena 35 producciones; Colombia ser\u00e1 pa\u00eds invitado de honor","author":"Nelson Feliz","date":"11 de agosto de 2023","format":false,"excerpt":"El XI FITE RD 2023 est\u00e1 dedicado a la reconocida actriz dominicana Karina Noble y, a nivel internacional, al actor y director teatral Mario Ernesto S\u00e1nchez. Un total de 35 producciones teatrales, que incluyen 18 procedentes de ocho pa\u00edses, as\u00ed como 17 obras que ser\u00e1n presentadas por grupos de la\u2026","rel":"","context":"En \u00abENTRETENIMIENTO\u00bb","block_context":{"text":"ENTRETENIMIENTO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/entretenimiento\/"},"img":{"alt_text":"Este encuentro con la prensa lo encabez\u00f3 la ministra de Cultura, Milagros Germ\u00e1n, quien estuvo acompa\u00f1ada de otras autoridades","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Este-encuentro-con-la-prensa-lo-encabezo-la-ministra-de-Cultura-Milagros-German-quien-estuvo-acompanada-de-otras-autoridades.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Este-encuentro-con-la-prensa-lo-encabezo-la-ministra-de-Cultura-Milagros-German-quien-estuvo-acompanada-de-otras-autoridades.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Este-encuentro-con-la-prensa-lo-encabezo-la-ministra-de-Cultura-Milagros-German-quien-estuvo-acompanada-de-otras-autoridades.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Este-encuentro-con-la-prensa-lo-encabezo-la-ministra-de-Cultura-Milagros-German-quien-estuvo-acompanada-de-otras-autoridades.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":68228,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/11\/22\/mariposas-de-acero-regresa-al-gran-teatro-del-cibao\/","url_meta":{"origin":53526,"position":1},"title":"\u201cMariposas de Acero\u201d regresa al Gran Teatro del Cibao","author":"BIMARY DE JES\u00daS Matos","date":"22 de noviembre de 2023","format":false,"excerpt":"SANTIAGO DE LOS CABALLEROS.- \u201cMariposas de Acero\u201d, el espect\u00e1culo emocionante y conmovedor que narra la vida de nuestras hero\u00ednas nacionales, las Hermanas Mirabal, se presentar\u00e1 nueva vez en el Gran Teatro del Cibao el pr\u00f3ximo s\u00e1bado 25 de noviembre, para conmemorar el \u201cD\u00eda Internacional de la Eliminaci\u00f3n de la Violencia\u2026","rel":"","context":"En \u00abENTRETENIMIENTO\u00bb","block_context":{"text":"ENTRETENIMIENTO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/entretenimiento\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Noticias-de-energia-18.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":110839,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/10\/01\/rtvd-lamenta-muerte-de-la-primerisima-actriz-josefina-gallart\/","url_meta":{"origin":53526,"position":2},"title":"RTVD lamenta muerte de la primer\u00edsima actriz Josefina Gallart","author":"Nelson Feliz","date":"1 de octubre de 2025","format":false,"excerpt":"Radio Televisi\u00f3n Dominicana (RTVD) lament\u00f3 la muerte de la primer\u00edsima actriz dominicana Josefina Gallart, quien forj\u00f3 una trayectoria impecable en el arte, interpretando de manera magistral tanto obras de drama como de comedia. \u201cNos unimos al dolor de la familia de Josefina Gallart, un orgullo dominicano del arte, especialmente un\u2026","rel":"","context":"En \u00abENTRETENIMIENTO\u00bb","block_context":{"text":"ENTRETENIMIENTO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/entretenimiento\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/JOSEFINA-GALLART-Y-LUIS-JOSE-GERMAN.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/JOSEFINA-GALLART-Y-LUIS-JOSE-GERMAN.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/JOSEFINA-GALLART-Y-LUIS-JOSE-GERMAN.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/JOSEFINA-GALLART-Y-LUIS-JOSE-GERMAN.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/JOSEFINA-GALLART-Y-LUIS-JOSE-GERMAN.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":60324,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/13\/maridalia-hernandez-jose-alberto-el-canario-y-wilfrido-vargas-estaran-en-concierto-agradecido-de-eddy-herrera\/","url_meta":{"origin":53526,"position":3},"title":"Maridalia Hern\u00e1ndez, Jos\u00e9 Alberto &#8220;El Canario&#8221; y Wilfrido Vargas estar\u00e1n en concierto \u201cAgradecido\u201d de Eddy Herrera","author":"Nelson Feliz","date":"13 de septiembre de 2023","format":false,"excerpt":"Bajo la producci\u00f3n de Edilenia Tactuk se presentar\u00e1 \u201cEl gal\u00e1n del merengue\u201d, el pr\u00f3ximo s\u00e1bado 23 de septiembre en El Gran Teatro del Cibao Emocionado y feliz, as\u00ed anunci\u00f3 Eddy Herrera a Maridalia Hern\u00e1ndez, Jos\u00e9 Alberto \"El Canario\" y Wilfrido Vargas, parte de los destacados artistas que lo acompa\u00f1ar\u00e1n el\u2026","rel":"","context":"En \u00abENTRETENIMIENTO\u00bb","block_context":{"text":"ENTRETENIMIENTO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/entretenimiento\/"},"img":{"alt_text":"Eddy Herrera","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Eddy-Herrera-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Eddy-Herrera-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Eddy-Herrera-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Eddy-Herrera-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":128823,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/04\/27\/mas-de-10-mil-estudiantes-viven-experiencia-del-simulador-de-vuelo-en-la-feria-regional-del-libro-y-la-cultura-del-cibao-2026\/","url_meta":{"origin":53526,"position":4},"title":"M\u00e1s de 10 mil estudiantes viven experiencia del simulador de vuelo","author":"Nelson Feliz","date":"27 de abril de 2026","format":false,"excerpt":"Un importante n\u00famero de participantes mostr\u00f3 inter\u00e9s en convertirse en pilotos aviadores en el futuro M\u00e1s de 10 mil estudiantes se dieron cita en el stand del Instituto Dominicano de Aviaci\u00f3n Civil (IDAC) para vivir la experiencia del simulador de vuelo de la Academia Superior de Ciencias Aeron\u00e1uticas (ASCA), donde\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260427-WA0160.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260427-WA0160.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260427-WA0160.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260427-WA0160.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260427-WA0160.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260427-WA0160.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":128153,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/04\/20\/idac-instala-simulador-de-vuelo-en-primera-feria-regional-del-libro-y-la-cultura-cibao-2026\/","url_meta":{"origin":53526,"position":5},"title":"IDAC instala Simulador de Vuelo en Primera Feria Regional del Libro y la Cultura Cibao 2026","author":"Nelson Feliz","date":"20 de abril de 2026","format":false,"excerpt":"Acercar la aviaci\u00f3n a la gente y despertar nuevas vocaciones es parte de la apuesta educativa de la instituci\u00f3n Santiago de los Caballero.\u2013 El Instituto Dominicano de Aviaci\u00f3n Civil (IDAC) y su \u00f3rgano de estudios especializados, la Academia Superior de Ciencias Aeron\u00e1uticas (ASCA), se suman a las instituciones educativas que\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260420-WA0285-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260420-WA0285-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260420-WA0285-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260420-WA0285-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260420-WA0285-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/IMG-20260420-WA0285-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/53526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=53526"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/53526\/revisions"}],"predecessor-version":[{"id":53528,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/53526\/revisions\/53528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/53527"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=53526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=53526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=53526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}