{"id":56440,"date":"2023-08-01T07:42:58","date_gmt":"2023-08-01T11:42:58","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=56440"},"modified":"2023-08-01T07:42:59","modified_gmt":"2023-08-01T11:42:59","slug":"el-pacto-inapa-mekorot-una-amenaza-a-nuestra-soberania-hidrica-y-derechos-fundamentales","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2023\/08\/01\/el-pacto-inapa-mekorot-una-amenaza-a-nuestra-soberania-hidrica-y-derechos-fundamentales\/","title":{"rendered":"El Pacto INAPA-Mekorot: Una Amenaza a Nuestra Soberan\u00eda H\u00eddrica y Derechos Fundamentales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por Felipe Lora Longo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los \u00faltimos d\u00edas, un asunto de gran trascendencia ha despertado preocupaci\u00f3n y controversia en la Rep\u00fablica Dominicana. Se trata del sorprendente \u201cpalo asechao\u201d que representa el convenio firmado entre el Instituto Nacional de Aguas Potables y Alcantarillados (INAPA) y la empresa estatal israel\u00ed Mekorot para la gesti\u00f3n del agua en nuestro pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, lo que con mucha fanfarria, aplausos y las sonrisas, debi\u00f3 vendernos la idea de que se trataba de una medida tendiente a \u201cfortalecer nuestra capacidad de manejo h\u00eddrico\u201d, se ha convertido, gracias a la Red Socioambiental Nacional, en una amenaza directa a nuestra soberan\u00eda y derechos fundamentales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Haciendo uso de la ley General de Libre Acceso a la Informaci\u00f3n P\u00fablica, la Red Socioambiental, una coalici\u00f3n de organizaciones y ciudadanos comprometidos con la protecci\u00f3n del medio ambiente y la justicia social, logr\u00f3 conseguir una copia del contrato INAPA-Mekorot donde encontraron diversas violaciones que ponen en riesgo nuestra soberan\u00eda h\u00eddrica y la gesti\u00f3n responsable de uno de nuestros recursos naturales m\u00e1s valiosos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el pacto, la falta de transparencia es evidente. A pesar de que se trata de un tema de vital importancia para el pa\u00eds, el convenio fue firmado sin la debida divulgaci\u00f3n de su contenido. La sociedad dominicana merece conocer los detalles de un acuerdo que afectar\u00e1 directamente nuestra vida cotidiana y el futuro de nuestra naci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra cuesti\u00f3n alarmante es la experiencia y tecnolog\u00eda de Mekorot en el manejo del agua, que no se ajustan a las condiciones ecol\u00f3gicas y acu\u00edferas de la Rep\u00fablica Dominicana.<br>Israel es un pa\u00eds con una realidad geogr\u00e1fica y clim\u00e1tica muy distinta a la nuestra, y las soluciones aplicadas en su territorio podr\u00edan no ser adecuadas para enfrentar los retos h\u00eddricos que enfrentamos en nuestro entorno tropical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero quiz\u00e1s lo m\u00e1s preocupante son las acusaciones y denuncias contra Mekorot por su papel en la ocupaci\u00f3n ilegal de territorios palestinos y la apropiaci\u00f3n indebida de recursos h\u00eddricos en esa regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa ha sido se\u00f1alada por organizaciones internacionales de derechos humanos, como Amnist\u00eda Internacional, por su complicidad en violaciones a los derechos fundamentales de la poblaci\u00f3n palestina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la falta de consulta y participaci\u00f3n ciudadana en la toma de decisiones es un grave error que atenta contra la democracia y el derecho del pueblo a ser escuchado en asuntos de relevancia nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gesti\u00f3n del agua es un tema que nos afecta a todos, y debemos tener voz en el proceso de definici\u00f3n de pol\u00edticas y estrategias para su manejo responsable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es imperativo que las autoridades competentes revisen a fondo este pacto y tomen en cuenta las denuncias y preocupaciones expresadas por la sociedad civil. Debemos priorizar la protecci\u00f3n de nuestra soberan\u00eda h\u00eddrica y garantizar que el agua sea manejada por dominicanos, para dominicanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es momento de detener esta alianza cuestionable y buscar soluciones internas que se ajusten a nuestras necesidades y realidades. Contamos con profesionales calificados y expertos en el manejo del agua que pueden desarrollar estrategias sostenibles y adaptadas a nuestro entorno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El agua es un recurso vital, es el bien com\u00fan de todos los dominicanos, y su gesti\u00f3n debe ser un asunto de inter\u00e9s nacional. No permitamos que intereses for\u00e1neos pongan en peligro nuestra soberan\u00eda h\u00eddrica y derechos fundamentales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hacemos un llamado a la sociedad dominicana a mantenerse informada y unida en esta lucha por la protecci\u00f3n de nuestro recurso m\u00e1s preciado. Exijamos a nuestras autoridades que escuchen nuestra voz y tomen las medidas necesarias para anular este pacto. Nuestro futuro y el de las generaciones venideras dependen de ello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es hora de defender nuestra soberan\u00eda h\u00eddrica y nuestros derechos fundamentales. No permitamos que el agua dominicana est\u00e9 en manos de intereses ajenos. Un\u00e1monos en esta causa y trabajemos juntos por un manejo responsable y sustentable de nuestro recurso m\u00e1s valioso. \u00a1El agua es nuestro tesoro nacional, defend\u00e1mosla lo que es!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Felipe Lora Longo En los \u00faltimos d\u00edas, un asunto de gran trascendencia ha despertado preocupaci\u00f3n y controversia en la Rep\u00fablica Dominicana. Se trata del sorprendente \u201cpalo asechao\u201d que representa&hellip;<\/p>\n","protected":false},"author":2,"featured_media":53225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[95],"tags":[434,5652,5650,5651],"class_list":["post-56440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","tag-amenaza","tag-derechos-fundamentales","tag-el-pacto-inapa-mekorot","tag-soberania-hidrica"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/06\/Felipe-Lora-Longo.jpg","jetpack-related-posts":[{"id":53431,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/06\/26\/gobierno-dominicano-firma-acuerdo-con-israel-para-plan-maestro-de-gestion-del-agua\/","url_meta":{"origin":56440,"position":0},"title":"Gobierno dominicano firma acuerdo con Israel para Plan Maestro de Gesti\u00f3n del Agua","author":"Nelson Feliz","date":"26 de junio de 2023","format":false,"excerpt":"El presidente Luis Abinader encabez\u00f3 este lunes la firma de un acuerdo para la elaboraci\u00f3n de un Plan Maestro de Gesti\u00f3n del Agua en la Rep\u00fablica Dominicana, que permitir\u00e1 gestionar este recurso desde el Estado de manera eficiente y eficaz, creando las condiciones de sostenibilidad a largo plazo. El acuerdo\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/06\/Presidencia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/06\/Presidencia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/06\/Presidencia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/06\/Presidencia.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":53571,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/06\/28\/director-coraasan-pondera-importancia-de-acuerdo-entre-rd-e-israel-sobre-gestion-del-agua\/","url_meta":{"origin":56440,"position":1},"title":"Director Coraasan pondera importancia de acuerdo entre RD e Israel sobre gesti\u00f3n del agua","author":"Nelson Feliz","date":"28 de junio de 2023","format":false,"excerpt":"Por Roberto P\u00e9rez El director de la Corporaci\u00f3n del Acueducto y Alcantarillado de Santiago (Coraasan), Andr\u00e9s Burgos, ponder\u00f3 la relevancia del \"Plan Maestro de Gesti\u00f3n del Agua en la Rep\u00fablica Dominicana\", acuerdo suscrito con el gobierno de Israel, que permitir\u00e1 gestionar este recurso desde el Estado de manera eficiente y\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Andr\u00e9s Burgos","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/06\/Andres-Burgos.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":77964,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/02\/27\/gobierno-apuesta-a-enfrentar-inversion-publica-en-agua\/","url_meta":{"origin":56440,"position":2},"title":"Gobierno apuesta a enfrentar inversi\u00f3n p\u00fablica en agua","author":"Nelson Feliz","date":"27 de febrero de 2024","format":false,"excerpt":"Ante evidencias de que la Rep\u00fablica Dominicana enfrenta un creciente estr\u00e9s h\u00eddrico en su territorio, el gobierno dominicano ha apostado por la inversi\u00f3n p\u00fablica en agua, tanto en infraestructura h\u00eddrica como en sistemas de agua potable y saneamiento. As\u00ed lo indic\u00f3 el presidente Luis Abinader durante su discurso de rendici\u00f3n\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"CAASD","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/CAASD.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/CAASD.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/CAASD.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/CAASD.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":132597,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/06\/04\/presidente-abinader-impulsa-transformacion-del-sector-agua\/","url_meta":{"origin":56440,"position":3},"title":"Presidente Abinader impulsa transformaci\u00f3n del sector agua","author":"Nelson Feliz","date":"4 de junio de 2026","format":false,"excerpt":"Punta Cana, La Altagracia.\u2013 El presidente Luis Abinader afirm\u00f3 este mi\u00e9rcoles que el saneamiento urbano debe ser considerado una prioridad estrat\u00e9gica para los pa\u00edses de Am\u00e9rica Latina y el Caribe, al advertir que no puede seguir siendo visto como un tema secundario ni exclusivamente t\u00e9cnico, debido a su impacto directo\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/saneamiento-urbano-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/saneamiento-urbano-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/saneamiento-urbano-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/saneamiento-urbano-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":110436,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/09\/28\/cuatro-acueductos-dan-el-primer-paso-hacia-la-resiliencia-hidrica-en-san-pedro-de-macoris-y-hato-mayor\/","url_meta":{"origin":56440,"position":4},"title":"Cuatro acueductos dan el primer paso hacia la resiliencia h\u00eddrica en San Pedro de Macor\u00eds y Hato Mayor","author":"Nelson Feliz","date":"28 de septiembre de 2025","format":false,"excerpt":"Proyecto regional liderado por PNUD aplica el \u00cdndice de Acueductos Seguros (IAS) y alista plan de mejoras funcionales. En el marco de la iniciativa \u201cFortalecimiento de Capacidades, Seguridad y Resiliencia de Infraestructuras Cr\u00edticas en Rep\u00fablica Dominicana, Cuba y Hait\u00ed\u201d, se realizaron levantamientos t\u00e9cnicos en cuatro sistemas de agua priorizados \u2014El\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/acueductos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/acueductos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/acueductos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/acueductos.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":103655,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/17\/dida-y-el-inap-formaran-servidores-publicos-en-seguridad-social\/","url_meta":{"origin":56440,"position":5},"title":"DIDA y el INAP formaran servidores p\u00fablicos en seguridad social","author":"Nelson Feliz","date":"17 de julio de 2025","format":false,"excerpt":"La Direcci\u00f3n General de Informaci\u00f3n y Defensa de los Afiliados a la Seguridad Social (DIDA) y el Instituto Nacional de Administraci\u00f3n P\u00fablica (INAP) firmaron un acuerdo de colaboraci\u00f3n interinstitucional que tiene como objetivo fundamental fortalecer la formaci\u00f3n de los servidores p\u00fablicos en materia de seguridad social. El acuerdo fue rubricado\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/dida-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/dida-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/dida-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/dida-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/56440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=56440"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/56440\/revisions"}],"predecessor-version":[{"id":56441,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/56440\/revisions\/56441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/53225"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=56440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=56440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=56440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}