{"id":61590,"date":"2023-09-28T13:17:08","date_gmt":"2023-09-28T17:17:08","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=61590"},"modified":"2023-09-28T13:17:09","modified_gmt":"2023-09-28T17:17:09","slug":"pelegrin-castillo-ve-canal-masacre-es-pretexto-para-unificar-fuerzas-en-haiti-contra-rd","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/28\/pelegrin-castillo-ve-canal-masacre-es-pretexto-para-unificar-fuerzas-en-haiti-contra-rd\/","title":{"rendered":"Pelegr\u00edn Castillo ve canal Masacre es pretexto para unificar fuerzas en Hait\u00ed contra RD"},"content":{"rendered":"\n<p>El vicepresidente del partido Fuerza Nacional Progresista (FNP) Pelegr\u00edn Castillo, ve el tema del canal en el r\u00edo Masacre es un pretexto para unificar fuerzas en Hait\u00ed contra la Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p>\u201cNo nos confundamos, son muy tontos los que creen que este es un tema de un canal, esto es una provocaci\u00f3n internacional montada deliberadamente por una serie de figuras que quieren derribar al primer pinistro de Hait\u00ed, Ariel Henry, y tensar las contradicciones en la Rep\u00fablica Dominicana\u201d, expres\u00f3 Castillo.<\/p>\n\n\n\n<p><strong>SOLUCION DOOMINICANA AL PROBLEMA HAITIANO<\/strong><\/p>\n\n\n\n<p>El dirigente pol\u00edtico, explic\u00f3 que con una crisis, ellos pueden viabilizar m\u00e1s f\u00e1cilmente la soluci\u00f3n dominicana al problema haitiano, precedida con una intervenci\u00f3n humanitaria.<\/p>\n\n\n\n<p>\u00abEn eso coinciden todos los sectores haitianos con unas cuantas excepciones, y tienen que preparar el escenario para eso\u00bb, asegur\u00f3 Castillo en el programa Toque Final con Julio Mart\u00ednez Pozo, que se transmite por Antena 7.<\/p>\n\n\n\n<p>Castillo, dijo que \u00ablos dominicanos deben de estar conscientes de esa situaci\u00f3n, porque hay fuerzas internacionales que est\u00e1n apostando a un escenario de conflicto para favorecer la intervenci\u00f3n internacional en la isla de Santo Domingo y as\u00ed imponer la soluci\u00f3n dominicana a los problemas haitianos\u00bb.<\/p>\n\n\n\n<p><strong>PARTE DEL PROBLEMA VIENE DE EU<\/strong><\/p>\n\n\n\n<p>El vicepresidente de la FNP, revel\u00f3 que \u00abparte del problema que est\u00e1 planteado en Hait\u00ed viene de Estados Unidos. Es ah\u00ed donde hay un sector interesado en alimentar el conflicto, porque ha estado durante muchos a\u00f1os enviando armas y formando grupos\u00bb.<\/p>\n\n\n\n<p>Agreg\u00f3 que \u00abesa situaci\u00f3n est\u00e1 conectada con el hecho de que hay otros sectores apoyados por Cuba y Venezuela, as\u00ed como tambi\u00e9n, las potencias extracontinentales China, Rusia e Ir\u00e1n, interesados en que en la isla de Santo Domingo pueda estallar un escenario de conflicto\u00bb.<\/p>\n\n\n\n<p>\u201cEn Hait\u00ed virtualmente no hay Gobierno, hay una situaci\u00f3n desesperada que afecta a millones de haitianos, y todo el que ha seguido esto sabe que esa crisis est\u00e1 concebida para trasladarla a la parte occidental de la isla de Santo Domingo\u201d, subray\u00f3.<\/p>\n\n\n\n<p><strong>PIDE NO CONFIAR EN GRANDES POTENCIAS<\/strong><\/p>\n\n\n\n<p>Dijo que la poblaci\u00f3n dominicana no puede confiar en las posiciones de las grandes potencias porque, en el fondo, est\u00e1n luchando por la hegemon\u00eda mundial, y el Caribe vuelve a ser escenario de esa lucha de las grandes potencias\u00bb.<\/p>\n\n\n\n<p>Pelegr\u00edn Castillo, indic\u00f3 que \u00aben este caso hay inter\u00e9s de intervenir en Hait\u00ed por una coalici\u00f3n alentada por Estados Unidos y Canad\u00e1, y que, en caso de que se cree una guerra civil, forzar el traslado de poblaciones hacia la Rep\u00fablica Dominicana y tratar de forzar una intervenci\u00f3n humanitaria en la parte oriental de la isla\u00bb.<\/p>\n\n\n\n<p>\u201cSi el liderazgo pol\u00edtico del pa\u00eds sigue dando se\u00f1ales ambivalentes, d\u00e9biles, frente al problema y no presenta una posici\u00f3n unificada, el riesgo de que la Rep\u00fablica Dominicana pague las consecuencias de esa crisis que se ha incubado en Hait\u00ed y prolongado deliberadamente, lo que es un crimen internacional de alta inteligencia, vamos a pagar como naci\u00f3n un precio muy caro\u201d, advirti\u00f3.<\/p>\n\n\n\n<p><strong>EU TIENE QUE MEDIR SUS PASOS<\/strong><\/p>\n\n\n\n<p>Indic\u00f3 que Estados Unidos tiene que medir bien sus pasos porque Rep\u00fablica Dominicana es el pa\u00eds m\u00e1s estable de la regi\u00f3n y, si es desestabilizado, ser\u00e1 en la isla completa, toda la regi\u00f3n y, probablemente, el continente, porque va a dar inicio a un conflicto donde la responsabilidad de Estados Unidos va a estar en primer plano y tambi\u00e9n las otras potencias, que de manera irresponsable, est\u00e1n en su juego de poder\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El vicepresidente del partido Fuerza Nacional Progresista (FNP) Pelegr\u00edn Castillo, ve el tema del canal en el r\u00edo Masacre es un pretexto para unificar fuerzas en Hait\u00ed contra la Rep\u00fablica&hellip;<\/p>\n","protected":false},"author":2,"featured_media":61592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[7688,217,7975,7977,1226,7976],"class_list":["post-61590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada","tag-canal-masacre","tag-haiti","tag-pelegrin-castillo","tag-pretexto","tag-republica-dominicana","tag-unificar-fuerzas"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/pelegrin-castillo-ve-canal-masacre-es-pretexto-para-unificar-fuerzas-en-haiti-contra-rd.jpg","jetpack-related-posts":[{"id":82289,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/04\/30\/pelegrin-castillo-dice-debate-organizado-por-anje-fue-para-bajar-tensiones\/","url_meta":{"origin":61590,"position":0},"title":"Pelegr\u00edn Castillo dice Debate organizado por ANJE fue para bajar tensiones","author":"Nelson Feliz","date":"30 de abril de 2024","format":false,"excerpt":"El vicepresidente de la Fuerza Nacional Progresista (FNP), sostuvo que el empresariado busca bajar las tensiones pol\u00edticas generadas por la oposici\u00f3n con el debate de los candidatos presidenciales realizado por la Asociaci\u00f3n de J\u00f3venes Empresarios (ANJE), con el fin de legitimar el proceso electoral y los eventuales resultados. Pelegr\u00edn Castillo,\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/pelegrin-castillo-ve-canal-masacre-es-pretexto-para-unificar-fuerzas-en-haiti-contra-rd.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/pelegrin-castillo-ve-canal-masacre-es-pretexto-para-unificar-fuerzas-en-haiti-contra-rd.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/pelegrin-castillo-ve-canal-masacre-es-pretexto-para-unificar-fuerzas-en-haiti-contra-rd.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/pelegrin-castillo-ve-canal-masacre-es-pretexto-para-unificar-fuerzas-en-haiti-contra-rd.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":61985,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/02\/historiador-zorrilla-ozuna-ve-correcta-la-decision-de-cerrar-la-frontera-con-haiti\/","url_meta":{"origin":61590,"position":1},"title":"Historiador Zorrilla Ozuna ve correcta la decisi\u00f3n de cerrar la frontera con Hait\u00ed","author":"BIMARY DE JES\u00daS Matos","date":"2 de octubre de 2023","format":false,"excerpt":"Santo Domingo.- El historiador, pol\u00edtico, abogado y exmilitar Jorge Zorrilla Ozuna, calific\u00f3 de correcta la decisi\u00f3n del Gobierno dominicano de cerrar la frontera con Hait\u00ed, tras los haitianos construir un canal para desviar las aguas del r\u00edo masacre, violentando el tratado de 1929. \u201cA ning\u00fan mandatario dominicano le gustar\u00eda cerrar\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-09-28-at-11.50.30-PM-1-10.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-09-28-at-11.50.30-PM-1-10.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-09-28-at-11.50.30-PM-1-10.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-09-28-at-11.50.30-PM-1-10.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":63589,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/13\/oea-propone-vias-de-solucion-al-conflicto-rd-haiti\/","url_meta":{"origin":61590,"position":2},"title":"OEA propone v\u00edas de soluci\u00f3n al conflicto RD-Hait\u00ed","author":"Nelson Feliz","date":"13 de octubre de 2023","format":false,"excerpt":"Almagro solicita que el Caricom se integre a misi\u00f3n t\u00e9cnica para evaluar aspectos h\u00eddricos y legales del conflicto. El secretario general de la Organizaci\u00f3n de los Estados Americanos (OEA) propuso este jueves 12 de octubre una reuni\u00f3n entre las delegaciones de la Rep\u00fablica Dominicana y Hait\u00ed para fomentar las discusiones\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"oea","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/oea.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/oea.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/oea.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/oea.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":72743,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/01\/02\/vicepresidente-de-la-fnp-ve-estrategia-eu-denuncia-que-por-rd-pasan-armas-a-haiti\/","url_meta":{"origin":61590,"position":3},"title":"Vicepresidente de la FNP ve estrategia EU denuncia que por RD pasan armas a Hait\u00ed","author":"Nelson Feliz","date":"2 de enero de 2024","format":false,"excerpt":"El vicepresidente de la Fuerza Nacional Progresista (FNP), Pelegr\u00edn Castillo, sostuvo que la denuncia de senadores estadounidenses de que por Rep\u00fablica Dominicana ingresan armas a Hait\u00ed es parte de una estrategia. La maniobra de c\u00edrculos de poder de EE: UU consiste en escalar el conflicto en Hait\u00ed a una guerra\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/pelegrin-castillo-ve-canal-masacre-es-pretexto-para-unificar-fuerzas-en-haiti-contra-rd.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/pelegrin-castillo-ve-canal-masacre-es-pretexto-para-unificar-fuerzas-en-haiti-contra-rd.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/pelegrin-castillo-ve-canal-masacre-es-pretexto-para-unificar-fuerzas-en-haiti-contra-rd.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/pelegrin-castillo-ve-canal-masacre-es-pretexto-para-unificar-fuerzas-en-haiti-contra-rd.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":110204,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/09\/26\/temistocles-montas-en-haiti-se-debe-desarrollar-el-estado-porque-no-existe\/","url_meta":{"origin":61590,"position":4},"title":"Tem\u00edstocles Mont\u00e1s : En Hait\u00ed se debe desarrollar el Estado, porque no existe","author":"Nelson Feliz","date":"26 de septiembre de 2025","format":false,"excerpt":"Mont\u00e1s explica que luego del Di\u00e1logo sobre la Crisis Haitiana y su Implicaci\u00f3n en Rep\u00fablica Dominicana, coordinado por el CES, lo importante es que se cumpla lo acordado El Partido de la Liberaci\u00f3n Dominicana asumi\u00f3 el compromiso respecto al tema haitiano en el marco del Di\u00e1logo impulsado por el Consejo\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Temistocles-Montas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Temistocles-Montas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Temistocles-Montas.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Temistocles-Montas.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":60485,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/14\/estos-son-los-haitianos-que-financian-el-canal-en-el-rio-masacre-segun-el-gobierno\/","url_meta":{"origin":61590,"position":5},"title":"Estos son los haitianos que &#8220;financian&#8221; el canal en el r\u00edo Masacre, seg\u00fan el Gobierno","author":"Nelson Feliz","date":"14 de septiembre de 2023","format":false,"excerpt":"El Gobierno dominicano dio a conocer los perfiles de las personalidades haitianas que, afirma, est\u00e1n financiando y respaldando la construcci\u00f3n informal del canal en Juana M\u00e9ndez para desviar el r\u00edo Masacre. El presidente Luis Abinader prohibi\u00f3 la entrada al pa\u00eds de estos nueve ciudadanos haitianos, al entender que pueden implicar\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Haitanos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Haitanos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Haitanos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Haitanos.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/61590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=61590"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/61590\/revisions"}],"predecessor-version":[{"id":61591,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/61590\/revisions\/61591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/61592"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=61590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=61590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=61590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}