{"id":62176,"date":"2023-10-03T13:12:26","date_gmt":"2023-10-03T17:12:26","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=62176"},"modified":"2023-10-03T13:13:00","modified_gmt":"2023-10-03T17:13:00","slug":"philippe-arroja-intensas-lluvias-sobre-algunas-zonas-de-las-antillas-menores","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/03\/philippe-arroja-intensas-lluvias-sobre-algunas-zonas-de-las-antillas-menores\/","title":{"rendered":"Philippe arroja intensas lluvias sobre algunas zonas de las Antillas Menores"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Los meteor\u00f3logos del NHC advirtieron de que los vientos m\u00e1s fuertes y precipitaciones se dejar\u00e1n sentir en las islas del sur de ese archipi\u00e9lago.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tormenta tropical Philippe prosigue este martes arrojando intensas lluvias, con potencial de producir inundaciones, en las islas de Sotavento y sectores de las de Barlovento, inform\u00f3 el Centro Nacional de Huracanes (NHC, en ingl\u00e9s) de EE.UU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El NHC indic\u00f3 que a las 12:00 GMT, el centro de Philippe se ubicaba a 55 millas (90 km) al este de Anegada, en las Islas V\u00edrgenes Brit\u00e1nicas, y presenta vientos m\u00e1ximos sostenidos de 50 millas por hora (85 km\/h).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se desplaza en direcci\u00f3n noroeste con una velocidad de 10 millas por hora (17 km\/h) y, seg\u00fan un probable patr\u00f3n de trayectoria, el centro del sistema pasar\u00e1 al norte de las Islas de Sotavento hoy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los meteor\u00f3logos del NHC advirtieron de que los vientos m\u00e1s fuertes y precipitaciones se dejar\u00e1n sentir en las islas del sur de ese archipi\u00e9lago, y que el centro de Philippe girar\u00e1 hacia el nornoroeste esta noche y el mi\u00e9rcoles hacia el norte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a esa trayectoria en los pr\u00f3ximos d\u00edas, se prev\u00e9 que Philippe se acerque a las Bermudas hacia el fin de semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antigua y Barbuda, donde se pueden producir hasta 8 pulgadas (200 mililitros) de lluvias, se hallan bajo aviso de tormenta tropical, mientras que se ha emitido una alerta para las Islas V\u00edrgenes Brit\u00e1nicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Philippe puede generar lluvias de hasta 5 pulgadas (127 mililitros) para el resto de las Islas de Sotavento y el norte de las Islas de Barlovento, lo que podr\u00eda ocasionar inundaciones aisladas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El oleaje del sistema afectar\u00e1 a partes de las costas atl\u00e1nticas del norte de las Islas de Sotavento, las Islas V\u00edrgenes y Puerto Rico hasta mitad de la semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una actualizaci\u00f3n difundida el pasado agosto, la Administraci\u00f3n Nacional de Oc\u00e9anos y Atm\u00f3sfera (NOAA, en ingl\u00e9s) de EE.UU. vaticin\u00f3 una temporada de huracanes en el Atl\u00e1ntico &#8220;por encima de lo normal&#8221;, con la formaci\u00f3n de entre 14 y 21 tormentas tropicales, de las cuales entre 6 y 11 ser\u00edan huracanes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la actual temporada, que concluye el pr\u00f3ximo 30 de noviembre, se han formado 17 tormentas tropicales y 6 huracanes, y uno de ellos, Lee, alcanz\u00f3 la categor\u00eda 5, la m\u00e1xima en la escala de intensidad Saffir-Simpson.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente Agencia EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los meteor\u00f3logos del NHC advirtieron de que los vientos m\u00e1s fuertes y precipitaciones se dejar\u00e1n sentir en las islas del sur de ese archipi\u00e9lago. La tormenta tropical Philippe prosigue este&hellip;<\/p>\n","protected":false},"author":2,"featured_media":62178,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[3831,8159,206,8017],"class_list":["post-62176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-antillas-menores","tag-centro-nacional-de-huracanes","tag-ee-uu","tag-philippe"],"jetpack-related-posts":[{"id":61688,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/29\/philippe-y-rina-siguen-al-este-de-las-antillas-menores-todavia-no-son-un-riesgo-para-tierra\/","url_meta":{"origin":62176,"position":0},"title":"Philippe y Rina siguen al este de las Antillas Menores; todav\u00eda no son un riesgo para tierra","author":"Nelson Feliz","date":"29 de septiembre de 2023","format":false,"excerpt":"Rina se convertir\u00e1 en depresi\u00f3n el pr\u00f3ximo domingo y no ofrece peligro a territorio alguno, seg\u00fan el pron\u00f3stico del NHC. En la actual temporada de huracanes se han formado 6 fen\u00f3menos. La tormenta tropical Philippe se mantiene casi est\u00e1tica este viernes en aguas abiertas del Atl\u00e1ntico y al este de\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Tormentas-Rina-y-Philippe-NHC.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Tormentas-Rina-y-Philippe-NHC.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Tormentas-Rina-y-Philippe-NHC.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Tormentas-Rina-y-Philippe-NHC.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":62362,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/04\/la-tormenta-philippe-arroja-intensas-lluvias-en-las-islas-virgenes-y-podria-llegar-a-maine\/","url_meta":{"origin":62176,"position":1},"title":"La tormenta Philippe arroja intensas lluvias en las Islas V\u00edrgenes y podr\u00eda llegar a Maine","author":"BIMARY DE JES\u00daS Matos","date":"4 de octubre de 2023","format":false,"excerpt":"\u00a0MIAMI.- La tormenta Philippe contin\u00faa este mi\u00e9rcoles arrojando fuertes lluvias en las caribe\u00f1as Islas V\u00edrgenes Brit\u00e1nicas mientras se desplaza hacia las Bermudas, que se hallan bajo vigilancia por este cicl\u00f3n, y con posibilidad de llegar el fin de semana a Maine (EE.UU.), inform\u00f3 el Centro Nacional de Huracanes (NHC, en\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-7.55.08-AM-7.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-7.55.08-AM-7.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-7.55.08-AM-7.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-7.55.08-AM-7.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-7.55.08-AM-7.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":60212,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/11\/margot-se-convierte-en-huracan-y-lee-sigue-en-categoria-3\/","url_meta":{"origin":62176,"position":2},"title":"Margot se convierte en hurac\u00e1n y Lee sigue en categor\u00eda 3","author":"Nelson Feliz","date":"11 de septiembre de 2023","format":false,"excerpt":"Miami.- La tormenta tropical Margot se convirti\u00f3 en el quinto hurac\u00e1n de la actual temporada del Atl\u00e1ntico sin que por el momento afecte a territorio alguno, mientras Lee contin\u00faa con fuerza de hurac\u00e1n mayor al norte de las Islas de Sotavento y con rumbo al sur de Bermudas. De acuerdo\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/margot.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/margot.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/margot.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/margot.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":64310,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/19\/la-tormenta-tammy-se-fortalece-y-amenaza-con-fuertes-lluvias\/","url_meta":{"origin":62176,"position":3},"title":"La tormenta Tammy se fortalece y amenaza con fuertes lluvias","author":"Nelson Feliz","date":"19 de octubre de 2023","format":false,"excerpt":"MIAMI.- La tormenta tropical Tammy se fortalece y amenaza con fuertes lluvias en un plazo de dos d\u00edas a Barbados, Dominica, Martinica y Guadalupe, Antigua, Barbuda, Montserrat, St. Kitts y Nevis, inform\u00f3 el Centro Nacional de Huracanes (NHC, en ingl\u00e9s) de EEUU. Tammy, la tormenta n\u00famero 19 de la actual\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":64611,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/22\/el-huracan-tammy-se-aleja-del-caribe-sin-nuevas-amenazas-en-tierra\/","url_meta":{"origin":62176,"position":4},"title":"El hurac\u00e1n Tammy se aleja del Caribe sin nuevas amenazas en tierra","author":"Nelson Feliz","date":"22 de octubre de 2023","format":false,"excerpt":"Tammy presentaba vientos m\u00e1ximos sostenidos de 85 millas por hora (140 km) con r\u00e1fagas m\u00e1s fuertes y tendr\u00e1 cierto fortalecimiento seguido de fluctuaciones, seg\u00fan el \u00faltimo bolet\u00edn del NHC. El hurac\u00e1n Tammy se aleja de la Islas Sotavento del Norte y se dirige hacia el norte en el Atl\u00e1ntico sin\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"Trayectoria del hurac\u00e1n Tammy","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Trayectoria-del-huracan-Tammy.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Trayectoria-del-huracan-Tammy.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Trayectoria-del-huracan-Tammy.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":67623,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/11\/17\/se-forma-potencial-ciclon-tropical-veintidos-en-el-caribe-segun-el-nhc-de-ee-uu\/","url_meta":{"origin":62176,"position":5},"title":"Se forma potencial cicl\u00f3n tropical Veintid\u00f3s en el Caribe, seg\u00fan el NHC de EE.UU.","author":"Nelson Feliz","date":"17 de noviembre de 2023","format":false,"excerpt":"Por Sara Tonks (CNN) -- El potencial cicl\u00f3n tropical Veintid\u00f3s se form\u00f3 sobre el mar Caribe occidental, seg\u00fan la actualizaci\u00f3n de las 4 pm del Centro Nacional de Huracanes (NHC por sus siglas en ingl\u00e9s). El sistema de tormentas se encuentra a unas 365 millas (587 kil\u00f3metros) al oeste-suroeste de\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/SATALITE.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/SATALITE.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/SATALITE.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/SATALITE.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Tormenta-tropical-Philippe.jpeg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/62176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=62176"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/62176\/revisions"}],"predecessor-version":[{"id":62177,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/62176\/revisions\/62177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/62178"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=62176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=62176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=62176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}