{"id":63172,"date":"2023-10-10T21:43:54","date_gmt":"2023-10-11T01:43:54","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=63172"},"modified":"2023-10-10T21:43:55","modified_gmt":"2023-10-11T01:43:55","slug":"observatorio-de-medios-digitales-anuncia-premio-nacional-de-periodismo-digital-2023","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/10\/observatorio-de-medios-digitales-anuncia-premio-nacional-de-periodismo-digital-2023\/","title":{"rendered":"Observatorio de Medios Digitales anuncia Premio Nacional de Periodismo Digital 2023"},"content":{"rendered":"\n<p><strong>La ceremonia de entrega ser\u00e1 el martes 28 de noviembre, en el Centro Indotel de la Zona Colonial.<\/strong><\/p>\n\n\n\n<p>Con el respaldo del Banco Popular y el Consorcio Energ\u00e9tico Punta Cana-Macao, el Observatorio de Medios Digitales anunci\u00f3 la sexta versi\u00f3n del Premio Nacional de Periodismo Digital de la Rep\u00fablica Dominicana, iniciativa que reconoce la labor de periodistas, comunicadores y due\u00f1os de medios digitales que hacen de la red un espacio con contenido de calidad, aportando desde su ejercicio informaci\u00f3n oportuna y veraz, para garantizar el derecho a la informaci\u00f3n que tienen los ciudadanos y ciudadanas.<\/p>\n\n\n\n<p>As\u00ed lo inform\u00f3 la periodista Cristal Acevedo, fundadora del Observatorio, quien explic\u00f3 que la premiaci\u00f3n este a\u00f1o trae novedades y nuevas categor\u00edas, agreg\u00f3 que el dise\u00f1o de las estatuillas estar\u00e1 a cargo de Grabo Estilo.<\/p>\n\n\n\n<p>Explic\u00f3 que para esta versi\u00f3n del evento se incluyen las categor\u00edas mejor podcast, mejor contenido difundido en digital y mejor dise\u00f1o web, las tres para reconocer no solo la calidad de los contenidos difundidos, sino tambi\u00e9n los avances en materia de dise\u00f1o que han experimentado los medios digitales nacionales, en los \u00faltimos a\u00f1os.<\/p>\n\n\n\n<p>Acevedo, detall\u00f3 que para postular al premio, los interesados deben acceder a la p\u00e1gina observatoriodemediosdigitales.com, donde tienen disponible un formulario de inscripci\u00f3n, el cual estar\u00e1 disponible hasta el 30 de octubre, fecha l\u00edmite para enviar expediente con fines de evaluaci\u00f3n.<\/p>\n\n\n\n<p>La ceremonia de entrega del Premio ser\u00e1 el martes 28 de noviembre, a las 7:00 de la noche en el Centro Indotel de la Zona Colonial. Cualquier informaci\u00f3n sobre la premiaci\u00f3n puede ser obtenida en la p\u00e1gina oficial del Observatorio, o enviando un correo a: <a href=\"mailto:observatoriodemediosdigitales@gmail.com\">observatoriodemediosdigitales@gmail.com<\/a>.<\/p>\n\n\n\n<p>El Premio Nacional de Periodismo Digital es una iniciativa del Observatorio de Medios Digitales Dominicanos que busca reconocer y destacar la labor de los trabajadores de medios digitales de Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p><strong>Categor\u00eda a premiar<\/strong><\/p>\n\n\n\n<p>Las categor\u00edas vigentes para el Premio, este 2023, son: periodista digital del a\u00f1o, mejor peri\u00f3dico nativo digital, mejor reportaje en digital, mejor proyecto de innovaci\u00f3n en medios digitales, mejor programa de medios digitales y mejor versi\u00f3n digital de un medio impreso.<\/p>\n\n\n\n<p>Adem\u00e1s, mejor peri\u00f3dico digital de salud, mejor peri\u00f3dico digital de deportes, mejor peri\u00f3dico digital de espect\u00e1culos, mejor peri\u00f3dico digital de turismo, mejor peri\u00f3dico digital de sociales y mejor peri\u00f3dico digital de econom\u00eda.<\/p>\n\n\n\n<p>Ser\u00e1n reconocidas tambi\u00e9n, las categor\u00edas mejor peri\u00f3dico digital del Sur, mejor peri\u00f3dico digital del Cibao, mejor peri\u00f3dico digital del Este, mejor peri\u00f3dico digital de Santo Domingo Norte, mejor peri\u00f3dico digital de Santo Domingo Oeste, mejor peri\u00f3dico digital de Santo Domingo Este y mejor periodista en redes sociales. Otras categor\u00edas a ser premiadas son: mejor nuevo medio digital, mejor podcast, mejor contenido difundido en digital y mejor dise\u00f1o Web.<\/p>\n\n\n\n<p>Como cada a\u00f1o, el Observatorio de Medios Digitales Dominicanos otorgar\u00e1 el galard\u00f3n denominado &#8220;Gran Premio Nacional de Periodismo Digital&#8221;, el cual ser\u00e1 entregado a un periodista que cuente con amplia trayectoria en medios digitales.<\/p>\n\n\n\n<p><strong>Bases del premio<\/strong><\/p>\n\n\n\n<p>1. Podr\u00e1n participar en una o varias categor\u00edas del Premio Nacional de Periodismo Digital, los y las periodistas y trabajadores de medios digitales que hayan laborado para un medio digital por lo menos en el \u00faltimo a\u00f1o.<\/p>\n\n\n\n<p>2. En el caso de la categor\u00eda reportaje, podr\u00e1n participar los trabajos difundidos en medios digitales, autor\u00eda de una persona o de un equipo de trabajo de cualquier tema de inter\u00e9s,&nbsp; publicado entre el 1 de enero y el 30 de octubre de 2023.<\/p>\n\n\n\n<p>3. Los trabajos pueden ser presentados por los medios, editores o periodistas realizadores y deben ser enviados los links, como fecha l\u00edmite el d\u00eda 30 de octubre de 2023, a las 12:00 de la noche.<\/p>\n\n\n\n<p>4. El expediente enviado para ser evaluado debe contener: Rese\u00f1a hist\u00f3rica del medio digital y perfil profesional del periodista, nombre completo, tel\u00e9fono de contacto, direcci\u00f3n y edad, as\u00ed como cualquier otro dato que se desee incluir, adem\u00e1s de los solicitados.<\/p>\n\n\n\n<p>5. En el caso de la postulaci\u00f3n para ser nominado en una de las categor\u00edas que reconocer\u00e1 a los medios digitales, espec\u00edficamente, se debe enviar una rese\u00f1a del medio y una del periodista due\u00f1o\/fundador de \u00e9ste.<\/p>\n\n\n\n<p>6. Los criterios de evaluaci\u00f3n son: calidad del contenido, trayectoria, incidencia medi\u00e1tica y aplicaci\u00f3n de los recursos del periodismo digital en la estructuraci\u00f3n de la plataforma y contenido gestionados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ceremonia de entrega ser\u00e1 el martes 28 de noviembre, en el Centro Indotel de la Zona Colonial. Con el respaldo del Banco Popular y el Consorcio Energ\u00e9tico Punta Cana-Macao,&hellip;<\/p>\n","protected":false},"author":2,"featured_media":63173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84,25],"tags":[6006,172,6005,8417,1845],"class_list":["post-63172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-portada","tag-medios-digitales","tag-nacional","tag-observatorio","tag-periodismo-digital-2023","tag-premio"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/observatorio-1.jpg","jetpack-related-posts":[{"id":66865,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/11\/10\/observatorio-anuncia-nominados-a-premio-nacional-de-periodismo-digital-2023\/","url_meta":{"origin":63172,"position":0},"title":"Observatorio anuncia nominados a Premio Nacional de Periodismo Digital 2023","author":"Nelson Feliz","date":"10 de noviembre de 2023","format":false,"excerpt":"El Observatorio de Medios Digitales Dominicanos anunci\u00f3 este jueves los nominados al Premio Nacional de Periodismo Digital 2023, iniciativa respaldada por el Banco Popular y el Consorcio Energ\u00e9tico Punta Cana-Macao (CEPM). El anuncio lo hizo la periodista Cristal Acevedo, presidenta del Observatorio, quien inform\u00f3 que este a\u00f1o la ceremonia de\u2026","rel":"","context":"En \u00abENTRETENIMIENTO\u00bb","block_context":{"text":"ENTRETENIMIENTO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/entretenimiento\/"},"img":{"alt_text":"Observatorio de Medios Digitales Dominicanos","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Observatorio-de-Medios-Digitales-Dominicanos.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":90005,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/10\/12\/observatorio-de-medios-digitales-abre-convocatoria-a-premio-nacional-de-periodismo-digital-2024\/","url_meta":{"origin":63172,"position":1},"title":"Observatorio de Medios Digitales abre convocatoria a Premio Nacional de Periodismo Digital 2024","author":"Nelson Feliz","date":"12 de octubre de 2024","format":false,"excerpt":"El Observatorio de Medios Digitales Dominicanos anunci\u00f3 este jueves la s\u00e9ptima versi\u00f3n del Premio Nacional de Periodismo Digital de la Rep\u00fablica Dominicana, iniciativa que reconoce la labor de periodistas, comunicadores y due\u00f1os de medios digitales. El anuncio lo hizo la periodista y maestra, Cristal Acevedo, quien explic\u00f3 que el evento\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/OBSE.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/OBSE.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/OBSE.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/OBSE.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":69064,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/11\/29\/observatorio-de-medios-digitales-realiza-con-exito-premio-nacional-de-periodismo-digital-2023-en-el-teatro-nacional-2\/","url_meta":{"origin":63172,"position":2},"title":"Observatorio de Medios Digitales realiza con \u00e9xito \u201cPremio Nacional de Periodismo Digital 2023\u201d en el Teatro Nacional","author":"Nelson Feliz","date":"29 de noviembre de 2023","format":false,"excerpt":"El Observatorio de Medios Digitales Dominicanos realiz\u00f3 con \u00e9xito este martes la sexta entrega de la ceremonia del Premio Nacional de Periodismo Digital. El evento fue realizado en la sala A\u00edda Bonnelly del Teatro Nacional con la asistencia de cientos de comunicadores, periodistas y due\u00f1os de medios digitales de todo\u2026","rel":"","context":"En \u00abENTRETENIMIENTO\u00bb","block_context":{"text":"ENTRETENIMIENTO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/entretenimiento\/"},"img":{"alt_text":"Cristal Acevedo","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Cristal-Acevedo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Cristal-Acevedo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Cristal-Acevedo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Cristal-Acevedo.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":57144,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/08\/09\/observatorio-realizara-segundo-estudio-de-uso-de-medios-digitales-en-republica-dominicana\/","url_meta":{"origin":63172,"position":3},"title":"Observatorio realizar\u00e1 Segundo estudio de uso de Medios Digitales en Rep\u00fablica Dominicana","author":"Nelson Feliz","date":"9 de agosto de 2023","format":false,"excerpt":"El Observatorio de Medios Digitales Dominicanos inform\u00f3 este mi\u00e9rcoles que realizar\u00e1 la segunda investigaci\u00f3n cient\u00edfica sobre uso de medios digitales en Rep\u00fablica Dominicana. La informaci\u00f3n fue ofrecida por la presidenta del Observatorio de Medios Digitales Dominicanos, periodista Cristal Acevedo, quien explic\u00f3 que con el estudio buscan verificar c\u00f3mo utilizan los\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Observatorio de Medios Digitales","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Observatorio-de-Medios-Digitales.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Observatorio-de-Medios-Digitales.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Observatorio-de-Medios-Digitales.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":111662,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/10\/12\/observatorio-de-medios-digitales-abre-convocatoria-para-premio-nacional-de-periodismo-digital-2025\/","url_meta":{"origin":63172,"position":4},"title":"Observatorio de Medios Digitales abre convocatoria para Premio Nacional de Periodismo Digital 2025","author":"Nelson Feliz","date":"12 de octubre de 2025","format":false,"excerpt":"El Observatorio de Medios Digitales Dominicanos inform\u00f3 este martes que est\u00e1n abiertas las postulaciones y el proceso de evaluaci\u00f3n para el Premio Nacional de Periodismo Digital de la Rep\u00fablica Dominicana 2025, iniciativa auspiciada por el Banco Popular. As\u00ed lo inform\u00f3 la periodista y maestra, Cristal Acevedo, quien precis\u00f3 que las\u2026","rel":"","context":"En \u00abTECNOL\u00d3GIA\u00bb","block_context":{"text":"TECNOL\u00d3GIA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/tecnologia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-08-at-10.47.54-AM.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-08-at-10.47.54-AM.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-08-at-10.47.54-AM.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-08-at-10.47.54-AM.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-08-at-10.47.54-AM.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":51578,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/06\/01\/cristal-acevedo-anuncia-prorroga-para-trabajadores-de-periodicos-digitales\/","url_meta":{"origin":63172,"position":5},"title":"Cristal Acevedo anuncia pr\u00f3rroga para trabajadores de peri\u00f3dicos digitales","author":"prenxa100","date":"1 de junio de 2023","format":false,"excerpt":"Santo Domingo.-. El Observatorio de Medios Digitales Dominicanos anunci\u00f3 este jueves que habilit\u00f3 una pr\u00f3rroga para que los trabajadores de peri\u00f3dicos digitales del pa\u00eds tengan tiempo de inscribirse en la habilitaci\u00f3n ocupacional que ha organizado junto al Instituto de Formaci\u00f3n T\u00e9cnico Profesional (Infotep). La fundadora y presidenta del Observatorio de\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/63172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=63172"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/63172\/revisions"}],"predecessor-version":[{"id":63174,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/63172\/revisions\/63174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/63173"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=63172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=63172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=63172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}