{"id":66452,"date":"2023-11-07T07:34:59","date_gmt":"2023-11-07T11:34:59","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=66452"},"modified":"2023-11-07T08:09:04","modified_gmt":"2023-11-07T12:09:04","slug":"udc-llama-a-respetar-la-constitucion-para-mantener-el-proceso-de-institucionalidad-y-democracia","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2023\/11\/07\/udc-llama-a-respetar-la-constitucion-para-mantener-el-proceso-de-institucionalidad-y-democracia\/","title":{"rendered":"UDC llama a respetar la Constituci\u00f3n, para mantener el proceso de institucionalidad y democracia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente de la Uni\u00f3n Dem\u00f3crata Cristiana-UDC-, Luis Acosta Moreta, Luis \u201cEl Gallo\u201d, dijo hoy que el mejor homenaje que se le puede hacer a la Constituci\u00f3n dominicana es luchar por reivindicar nuestra soberan\u00eda y hacer frente al hambre y la exclusi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que en estos momentos que vive la Rep\u00fablica Dominicana hay peligros sobre nuestro territorio, queriendo poner en peligro por la soberan\u00eda, y solo la reciedumbre de los dominicanos, encabezados por el presidente Luis Abinader , mantendr\u00e1 al pa\u00eds de pie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asegur\u00f3 que los dominicanos seguir\u00e1n levantando los principios de lucha de los febreristas, que impulsaron el nacimiento de la Rep\u00fablica imponi\u00e9ndose a una groser\u00e1 intervenci\u00f3n militar de los haitianos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Junto al presidente Abinader est\u00e1 la posici\u00f3n firme, vertical y decidida de los militares dominicanos, que con su coraje y disciplina mantienen viva la llama del patriotismo en la lucha por la reivindicaci\u00f3n de nuestro territorio y nuestra soberan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque ahora hay nuevos tiempos, los haitianos est\u00e1n demostrando con sus provocaciones que no creen en la paz y el respeto entre los pueblos, y los dominicanos han sido muy pacientes soportando los chantajes y las afrentas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando se conmemora una nueva fecha de la proclamaci\u00f3n de la primera Constituci\u00f3n dominicana, el momento es propicio para hacer fe de que en este pa\u00eds se mantendr\u00e1 la libertad, la independencia y la soberan\u00eda, como la instauraron los independentistas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que la Constituci\u00f3n nadie la puede considerar ahora c\u00f3mo un simple pedazo de papel, porque es la Carta sustantiva del devenir de la vida p\u00fablica nacional, y todos los dominicanos deben estar sometidos a ella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resalt\u00f3 que el presidente Luis Abinader es un mandatario respetuoso de la Constituci\u00f3n y las leyes, que cada d\u00eda da demostraciones de que est\u00e1 trabajando por el desarrollo nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apuntt\u00f3 que una de las razones que tiene la UDC para llevar a Abinader como su candidato presidencial, es su firme posici\u00f3n en defensa de la soberan\u00eda y la institucionalidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adi\u00f3 que el presidente Abinader da el ejemplo cada d\u00eda de que la Constituci\u00f3n y las leyes dominicanas tienen que ser respetadas, por los gobernantes, y por todos los ciudadanos,. Como manda un estado de derechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al mismo tiempo, Luis \u201cEl Gallo\u201d, dijo que el poder institucional tiene que ser respaldado por una lucha para mejorar las condiciones de vida de la mayor\u00eda de dominicanos que viven en condici\u00f3n de m\u00e1xima pobreza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adi\u00f3 que demagogos han querido jugar con el hambre y la miseria de los dominicanos, pero hoy hay un presidente justo que trabaja a favor de los pobres, los excluidos, los m\u00e1s necesitados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Uni\u00f3n Dem\u00f3crata Cristiana-UDC-, Luis Acosta Moreta, Luis \u201cEl Gallo\u201d, dijo hoy que el mejor homenaje que se le puede hacer a la Constituci\u00f3n dominicana es luchar&hellip;<\/p>\n","protected":false},"author":2,"featured_media":66453,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[2234],"class_list":["post-66452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada","tag-udc"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/udc.jpg","jetpack-related-posts":[{"id":119963,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/01\/19\/luis-el-gallo-rechaza-de-forma-categorica-cualquier-sometimiento-a-la-cidh\/","url_meta":{"origin":66452,"position":0},"title":"Luis \u201cEl Gallo\u201d rechaza de forma categ\u00f3rica cualquier sometimiento a la CIDH","author":"Nelson Feliz","date":"19 de enero de 2026","format":false,"excerpt":"El presidente del Partido Uni\u00f3n Dem\u00f3crata Cristiana \u2013UDC-, Luis Acosta Moreta, Luis \u201cEl Gallo\u201d, lanz\u00f3 una en\u00e9rgica advertencia contra cualquier intento de someter nuevamente a la Rep\u00fablica Dominicana a la Corte Interamericana de Derechos Humanos (Corte IDH), al considerar que dicha pretensi\u00f3n constituye una agresi\u00f3n directa a la soberan\u00eda nacional,\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"Luis Acosta Moreta","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-25-at-9.01.49-AM.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-25-at-9.01.49-AM.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-25-at-9.01.49-AM.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-25-at-9.01.49-AM.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":113833,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/11\/06\/es-deber-de-los-dominicanos-respetar-la-constitucion-y-buscar-soluciones-mediante-el-consenso-dice-udc\/","url_meta":{"origin":66452,"position":1},"title":"&#8220;Es deber de los dominicanos respetar la Constituci\u00f3n y buscar soluciones mediante el consenso&#8221;, dice UDC","author":"Nelson Feliz","date":"6 de noviembre de 2025","format":false,"excerpt":"El presidente de la Uni\u00f3n Dem\u00f3crata Cristiana -UDC-, Luis Acosta Moreta, Luis \u201cEl Gallo\u201d, consider\u00f3 hoy que es un deber de cada dominicano respetar la Constituci\u00f3n y velar por el mantenimiento de la democracia y la institucionalidad nacional. Afirm\u00f3 que la democracia actual que tienen los dominicanos ha costado sangre\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"D\u00eda de la Constituci\u00f3n","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Dia-de-la-Constitucion.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Dia-de-la-Constitucion.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Dia-de-la-Constitucion.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":130465,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/13\/luis-el-gallo-exige-respeto-a-la-soberania-en-tratados-internacionales\/","url_meta":{"origin":66452,"position":2},"title":"Luis \u201cEl Gallo\u201d exige respeto a la soberan\u00eda en tratados internacionales","author":"Nelson Feliz","date":"13 de mayo de 2026","format":false,"excerpt":"El presidente de la Uni\u00f3n Dem\u00f3crata Cristiana -UDC- Luis Acosta Moreta, Luis \u201cEl Gallo\u201d, consider\u00f3 hoy que cualquier tratado internacional que firme el pa\u00eds, debe tener como punto central el respeto a la soberan\u00eda, la institucionalidad y la democracia nacional. Se\u00f1al\u00f3 que nunca mediante un tratado se debe poner en\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"Luis Acosta Moreta","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Luis-Acosta-Moreta.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Luis-Acosta-Moreta.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Luis-Acosta-Moreta.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Luis-Acosta-Moreta.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":100269,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/06\/02\/udc-insta-al-ces-a-priorizar-la-defensa-de-la-soberania-y-la-seguridad-nacional-en-sus-plenarias\/","url_meta":{"origin":66452,"position":3},"title":"UDC insta al CES a priorizar la defensa de la soberan\u00eda y la seguridad nacional en sus plenarias","author":"Nelson Feliz","date":"2 de junio de 2025","format":false,"excerpt":"El presidente de la Uni\u00f3n Dem\u00f3crata Cristiana (UDC), Luis Acosta Moreta, Luis \u201cEl Gallo\u201d, expres\u00f3 su respaldo al inicio del di\u00e1logo en el Consejo Econ\u00f3mico y Social (CES) y exhort\u00f3 a que, en las discusiones sobre la situaci\u00f3n haitiana, se anteponga la defensa de la patria. Acosta Moreta destac\u00f3 la\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"Luis Acosta Moreta","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-02-at-9.43.18-PM.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-02-at-9.43.18-PM.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-02-at-9.43.18-PM.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-02-at-9.43.18-PM.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":110091,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/09\/25\/udc-respalda-a-presidente-abinader-al-pedir-comunidad-internacional-acuda-en-auxilio-de-haiti\/","url_meta":{"origin":66452,"position":4},"title":"UDC respalda a presidente Abinader, al pedir comunidad internacional acuda en auxilio de Hait\u00ed","author":"Nelson Feliz","date":"25 de septiembre de 2025","format":false,"excerpt":"El presidente de la Uni\u00f3n Dem\u00f3crata Cristiana \u2013UDC-, Luis Acosta Moreta, Luis \u201cEl Gallo\u201d salud\u00f3 y apoy\u00f3 hoy los pronunciamientos hechos por el presidente Luis Abinader de que una fuerza multinacional es la que debe buscar la paz y la soluci\u00f3n de los problemas haitianos. Tambi\u00e9n se\u00f1al\u00f3 como trascendente la\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Luis-Abinader-3-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Luis-Abinader-3-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Luis-Abinader-3-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Luis-Abinader-3-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":120705,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/01\/27\/luis-el-gallo-dice-mejor-homenaje-a-duarte-es-luchar-por-una-republica-libre-e-independiente\/","url_meta":{"origin":66452,"position":5},"title":"Luis \u201cEl Gallo\u201d dice mejor homenaje a Duarte es luchar por una rep\u00fablica libre e independiente","author":"Nelson Feliz","date":"27 de enero de 2026","format":false,"excerpt":"El presidente de la Uni\u00f3n Dem\u00f3crata Cristiana \u2013UDC-, Luis Acosta Moreta, Luis \u201cEl Gallo\u201d, consider\u00f3 hoy que el mejor homenaje que se puede rendir a Juan Pablo Duarte es mantener la lucha por las libertades p\u00fablicas e institucionales y defender la soberan\u00eda y la territorialidad nacional. Afirmo que en este\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"Luis Acosta Moreta","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-25-at-9.01.49-AM.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-25-at-9.01.49-AM.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-25-at-9.01.49-AM.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-25-at-9.01.49-AM.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/66452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=66452"}],"version-history":[{"count":2,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/66452\/revisions"}],"predecessor-version":[{"id":66458,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/66452\/revisions\/66458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/66453"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=66452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=66452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=66452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}