{"id":68781,"date":"2023-11-27T19:30:42","date_gmt":"2023-11-27T23:30:42","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=68781"},"modified":"2023-11-27T19:30:44","modified_gmt":"2023-11-27T23:30:44","slug":"embajadora-sonia-guzman-participa-en-noche-internacional-en-academia-del-fbi-en-virginia-eeuu","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2023\/11\/27\/embajadora-sonia-guzman-participa-en-noche-internacional-en-academia-del-fbi-en-virginia-eeuu\/","title":{"rendered":"Embajadora Sonia Guzm\u00e1n participa en Noche Internacional en Academia del FBI en Virginia-EEUU"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">VIRGINIA, Estados Unidos. La embajadora dominicana en los Estados Unidos, Sonia Guzm\u00e1n, particip\u00f3 en la Noche Internacional realizada en el marco de la Sesi\u00f3n 288 de la Academia del Bur\u00f3 Federal de Investigaciones (FBI) en Quantico, Virginia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la noche internacional fueron exhibidas y compartidas informaciones sobre la cultura dominicana, costumbres, gastronom\u00eda y tradiciones con profesores, estudiantes e invitados especiales. Los asistentes disfrutaron del t\u00edpico mang\u00fa con los tres golpes y diferentes bebidas dominicanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La embajadora Sonia Guzm\u00e1n inform\u00f3 que es la primera vez en 23 a\u00f1os que la Rep\u00fablica Dominicana cuenta con una representante como alumna en el programa Sesi\u00f3n 288 sobre t\u00e9cnicas de investigaciones criminales, que cuenta con m\u00e1s de 200 participantes de m\u00e1s de 25 pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra participante es la abogada y crimin\u00f3loga, Anny Alexandra Cuello, quien desde el 2016 se desempe\u00f1a como agente y enlace para colaboraciones interinstitucionales, y adem\u00e1s forma parte de la Unidad de Investigaciones Criminales del Ministerio P\u00fablico adscrita a la Procuradur\u00eda General de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guzm\u00e1n felicit\u00f3 la participaci\u00f3n de Cuello en esta jornada de capacitaci\u00f3n, la cual ha tenido un desempe\u00f1o excelente, seg\u00fan los directivos de la Academia del FBI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diplom\u00e1tica destac\u00f3 que gracias a este manejo, el FBI ha manifestado su disposici\u00f3n de ampliar la participaci\u00f3n de dominicanos en el mismo y de reforzar este programa conjunto con RD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La graduaci\u00f3n se llevar\u00e1 a cabo el pr\u00f3ximo jueves 7 de diciembre en el auditorio de la Academia del FBI, en la base militar de Los Marines de Quantico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIRGINIA, Estados Unidos. La embajadora dominicana en los Estados Unidos, Sonia Guzm\u00e1n, particip\u00f3 en la Noche Internacional realizada en el marco de la Sesi\u00f3n 288 de la Academia del Bur\u00f3&hellip;<\/p>\n","protected":false},"author":2,"featured_media":68782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3164,2991,793,1638,9865,5275,9866],"class_list":["post-68781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada","tag-academia","tag-embajadora","tag-fbi","tag-internacional","tag-noche","tag-sonia-guzman","tag-virginia-eeuu"],"jetpack-related-posts":[{"id":96376,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/30\/diversas-instituciones-y-personalidades-reconocen-labor-de-sonia-guzman-frente-a-la-embajada-dominicana-en-los-ee-uu\/","url_meta":{"origin":68781,"position":0},"title":"Diversas instituciones y personalidades reconocen labor de Sonia Guzm\u00e1n frente a la Embajada Dominicana en los EE.UU.","author":"Nelson Feliz","date":"30 de marzo de 2025","format":false,"excerpt":"Diplom\u00e1ticos de distintos pa\u00edses participaron en la recepci\u00f3n de despedida y en concierto de jazz. La gesti\u00f3n culmin\u00f3 este fin de semana. Washington, D.C. Diversas personalidades e instituciones entregaron reconocimientos a Sonia Guzm\u00e1n por su labor como embajadora dominicana en los Estados Unidos durante cuatro a\u00f1os. Entre los reconocimientos se\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"Sonia Guzm\u00e1n","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Sonia-Guzman-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Sonia-Guzman-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Sonia-Guzman-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Sonia-Guzman-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":92975,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/01\/21\/sonia-guzman-participa-en-encuentro-de-donald-trump-en-el-congreso-de-los-eeuu\/","url_meta":{"origin":68781,"position":1},"title":"Sonia Guzm\u00e1n participa en encuentro de Donald Trump en el Congreso de los EEUU","author":"Nelson Feliz","date":"21 de enero de 2025","format":false,"excerpt":"WASHINGTON, Estados Unidos. La embajadora dominicana en los Estados Unidos saliente, Sonia Guzm\u00e1n, particip\u00f3 en un encuentro organizado por el presidente de los Estados Unidos, Donald Trump, con delegaciones diplom\u00e1ticas, pol\u00edticos, empresarios y otras personalidades. El encuentro fue realizado en un sal\u00f3n del Congreso de los Estados Unidos y se\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"Sonia Guzm\u00e1n","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/01\/Sonia-Guzman.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/01\/Sonia-Guzman.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/01\/Sonia-Guzman.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":96213,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/26\/embajada-dominicana-en-ee-uu-desarrollo-iniciativas-en-favor-de-dominicanos-en-el-exterior\/","url_meta":{"origin":68781,"position":2},"title":"Embajada Dominicana en EE.UU. desarroll\u00f3 iniciativas en favor de dominicanos en el exterior","author":"Nelson Feliz","date":"26 de marzo de 2025","format":false,"excerpt":"WASHINGTON, D.C. La Embajada Dominicana en los Estados Unidos encabezada por su representante, Sonia Guzm\u00e1n, desarroll\u00f3 cientos de iniciativas en 10 materias en favor de los dominicanos que residen en esa naci\u00f3n y en la Rep\u00fablica Dominicana, durante sus cuatro a\u00f1os de gesti\u00f3n. Sonia Guzm\u00e1n inform\u00f3 que junto a un\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Sonia-Guzman-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":79474,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/03\/27\/embajada-dominicana-en-eeuu-presenta-pelicula-de-freddy-beras-goico-en-washington-2\/","url_meta":{"origin":68781,"position":3},"title":"Embajada Dominicana en EEUU presenta pel\u00edcula de Freddy Beras Goico en Washington","author":"BIMARY DE JES\u00daS Matos","date":"27 de marzo de 2024","format":false,"excerpt":"ESTADOS UNIDOS. La Embajada Dominicana en los Estados Unidos realiz\u00f3 una presentaci\u00f3n especial de la pel\u00edcula \u201cFreddy\u201d, con la presencia de su director, Giancarlo Beras-Goico, quien comparti\u00f3 con representantes de la comunidad dominicana residente en el \u00e1rea de Washington DC, Maryland y Virginia. La embajadora Sonia Guzm\u00e1n agradeci\u00f3 la colaboraci\u00f3n\u2026","rel":"","context":"En \u00abENTRETENIMIENTO\u00bb","block_context":{"text":"ENTRETENIMIENTO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/entretenimiento\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-27-at-11.14.18-AM.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-27-at-11.14.18-AM.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-27-at-11.14.18-AM.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-27-at-11.14.18-AM.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-27-at-11.14.18-AM.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":79366,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/03\/26\/embajada-dominicana-en-eeuu-presenta-pelicula-de-freddy-beras-goico-en-washington\/","url_meta":{"origin":68781,"position":4},"title":"Embajada Dominicana en EEUU presenta pel\u00edcula de Freddy Beras Goico en Washington","author":"BIMARY DE JES\u00daS Matos","date":"26 de marzo de 2024","format":false,"excerpt":"Martin Restituyo Estados Unidos. La Embajada Dominicana en los Estados Unidos realiz\u00f3 una presentaci\u00f3n especial de la pel\u00edcula \u201cFreddy\u201d, con la presencia de su director, Giancarlo Beras-Goico, quien comparti\u00f3 con representantes de la comunidad dominicana residente en el \u00e1rea de Washington DC, Maryland y Virginia. La embajadora Sonia Guzm\u00e1n agradeci\u00f3\u2026","rel":"","context":"En \u00abENTRETENIMIENTO\u00bb","block_context":{"text":"ENTRETENIMIENTO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/entretenimiento\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/03\/IMG-20240326-WA0025.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/03\/IMG-20240326-WA0025.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/03\/IMG-20240326-WA0025.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/03\/IMG-20240326-WA0025.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/03\/IMG-20240326-WA0025.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":79912,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/04\/01\/embajada-dominicana-en-eeuu-presenta-pelicula-de-freddy-beras-goico-en-washington-3\/","url_meta":{"origin":68781,"position":5},"title":"Embajada Dominicana en EEUU presenta pel\u00edcula de Freddy Beras Goico en Washington","author":"BIMARY DE JES\u00daS Matos","date":"1 de abril de 2024","format":false,"excerpt":"Estados Unidos. La Embajada Dominicana en los Estados Unidos realiz\u00f3 una presentaci\u00f3n especial de la pel\u00edcula \u201cFreddy\u201d, con la presencia de su director, Giancarlo Beras-Goico, quien comparti\u00f3 con representantes de la comunidad dominicana residente en el \u00e1rea de Washington DC, Maryland y Virginia. La embajadora Sonia Guzm\u00e1n agradeci\u00f3 la colaboraci\u00f3n\u2026","rel":"","context":"En \u00abENTRETENIMIENTO\u00bb","block_context":{"text":"ENTRETENIMIENTO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/entretenimiento\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-01-at-1.40.13-PM.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-01-at-1.40.13-PM.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-01-at-1.40.13-PM.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-01-at-1.40.13-PM.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-01-at-1.40.13-PM.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Sonia-Guzman.jpg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/68781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=68781"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/68781\/revisions"}],"predecessor-version":[{"id":68783,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/68781\/revisions\/68783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/68782"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=68781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=68781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=68781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}