{"id":71558,"date":"2023-12-20T17:20:26","date_gmt":"2023-12-20T21:20:26","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=71558"},"modified":"2023-12-20T17:21:07","modified_gmt":"2023-12-20T21:21:07","slug":"mirex-saluda-decision-del-tribunal-constitucional-sobre-el-ingreso-a-la-carrera-diplomatica","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2023\/12\/20\/mirex-saluda-decision-del-tribunal-constitucional-sobre-el-ingreso-a-la-carrera-diplomatica\/","title":{"rendered":"MIREX afirma la decisi\u00f3n del Tribunal Constitucional sobre el ingreso a la carrera diplom\u00e1tica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Santo Domingo.-El Ministerio de Relaciones Exteriores salud\u00f3 la decisi\u00f3n del Tribunal Constitucional que declar\u00f3 admisible el recurso de revisi\u00f3n constitucional incohado por el MIREX en contra de la sentencia de la Suprema Corte de Justicia TS-22-0868 la cual ordenaba a esta instituci\u00f3n el reintegro de una ex funcionaria que alegaba ser de carrera diplom\u00e1tica solo porque ten\u00eda 10 a\u00f1os de servicio, sin haber agotado el proceso para entrar a este sistema de funci\u00f3n p\u00fablica especial. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">  La Canciller\u00eda detall\u00f3 que en el comunicado 82\/23, esta Alta Corte notifica que fall\u00f3 acoger en cuanto al fondo el referido recurso de revisi\u00f3n constitucional de decisi\u00f3n jurisdiccional y, en consecuencia anular la sentencia de la SCJ.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">  El MIREX afirm\u00f3 que este dispositivo sienta un precedente en la justicia que viene a sustentar y fortalecer la Ley 630-16 Org\u00e1nica del Ministerio de Relaciones Exteriores y su cap\u00edtulo 10 sobre la Carrera Diplom\u00e1tica, la cual se basa en la profesionalidad, la \u00e9tica y el m\u00e9rito, que garantiza el ingreso por concurso a la carrera, la evaluaci\u00f3n, capacitaci\u00f3n, ascenso, traslado, alternancia, estabilidad, disciplina y retiro de las funcionarias y los funcionarios diplom\u00e1ticos de carrera.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> El canciller Roberto \u00c1lvarez agreg\u00f3 que el TC valid\u00f3 los alegatos del MIREX para recurrir la sentencia de la SCJ que versaban sobre la modificaci\u00f3n que sufri\u00f3 la ley de este Ministerio del a\u00f1o 1964 con otras legislaciones como la ley de Funci\u00f3n P\u00fablica y la 630-16 de Relaciones Exteriores.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">  \u201cEs en base al m\u00e9rito que ahora, junto a otros factores, se adquiere el derecho a ser funcionario de carrera diplom\u00e1tica, no solo por el tiempo de servicio, as\u00ed que estamos hoy celebrando esta gran victoria, por lo que agradezco a la Direcci\u00f3n Jur\u00eddica del MIREX y el equipo legal externo que trabaj\u00f3 con este tema durante dos a\u00f1os hasta lograr que se ratifique lo establecido por la legislaci\u00f3n vigente\u201d, expres\u00f3 el ministro \u00c1lvarez.<\/p>\n\n\n<figure class=\"wp-block-post-featured-image\"><img decoding=\"async\" width=\"1600\" height=\"960\" src=\"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/IMG-20231220-WA0070.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/IMG-20231220-WA0070.jpg 1600w, https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/IMG-20231220-WA0070-300x180.jpg 300w, https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/IMG-20231220-WA0070-1024x614.jpg 1024w, https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/IMG-20231220-WA0070-768x461.jpg 768w, https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/IMG-20231220-WA0070-1536x922.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.-El Ministerio de Relaciones Exteriores salud\u00f3 la decisi\u00f3n del Tribunal Constitucional que declar\u00f3 admisible el recurso de revisi\u00f3n constitucional incohado por el MIREX en contra de la sentencia de&hellip;<\/p>\n","protected":false},"author":3,"featured_media":71559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[],"class_list":["post-71558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/IMG-20231220-WA0070.jpg","jetpack-related-posts":[{"id":51181,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/05\/29\/tc-impone-sancion-economica-definitiva-a-la-dgii\/","url_meta":{"origin":71558,"position":0},"title":"TC impone sanci\u00f3n econ\u00f3mica definitiva a la DGII","author":"prenxa100","date":"29 de mayo de 2023","format":false,"excerpt":"La suma que tiene que pagar DGII asciende a 508 millones. SANTO DOMINGO.-.El Tribunal Constitucional convirti\u00f3 en definitiva la sentencia que impone el astreinte (sanci\u00f3n econ\u00f3mica), a la Direcci\u00f3n General de Impuestos Internos (DGII), suma que a la fecha asciende a 508 millones de pesos, que deber\u00e1 pagar al abogado\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":98088,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/05\/01\/tc-prohibe-el-uso-de-apodos-en-los-procesos-judiciales\/","url_meta":{"origin":71558,"position":1},"title":"TC proh\u00edbe el uso de apodos en los procesos judiciales","author":"Nelson Feliz","date":"1 de mayo de 2025","format":false,"excerpt":"El Tribunal Constitucional consider\u00f3 que el uso de motes vulnera la presunci\u00f3n de inocencia. El Tribunal Constitucional emiti\u00f3 la sentencia TC\/0225\/25 en la que proh\u00edbe al Ministerio P\u00fablico y sus dependencias utilizar p\u00fablicamente motes o sobrenombres en sus expedientes judiciales, tras determinar que esta pr\u00e1ctica vulnera la presunci\u00f3n de inocencia,\u2026","rel":"","context":"En \u00abJUSTICIA\u00bb","block_context":{"text":"JUSTICIA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/justicia\/"},"img":{"alt_text":"Tribunal Constitucional","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Tribunal-Constitucional.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Tribunal-Constitucional.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Tribunal-Constitucional.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Tribunal-Constitucional.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":64948,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/24\/tc-confirma-sentencia-tc-0227-23-ordena-cierre-de-la-carcel-de-bellas-colinas-en-manoguayabo\/","url_meta":{"origin":71558,"position":2},"title":"TC confirma sentencia TC\/0227\/23, ordena cierre de la c\u00e1rcel de Bellas Colinas en Manoguayabo","author":"Nelson Feliz","date":"24 de octubre de 2023","format":false,"excerpt":"Por Martin Restituyo El Tribunal Constitucional ha emitido una decisi\u00f3n crucial al confirmar la sentencia de amparo (TC\/0227\/23) y ordena el cierre inmediato de la c\u00e1rcel de Bellas Colinas, ubicada en el sector de Manoguayabo, Santo Domingo Oeste. Esta resoluci\u00f3n pone fin a una larga lucha por la justicia y\u2026","rel":"","context":"En \u00abJUSTICIA\u00bb","block_context":{"text":"JUSTICIA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/justicia\/"},"img":{"alt_text":"carcelita","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/carcelita-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/carcelita-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/carcelita-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/carcelita-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":108101,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/09\/03\/tc-evaluara-si-la-suprema-corte-vulnero-derechos-a-rosa-amalia-pilarte\/","url_meta":{"origin":71558,"position":3},"title":"TC evaluar\u00e1 si la Suprema Corte vulner\u00f3 derechos a Rosa Amalia Pilarte","author":"Nelson Feliz","date":"3 de septiembre de 2025","format":false,"excerpt":"En el recurso de revisi\u00f3n constitucional que someti\u00f3 la exdiputada Rosa Amalia Pilarte a la sentencia que la condena a cinco a\u00f1os de prisi\u00f3n por lavado de activos, el Tribunal Constitucional (TC) verificar\u00e1 si la decisi\u00f3n de la Suprema Corte de Justicia (SCJ) viola algunos de los fallos precedentes del\u2026","rel":"","context":"En \u00abJUSTICIA\u00bb","block_context":{"text":"JUSTICIA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/justicia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Rosa-Amalia-Pilarte.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Rosa-Amalia-Pilarte.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Rosa-Amalia-Pilarte.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Rosa-Amalia-Pilarte.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":85035,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/06\/21\/scj-se-reserva-fallo-sobre-el-recurso-de-casacion-del-empresario-antonio-carbone\/","url_meta":{"origin":71558,"position":4},"title":"SCJ se reserva fallo sobre el recurso de casaci\u00f3n del empresario Antonio Carbone","author":"Nelson Feliz","date":"21 de junio de 2024","format":false,"excerpt":"Decenas de personas protestan. Defensores de derechos humanos piden que se respeten los derechos del empresario extranjero. Los jueces de la Segunda Sala Penal de la Suprema Corte de Justicia (SCJ) reservaron el fallo remitido por el Tribunal Constitucional (TC) sobre la audiencia sobre el recurso de casaci\u00f3n sobre el\u2026","rel":"","context":"En \u00abJUSTICIA\u00bb","block_context":{"text":"JUSTICIA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/justicia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Antonio-Carbone.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Antonio-Carbone.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Antonio-Carbone.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":57307,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/08\/10\/consultor-juridico-reafirma-la-sujecion-total-del-gobierno-al-orden-constitucional\/","url_meta":{"origin":71558,"position":5},"title":"Consultor Jur\u00eddico reafirma la sujeci\u00f3n total del gobierno al orden constitucional","author":"Nelson Feliz","date":"10 de agosto de 2023","format":false,"excerpt":"El consultor jur\u00eddico del Poder Ejecutivo, Doctor Antoliano Peralta Romero, se refiri\u00f3 a la situaci\u00f3n de las sentencias emitidas por el Tribunal Constitucional pendientes de ejecuci\u00f3n por parte de \u00f3rganos de la Administraci\u00f3n P\u00fablica. Al ser abordado por periodistas que cubren la fuente del Palacio Nacional, el funcionario sostuvo \u201cque\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Antoliano Peralta Romero","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Antoliano-Peralta-Romero.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Antoliano-Peralta-Romero.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Antoliano-Peralta-Romero.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Antoliano-Peralta-Romero.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=71558"}],"version-history":[{"count":2,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71558\/revisions"}],"predecessor-version":[{"id":71561,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71558\/revisions\/71561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/71559"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=71558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=71558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=71558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}