{"id":71581,"date":"2023-12-21T07:00:52","date_gmt":"2023-12-21T11:00:52","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=71581"},"modified":"2023-12-21T07:12:58","modified_gmt":"2023-12-21T11:12:58","slug":"presidente-luis-abinader-sobre-ex-administrador-loteria-nacional","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2023\/12\/21\/presidente-luis-abinader-sobre-ex-administrador-loteria-nacional\/","title":{"rendered":"Aclaraci\u00f3n p\u00fablica por el Equipo de Michel Dicent"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>El Presidente Luis Abinader sobre ex administrador Loter\u00eda Nacional<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos dirigimos a ustedes para aclarar y desmentir informaci\u00f3n falsa que ha circulado recientemente en relaci\u00f3n con las declaraciones del Excelent\u00edsimo Se\u00f1or presidente de la Rep\u00fablica Dominicana, Luis Abinader, durante su participaci\u00f3n en el programa radial &#8220;Sol de la Ma\u00f1ana&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras una exhaustiva revisi\u00f3n del video en cuesti\u00f3n, queremos dejar claro que en ning\u00fan momento el se\u00f1or presidente mencion\u00f3 al ex administrador de la Loter\u00eda Nacional, Michell Dicent como se ha querido resaltar, como responsable del \u00fanico caso judicializado que ha afectado el patrimonio nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, verificamos la informaci\u00f3n en el peri\u00f3dico digital que supuestamente public\u00f3 la noticia, y no encontramos evidencia de que dicha informaci\u00f3n haya sido publicada en su portal, ni en ning\u00fan peri\u00f3dico que se respete, porque el presidente nunca dijo eso. Esto nos lleva a cuestionar la veracidad de la afirmaci\u00f3n y a sospechar que el objetivo detr\u00e1s de esta supuesta publicaci\u00f3n es generar un ambiente de odio y conflicto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un momento en el que la transparencia y la verdad son fundamentales, instamos a la sociedad a ser cautelosa y cr\u00edtica con la informaci\u00f3n que circula en l\u00ednea. La difusi\u00f3n de noticias falsas solo contribuye a socavar la confianza y generar divisiones innecesarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reafirmamos nuestro compromiso con la honestidad y la justicia; Dicent al cuestionarlo sobre el tema solo dijo: El presidente no dijo eso y al final de todo, Dios sabr\u00e1, adem\u00e1s el presidente esta en lo correcto, el nombro justicia independiente los resultados lo veremos y esto est\u00e1 muy joven aun dejemos que el tiempo corra y el que quiera que busque el video en la plataforma del sol de la ma\u00f1ana em RCC MEDIA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De ser as\u00ed se estar\u00eda contradiciendo algo que en ning\u00fan momento hizo con respeto y estima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Equipo de apoyo Y de defensa Michell Dicent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Presidente Luis Abinader sobre ex administrador Loter\u00eda Nacional Nos dirigimos a ustedes para aclarar y desmentir informaci\u00f3n falsa que ha circulado recientemente en relaci\u00f3n con las declaraciones del Excelent\u00edsimo&hellip;<\/p>\n","protected":false},"author":2,"featured_media":71582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3725,10594,67,935],"class_list":["post-71581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada","tag-ex-administrador","tag-loteria-nacional","tag-luis-abinader","tag-presidente"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Luis-Abinader-vs-Michel-Dicent.jpg","jetpack-related-posts":[{"id":103836,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/18\/ex-administrador-de-la-loteria-nacional-arremete-contra-el-ex-ministro-de-hacienda-jochi-vicente-video\/","url_meta":{"origin":71581,"position":0},"title":"Ex administrador de la Loter\u00eda Nacional arremete contra el ex ministro de Hacienda Jochi Vicente \/ Video","author":"Nelson Feliz","date":"18 de julio de 2025","format":false,"excerpt":"Luis Michel Dicent, ex administrador de la Loter\u00eda Nacional, arremete contra el ex ministro de Hacienda, Jochi Vicente: \u201cNo creo que nadie renuncie al Ministerio de Hacienda\u201d Por Johnny Alc\u00e1ntara Monse\u00f1or Nouel, (Bonao).-.El ex administrador de la Loter\u00eda Nacional Dominicana, Luis Michel Dicent, rompi\u00f3 el silencio y lanz\u00f3 duras acusaciones\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Michel Dicent","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Michel-Dicent.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Michel-Dicent.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Michel-Dicent.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Michel-Dicent.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":71118,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/12\/17\/ex-administrador-de-la-loteria-revela-funcionarios-del-prm-quieren-hacerles-desaparecer-politicamente\/","url_meta":{"origin":71581,"position":1},"title":"Ex administrador de la Loter\u00eda revela funcionarios del PRM quieren hacerles desaparecer pol\u00edticamente \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0","author":"Nelson Feliz","date":"17 de diciembre de 2023","format":false,"excerpt":"El ex administrador de la Loter\u00eda Nacional Dominicana, y ex secretario general del Partido Revolucionario Moderno (PRM) en la Provincia Monse\u00f1or Nouel (Bonao), Luis Michel Dicent, denunci\u00f3 hoy que altos funcionarios y dirigentes dentro y fuera del PRM quien hacerle desaparecer de la pol\u00edtica. Dicent, pidi\u00f3 a los funcionarios del\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"Luis Michel Dicent","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Luis-Michel-Dicent.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Luis-Michel-Dicent.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Luis-Michel-Dicent.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":63727,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/15\/video-ex-administrador-de-la-loteria-arremete-contra-el-ministerio-publico-y-los-abogados-del-estado\/","url_meta":{"origin":71581,"position":2},"title":"Video: Ex administrador de la loter\u00eda arremete contra el Ministerio P\u00fablico y los abogados del Estado \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0","author":"Nelson Feliz","date":"15 de octubre de 2023","format":false,"excerpt":"El ex administrador de la Loter\u00eda Nacional, Luis Maisichell Dicent, arremeti\u00f3 este domingo en contra el Ministerio P\u00fablico, quienes se han valido de los medios de comunicaci\u00f3n,\u00a0 para da\u00f1arles la imagen a personas de trabajo y honradas que llegaron al tren gubernamental a servirles a la patria, sin embargo los\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Michel Dicent","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Michel-Dicent.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Michel-Dicent.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Michel-Dicent.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Michel-Dicent.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":132671,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/06\/05\/luis-dicent-acusa-a-jochi-vicente-de-los-actos-de-corrupcion-y-demandas-cometidos-en-la-loteria\/","url_meta":{"origin":71581,"position":3},"title":"Luis Dicent acusa a Jochi Vicente de los actos de corrupci\u00f3n y demandas cometidos en la loter\u00eda","author":"Nelson Feliz","date":"5 de junio de 2026","format":false,"excerpt":"Santo Domingo.-. El exadministrador de la general de la Loter\u00eda Nacional, Luis Maisichell Dicent, quien fue nombrado mediante el decreto n\u00fam. 388-20, emitido el 23 de agosto de 2020, por el presidente Luis Abinader, denunci\u00f3 hoy que el exministro de Hacienda, Jochi Vicente, es el primer enemigo que tiene este\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Luis Michel Dicent","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Luis-Michel-Dicent.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Luis-Michel-Dicent.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/12\/Luis-Michel-Dicent.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":49218,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/05\/09\/ex-administrador-de-la-loteria-es-captado-en-las-calles-de-bonao-manejando-un-trimotor\/","url_meta":{"origin":71581,"position":4},"title":"Ex Administrador de la loter\u00eda es captado en las calles de Bonao manejando un trimotor","author":"prenxa100","date":"9 de mayo de 2023","format":false,"excerpt":"No quiero abundar mucho, porque yo conoc\u00ed a Michel Dicent antes de ser administrador de la loter\u00eda y siendo funcionario nunca vi en \u00e9l, eso que describ\u00edan y mucho menos vinculado a un hecho aberrante de alterar el sorteo. Hoy me llega esta imagen y no se si sentirme feliz,\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":112485,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/10\/22\/ex-administrador-de-la-loteria-nacional-dominicana-la-historia-de-un-hombre-al-que-su-propio-partido-olvido\/","url_meta":{"origin":71581,"position":5},"title":"Ex administrador de la Loter\u00eda Nacional Dominicana: la historia de un hombre al que su propio partido olvid\u00f3","author":"Nelson Feliz","date":"22 de octubre de 2025","format":false,"excerpt":"Por: Nelson Feliz A veces me pregunto si realmente tiene sentido so\u00f1ar, creer en algo o luchar por un ideal en un mundo donde la lealtad parece no tener valor. Me lo pregunto porque he visto de cerca lo que ocurre cuando la integridad choca con la indiferencia del poder.\u2026","rel":"","context":"En \u00abOPINI\u00d3N\u00bb","block_context":{"text":"OPINI\u00d3N","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/opinion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Michel-Dicent.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Michel-Dicent.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/10\/Michel-Dicent.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=71581"}],"version-history":[{"count":3,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71581\/revisions"}],"predecessor-version":[{"id":71600,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/71581\/revisions\/71600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/71582"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=71581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=71581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=71581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}