{"id":73192,"date":"2024-01-06T23:37:37","date_gmt":"2024-01-07T03:37:37","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=73192"},"modified":"2024-01-06T23:37:38","modified_gmt":"2024-01-07T03:37:38","slug":"roberto-angel-encabeza-entrega-de-juguetes-en-santiago","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2024\/01\/06\/roberto-angel-encabeza-entrega-de-juguetes-en-santiago\/","title":{"rendered":"Roberto \u00c1ngel encabeza entrega de juguetes en Santiago"},"content":{"rendered":"\n<p><strong>El director de Proyectos Estrat\u00e9gicos y Programas Especiales de la Presidencia afirma que la ni\u00f1ez tiene un espacio importante en el gobierno de Luis Abinader<\/strong><\/p>\n\n\n\n<p>El director de Proyectos Estrat\u00e9gicos y Programas Especiales de la Presidencia, Roberto \u00c1ngel Salcedo, entreg\u00f3 este s\u00e1bado juguetes a miles de ni\u00f1os de familias pobres del sector San Jos\u00e9 de la Mina y del municipio Tamboril, en Santiago, con lo que busca llevar alegr\u00eda y diversi\u00f3n a la ni\u00f1ez de escasos recursos, con motivo del D\u00eda de los Reyes Magos.<\/p>\n\n\n\n<p>Al hacer la entrega, en el marco del programa &#8220;Cerca de Ti&#8221;, Roberto \u00c1ngel destac\u00f3 que en el gobierno del presidente Luis Abinader la ni\u00f1ez tiene un lugar muy importante y de primer orden, ya que son el futuro de la naci\u00f3n.<\/p>\n\n\n\n<p>El funcionario sostuvo que el prop\u00f3sito es que en esta fecha especial la ni\u00f1ez de Santiago reciba juguetes y pueda disfrutar de la alegr\u00eda que caracteriza esa festividad, que es parte de la idiosincrasia del dominicano.<\/p>\n\n\n\n<p>&#8220;Lo que procuramos es que este d\u00eda quede en el recuerdo, donde ustedes puedan jugar, divertirse y compartir con sus amiguitos de los juguetes y regalos que le entregaremos&#8221;, expres\u00f3 Roberto \u00c1ngel, ante los cientos de ni\u00f1os que acudieron al club San Jos\u00e9 de la Mina, en el sector del mismo nombre.<\/p>\n\n\n\n<p>Agreg\u00f3 que en tiempos pasados la ni\u00f1ez no sent\u00eda la generosidad de los gobiernos y se quedaban sin regalos, pero que el presidente Abinader ha instruido a que ning\u00fan ni\u00f1o se quede sin recibir juguetes.<\/p>\n\n\n\n<p>Resalt\u00f3 que con ese tipo de actividades el gobierno de Abinader busca incorporar a las familias vulnerables y que hist\u00f3ricamente han estado marginadas y excluidas.<\/p>\n\n\n\n<p>Juguetes educativos<\/p>\n\n\n\n<p>Los juguetes educativos y tecnol\u00f3gicos, fueron recibidos con mucha alegr\u00eda por los ni\u00f1os de esos sectores, los cuales manifestaron su alegr\u00eda con los juguetes que recibieron.<\/p>\n\n\n\n<p>A los infantes le fueron entregados mu\u00f1ecas, bicicletas, patinetas, rompecabezas, juguetes tecnol\u00f3gicos y disfrutaron de un show de payasos, con el que bailaron y comieron palomitas, entre otros atractivos para el disfrute de los ni\u00f1os.<\/p>\n\n\n\n<p>Autoridades presentes<\/p>\n\n\n\n<p>Durante las diferentes actividades, Roberto \u00c1ngel estuvo acompa\u00f1ado por la diputada Soraya Su\u00e1rez, el director regional de Promypime, Milton Mart\u00ednez, as\u00ed como regidores y representantes de las diferentes juntas de vecinos de la comunidad de San Jos\u00e9 de la Mina, ubicado en la regi\u00f3n sureste de Santiago y del alcalde Anyolino Germos\u00e9n del municipio Tamboril.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director de Proyectos Estrat\u00e9gicos y Programas Especiales de la Presidencia afirma que la ni\u00f1ez tiene un espacio importante en el gobierno de Luis Abinader El director de Proyectos Estrat\u00e9gicos&hellip;<\/p>\n","protected":false},"author":2,"featured_media":73193,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35,25],"tags":[10955,646,1049],"class_list":["post-73192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada","tag-juguetes","tag-roberto-angel-salcedo","tag-santiago"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/01\/Roberto-Angel-Salcedo-1.jpg","jetpack-related-posts":[{"id":66943,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/11\/11\/roberto-angel-gobierno-de-abinader-combate-pobreza-en-puerto-plata-permanente\/","url_meta":{"origin":73192,"position":0},"title":"Roberto \u00c1ngel: \u201cGobierno de Abinader combate pobreza en Puerto Plata permanente\u201d","author":"Nelson Feliz","date":"11 de noviembre de 2023","format":false,"excerpt":"Encabeza este fin de semana jornadas \u201cPrimero T\u00fa\u201d y \u201cCerca de T\u00ed\u201d en Rinc\u00f3n, La Vega, y en Altamira y Montellano, de Puerto Plata. El director de Proyectos Estrat\u00e9gicos y Especiales de la Presidencia, Roberto \u00c1ngel Salcedo, afirm\u00f3 este s\u00e1bado que el combate a la pobreza por el gobierno del\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Roberto \u00c1ngel Salcedo","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Roberto-Angel-Salcedo-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Roberto-Angel-Salcedo-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Roberto-Angel-Salcedo-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Roberto-Angel-Salcedo-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":61044,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/21\/roberto-angel-asegura-pueblos-fronterizos-son-prioridad-para-el-presidente-abinader\/","url_meta":{"origin":73192,"position":1},"title":"Roberto \u00c1ngel asegura pueblos fronterizos son prioridad para el presidente Abinader","author":"Nelson Feliz","date":"21 de septiembre de 2023","format":false,"excerpt":"En \u00faltimos tres d\u00edas miles de personas resultan beneficiadas con acciones sociales del Gobierno en comunidades vulnerables de Comendador, Hondo Valle y Juan Santiago en Elias Pi\u00f1a; El Cercado y La Rancha, en la provincia San Juan. El director de los proyectos Estrat\u00e9gicos y Especiales de la Presidencia, Roberto \u00c1ngel\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"Roberto \u00c1ngel Salcedo","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Roberto-Angel-Salcedo-6-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Roberto-Angel-Salcedo-6-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Roberto-Angel-Salcedo-6-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Roberto-Angel-Salcedo-6-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":49637,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/05\/12\/roberto-angel-gobierno-de-abinader-llega-a-todos-los-rincones-del-pais\/","url_meta":{"origin":73192,"position":2},"title":"Roberto \u00c1ngel: Gobierno \u00a0de Abinader llega a todos los rincones del pa\u00eds","author":"prenxa100","date":"12 de mayo de 2023","format":false,"excerpt":"Arenoso, provincia Duarte. El director general de los Proyectos Estrat\u00e9gicos y Especiales de la Presidencia (Propeep) Roberto \u00c1ngel Salcedo, ratific\u00f3 este viernes que las pol\u00edticas de inclusi\u00f3n social del presidente Luis Abinader y su gobierno llegan a todos los rincones del pa\u00eds. El director de Propeep dijo que el objetivo\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":54180,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/07\/08\/roberto-angel-afirma-combate-a-la-pobreza-es-prioridad-del-presidente-abinader\/","url_meta":{"origin":73192,"position":3},"title":"Roberto \u00c1ngel afirma combate a la pobreza es prioridad del presidente Abinader","author":"Nelson Feliz","date":"8 de julio de 2023","format":false,"excerpt":"El director de Proyectos Especiales de la Presidencia visit\u00f3 las provincias Duarte y Puerto Plata, donde inaugur\u00f3 jornadas de inclusi\u00f3n social, entreg\u00f3 Paseos de Los Colores y desarroll\u00f3 el programa \"Cerca de Ti\" Por Martin Restituyo El director de Proyectos Especiales de la Presidencia, Roberto \u00c1ngel Salcedo, afirm\u00f3 este s\u00e1bado\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"Roberto \u00c1ngel Salcedo","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Roberto-Angel-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Roberto-Angel-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Roberto-Angel-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Roberto-Angel-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":60371,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/13\/roberto-angel-afirma-politica-social-de-abinader-es-efectiva-y-permanente-en-monte-plata-y-el-pais\/","url_meta":{"origin":73192,"position":4},"title":"Roberto \u00c1ngel afirma pol\u00edtica social de Abinader es efectiva y permanente en Monte Plata y el pa\u00eds","author":"Nelson Feliz","date":"13 de septiembre de 2023","format":false,"excerpt":"Los Proyectos Estrat\u00e9gicos y Especiales de la Presidencia desarrollan tres d\u00edas de jornadas de inclusi\u00f3n social en comunidades de Sabana Grande de Boy\u00e1, Peralvillo y Yamas\u00e1 El director de Proyectos Estrat\u00e9gicos y Especiales de la Presidencia, Roberto \u00c1ngel Salcedo, afirm\u00f3 este mi\u00e9rcoles que la pol\u00edtica social del presidente Luis Abinader\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"Roberto \u00c1ngel Salcedo","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Roberto-Angel-Salcedo-2-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Roberto-Angel-Salcedo-2-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Roberto-Angel-Salcedo-2-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Roberto-Angel-Salcedo-2-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":67737,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/11\/17\/roberto-angel-el-gobierno-esta-enfocado-en-romper-circulo-de-pobreza-en-sde-y-monte-plata\/","url_meta":{"origin":73192,"position":5},"title":"Roberto \u00c1ngel: El gobierno est\u00e1 enfocado en romper c\u00edrculo de pobreza en SDE y Monte Plata","author":"Nelson Feliz","date":"17 de noviembre de 2023","format":false,"excerpt":"Encabeza jornadas de inclusi\u00f3n social en los barrios Puerto Rico, de Santo Domingo Este, y Los Suizos, de Monte Plata, donde miles de personas resultaron beneficiadas El director general de Proyectos Estrat\u00e9gicos y Especiales de la Presidencia, Roberto \u00c1ngel Salcedo, asegur\u00f3 que el gobierno del presidente Luis Abinader est\u00e1 enfocado\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"Roberto \u00c1ngel Salcedo","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Roberto-Angel-Salcedo-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Roberto-Angel-Salcedo-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Roberto-Angel-Salcedo-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/Roberto-Angel-Salcedo-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/73192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=73192"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/73192\/revisions"}],"predecessor-version":[{"id":73194,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/73192\/revisions\/73194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/73193"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=73192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=73192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=73192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}