{"id":83619,"date":"2024-05-20T21:33:44","date_gmt":"2024-05-21T01:33:44","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=83619"},"modified":"2024-05-20T21:33:44","modified_gmt":"2024-05-21T01:33:44","slug":"presidente-abinader-anuncia-viajara-a-italia-el-vaticano-y-portugal","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2024\/05\/20\/presidente-abinader-anuncia-viajara-a-italia-el-vaticano-y-portugal\/","title":{"rendered":"Presidente Abinader anuncia viajar\u00e1 a Italia, el Vaticano y Portugal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Durante este viaje, el jefe del Estado sostendr\u00e1 un encuentro en el Vaticano con el Papa Francisco.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente Luis Abinader anunci\u00f3 este lunes que a partir del pr\u00f3ximo viernes 24 de mayo viajar\u00e1 a Italia, el Vaticano y Portugal, y que durante su permanencia en Roma sostendr\u00e1 un encuentro con el Papa Francisco, as\u00ed como reuniones bilaterales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas informaciones las ofreci\u00f3 el mandatario durante LA Semanal con la Prensa realizada como de costumbre en el sal\u00f3n Las Cari\u00e1tides del Palacio Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al explicar sobre su agenda en Europa, el jefe del Estado inform\u00f3 que partir\u00e1 del pa\u00eds el pr\u00f3ximo viernes 24 hacia Roma, Italia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sostuvo que ya para el 27 de mayo sostendr\u00e1 una reuni\u00f3n con el presidente de Italia, Sergio Matarella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3, que ese mismo d\u00eda, \u00e9l, su esposa e hijas sostendr\u00e1n un encuentro con el Papa Francisco, al tiempo que mantendr\u00e1 una reuni\u00f3n bilateral con autoridades del Vaticano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, el 28 de mayo, viajar\u00e1 a la Rep\u00fablica Portuguesa, donde se reunir\u00e1 con el presidente de esta naci\u00f3n, Marcel Rebelo de Sousa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con Rebelo de Sousa, el presidente Abinader manifest\u00f3 discutir\u00e1n sobre proyectos que estudian conjuntamente en las \u00e1reas de turismo de playa, turismo inmobiliario, turismo de retiro y diferentes programas de inteligencia artificial y de la informaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante este viaje, el jefe del Estado sostendr\u00e1 un encuentro en el Vaticano con el Papa Francisco. El presidente Luis Abinader anunci\u00f3 este lunes que a partir del pr\u00f3ximo viernes&hellip;<\/p>\n","protected":false},"author":2,"featured_media":54873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35,25],"tags":[1870,67,10696,2194,9060],"class_list":["post-83619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada","tag-italia","tag-luis-abinader","tag-portugal","tag-vaticano","tag-viajara"],"jetpack-related-posts":[{"id":83814,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/05\/24\/abinader-llega-a-italia-para-audiencia-privada-con-el-papa-francisco\/","url_meta":{"origin":83619,"position":0},"title":"Abinader llega a Italia para audiencia privada con el papa Francisco","author":"Nelson Feliz","date":"24 de mayo de 2024","format":false,"excerpt":"Roma, Italia. - El presidente Luis Abinader lleg\u00f3 a la capital italiana, Roma, a las 1:16 horas junto a su familia y ser\u00e1n recibidos este lunes en audiencia privada por Su Santidad, el papa Francisco, en la Ciudad del Vaticano. El jefe de Estado dominicano al llegar a Roma, fue\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"Luis Abinader","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Luis-Abinader-i.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Luis-Abinader-i.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Luis-Abinader-i.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Luis-Abinader-i.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":83753,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/05\/24\/el-papa-francisco-recibira-este-27-de-mayo-en-audiencia-al-presidente-luis-abinader\/","url_meta":{"origin":83619,"position":1},"title":"El papa Francisco recibir\u00e1 este 27 de mayo en audiencia al presidente Luis Abinader","author":"Nelson Feliz","date":"24 de mayo de 2024","format":false,"excerpt":"El papa Francisco recibir\u00e1 el 27 de mayo en audiencia al\u00a0presidente\u00a0de la Rep\u00fablica, Luis Abinader, confirm\u00f3 este viernes la oficina de prensa del\u00a0Vaticano. La audiencia se celebrar\u00e1 a las 09:00 hora italiana (07:00 GMT) en el palacio apost\u00f3lico en la Sala de la Biblioteca, donde los pont\u00edfices reciben a los\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"PAPA","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/IMG_8451.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/IMG_8451.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/IMG_8451.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/IMG_8451.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/IMG_8451.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":84244,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/06\/04\/presidente-abinader-habla-de-los-resultados-de-su-viaje-a-europa\/","url_meta":{"origin":83619,"position":2},"title":"Presidente Abinader habla de los resultados de su viaje a Europa","author":"Nelson Feliz","date":"4 de junio de 2024","format":false,"excerpt":"Durante su viaje sostuvo una audiencia privada con el papa Francisco, se reuni\u00f3 con el cardenal el Pietro Parolin y monse\u00f1or Paul Richard Gallagher, al tiempo que con sus hom\u00f3logos de Italia y Portugal habl\u00f3 de temas bilaterales, el fortalecimiento del turismo, intercambio comercial y la ampliaci\u00f3n de los programas\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"Luis Abinader","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Luis-Abinader-4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Luis-Abinader-4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Luis-Abinader-4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Luis-Abinader-4.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":97658,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/25\/abinader-viaja-hoy-al-vaticano-al-funeral-de-su-santidad-el-papa-francisco\/","url_meta":{"origin":83619,"position":3},"title":"Abinader viaja hoy al Vaticano al funeral de su Santidad el Papa Francisco","author":"Nelson Feliz","date":"25 de abril de 2025","format":false,"excerpt":"Mandatario dominicano, se suma as\u00ed a otros jefes de estado y de gobiernos que asisten a los actos por el fallecimiento del Sumo Pont\u00edfice. El presidente Luis Abinader y la primera dama, Raquel Arbaje, viajar\u00e1n este viernes al Vaticano para asistir a la misa funeral de Su Santidad el papa\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/luis-abinader-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/luis-abinader-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/luis-abinader-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":84169,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/06\/01\/abinader-regresa-al-pais-tras-su-viaje-oficial-a-europa\/","url_meta":{"origin":83619,"position":4},"title":"Abinader regresa al pa\u00eds tras su viaje oficial a Europa","author":"Nelson Feliz","date":"1 de junio de 2024","format":false,"excerpt":"El presidente Luis Abinader regres\u00f3 al pa\u00eds este s\u00e1bado tras su viaje por Europa, donde tuvo una audiencia privada con el papa Francisco, en la Ciudad del Vaticano, y se reuni\u00f3 con sus hom\u00f3logos de Italia y Portugal. A su llegada al pa\u00eds, el mandatario fue recibido por el ministro\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Raquel Arbaje y Luis Abinader","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Raquel-Arbaje-y-Luis-Abinader.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Raquel-Arbaje-y-Luis-Abinader.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Raquel-Arbaje-y-Luis-Abinader.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Raquel-Arbaje-y-Luis-Abinader.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":83907,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/05\/27\/abinader-se-reune-con-su-homologo-italiano-sergio-mattarella\/","url_meta":{"origin":83619,"position":5},"title":"Abinader se re\u00fane con su hom\u00f3logo italiano, Sergio Mattarella","author":"Nelson Feliz","date":"27 de mayo de 2024","format":false,"excerpt":"Roma, Italia. - El presidente Luis Abinader sostuvo una reuni\u00f3n con su hom\u00f3logo de la Rep\u00fablica Italiana, Sergio Mattarella, en el Palacio de Quirinal, donde conversaron sobre diferentes temas de inter\u00e9s para ambas naciones. El mandatario dominicano agradeci\u00f3 al presidente Mattarella por el c\u00e1lido recibimiento y aprovech\u00f3 para invitarlo a\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"Luis Abinader y Sergio Mattarella","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Luis-Abinader-y-Sergio-Mattarella-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Luis-Abinader-y-Sergio-Mattarella-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Luis-Abinader-y-Sergio-Mattarella-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Luis-Abinader-y-Sergio-Mattarella-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Luis-Abinader-viaja.jpg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=83619"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83619\/revisions"}],"predecessor-version":[{"id":83620,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83619\/revisions\/83620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/54873"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=83619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=83619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=83619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}