{"id":83836,"date":"2024-05-26T15:27:36","date_gmt":"2024-05-26T19:27:36","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=83836"},"modified":"2024-05-26T15:27:37","modified_gmt":"2024-05-26T19:27:37","slug":"crees-asegura-que-el-gobierno-elevara-ingresos-en-1-5-del-pib-con-la-reforma-tributaria","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2024\/05\/26\/crees-asegura-que-el-gobierno-elevara-ingresos-en-1-5-del-pib-con-la-reforma-tributaria\/","title":{"rendered":"CREES asegura que el gobierno elevar\u00e1 ingresos en 1.5% del PIB con la reforma tributaria"},"content":{"rendered":"\n<p><strong>Miguel Collado plantea reducci\u00f3n ITBIS a 10%, ISR 18% y eliminaci\u00f3n otros impuestos distorsionadores.<\/strong><\/p>\n\n\n\n<p><strong>Dice hay que romper c\u00edrculo vicioso de parches fiscales para seguir incrementando el gasto.<\/strong><\/p>\n\n\n\n<p>El vicepresidente ejecutivo del Centro Regional de Estrategias Econ\u00f3micas Sostenibles (CREES), Miguel Collado, asegur\u00f3 que con la propuesta de Reforma Tributaria que plantea, el gobierno podr\u00eda incrementar sus recaudaciones en 1.5% del Producto Interno Bruto en el primer a\u00f1o de aplicaci\u00f3n.<\/p>\n\n\n\n<p>Collado record\u00f3 que cuando en 1992, se propuso una Reforma Tributaria que iba a bajar el Impuesto Sobre la Renta, que en tres a\u00f1os se redujo de 46 a 25%, le dijeron al entonces presidente Joaqu\u00edn Balaguer que iban a caer las recaudaciones y no tendr\u00eda dinero para pagar las n\u00f3minas del Estado, y lo cierto es que al tercer mes de implementar dichas reformas las recaudaciones, se duplicaron.<\/p>\n\n\n\n<p>El vicepresidente de la CREES dijo que el actual es un ambiente totalmente diferente, con una administraci\u00f3n tributaria distinta y m\u00e1s capacitada.<\/p>\n\n\n\n<p>El profesional de la econom\u00eda insisti\u00f3 que la propuesta que formula el CREES, contrario a lo que sucedi\u00f3 con la reforma 253-2012 que es la m\u00e1s reciente que se ha hecho, le garantiza al gobierno, en el primer a\u00f1o, un incremento de hasta 1.5% del PIB, siendo conservador.<\/p>\n\n\n\n<p>Agreg\u00f3 que la discusi\u00f3n y aprobaci\u00f3n de la reforma tributaria, que ya el presidente Luis Abinader ha comenzado a socializar con distintos sectores de la vida nacional, tiene que ser discutida y aprobada para que entre en vigencia con el Presupuesto del 2025.<\/p>\n\n\n\n<p>\u201cEsta propuesta, contrario a la llamada reforma 253-12, que tengo que referirme obligatoriamente porque es el referente m\u00e1s reciente que tenemos, tiene la vocaci\u00f3n de incrementar la Presi\u00f3n Tributaria entre 1.3 a 1.5%, en el primer a\u00f1o, hablando de manera conservadora, no hay que esperar al tercero, es decir, dicho incremento se lograr\u00eda en el 2025, porque se estar\u00eda ampliando las bases\u201d, reiter\u00f3.<\/p>\n\n\n\n<p><strong>ALTA EVASI\u00d3N<\/strong><\/p>\n\n\n\n<p>Explic\u00f3 que en la actualidad hay un 43% de evasi\u00f3n fiscal del ITBIS y un 62% del Impuesto Sobre la Renta, pero la clave est\u00e1 en que el sistema se est\u00e1 prestando a mucha evasi\u00f3n y elusi\u00f3n.<\/p>\n\n\n\n<p>Miguel Collado &nbsp;record\u00f3 que quien cre\u00f3 el Impuesto del Valor Agregado (IVA), en Francia, dijo que el c\u00e1ncer de ese tributo son las exenciones.<\/p>\n\n\n\n<p>\u201cTener cohabitando en un establecimiento bienes al 18%, al 16%, y bienes exentos, no a tasa cero, exentos totalmente, hay unos vasos comunicantes que se prestan a muchas cosas, entonces, para lograr la eficiencia tributaria y la sostenibilidad, poder desmontar esos impuestos que mencionaba anteriormente, si se ampl\u00eda la base del IVA, que en este caso se le llama correctamente, se va a lograr mucha eficiencia recaudatoria\u201d, detall\u00f3 Collado.<\/p>\n\n\n\n<p>Recalc\u00f3 que para lograr esos objetivos hay que bajar las tasas, \u201chaciendo m\u00e1s amigable la tasa del Impuesto Sobre la Renta, y la misma del IVA, se va a tener un Sistema Tributario menos propenso a la evasi\u00f3n y la elusi\u00f3n, y se har\u00e1 m\u00e1s f\u00e1cil incluir personas que en la actualidad se encuentran en la informalidad\u201d.<\/p>\n\n\n\n<p>Collado dijo que eso, tambi\u00e9n permitir\u00eda un incremento de los ingresos de la Seguridad Social, y habr\u00e1 m\u00e1s inversiones como consecuencia de la formalidad, con mejores puestos de trabajo, en mejor cuant\u00eda, de m\u00e1s calidad y, por ende, m\u00e1s productivo.<\/p>\n\n\n\n<p>\u201cYo s\u00e9 que es un poco dif\u00edcil de entender, lo es, y estamos bastante claro, el trabajo de nosotros como instituci\u00f3n es tratar de convencer que hay algo diferente que, incluso, funcion\u00f3 en Rep\u00fablica Dominicana, y Francisco Ca\u00f1ahuate quien est\u00e1 colaborando con el CREES fue una figura importante en la reforma de principio de los a\u00f1os 90\u201d, aclar\u00f3.<\/p>\n\n\n\n<p>El profesional de la econom\u00eda sostuvo que, tambi\u00e9n, se necesitan otras reformas estructurales entre ellas la del C\u00f3digo Laboral.<\/p>\n\n\n\n<p><strong>Miguel Collado plantea reducci\u00f3n ITBIS a 10%, ISR 18% y eliminaci\u00f3n otros impuestos distorsionadores<\/strong><\/p>\n\n\n\n<p>Miguel Collado Di Franco inform\u00f3 que la propuesta que tiene ese centro de investigaci\u00f3n contempla una transformaci\u00f3n fiscal que implicar\u00eda la reducci\u00f3n del Impuesto Sobre la Renta hasta llegar a una tasa del 18%, y en el caso del ITBIS bajarlo al 10%, ampliando la base impositiva.<\/p>\n\n\n\n<p>\u201cEn el caso del Impuesto Sobre la Renta, la propuesta ser\u00eda llegar a una tasa de 18%, que estar\u00eda por debajo de la Tasa Efectiva de Tributaci\u00f3n, porque el enfoque fiscalista establece que no ese puede estar muy distanciado de esa tasa, y esa Tasa Efectiva de Tributaci\u00f3n en Rep\u00fablica Dominicana oscila entre el 16 al 17%, con un incumplimiento tributario que supera el 60%, sin incluir las exenciones\u201d, indic\u00f3 Collado.<\/p>\n\n\n\n<p>El vicepresidente ejecutivo del CREES, agreg\u00f3 que esa es una forma de lograr esos prop\u00f3sitos, que son varios, entre ellos, sostenibilidad fiscal, y los temas relativos, a los incentivos, evasi\u00f3n y elusi\u00f3n, con la finalidad de atraer m\u00e1s inversiones.<\/p>\n\n\n\n<p><strong>REDUCIR LA INFORMALIDAD<\/strong><\/p>\n\n\n\n<p>Dijo que esa transformaci\u00f3n fiscal debe reducir la informalidad, la evasi\u00f3n de aquellos que est\u00e1n en la formalidad y declaran menos, y la elusi\u00f3n que es acogerse a lo que permite el C\u00f3digo Tributario para disminuir la carga impositiva.<\/p>\n\n\n\n<p>\u201cEn el caso del IVA (ITBIS), si tu quieres un sistema m\u00e1s eficiente en t\u00e9rminos recaudatorios, y quiere evitar las evasiones que se dan por tener altas exenciones, altas en t\u00e9rminos de volumen en ese impuesto, necesariamente, por eficiencia, para poder recaudar m\u00e1s por el IVA, lograr la bajada del Impuesto Sobre la Renta, y recaudar m\u00e1s por ese impuesto, tiene que ampliar la base del ITBIS, pero bajarlo al 10% que, ahora mismo, es similar a la Base de Tributaci\u00f3n\u201d, detall\u00f3.<\/p>\n\n\n\n<p>Miguel Collado dijo que esas transformaciones deber\u00edan hacerse en tres a\u00f1os para ir desmontando esos impuestos, y ampliando las bases para llegar a un IVA del 18 y 16%, que tenemos ahora, al 10%, para ir agregando bienes a las bases en ese periodo de tiempo, hasta llegar a la meta anteriormente citada.<\/p>\n\n\n\n<p>Aclar\u00f3 que a eso hay que agregar la eliminaci\u00f3n de impuestos distorsionadores como el que graba los ingresos de los ahorros, la doble tributaci\u00f3n como el que graba la renta y los dividendos, el impuesto a los cheques y transferencias bancarias, y la distorsi\u00f3n en el impuesto a los seguros.<\/p>\n\n\n\n<p><strong>Dice hay que romper c\u00edrculo vicioso de parches fiscales para seguir incrementando el gasto<\/strong><\/p>\n\n\n\n<p>El vicepresidente ejecutivo del CREES es de opini\u00f3n que en el pa\u00eds se debe aprobar la Ley de Responsabilidad Fiscal que garantice una mejor calidad en el gasto p\u00fablico.<\/p>\n\n\n\n<p>\u201cEs imprescindible que rompamos el c\u00edrculo vicioso que tenemos en Rep\u00fablica Dominicana, que se hacen parches fiscales para extraer m\u00e1s recursos de los contribuyentes, pero se incrementa el gasto, entonces, seguimos con los d\u00e9ficits, y se vuelve a la discusi\u00f3n de que hay que hacer una nueva reforma\u201d, deplor\u00f3 Miguel Collado.<\/p>\n\n\n\n<p>Agreg\u00f3 que, bajo ese esquema, se sigue la carrera de endeudamiento, o por la parte administrativa se siguen haciendo modificaciones, aunque no se haga por una ley, se piden adelantos, pero, ese c\u00edrculo vicioso hay que romperlo.<\/p>\n\n\n\n<p>\u201cEntonces, por eso se hace necesario una reforma por la parte tributaria que sea sostenible, pero necesitamos orden en la parte de las finanzas p\u00fablicas en lo relacionado, no solamente con el gasto, como propone la Ley de Responsabilidad Fiscal sometida por el ministerio de Hacienda, que busca limitar el gasto primario, sino, tambi\u00e9n, de d\u00e9ficit fiscal\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Collado dijo que el CREES es de opini\u00f3n que con un crecimiento holgado que permita al gobierno ejercer sus funciones, con la reforma tributaria que est\u00e1n proponiendo, en cuatro a\u00f1os podr\u00eda haber un super\u00e1vit fiscal, y al tercer a\u00f1o se podr\u00eda estar acercando al equilibrio.<\/p>\n\n\n\n<p>\u201cA eso es que debemos aspirar, hay que tener cuidado, porque si lo que queremos es extraer m\u00e1s recursos de los contribuyentes para seguir gastando, vamos a seguir en ese c\u00edrculo vicioso, y en un tiempo estaremos diciendo de nuevo que hace falta otra reforma\u201d, advirti\u00f3.<\/p>\n\n\n\n<p>Explic\u00f3 que una situaci\u00f3n de ese tipo lo \u00fanico que provoca es incertidumbre en los agentes econ\u00f3micos, porque si se habla de reducir o eliminar las exenciones, pero qu\u00e9 agente econ\u00f3mico va a querer establecer en un pa\u00eds con altas tasas de impuestos, tema de electricidad, transporte entre los m\u00e1s caro de la regi\u00f3n, temas de costos laborales no salariales y, todav\u00eda, los temas de inseguridad jur\u00eddica.<\/p>\n\n\n\n<p>Fuente programa D\u00b4AGENDA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miguel Collado plantea reducci\u00f3n ITBIS a 10%, ISR 18% y eliminaci\u00f3n otros impuestos distorsionadores. Dice hay que romper c\u00edrculo vicioso de parches fiscales para seguir incrementando el gasto. El vicepresidente&hellip;<\/p>\n","protected":false},"author":2,"featured_media":83837,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[39,25],"tags":[13134,171,13137,1696,13135,1274,13136],"class_list":["post-83836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-portada","tag-crees","tag-gobierno","tag-isr","tag-itbis","tag-miguel-collado","tag-propuesta","tag-reforma-tributaria"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Miguel-Collado-Di-Franco.jpg","jetpack-related-posts":[{"id":107924,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/09\/01\/diputado-elias-wessin-presenta-iniciativas-de-reforma-fiscal-y-tributaria\/","url_meta":{"origin":83836,"position":0},"title":"Diputado El\u00edas Wessin presenta iniciativas de Reforma Fiscal y Modernizaci\u00f3n de la Administraci\u00f3n P\u00fablica","author":"Nelson Feliz","date":"1 de septiembre de 2025","format":false,"excerpt":"El diputado nacional y vice-vocero del Bloque PQDC-PRD, El\u00edas Wessin, someti\u00f3 al Congreso Nacional dos proyectos de gran trascendencia para el futuro institucional y econ\u00f3mico de la Rep\u00fablica Dominicana: 1) el Proyecto de Reforma Fiscal y Tributaria y 2) el Proyecto de Modernizaci\u00f3n de la Administraci\u00f3n P\u00fablica. Ambas iniciativas se\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Elias-Wessin-Chavez-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Elias-Wessin-Chavez-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Elias-Wessin-Chavez-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/Elias-Wessin-Chavez-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":114199,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/11\/11\/leonel-en-favor-de-los-trabajadores-exige-indexacion-el-salario-no-debe-ser-botin-del-fisco\/","url_meta":{"origin":83836,"position":1},"title":"Leonel en favor de los trabajadores: exige indexaci\u00f3n \u201cel salario no debe ser bot\u00edn del fisco\u201d","author":"Nelson Feliz","date":"11 de noviembre de 2025","format":false,"excerpt":"Durante gobiernos de Leonel Fern\u00e1ndez la indexaci\u00f3n del ISR se aplicaba sin controversias, conforme a la ley. En medio de las discusiones sobre el deterioro del poder adquisitivo de los trabajadores formales y la ausencia de ajustes al tramo exento del Impuesto Sobre la Renta (ISR), el expresidente de la\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/leonel.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/leonel.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/leonel.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/leonel.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":116071,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/11\/27\/dgii-destaca-informe-del-fmi-sobre-reduccion-del-incumplimiento-tributario-del-itbis\/","url_meta":{"origin":83836,"position":2},"title":"DGII destaca informe del FMI sobre reducci\u00f3n del incumplimiento tributario del Itbis","author":"Nelson Feliz","date":"27 de noviembre de 2025","format":false,"excerpt":"El informe identifica los sectores econ\u00f3micos con mayores niveles de incumplimiento, entre ellos construcci\u00f3n-comercio, hoteles-restaurantes y servicios profesionales. El Fondo Monetario Internacional (FMI) junto con la Direcci\u00f3n General de Impuestos Internos (DGII) dieron a conocer un informe que determina mejoras significativas en el desempe\u00f1o del Impuesto sobre Transferencias de Bienes\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/DGII.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/DGII.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/DGII.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/DGII.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":113871,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/11\/06\/la-propuesta-para-indexar-los-salarios-es-populista-y-politiquera-segun-diputados-del-prm\/","url_meta":{"origin":83836,"position":3},"title":"La propuesta para indexar los salarios es populista y politiquera, seg\u00fan diputados del PRM","author":"Nelson Feliz","date":"6 de noviembre de 2025","format":false,"excerpt":"El senador Omar Fern\u00e1ndez propuso aplicar el C\u00f3digo Tributario en el presupuesto del 2026 para ajustar los impuestos de los salarios. Diputados oficialistas del Partido Revolucionario Moderno (PRM) calificaron como una propuesta \"politiquera\" y \"populista\" la iniciativa del senador Omar Fern\u00e1ndez para aplicar la indexaci\u00f3n salarial establecida en la ley\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/camara-diputados.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/camara-diputados.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/camara-diputados.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/camara-diputados.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":116495,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/12\/01\/abinader-dice-que-no-existe-un-plan-para-someter-una-reforma-fiscal-en-enero-de-2026\/","url_meta":{"origin":83836,"position":4},"title":"Abinader dice que no existe un plan para someter una reforma fiscal en enero de 2026","author":"Nelson Feliz","date":"1 de diciembre de 2025","format":false,"excerpt":"El presidente de la Rep\u00fablica dijo que sobre el tema ya se ha pronunciado en varias ocasiones el ministro de Hacienda, Mag\u00edn D\u00edaz. El presidente de la Rep\u00fablica, Luis Abinader, neg\u00f3 que su gobierno tenga previsto someter una reforma fiscal en enero de 2026, luego de que surgieran rumores p\u00fablicos\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Luis-Abinader-4-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Luis-Abinader-4-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Luis-Abinader-4-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Luis-Abinader-4-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":125006,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/03\/18\/temistocles-montas-el-pld-esta-preparado-para-competir-y-ganar\/","url_meta":{"origin":83836,"position":5},"title":"Tem\u00edstocles Mont\u00e1s: El PLD est\u00e1 preparado para competir y ganar","author":"Nelson Feliz","date":"18 de marzo de 2026","format":false,"excerpt":"Mont\u00e1s adelanta que en las pr\u00f3ximas elecciones esa organizaci\u00f3n, llevar\u00e1 sus propios candidatos. El vicepresidente del Partido de la Liberaci\u00f3n Dominicana (PLD), Tem\u00edstocles Mont\u00e1s adelant\u00f3 que en las pr\u00f3ximas elecciones esa organizaci\u00f3n, llevar\u00e1 sus propios candidatos tanto a nivel presidencial como municipal. \u201cSe le est\u00e1 diciendo a la militancia y\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"Tem\u00edstocles Montas","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Temistocles-Montas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Temistocles-Montas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Temistocles-Montas.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Temistocles-Montas.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=83836"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83836\/revisions"}],"predecessor-version":[{"id":83838,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/83836\/revisions\/83838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/83837"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=83836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=83836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=83836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}