{"id":85110,"date":"2024-06-22T22:58:19","date_gmt":"2024-06-23T02:58:19","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=85110"},"modified":"2024-06-22T22:58:21","modified_gmt":"2024-06-23T02:58:21","slug":"al-menos-39-personas-murieron-en-ataques-israelies-en-el-norte-de-gaza-dicen-las-autoridades","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2024\/06\/22\/al-menos-39-personas-murieron-en-ataques-israelies-en-el-norte-de-gaza-dicen-las-autoridades\/","title":{"rendered":"Al menos 39 personas murieron en ataques israel\u00edes en el norte de Gaza, dicen las autoridades"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">POR JACK JEFFERY Y WAFAA SHURAFA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DEIR AL-BALAH, Franja de Gaza (AP) \u2014 Al menos 39 personas murieron el s\u00e1bado por ataques israel\u00edes en el norte de Gaza, mientras los trabajadores de rescate se apresuraban a encontrar sobrevivientes bajo los escombros, seg\u00fan funcionarios palestinos y hospitalarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fadel Naem, director del Hospital al-Ahli en la ciudad de Gaza, dijo a The Associated Press que m\u00e1s de tres docenas de cad\u00e1veres llegaron al hospital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Defensa Civil Palestina, un grupo de emergencia activo en Gaza, dijo que sus trabajadores de emergencia estaban excavando en busca de sobrevivientes en el lugar de un ataque en el campo de refugiados de Shati, al oeste de la ciudad de Gaza, y que hab\u00edan retirado varias docenas de cad\u00e1veres de un edificio atacado por un israel\u00ed ataque en un barrio oriental de la ciudad de Gaza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Israel dijo el s\u00e1bado que sus aviones de combate atacaron dos sitios militares de Hamas en el \u00e1rea de la ciudad de Gaza, pero no dio m\u00e1s detalles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las muertes se producen un d\u00eda despu\u00e9s de que al menos 25 personas murieran en ataques a campamentos de tiendas y 50 resultaran heridas cerca de la ciudad sure\u00f1a de Rafah.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Israel dijo el s\u00e1bado que continuaba operando en el centro y sur de Gaza y que hab\u00eda seguido adelante con su invasi\u00f3n de Rafah, donde m\u00e1s de un mill\u00f3n de palestinos hab\u00edan buscado refugio de los combates en otros lugares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda ha huido de la ciudad, pero las Naciones Unidas dicen que ning\u00fan lugar en Gaza es seguro y que las condiciones humanitarias son terribles, ya que las familias se refugian en tiendas de campa\u00f1a y apartamentos hacinados sin alimentos, agua ni suministros m\u00e9dicos adecuados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un ataque israel\u00ed separado el s\u00e1bado en el valle oriental de Bekaa en el L\u00edbano mat\u00f3 a un miembro del ala militar de al-Jamaa al-Islamiya, o Grupo Isl\u00e1mico, una facci\u00f3n musulmana sunita estrechamente aliada de Ham\u00e1s, seg\u00fan el grupo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El miembro fue el s\u00e9ptimo muerto por ataques israel\u00edes en el L\u00edbano desde que comenz\u00f3 la guerra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La guerra entre Israel y Hamas estall\u00f3 el 7 de octubre, cuando militantes de Hamas que atacaron el sur de Israel mataron a unas 1.200 personas y tomaron como rehenes a unas 250 m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Israel ha respondido bombardeando e invadiendo el enclave, matando a m\u00e1s de 37.400 palestinos all\u00ed, seg\u00fan el Ministerio de Salud de Gaza, que no distingue entre combatientes y civiles en su recuento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n el s\u00e1bado, el ej\u00e9rcito de Israel dijo que un hombre israel\u00ed fue asesinado a tiros en la ciudad de Qalqilya, en el norte de Cisjordania , donde las fuerzas israel\u00edes mataron a tiros a dos militantes el viernes, el \u00faltimo estallido de violencia en el territorio desde que estall\u00f3 la guerra entre Israel y Hamas .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al menos 549 palestinos en el territorio han muerto por fuego israel\u00ed desde que comenz\u00f3 la guerra, seg\u00fan el Ministerio de Salud palestino, que rastrea los asesinatos. Durante el mismo per\u00edodo, los palestinos en Cisjordania han matado al menos a nueve israel\u00edes, incluidos cinco soldados, seg\u00fan datos de la ONU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ciudadanos israel\u00edes tienen prohibido ingresar a Qalqilya y otras \u00e1reas de Cisjordania que est\u00e1n bajo el control de la Autoridad Palestina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En abril, la muerte de un colono israel\u00ed de 14 a\u00f1os desat\u00f3 una serie de ataques de colonos contra ciudades palestinas del territorio. El ej\u00e9rcito dijo que m\u00e1s tarde arrestaron a un palestino en relaci\u00f3n con el asesinato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El s\u00e1bado, el Ministerio de Salud palestino dijo que un ni\u00f1o palestino de 12 a\u00f1os muri\u00f3 a causa de las heridas tras recibir un disparo de las fuerzas israel\u00edes en Ramallah la semana pasada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al comentar sobre el tiroteo, el ej\u00e9rcito israel\u00ed dijo que sus fuerzas allanaron el campo de refugiados de al-Amari cerca de Ramallah para arrestar a un sospechoso el viernes y luego abrieron fuego contra un grupo de palestinos que les arrojaban piedras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Israel dijo el s\u00e1bado que estaba investigando un incidente separado sobre la conducta de sus soldados despu\u00e9s de que apareci\u00f3 en l\u00ednea un video que mostraba a un palestino herido siendo transportado sobre el cap\u00f3 de un veh\u00edculo blindado israel\u00ed en el norte de Cisjordania.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ej\u00e9rcito dijo que el hombre en el video era un sospechoso buscado y result\u00f3 herido durante un intercambio de disparos entre militantes palestinos y fuerzas israel\u00edes cerca de la ciudad de Jenin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hombre estaba siendo transportado a una ambulancia de la Media Luna Roja situada cerca, dijo. El ej\u00e9rcito dijo que la conducta en el v\u00eddeo no \u201cse ajustaba a los valores\u201d del ej\u00e9rcito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ira en todo el pa\u00eds est\u00e1 creciendo por el manejo del gobierno de la guerra en Gaza y la crisis de los rehenes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El s\u00e1bado, decenas de miles de personas se manifestaron en Tel Aviv pidiendo nuevas elecciones y que el gobierno devuelva a los rehenes a casa. Entre las familias se encontraban los padres de Naama Levy, una soldado israel\u00ed que cumpli\u00f3 20 a\u00f1os en cautiverio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POR JACK JEFFERY Y WAFAA SHURAFA DEIR AL-BALAH, Franja de Gaza (AP) \u2014 Al menos 39 personas murieron el s\u00e1bado por ataques israel\u00edes en el norte de Gaza, mientras los&hellip;<\/p>\n","protected":false},"author":2,"featured_media":85111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[5605,949,8301,686,13747],"class_list":["post-85110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-ataques","tag-autoridades","tag-israelies","tag-muertos","tag-norte-de-gaza"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/muertos.jpg","jetpack-related-posts":[{"id":84325,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/06\/06\/un-ataque-israeli-mata-al-menos-a-33-personas-en-una-escuela-de-gaza\/","url_meta":{"origin":85110,"position":0},"title":"Un ataque israel\u00ed mata al menos a 33 personas en una escuela de Gaza","author":"Nelson Feliz","date":"6 de junio de 2024","format":false,"excerpt":"POR WAFAA SHURAFA Y SAMY MAGDY DEIR AL-BALAH, Franja de Gaza (AP) \u2014 Un ataque israel\u00ed la madrugada del jueves contra una escuela que albergaba a palestinos desplazados en el centro de Gaza mat\u00f3 a m\u00e1s de 30 personas, entre ellas 23 mujeres y ni\u00f1os, seg\u00fan funcionarios de salud locales.\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/ATAQUE.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/ATAQUE.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/ATAQUE.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/ATAQUE.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":63967,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/17\/los-bombardeos-israelies-en-gaza-matan-a-decenas-de-personas\/","url_meta":{"origin":85110,"position":1},"title":"Los bombardeos israel\u00edes en Gaza matan a decenas de personas","author":"Nelson Feliz","date":"17 de octubre de 2023","format":false,"excerpt":"POR NAJIB JOBAIN, SAMYA KULLAB Y RAVI NESSMAN KHAN YOUNIS, Franja de Gaza (AP) \u2014 Israel bombarde\u00f3 el martes zonas del sur de Gaza a donde hab\u00eda dicho a los palestinos que huyeran antes de una invasi\u00f3n prevista, matando a decenas de personas. Mientras tanto, los mediadores luchaban por salir\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"BOMBARDEOS","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/BOMBARDEOS.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/BOMBARDEOS.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/BOMBARDEOS.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":78340,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/03\/15\/palestinos-asesinados-mientras-esperaban-ayuda-en-gaza-dice-el-ministerio-de-salud\/","url_meta":{"origin":85110,"position":2},"title":"Palestinos asesinados mientras esperaban ayuda en Gaza, dice el Ministerio de Salud","author":"BIMARY DE JES\u00daS Matos","date":"15 de marzo de 2024","format":false,"excerpt":"Gaza.-Mientras palestinos hac\u00edan fila en Gaza el viernes para recibir ayuda, dos ataques israel\u00edes mataron a decenas de civiles, seg\u00fan Ham\u00e1s. El Ej\u00e9rcito de Israel dijo que estaba investigando los dos incidentes. Mientras palestinos hac\u00edan fila para recibir ayuda en Gaza el viernes temprano, dos ataques israel\u00edes, uno en el\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":97805,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/28\/ataques-israelies-en-gaza-matan-al-menos-a-27-palestinos\/","url_meta":{"origin":85110,"position":3},"title":"Ataques israel\u00edes en Gaza matan al menos a 27 palestinos","author":"Nelson Feliz","date":"28 de abril de 2025","format":false,"excerpt":"POR WAFAA SHURAFA and SAMY MAGDY DEIR AL-BALAH, Franja de Gaza (AP) \u2014 Los ataques israel\u00edes en la Franja de Gaza durante la noche del domingo el lunes mataron al menos a 27 palestinos, seg\u00fan funcionarios de salud locales. No hubo comentarios inmediatos por parte del Ej\u00e9rcito israel\u00ed. Israel ha\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/palestinos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/palestinos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/palestinos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/palestinos.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":67908,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/11\/20\/estallan-intensos-combates-alrededor-de-otro-hospital-de-gaza\/","url_meta":{"origin":85110,"position":4},"title":"Estallan intensos combates alrededor de otro hospital de Gaza","author":"Nelson Feliz","date":"20 de noviembre de 2023","format":false,"excerpt":"Evac\u00faan beb\u00e9s de un hospital en el norte de Gaza en Egipto. POR NAJIB JOBAIN Y SAMY MAGDY KHAN YOUNIS, Franja de Gaza (AP) \u2014 El lunes estallaron intensos combates alrededor de un hospital en el norte de Gaza donde miles de pacientes y personas desplazadas se han refugiado durante\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"BOMBARDEOS","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/bombardeos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/bombardeos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/bombardeos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/11\/bombardeos.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":62782,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/10\/07\/se-eleva-a-a-mas-de-300-el-numero-de-israelies-fallecidos-tras-el-ataque-de-hamas\/","url_meta":{"origin":85110,"position":5},"title":"Se eleva a a m\u00e1s de 300 el n\u00famero de israel\u00edes fallecidos tras el ataque de Ham\u00e1s","author":"Nelson Feliz","date":"7 de octubre de 2023","format":false,"excerpt":"La cifra de fallecidos podr\u00eda aumentar en las pr\u00f3ximas horas, dada la gravedad de algunos de los heridos. M\u00e1s de 300 ciudadanos israel\u00edes han muerto como consecuencia del ataque llevado a cabo el s\u00e1bado desde la Franja de Gaza por el grupo islamista Ham\u00e1s contra el territorio de Israel, informaron\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"La gente eval\u00faa la destrucci\u00f3n causada por los ataques a\u00e9reos israel\u00edes en la ciudad de Gaza el 7 de octubre de 2023. Militantes palestinos han comenzado una \"guerra\" contra Israel, en la que se infiltraron por aire, mar y tierra desde la bloqueada Franja de Gaza.AFP\/ MOHAMMED ABED","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Ataques.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Ataques.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Ataques.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/Ataques.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=85110"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85110\/revisions"}],"predecessor-version":[{"id":85112,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/85110\/revisions\/85112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/85111"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=85110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=85110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=85110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}