{"id":86004,"date":"2024-07-14T21:09:49","date_gmt":"2024-07-15T01:09:49","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=86004"},"modified":"2024-07-14T21:09:50","modified_gmt":"2024-07-15T01:09:50","slug":"rechazan-aumento-de-impuestos-en-north-bergen","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2024\/07\/14\/rechazan-aumento-de-impuestos-en-north-bergen\/","title":{"rendered":"Rechazan aumento de impuestos en North Bergen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por Vicente Balbuena<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Residentes de la ciudad de North Bergen en New Jersey, rechazaron el aumento de un 10% a los impuestos vigentes, por parte del alcalde Nicholas Sacco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El comunicador dominicano, Erick Estrella, quien habl\u00f3 en representaci\u00f3n de los afectados, record\u00f3 que anteriormente los pobladores de dicha localidad, hab\u00edan sido sentenciados a un impuesto de 128 d\u00f3lares en desmedro de los propietarios de viviendas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Calific\u00f3 de desafortunado e improcedente, la aplicaci\u00f3n de dicho impuesto, ya que a su juicio, la medida reduce el poder adquisitivo econ\u00f3mico per c\u00e1pita de las familias, desmejorando su calidad de vida, al tiempo de revelar que la alcald\u00eda, que preside Sacco, tiene un presupuesto disponible de 116.1 millones, suficientes para cubrir las necesidades de demandas de la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;El aumento de impuestos del 9.7%, equivalente a 570 d\u00f3lares para los due\u00f1os de casas en tasaci\u00f3n promedio, se atribuye a un aumento en los costos de pensiones y atenci\u00f3n m\u00e9dica de los empleados del cabildo, as\u00ed como una ca\u00edda en la ayuda estatal en el presupuesto aprobado la semana pasada, la cual se redujo a 2 millones de d\u00f3lares&#8221;, refiri\u00f3 Estrella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el denunciante de la comunidad, el plan de gasto general ser\u00eda de 1.4 millones de d\u00f3lares, m\u00e1s que el a\u00f1o pasado, pero la carga para los propietarios de viviendas aumentaron significativamente de 67.7 a 74.2 millones de d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con relaci\u00f3n el aumento se program\u00f3 una audiencia presupuestaria, como parte de la reuni\u00f3n de la Junta de Comisionados de North Bergen, pautada para este mi\u00e9rcoles 17 de julio a las 11 de la ma\u00f1ana en el Township Hall.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se inform\u00f3 que la asignaci\u00f3n de ayuda estatal de North Bergen fue de 8 millones, menor en el presente 2024, que el pasado 2023. &#8220;Si esa cifra se hubiera mantenido igual, el municipio habr\u00eda visto un aumento de impuestos insignificantes en el presupuesto actual&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La preocupaci\u00f3n se ha apoderado de la poblaci\u00f3n, la que espera que el aumento de impuestos sea revisado este mi\u00e9rcoles, y se respete la voluntad de la mayor\u00eda, dejando sin efecto la pretensi\u00f3n de Sacco.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Vicente Balbuena Residentes de la ciudad de North Bergen en New Jersey, rechazaron el aumento de un 10% a los impuestos vigentes, por parte del alcalde Nicholas Sacco. El&hellip;<\/p>\n","protected":false},"author":2,"featured_media":86005,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[39],"tags":[292,13945,2502,14092],"class_list":["post-86004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-aumento","tag-erick-estrella","tag-impuestos","tag-north-bergen"],"jetpack-related-posts":[{"id":85606,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/07\/03\/estrella-informa-alcalde-de-north-bergen-pretende-mutilar-parque\/","url_meta":{"origin":86004,"position":0},"title":"Estrella informa alcalde de North Bergen pretende mutilar parque","author":"Nelson Feliz","date":"3 de julio de 2024","format":false,"excerpt":"Por Vicente Balbuena New Jersey.- El reconocido corresponsal de radio y televisi\u00f3n, Erick Estrella, inform\u00f3 que el alcalde de la ciudad de North Bergen, Nicholas Sacco, pretende mutilar el \u00e1rea terrenal del parque de esa importante localidad. Estrella, al ser entrevistado v\u00eda\u00a0telef\u00f3nica\u00a0en el programa, \"Espont\u00e1neamente\", que produce y conduce, Omar\u2026","rel":"","context":"En \u00abENTRETENIMIENTO\u00bb","block_context":{"text":"ENTRETENIMIENTO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/entretenimiento\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/07\/Erick-Estrella.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":97287,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/18\/venecia-amplia-su-programa-de-impuestos-a-visitantes-para-combatir-el-exceso-de-turismo\/","url_meta":{"origin":86004,"position":1},"title":"Venecia ampl\u00eda su programa de impuestos a visitantes para combatir el exceso de turismo","author":"Nelson Feliz","date":"18 de abril de 2025","format":false,"excerpt":"POR COLLEEN BARRY VENECIA, Italia (AP) \u2014 A partir del viernes, Venecia cobrar\u00e1, por segundo a\u00f1o consecutivo, un impuesto de llegada a los turistas que visitan por un d\u00eda la famosa ciudad de los canales, una medida para combatir el exceso de turismo que, seg\u00fan las autoridades, pone en riesgo\u2026","rel":"","context":"En \u00abTURISMO\u00bb","block_context":{"text":"TURISMO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/turismo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/venecia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/venecia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/venecia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/venecia.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":97999,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/30\/hawai-planea-aumentar-el-impuesto-hotelero-para-afrontar-el-cambio-climatico\/","url_meta":{"origin":86004,"position":2},"title":"Haw\u00e1i planea aumentar el impuesto hotelero para afrontar el cambio clim\u00e1tico","author":"Nelson Feliz","date":"30 de abril de 2025","format":false,"excerpt":"Por AUDREY McAVOY HONOLULU (AP) \u2014 En una medida pionera, los legisladores de Haw\u00e1i est\u00e1n listos para aumentar un impuesto aplicado a los viajeros que se alojan en hoteles, alquileres vacacionales y otros alojamientos de corto plazo y destinar el nuevo dinero a programas para enfrentar el calentamiento del planeta.\u2026","rel":"","context":"En \u00abTURISMO\u00bb","block_context":{"text":"TURISMO","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/turismo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Hawai.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Hawai.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Hawai.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Hawai.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":122678,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/02\/20\/alcalde-nyc-subir-impuestos-a-la-propiedad-si-no-se-aumenta-impuestos-a-los-mas-ricos-dominicanos-se-afectarian\/","url_meta":{"origin":86004,"position":3},"title":"Alcalde NYC: Subir impuestos a la propiedad si no se aumenta impuestos a los m\u00e1s ricos; dominicanos se afectar\u00edan","author":"Nelson Feliz","date":"20 de febrero de 2026","format":false,"excerpt":"Por Ram\u00f3n Mercedes NUEVA YORK.- Miles de dominicanos, entre otras etnias, propietarios de diferentes negocios en esta ciudad, ser\u00edan afectados si se cumple la advertencia del alcalde Zohran Mamdani de que se ver\u00e1 obligado a subir los impuestos a la propiedad para paliar el d\u00e9ficit presupuestario de la Gran Manzana\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/02\/IMG-20260220-WA0073.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/02\/IMG-20260220-WA0073.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/02\/IMG-20260220-WA0073.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":90138,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/10\/13\/gregorio-morrobel-advierte-reforma-afecta-negativamente-a-la-diaspora\/","url_meta":{"origin":86004,"position":4},"title":"Gregorio Morrobel advierte reforma afecta &#8220;negativamente&#8221; a la di\u00e1spora","author":"Nelson Feliz","date":"13 de octubre de 2024","format":false,"excerpt":"Por JHONNY TRINIDAD El presidente del partido Fuerza del Pueblo (FP) en Manhattan, Gregorio Morrobel, critic\u00f3 el proyecto de Ley de Modernizaci\u00f3n Fiscal enviado al Congreso Nacional por el presidente Luis Abinader para aumentar los ingresos del Estado. Dijo que el proyecto crea un Impuesto a la Propiedad, lo que\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/Morrobel.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/Morrobel.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/Morrobel.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/Morrobel.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":87865,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/08\/18\/carlos-pena-define-discurso-de-abinader-como-plagio-y-pieza-apologetica-para-aumentar-impuestos\/","url_meta":{"origin":86004,"position":5},"title":"Carlos Pe\u00f1a define discurso de Abinader como plagio y pieza apolog\u00e9tica para aumentar impuestos","author":"Nelson Feliz","date":"18 de agosto de 2024","format":false,"excerpt":"El presidente del Partido Generaci\u00f3n de Servidores (GenS), Carlos Pe\u00f1a consider\u00f3 que el discurso de Lu\u00eds Abinader, adem\u00e1s de ser un plagio al pastor Martin Luther King en su alocuci\u00f3n hist\u00f3rica \u201cYo tengo un sue\u00f1o\u201d, fue una pieza apolog\u00e9tica a sus intenciones de aumentarle los impuestos al pueblo dominicano. Pe\u00f1a,\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"Carlos Pe\u00f1a","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Carlos-Pena.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Carlos-Pena.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Carlos-Pena.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Carlos-Pena.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/07\/Erick-Estrella-1.jpg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/86004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=86004"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/86004\/revisions"}],"predecessor-version":[{"id":86006,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/86004\/revisions\/86006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/86005"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=86004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=86004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=86004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}