{"id":86319,"date":"2024-07-22T23:14:22","date_gmt":"2024-07-23T03:14:22","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=86319"},"modified":"2024-07-22T23:14:23","modified_gmt":"2024-07-23T03:14:23","slug":"presidente-abinader-presenta-avances-de-inabie-en-la-semanal","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2024\/07\/22\/presidente-abinader-presenta-avances-de-inabie-en-la-semanal\/","title":{"rendered":"Presidente Abinader presenta avances de INABIE en LA Semanal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Alimentaci\u00f3n, salud visual, bucal y auditiva, \u00fatiles escolares y uniformes.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente Luis Abinader inform\u00f3 este lunes que el Instituto Nacional de Bienestar Estudiantil, INABIE, ha trabajado incansablemente en esta gesti\u00f3n de gobierno para mejorar la calidad de vida de los estudiantes dominicanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a los diferentes programas, se ha logrado impactar positivamente la alimentaci\u00f3n y la salud visual, bucal y auditiva de ni\u00f1os y j\u00f3venes, a quienes adem\u00e1s se les contin\u00faa entregando \u00fatiles escolares y uniformes para que puedan acceder a la educaci\u00f3n en igualdad de condiciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma, el presidente agreg\u00f3 que gracias a la implementaci\u00f3n del Programa de Alimentaci\u00f3n Escolar (PAE), en el pa\u00eds se ha reducido la pobreza monetaria en 4.4 puntos porcentuales entre 2022 y 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Raciones alimenticias<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este \u00faltimo a\u00f1o escolar, correspondiente al per\u00edodo 2023-2024, se han entregado m\u00e1s de 966 millones de raciones alimenticias distribuidas de la siguiente manera: m\u00e1s de 312 millones de raciones de pan y galletas nutritivas, m\u00e1s de 349 millones de raciones de leche y preparado l\u00e1cteo y m\u00e1s de 2.9 millones de raciones de frutas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el almuerzo escolar se han entregado m\u00e1s de 269 millones para la jornada extendida, m\u00e1s de 26 millones en las modalidades PAE Rural y otros, m\u00e1s de 3.8 millones para el programa Prepara y m\u00e1s de 469 mil para el programa Oportunidad 14-24.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, en este \u00faltimo a\u00f1o escolar se han servido 71 millones de litros de leche para el desayuno, brindado apoyo directo a los ganaderos y alcanzando por primera vez que el 100% de la leche sea de producci\u00f3n nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas informaciones las ofreci\u00f3 el jefe de Estado durante LA Semanal con la Prensa realizada en el sal\u00f3n Las Cari\u00e1tides del Palalacio Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aumento de las inspecciones<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario inform\u00f3 tambi\u00e9n que se han realizado m\u00e1s de 21 mil supervisiones de an\u00e1lisis de laboratorio y fiscalizaciones de estas raciones durante el periodo escolar 2023-2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mejora en la alimentaci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas mejor\u00edas continuar\u00e1n aplic\u00e1ndose en el pr\u00f3ximo a\u00f1o escolar 2024-2025 con un plan piloto que entregar\u00e1 2.9 millones de raciones de frutas frescas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los beneficios de este plan ser\u00e1n: la reducci\u00f3n de sodio de 300% a 88% del requerimiento diet\u00e9tico diario, la eliminaci\u00f3n de 18 millones de libras de az\u00facar al retirar el n\u00e9ctar que se ofrec\u00eda en la merienda y la disminuci\u00f3n en el consumo de grasas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fortalecimiento de la ley<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s dijo que con esto, se est\u00e1 cumpliendo el art\u00edculo 177 de la Ley 66-97 que ordena ofrecer servicios de salud escolar con la instalaci\u00f3n de m\u00f3dulos fijos en la sede, el aumento de las jornadas de salud en diversos puntos del pa\u00eds y de la cantidad de m\u00f3dulos de salud bucal en escuelas, as\u00ed como con el incremento de lentes, medicamentos de alto costo, intervenciones bucales y dispositivos auditivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salud escolar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salud visual<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a la salud visual, el mandatario expres\u00f3 que ya se han beneficiado 146,420 personas y 9,056 personas con lentes oftalmol\u00f3gicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precis\u00f3 que por cada lente oftalmol\u00f3gico los beneficiarios se ahorraron de RD$4,500 a RD$11,500.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salud auditiva<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respecto a la salud auditiva, el jefe de Estado dijo que se beneficiaron 12,245 personas y con auxiliares auditivos 1,587.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del mismo modo, se\u00f1al\u00f3 que fueron atendidos 254 ni\u00f1os de INAIPI. Con todo esto se logr\u00f3 RD$75 mil de ahorro por cada auditivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salud bucal<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente Abinader sostuvo que en salud bucal hubo 102,888 beneficiarios, 668,368 intervenciones bucales y 960 ni\u00f1os de INAIPI atendidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salud preventiva<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hubo m\u00e1s de 1.8 millones de beneficiarios de la Jornada Nacional de Desparasitaci\u00f3n y se entregaron 14 millones de medicamentos desparasitantes, manchas, hongos, piojos, virus gripales y deficiencia de vitaminas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Utiler\u00eda escolar a tiempo para todos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La utiler\u00eda escolar afirm\u00f3 que llegar\u00e1 completa y a todos, las indumentarias necesarias para ir a las aulas, de cara al pr\u00f3ximo a\u00f1o escolar 2024-2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Habr\u00e1 1.8 millones de kits para igual n\u00famero de estudiantes y m\u00e1s de 6 mil escuelas p\u00fablicas beneficiadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kits escolares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, el gobernante se\u00f1al\u00f3 que habr\u00e1 m\u00e1s de 720 mil familias beneficiadas y un ahorro por kit de RD$5,000 en polocher, pantal\u00f3n, medias, zapatos, mochilas, cuadernos, regla, l\u00e1piz y cartabones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estatus de entrada de uniformes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el a\u00f1o escolar 2024-2025, explic\u00f3 que m\u00e1s de 1,267,643 kits han sido entregados hasta la fecha y han sido impactados 4,722 centros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un 100% las provincias de Montecristi, Dajab\u00f3n, Santiago Rodr\u00edguez, El\u00edas Pi\u00f1a, Independencia, Pedernales, San Juan de la Manguana, Bahoruco, Peravia, Monse\u00f1or Nouel, Santiago, Espaillat, Mar\u00eda Trinidad S\u00e1nchez, Saman\u00e1, Hato Mayor, El Seibo, San Jos\u00e9 de Ocoa, San Crist\u00f3bal y Valverde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se han beneficiado de un 25% a 60% Barahona, Santo Domingo, Distrito Nacional, S\u00e1nchez Ram\u00edrez y San Pedro de Macor\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Impacto en la econom\u00eda 2020-204<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jefe de Estado manifest\u00f3 que se han contratado a trav\u00e9s del portal de compras y contrataciones RD$82,451 millones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un monto adjudicado a MIPYMES de m\u00e1s de RD$51 millones y el 41% del monto adjudicado a MIPYMES Mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Impacto en la agropecuaria<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed m\u00e1s de 120 millones de libras de productos agropecuarios nacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*Dinamizaci\u00f3n de la industria textil y de calzado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta con m\u00e1s de 5 millones de inversi\u00f3n en estos rubros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alimentaci\u00f3n, salud visual, bucal y auditiva, \u00fatiles escolares y uniformes. El presidente Luis Abinader inform\u00f3 este lunes que el Instituto Nacional de Bienestar Estudiantil, INABIE, ha trabajado incansablemente en esta&hellip;<\/p>\n","protected":false},"author":2,"featured_media":86320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[39,25],"tags":[1192,9338,11574,67],"class_list":["post-86319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-portada","tag-avances","tag-inabie","tag-la-semanal","tag-luis-abinader"],"jetpack-related-posts":[{"id":119081,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/01\/06\/inabie-brinda-atencion-en-salud-a-mas-de-311000-estudiantes-en-2025\/","url_meta":{"origin":86319,"position":0},"title":"INABIE brinda atenci\u00f3n en salud a m\u00e1s de 311,000 estudiantes en 2025","author":"Nelson Feliz","date":"6 de enero de 2026","format":false,"excerpt":"Las acciones impactaron a m\u00e1s de 2.1 millones de beneficiarios y contribuyeron a reducir el gasto familiar y avanzar hacia el objetivo de Hambre Cero. El Instituto Nacional de Bienestar Estudiantil (INABIE) consolid\u00f3 en 2025 su impacto social al superar por segundo a\u00f1o consecutivo, los 1,000 millones de raciones alimenticias\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"INABIE","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/INABIE.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/INABIE.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/INABIE.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/INABIE.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":106741,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/08\/18\/victor-castro-agradece-confianza-del-presidente-abinader-y-destaca-logros-para-el-bienestar-estudiantil\/","url_meta":{"origin":86319,"position":1},"title":"V\u00edctor Castro agradece confianza del presidente Abinader y destaca logros para el bienestar estudiantil","author":"Nelson Feliz","date":"18 de agosto de 2025","format":false,"excerpt":"Bajo la administraci\u00f3n de Castro se implementaron mejoras en la alimentaci\u00f3n escolar, se ampli\u00f3 la cobertura de salud a los estudiantes y se comenz\u00f3 la entrega universal de la utiler\u00eda escolar. V\u00edctor Castro se despidi\u00f3 este lunes de su cargo como director ejecutivo del Instituto Nacional de Bienestar Estudiantil agradeciendo\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/Victor-Castro.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/Victor-Castro.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/Victor-Castro.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/08\/Victor-Castro.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":103207,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/13\/inabie-impacta-a-boca-chica-con-utileria-escolar-y-atenciones-de-salud\/","url_meta":{"origin":86319,"position":2},"title":"INABIE impacta a Boca Chica con utiler\u00eda escolar y atenciones de salud","author":"Nelson Feliz","date":"13 de julio de 2025","format":false,"excerpt":"El Instituto Nacional de Bienestar Estudiantil (INABIE) encabez\u00f3 este fin de semana El Gobierno en las Provincias en el municipio de Boca Chica, donde realiz\u00f3 un acto de entrega de utiler\u00eda escolar, benefici\u00f3 a estudiantes con una jornada de salud integral y sostuvo un encuentro con autoridades locales y comunitarios,\u2026","rel":"","context":"En \u00abSALUD\u00bb","block_context":{"text":"SALUD","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/salud\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/JORNADA-DE-SALUD.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/JORNADA-DE-SALUD.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/JORNADA-DE-SALUD.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/JORNADA-DE-SALUD.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":103938,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/20\/inabie-entrega-utileria-escolar-en-el-distrito-15-03-y-lleva-servicios-de-salud\/","url_meta":{"origin":86319,"position":3},"title":"INABIE entrega utiler\u00eda escolar en el Distrito 15-03 y lleva servicios de salud","author":"Nelson Feliz","date":"20 de julio de 2025","format":false,"excerpt":"El instituto de bienestar entreg\u00f3 20,593 kits escolares en 52 centros beneficiarios del programa de Utiler\u00eda Escolar. El Instituto Nacional de Bienestar Estudiantil (INABIE) complet\u00f3 este s\u00e1bado la entrega de 20,593 kits escolares para el Distrito Educativo 15-03 durante una nueva jornada de \u201cEl Gobierno en las Provincias\u201d en el\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/SALUD.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/SALUD.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/SALUD.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/SALUD.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":81562,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/04\/22\/inabie-informa-ha-beneficiado-a-mas-de-38900-estudiantes-con-servicios-gratuitos-de-salud-integral\/","url_meta":{"origin":86319,"position":4},"title":"INABIE informa ha beneficiado a m\u00e1s de 38,900 estudiantes con servicios gratuitos de salud integral","author":"BIMARY DE JES\u00daS Matos","date":"22 de abril de 2024","format":false,"excerpt":"SANTO DOMINGO.- Durante el primer trimestre de este a\u00f1o, el Instituto Nacional de Bienestar Estudiantil (INABIE) benefici\u00f3 a un total de 38,932 estudiantes de las escuelas p\u00fablicas a nivel nacional, a trav\u00e9s de los servicios gratuitos de salud integral que se brindan a los escolares en las jornadas de salud,\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/6a0c8a05-4f4b-48f5-a1d9-1ad180753c4a-11.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/6a0c8a05-4f4b-48f5-a1d9-1ad180753c4a-11.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/6a0c8a05-4f4b-48f5-a1d9-1ad180753c4a-11.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/6a0c8a05-4f4b-48f5-a1d9-1ad180753c4a-11.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/6a0c8a05-4f4b-48f5-a1d9-1ad180753c4a-11.webp?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/6a0c8a05-4f4b-48f5-a1d9-1ad180753c4a-11.webp?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":124983,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/03\/18\/inabie-entrega-124-lentes-a-estudiantes-en-puerto-plata\/","url_meta":{"origin":86319,"position":5},"title":"INABIE entrega 124 lentes a estudiantes en Puerto Plata","author":"Nelson Feliz","date":"18 de marzo de 2026","format":false,"excerpt":"Adem\u00e1s, benefici\u00f3 a los alumnos con 2,496 medicamentos esenciales y 395 kits de higiene bucal, como parte de las acciones de salud integral de su equipo m\u00e9dico. El Instituto Nacional de Bienestar Estudiantil (INABIE) realiz\u00f3 la entrega de 124 lentes correctivos a estudiantes del Distrito Educativo 11-02, como parte de\u2026","rel":"","context":"En \u00abSALUD\u00bb","block_context":{"text":"SALUD","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/salud\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/INABIE-entrega-124-lentes-correctivos-a-estudiantes-del-Distrito-Educativo-11-02-de-Puerto-Plata.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/INABIE-entrega-124-lentes-correctivos-a-estudiantes-del-Distrito-Educativo-11-02-de-Puerto-Plata.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/INABIE-entrega-124-lentes-correctivos-a-estudiantes-del-Distrito-Educativo-11-02-de-Puerto-Plata.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/INABIE-entrega-124-lentes-correctivos-a-estudiantes-del-Distrito-Educativo-11-02-de-Puerto-Plata.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/07\/Luis-Abinader-2.jpg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/86319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=86319"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/86319\/revisions"}],"predecessor-version":[{"id":86321,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/86319\/revisions\/86321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/86320"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=86319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=86319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=86319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}