{"id":88035,"date":"2024-08-21T17:00:00","date_gmt":"2024-08-21T21:00:00","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=88035"},"modified":"2024-08-21T11:18:48","modified_gmt":"2024-08-21T15:18:48","slug":"leidy-blanco-dice-pc-favorece-disminucion-de-los-diputados","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2024\/08\/21\/leidy-blanco-dice-pc-favorece-disminucion-de-los-diputados\/","title":{"rendered":"Leidy Blanco dice PC favorece disminuci\u00f3n de los diputados"},"content":{"rendered":"\n<p>La miembro del Consejo y Coordinadora de la Unidad de An\u00e1lisis Pol\u00edtico de Participaci\u00f3n Ciudadana (PC), Leidy Blanco Garc\u00eda, expres\u00f3 que, respecto a la disminuci\u00f3n de la cantidad de diputados, plante\u00f3 que la propuesta de reforma constitucional hecha por el Poder Ejecutivo presenta oportunidades de mejora.<\/p>\n\n\n\n<p>La representante de PC, consider\u00f3 que es cuestionable que se quieran reducir los diputados en el Congreso Nacional, pero a la vez aumentar de 5 a 20 los diputados nacionales.<\/p>\n\n\n\n<p>Blanco Garc\u00eda, destac\u00f3 la falta de correlaci\u00f3n entre la poblaci\u00f3n dominicana y el n\u00famero de diputados, comparando la situaci\u00f3n de la Rep\u00fablica Dominicana con la de Costa Rica.<\/p>\n\n\n\n<p>Dijo que mientras Costa Rica, con 5.5 millones de habitantes, cuenta con 57 diputados, la Rep\u00fablica Dominicana, con 11 millones de habitantes, tiene 191 legisladores.<\/p>\n\n\n\n<p>\u201cEl congreso es un costo y sabemos que la democracia tiene un costo, pero ese costo debe ser racional a lo que espera la sociedad dominicana. No podemos seguir gastando tanto en un congreso que no retribuye en eso que nosotros gastamos\u201d, expres\u00f3 Blanco Garc\u00eda.<\/p>\n\n\n\n<p>Precis\u00f3 que, aunque los diputados nacionales deber\u00edan garantizar mayor pluralidad, nivel de democracia y participaci\u00f3n de los partidos minoritarios, en la pr\u00e1ctica esto no se cumple ya que actualmente de los 5 diputados nacionales que existen solo uno representa un partido mayoritario.<\/p>\n\n\n\n<p>Deplor\u00f3 que los mismos no sean electos por el voto popular, sino por \u201cel dedo\u201d a conveniencia de los partidos pol\u00edticos. \u201cNo podemos cambiar el voto directo por una designaci\u00f3n. Eso debe quedar claro\u201d, se\u00f1aliz\u00f3.<\/p>\n\n\n\n<p>La representante de Participaci\u00f3n Ciudadana, abog\u00f3 por la eliminaci\u00f3n del Parlamento Centroamericano (Parlacen), se\u00f1alando que esta reforma constitucional habr\u00eda sido una excelente oportunidad para suprimir de una vez por todas esta entidad, que considera \u201csolo representa un gasto para el Estado y de apoyo para la impunidad\u201d.<\/p>\n\n\n\n<p>En cuanto a la unificaci\u00f3n de las elecciones, expres\u00f3 su preferencia por mantener la separaci\u00f3n de los comicios, como estaba establecido anteriormente, con dos a\u00f1os de diferencia entre las elecciones congresuales y municipales, y las presidenciales.<\/p>\n\n\n\n<p>Leidy Blanco Garc\u00eda, agreg\u00f3 que, si se desea reducir el elevado costo de las elecciones, es necesario disminuir el financiamiento p\u00fablico y asegurar que los partidos cumplan con los tiempos de campa\u00f1a, estableciendo sanciones robustas en la Ley de partidos pol\u00edticos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La miembro del Consejo y Coordinadora de la Unidad de An\u00e1lisis Pol\u00edtico de Participaci\u00f3n Ciudadana (PC), Leidy Blanco Garc\u00eda, expres\u00f3 que, respecto a la disminuci\u00f3n de la cantidad de diputados,&hellip;<\/p>\n","protected":false},"author":2,"featured_media":88033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35,25],"tags":[274,3243,14970,1459],"class_list":["post-88035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada","tag-diputados","tag-disminucion","tag-leidy-blanco","tag-pc"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Leidy-Blanco.jpg","jetpack-related-posts":[{"id":100339,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/06\/05\/comision-que-estudia-proyecto-de-ley-sobre-libertad-de-expresion-escucho-a-representantes-de-pc\/","url_meta":{"origin":88035,"position":0},"title":"Comisi\u00f3n que estudia proyecto de ley sobre libertad de expresi\u00f3n escuch\u00f3 a representantes de PC","author":"Nelson Feliz","date":"5 de junio de 2025","format":false,"excerpt":"Por: Adalgisa S\u00e1nchez La Comisi\u00f3n Especial que tiene a su cargo analizar y estudiar el Proyecto de Ley Org\u00e1nica de Libertad de Expresi\u00f3n y Medios Audiovisuales, recibi\u00f3 este mi\u00e9rcoles a representantes de Participaci\u00f3n Ciudadana, quienes afirmaron est\u00e1r de acuerdo con la creaci\u00f3n de esta ley, sin embargo, expusieron su preocupaci\u00f3n\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Comisi\u00f3n Especial","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/Comision-Especial.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/Comision-Especial.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/Comision-Especial.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/Comision-Especial.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":104250,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/22\/pc-pide-investigar-congresistas-que-no-han-declarado-bienes\/","url_meta":{"origin":88035,"position":1},"title":"PC pide investigar congresistas que no han declarado bienes","author":"Nelson Feliz","date":"22 de julio de 2025","format":false,"excerpt":"El movimiento Participaci\u00f3n Ciudadana (PC) pidi\u00f3 este martes al Ministerio P\u00fablico investigar a los congresistas y ex congresistas que no han presentado su declaraci\u00f3n jurada de patrimonio. Informaci\u00f3n suministrada por la C\u00e1mara de Cuentas, a solicitud de PC, revela que 20 diputados de los elegidos en 2024 y 78 que\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Participacion-Ciudadana.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Participacion-Ciudadana.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Participacion-Ciudadana.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Participacion-Ciudadana.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":88032,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/08\/21\/pc-favorece-blindaje-para-la-reeleccion-y-fortalecimiento-del-ministerio-publico\/","url_meta":{"origin":88035,"position":2},"title":"PC favorece blindaje para la reelecci\u00f3n y fortalecimiento del Ministerio P\u00fablico","author":"Nelson Feliz","date":"21 de agosto de 2024","format":false,"excerpt":"La miembro del Consejo y Coordinadora de la Unidad de An\u00e1lisis Pol\u00edtico de Participaci\u00f3n Ciudadana (PC), Leidy Blanco Garc\u00eda, expres\u00f3 el respaldo a varios puntos clave de la reforma constitucional presentada por el presidente Luis Abinader, destacando la importancia de las medidas para impedir la reelecci\u00f3n presidencial y fortalecer al\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Leidy Blanco Garc\u00eda","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Leidy-Blanco.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Leidy-Blanco.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Leidy-Blanco.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Leidy-Blanco.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":50592,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/05\/22\/leidy-laura-nunez-lanza-precandidatura-a-diputada-fp\/","url_meta":{"origin":88035,"position":3},"title":"Leidy Laura N\u00fa\u00f1ez lanza precandidatura a diputada FP","author":"prenxa100","date":"22 de mayo de 2023","format":false,"excerpt":"NUEVA YORK. \u2013La dirigente nacional de la Fuerza del Pueblo(FP), Leidy Laura N\u00fa\u00f1ez, exhibi\u00f3 sus m\u00fasculos y fortaleza al lanzar su precandidatura a diputada en un acto en el que abarrot\u00f3 el local principal de su organizaci\u00f3n, en Manhattan. Visiblemente emocionada y en compa\u00f1\u00eda de su esposo el exdiputado Alfredo\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":110364,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/09\/28\/procuradora-general-recibe-una-comision-de-participacion-ciudadana\/","url_meta":{"origin":88035,"position":4},"title":"Procuradora general recibe una comisi\u00f3n de Participaci\u00f3n Ciudadana","author":"Nelson Feliz","date":"28 de septiembre de 2025","format":false,"excerpt":"\u00a0Explica el Plan Operativo de su gesti\u00f3n en diversas \u00e1reas, los avances y desaf\u00edos en materia de lucha contra la corrupci\u00f3n administrativa y la necesidad de que la poblaci\u00f3n se mantenga vigilante por la transparencia y una cultura de cero impunidad. La procuradora general de la Rep\u00fablica, Yeni Berenice Reynoso,\u2026","rel":"","context":"En \u00abJUSTICIA\u00bb","block_context":{"text":"JUSTICIA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/justicia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/procuradora.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/procuradora.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/procuradora.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/09\/procuradora.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":57225,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/08\/10\/prd-recibe-a-comision-de-pc-y-reitera-su-compromiso-con-la-transparencia\/","url_meta":{"origin":88035,"position":5},"title":"PRD recibe a comisi\u00f3n de PC y reitera su compromiso con la transparencia","author":"Nelson Feliz","date":"10 de agosto de 2023","format":false,"excerpt":"El candidato presidencial del Partido Revolucionario Dominicano, Miguel Vargas recibi\u00f3 en la Casa Nacional del PRD a una comitiva de Participaci\u00f3n Ciudadana, como parte del proceso de observaci\u00f3n que inici\u00f3 dicha entidad, en torno a la organizaci\u00f3n y montaje de las elecciones nacionales del 2024. El presidente del PRD resalt\u00f3\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/REUNION-PC-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/REUNION-PC-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/REUNION-PC-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/REUNION-PC-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=88035"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88035\/revisions"}],"predecessor-version":[{"id":88036,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88035\/revisions\/88036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/88033"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=88035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=88035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=88035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}