{"id":88501,"date":"2024-08-29T19:44:21","date_gmt":"2024-08-29T23:44:21","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=88501"},"modified":"2024-08-29T19:44:21","modified_gmt":"2024-08-29T23:44:21","slug":"big-prospect-league-pondra-en-marcha-4to-torneo-en-la-cuaba-pedro-brand","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2024\/08\/29\/big-prospect-league-pondra-en-marcha-4to-torneo-en-la-cuaba-pedro-brand\/","title":{"rendered":"Big Prospect League pondr\u00e1 en marcha 4to Torneo en La Cuaba &#8211; Pedro Brand"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Participaran Ocho Academias Con Jugadores Clase 2026-2027.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la participaci\u00f3n de m\u00e1s de 250 atletas La Big Prospect League pondr\u00e1 en marcha el 4to Torneo De B\u00e9isbol Clase 2026-2027 correspondiente a la zona de La Cuaba Pedro Brand.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El anuncio fue hecho por el dirigente Osiris Reynoso Presidente y Director T\u00e9cnico de BPL-BEISBOL, quien destaco que en esta versi\u00f3n se estar\u00e1 jugando con ocho academias incluyendo la Academia Wilbel N\u00fa\u00f1ez desde la Provincia de La Vega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta cuarta versi\u00f3n contaremos con ocho academias las cuales se estar\u00e1n enfrentando en formato de todos contra todos para definir los equipos que pasaran a las semi finales y finales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"575\" height=\"1024\" src=\"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Edwin-Castillo-Presidente-de-Ray-Academy-campeones-del-3er-Torneo-575x1024.jpeg\" alt=\"\" class=\"wp-image-88503\" srcset=\"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Edwin-Castillo-Presidente-de-Ray-Academy-campeones-del-3er-Torneo-575x1024.jpeg 575w, https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Edwin-Castillo-Presidente-de-Ray-Academy-campeones-del-3er-Torneo-169x300.jpeg 169w, https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Edwin-Castillo-Presidente-de-Ray-Academy-campeones-del-3er-Torneo-768x1367.jpeg 768w, https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Edwin-Castillo-Presidente-de-Ray-Academy-campeones-del-3er-Torneo-863x1536.jpeg 863w, https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Edwin-Castillo-Presidente-de-Ray-Academy-campeones-del-3er-Torneo.jpeg 899w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cada academia estar\u00e1 jugando 14 partidos de serie regular, donde clasificar\u00e1n los mejores cinco, el primero se sienta mientras que segundo vs quinto lugar y tercero vs cuarto jugar\u00e1n semis finales a muerte s\u00fabita respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se estar\u00e1 jugando los d\u00edas martes, jueves y viernes en los diferentes estadios de las academias participantes a partir de las 10:00 am y las 2:00 p.m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El este 4to torneo que inicia este martes 3 de septiembre La academia Ray estar\u00e1 defendiendo su corona frente a las academias Los Brothers, Marino Sierra, Dominican Baseball, Line Drive, Jos\u00e9 Almonte, Pichardo y Wilbel N\u00fa\u00f1ez desde La Vega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer torneo en la zona de La Cuaba Pedro Brand fue ganado por la Academia de Line Drive a la academia Niche, el segundo fue ganado por Sierra a la academia de JLR y el 3ro por la Academia de Ray a la academia Lej de San Francisco de Macor\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Participaran Ocho Academias Con Jugadores Clase 2026-2027. Con la participaci\u00f3n de m\u00e1s de 250 atletas La Big Prospect League pondr\u00e1 en marcha el 4to Torneo De B\u00e9isbol Clase 2026-2027 correspondiente&hellip;<\/p>\n","protected":false},"author":2,"featured_media":88502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[15171,12843,7930,80,1133,2343],"class_list":["post-88501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-big-prospect-league","tag-bpl-beisbol","tag-la-cuaba","tag-marcha","tag-pedro-brand","tag-torneo"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Edwin-Castillo-Presidente-de-Ray-Academy-campeones-del-3er-Torneo-1.jpg","jetpack-related-posts":[{"id":128500,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/04\/23\/big-prospect-league-bpl-beisbol-pondra-en-marcha-4to-torneo-en-guerra-san-isidro\/","url_meta":{"origin":88501,"position":0},"title":"Big Prospect League (BPL-BEISBOL) pondr\u00e1 en marcha 4to Torneo en Guerra &#8211; San Isidro","author":"Nelson Feliz","date":"23 de abril de 2026","format":false,"excerpt":"Participaran 8 academias con jugadores elegibles clase Enero 2028 Enero 2029 Con la participaci\u00f3n de m\u00e1s de 200 atletas La Big Prospect League pondr\u00e1 en marcha su 4to Torneo de Beisbol correspondiente a la zona de Guerra San Isidro en el cual estar\u00e1n participando jugadores Clase enero 2028 enero 2029.\u2026","rel":"","context":"En \u00abDEPORTES\u00bb","block_context":{"text":"DEPORTES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/deportes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/Osiris-Reynoso-Entrega-la-copa-de-Campeones-al-manager-Rennie-Francisco-de-la-Academia-Los-Bautys-y-los-jugadores.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/Osiris-Reynoso-Entrega-la-copa-de-Campeones-al-manager-Rennie-Francisco-de-la-Academia-Los-Bautys-y-los-jugadores.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/Osiris-Reynoso-Entrega-la-copa-de-Campeones-al-manager-Rennie-Francisco-de-la-Academia-Los-Bautys-y-los-jugadores.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/Osiris-Reynoso-Entrega-la-copa-de-Campeones-al-manager-Rennie-Francisco-de-la-Academia-Los-Bautys-y-los-jugadores.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84009,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/05\/28\/delgado-y-medina-guian-academia-lej-a-final-en-3er-torneo-bpl-beisbol\/","url_meta":{"origin":88501,"position":1},"title":"Delgado y Medina Gu\u00edan Academia LEJ a Final En 3er. Torneo BPL-BEISBOL","author":"Nelson Feliz","date":"28 de mayo de 2024","format":false,"excerpt":"La Cuaba Pedro Brand Clase 2025-2026 Yariel Delgado con dos outs y bases llenas conect\u00f3 un sencillo a Jefferson Gonz\u00e1lez en la parte alta de la octava entrada, impulsando las carreras de la ventaja para que la Academia de LEJ de San Francisco de Macor\u00eds venciera con score de 8\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"Los jugadores Jos\u00e9 Medina Clase 2026 y Yariel Delgado clase 2028.","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/GUIAN.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/GUIAN.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/GUIAN.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/GUIAN.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":102432,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/04\/bplbeisbol-anuncia-torneo-de-beisbol-clase-2027-2028-en-el-cibao\/","url_meta":{"origin":88501,"position":2},"title":"BPLBEISBOL anuncia &#8220;Torneo de B\u00e9isbol clase 2027-2028&#8221; en el Cibao","author":"Nelson Feliz","date":"4 de julio de 2025","format":false,"excerpt":"Participaran 4 Academias y otras como invitadas. Con la participaci\u00f3n de m\u00e1s de 100 atletas La Big Prospect League BPLBEISBOL, pondr\u00e1 en marcha su 1er. Torneo De Beisbol Clase 2027-2028 correspondiente a la zona del Cibao. As\u00ed lo informo el dirigente Osiris Reynoso Ceo de BPL-BEISBOL, quien destac\u00f3 el gran\u2026","rel":"","context":"En \u00abDEPORTES\u00bb","block_context":{"text":"DEPORTES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/deportes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Flyers-Academias-del-Cibao.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Flyers-Academias-del-Cibao.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Flyers-Academias-del-Cibao.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Flyers-Academias-del-Cibao.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":85463,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/06\/30\/bpl-beisbol-termina-primera-ronda-del-torneo-crazy-cup\/","url_meta":{"origin":88501,"position":3},"title":"BPL- B\u00c9ISBOL termina primera ronda del Torneo Crazy Cup","author":"Nelson Feliz","date":"30 de junio de 2024","format":false,"excerpt":"Diecis\u00e9is equipos avanzan a la segunda ronda. La Big Prospect League (BPL-B\u00c9ISBOL) finaliz\u00f3 su primera ronda del torneo Crazy Cup clase (2025-2026-27), con la participaci\u00f3n de 32 academias que vieron acci\u00f3n en esta primera etapa que estuvo marcada por destacadas actuaciones en el terreno de juego. Los municipios de Santo\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/BPLBEISBOL-CRAZY-CUP-2024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/BPLBEISBOL-CRAZY-CUP-2024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/BPLBEISBOL-CRAZY-CUP-2024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/BPLBEISBOL-CRAZY-CUP-2024.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":82814,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/05\/07\/academia-lf-martinez-pasa-a-semi-final-en-4to-torneo-bpl-beisbol-sd-norte-clase-2026-2027\/","url_meta":{"origin":88501,"position":4},"title":"Academia LF Mart\u00ednez pasa a Semi Final en 4to Torneo BPL-Beisbol SD-Norte Clase 2026-2027","author":"Esteffany Vargas","date":"7 de mayo de 2024","format":false,"excerpt":"El seccionado de la Academia LF Mart\u00ednez (YINDO) derroto con score de 7 carreras por 5 a la academia BIBI \u00a0para asegurar su participaci\u00f3n en la semi-final de su divisi\u00f3n del 4to Torneo de B\u00e9isbol Clase 2026-2027 de la Big Prospect League (BPL-BEISBOL) correspondiente a Santo Domingo Norte. Los apadrinados\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Jugadores-Academia-LF-MARTINEZ-YINDO.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Jugadores-Academia-LF-MARTINEZ-YINDO.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Jugadores-Academia-LF-MARTINEZ-YINDO.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":90106,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/10\/13\/academia-nelsy-brito-bayahibe-pasa-a-final-bpl-beisbol-del-torneo-crazy-cup\/","url_meta":{"origin":88501,"position":5},"title":"Academia Nelsy Brito (Bayahibe) pasa a final BPL- B\u00c9ISBOL del Torneo Crazy Cup","author":"Nelson Feliz","date":"13 de octubre de 2024","format":false,"excerpt":"Espera el Ganador de Ray y Los Bautys Tras La Corona y Premio Met\u00e1lico. Las academia de Nelsy Brito (El S\u00edndico) desde Bayahibe la zona este derroto con score de 7 carreras por 6 a la academia de banana para avanzar a La final del torneo organizado por Big Prospect\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"Los entrenadores Miguel Caceres y Jose de la Cruz junto a los jugadores de la academia Nelsy Brito.","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/MIguel-Caceres-y-Jose-de-La-Cruz-junto-a-los-Jugadores-Academia-Nelsy-Brito.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/MIguel-Caceres-y-Jose-de-La-Cruz-junto-a-los-Jugadores-Academia-Nelsy-Brito.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/MIguel-Caceres-y-Jose-de-La-Cruz-junto-a-los-Jugadores-Academia-Nelsy-Brito.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/10\/MIguel-Caceres-y-Jose-de-La-Cruz-junto-a-los-Jugadores-Academia-Nelsy-Brito.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=88501"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88501\/revisions"}],"predecessor-version":[{"id":88504,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/88501\/revisions\/88504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/88502"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=88501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=88501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=88501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}