{"id":91269,"date":"2024-11-15T23:09:42","date_gmt":"2024-11-16T03:09:42","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=91269"},"modified":"2024-11-15T23:09:43","modified_gmt":"2024-11-16T03:09:43","slug":"danilo-valora-el-esfuerzo-dedicacion-y-trabajo-de-los-miembros-del-cp","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2024\/11\/15\/danilo-valora-el-esfuerzo-dedicacion-y-trabajo-de-los-miembros-del-cp\/","title":{"rendered":"Danilo valora el esfuerzo, dedicaci\u00f3n y trabajo de los miembros del CP"},"content":{"rendered":"\n<p><strong>Con reuni\u00f3n en su sede nacional,\u00a0Comit\u00e9 Pol\u00edtico del PLD\u00a0concluye su trabajo para dar paso al nuevo CP que ser\u00e1 juramentado el 24 de noviembre.<\/strong><\/p>\n\n\n\n<p>El Comit\u00e9 Pol\u00edtico del Partido de la Liberaci\u00f3n Dominicana (PLD)&nbsp;se reuni\u00f3 este viernes conociendo los detalles pendientes del desarrollo del X Congreso Ordinario Reinaldo Pared antes de la fecha de clausura, pautada para el domingo 24 de noviembre del a\u00f1o en curso.<\/p>\n\n\n\n<p>Danilo Medina, Presidente del PLD, presidi\u00f3 el encuentro teniendo a su lado en la L\u00ednea Central al nuevo Secretario General de la Organizaci\u00f3n, Johnny Pujols, al pasado candidato presidencial, Abel Mart\u00ednez y Cristina Lizardo, Coordinadora de la Comisi\u00f3n Organizadora del Congreso.<\/p>\n\n\n\n<p>Correspondi\u00f3 a Lizardo informar de los aprestos organizativos de la Plenaria de Clausura del Congreso, as\u00ed como los procesos electorales pendientes, presentando los casos de la escogencia de los 20 miembros del Comit\u00e9 Central en el exterior y las elecciones complementarias en los municipios Crist\u00f3bal y Jiman\u00ed de la Provincia Independencia, que se realizan en el fin de semana en curso. &nbsp;<\/p>\n\n\n\n<p>Confirm\u00f3 que la ceremonia de clausura del Congreso se realizar\u00e1 combinando una participaci\u00f3n presencial y otra a distancia en donde los delegados y delegadas se reunir\u00e1n en los locales partidarios o en sus hogares siguiendo las incidencias del acto de forma virtual, transmitido desde la sede nacional del PLD.<\/p>\n\n\n\n<p>Para la actividad, que inici\u00f3 a los 10 y 15 minutos de la ma\u00f1ana, se unific\u00f3 una agenda de la clausura en la que quedar\u00e1 formalmente juramentado el nuevo Comit\u00e9 Pol\u00edtico y se entregar\u00e1 el informe final de los trabajos congresuales y clausurar dicho Congreso.<\/p>\n\n\n\n<p>35 de los 45 miembros del Comit\u00e9 Pol\u00edtico, que en el encuentro de este jueves concluy\u00f3 sus labores, asistieron con las excusas tramitadas por los ausentes.<\/p>\n\n\n\n<p>Al finalizar la reuni\u00f3n, pr\u00f3ximo al mediod\u00eda, el dos veces Presidente de la Rep\u00fablica, Danilo Medina, valor\u00f3 el trabajo, dedicaci\u00f3n y esfuerzo de los miembros del Comit\u00e9 Pol\u00edtico en estos \u201ca\u00f1os dif\u00edciles&#8221; para la organizaci\u00f3n pol\u00edtica. Este Comit\u00e9 Pol\u00edtico hizo su trabajo\u201d, dijo.<\/p>\n\n\n\n<p>Apunt\u00f3 que \u201cen ese tiempo quiz\u00e1s no se alcanzaron todos los \u00e9xitos deseados, pero el PLD se mantiene intacto, va en crecimiento, lo que constituye un reto para el nuevo Comit\u00e9 Pol\u00edtico mantener esa l\u00ednea ascendente y de identificaci\u00f3n con las comunidades y la solidaridad con los sectores nacionales\u201d, acot\u00f3. &nbsp;&nbsp;<\/p>\n\n\n\n<p>Danilo Medina dijo estar plenamente confiado que, con la resiliencia demostrada por la organizaci\u00f3n pol\u00edtica, se trabajar\u00e1 mucho mejor y el PLD seguir\u00e1 ejerciendo su vocaci\u00f3n de servicio y solidaridad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con reuni\u00f3n en su sede nacional,\u00a0Comit\u00e9 Pol\u00edtico del PLD\u00a0concluye su trabajo para dar paso al nuevo CP que ser\u00e1 juramentado el 24 de noviembre. El Comit\u00e9 Pol\u00edtico del Partido de&hellip;<\/p>\n","protected":false},"author":2,"featured_media":91270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3500,501,14880,15909,475,967],"class_list":["post-91269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portada","tag-comite-politico","tag-danilo-medina","tag-dedicacion","tag-esfuerzo","tag-miembros","tag-trabajo"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2024\/11\/Danilo-Medina-2.jpg","jetpack-related-posts":[{"id":91327,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/11\/15\/danilo-valora-el-esfuerzo-dedicacion-y-trabajo-de-los-miembros-del-cp-2\/","url_meta":{"origin":91269,"position":0},"title":"Danilo valora el esfuerzo, dedicaci\u00f3n y trabajo de los miembros del CP","author":"Nelson Feliz","date":"15 de noviembre de 2024","format":false,"excerpt":"Con reuni\u00f3n en su sede nacional, Comit\u00e9 Pol\u00edtico del PLD concluye su trabajo para dar paso al nuevo CP que ser\u00e1 juramentado el 24 de noviembre. El Comit\u00e9 Pol\u00edtico del Partido de la Liberaci\u00f3n Dominicana (PLD) se reuni\u00f3 este viernes conociendo los detalles pendientes del desarrollo del X Congreso Ordinario\u2026","rel":"","context":"En \u00abPORTADA\u00bb","block_context":{"text":"PORTADA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/portada\/"},"img":{"alt_text":"Danilo Medina","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/11\/Danilo-Medina-3.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/11\/Danilo-Medina-3.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/11\/Danilo-Medina-3.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/11\/Danilo-Medina-3.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/11\/Danilo-Medina-3.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/11\/Danilo-Medina-3.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":121158,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/02\/01\/danilo-explica-reestructuracion-del-pld-y-avances-para-definir-el-perfil-aspirante-presidencial-video\/","url_meta":{"origin":91269,"position":1},"title":"Danilo explica reestructuraci\u00f3n del PLD y avances para definir el perfil aspirante presidencial | Video","author":"Nelson Feliz","date":"1 de febrero de 2026","format":false,"excerpt":"\u201cEstamos transformando la estructura del Partido para organizarlo desde las mesas y recintos electorales\u201d afirma Danilo Medina. \u201cel PRM va para fuera y ser\u00e1 el PLD que lo sacar\u00e1\u00bb, apunt\u00f3. El expresidente de la Rep\u00fablica y presidente del Partido de la Liberaci\u00f3n Dominicana (PLD), Danilo Medina, inform\u00f3 que la organizaci\u00f3n\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/02\/danilo-medina-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/02\/danilo-medina-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/02\/danilo-medina-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/02\/danilo-medina-1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":125632,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/03\/24\/pld-conforma-comision-de-consulta-sobre-aspirantes-presidenciales\/","url_meta":{"origin":91269,"position":2},"title":"PLD conforma Comisi\u00f3n de Consulta sobre Aspirantes Presidenciales","author":"Nelson Feliz","date":"24 de marzo de 2026","format":false,"excerpt":"Comit\u00e9 Pol\u00edtico escoge la fecha del domingo 18 de octubre para la realizaci\u00f3n de la Consulta. El Partido de la Liberaci\u00f3n Dominicana (PLD) conform\u00f3 la comisi\u00f3n que organizar\u00e1 el proceso de consulta para la escogencia del aspirante presidencial. La informaci\u00f3n fue dada por el secretario general del PLD, Johnny Pujos,\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/1-24.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/1-24.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/1-24.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/1-24.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":102903,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/09\/danilo-medina-va-el-domingo-al-municipio-sde\/","url_meta":{"origin":91269,"position":3},"title":"Danilo Medina va el domingo al municipio SDE","author":"Nelson Feliz","date":"9 de julio de 2025","format":false,"excerpt":"El PLD en la Circunscripci\u00f3n Dos del municipio Santo Domingo Este organiza asamblea que presidir\u00e1n Danilo Medina y Johnny Pujols el pr\u00f3ximo domingo. El Partido de la Liberaci\u00f3n Dominicana (PLD) en la Circunscripci\u00f3n Electoral n\u00famero 2 del municipio Santo Domingo Este se prepara para recibir en ese territorio al presidente\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"Danilo Medina","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Danilo-Medina-02.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Danilo-Medina-02.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Danilo-Medina-02.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/05\/Danilo-Medina-02.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":101931,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/06\/29\/danilo-medina-reitera-que-con-el-pld-se-vivia-mejor-video\/","url_meta":{"origin":91269,"position":4},"title":"Danilo Medina reitera que con el PLD se viv\u00eda mejor | Video","author":"Nelson Feliz","date":"29 de junio de 2025","format":false,"excerpt":"Danilo Medina presagia el retorno del Partido de la Liberaci\u00f3n Dominicana al Poder amarrado de la bandera morada, la estrella amarilla y sus siglas PLD. https:\/\/twitter.com\/i\/status\/1939406713511416262 El ex presidente de la Rep\u00fablica y Presidente del Partido de la liberaci\u00f3n Dominicana (PLD) Danilo Medina, declar\u00f3 no sentirse extra\u00f1ado con el aumento\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/as-sc-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/as-sc-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/as-sc-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/06\/as-sc-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":102901,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/09\/se-reune-este-jueves-el-cp-del-pld\/","url_meta":{"origin":91269,"position":5},"title":"Se re\u00fane este jueves el CP del PLD","author":"Nelson Feliz","date":"9 de julio de 2025","format":false,"excerpt":"Ser\u00e1 este jueves la reuni\u00f3n del Comit\u00e9 Pol\u00edtico del PLD para conocer la sentencia del TSE sobre las aspiraciones de precandidaturas presidencial. El escenario en la Casa Nacional Reinaldo Pared P\u00e9rez del Partido de la Liberaci\u00f3n Dominicana (PLD) est\u00e1 preparado para recibir a los miembros del Comit\u00e9 Pol\u00edtico de la\u2026","rel":"","context":"En \u00abPOLITICA\u00bb","block_context":{"text":"POLITICA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/politica\/"},"img":{"alt_text":"CASA PLD","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/CASA-PLD.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/CASA-PLD.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/CASA-PLD.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/CASA-PLD.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/91269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=91269"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/91269\/revisions"}],"predecessor-version":[{"id":91271,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/91269\/revisions\/91271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/91270"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=91269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=91269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=91269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}