{"id":93864,"date":"2025-02-21T22:50:33","date_gmt":"2025-02-22T02:50:33","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=93864"},"modified":"2025-02-21T22:50:34","modified_gmt":"2025-02-22T02:50:34","slug":"presidente-del-senado-apoya-la-modificacion-a-ley-de-residuos-solidos","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/02\/21\/presidente-del-senado-apoya-la-modificacion-a-ley-de-residuos-solidos\/","title":{"rendered":"Presidente del Senado apoya la modificaci\u00f3n a ley de Residuos S\u00f3lidos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente del Senado de la Rep\u00fablica, Ricardo De Los Santos, dijo que apoya la modificaci\u00f3n a ley General de Gesti\u00f3n Integral y Procedimiento de Residuos S\u00f3lidos en la Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El senador dijo \u201cEstamos escuchando todos los sectores para la modificaci\u00f3n a la ya debatida ley\u201d, asegur\u00f3 Ricardo De Los Santos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Legislador reconoce que aunque la ley fue aprobada por la c\u00e1mara Alta se pueden hacer modificaciones, debido que misma tiene muchas debilidades que habr\u00e1 que corregir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a8Todo el mundo apoya la ley y la ve necesaria porque viene a colaborar y a proteger le medio ambiente\u00a8, consider\u00f3 el senador durante una entrevista en el programa televisivo, Hoy Mismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El legislador manifest\u00f3 que est\u00e1 en la mejor disposici\u00f3n de brindar el apoyo que sea necesario para que la pieza legislativa sea una realidad en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valor\u00f3 que si bien es cierto que la propuesta normativa tiene algunas debilidades de forma, no de fondo, es uno de los pocos proyectos que cuenta con un amplio respaldo de todos los sectores sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De los Santos indic\u00f3 que aunque ya fue aprobada, a\u00fan se le pueden hacer las modificaciones necesarias a la ley, por tratarse de un Congreso bicameral, que permite pasar los proyecos por una c\u00e1mara y luego filtrar en la otra, lo que garantiza que lo que se pudo haber escapado, se puede coreregir a tiempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente del Senado de la Rep\u00fablica, Ricardo De Los Santos, dijo que apoya la modificaci\u00f3n a ley General de Gesti\u00f3n Integral y Procedimiento de Residuos S\u00f3lidos en la Rep\u00fablica&hellip;<\/p>\n","protected":false},"author":2,"featured_media":93865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35],"tags":[16899,6826,935,413],"class_list":["post-93864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","tag-ley-de-residuos-solidos","tag-modificacion","tag-presidente","tag-senado"],"jetpack-related-posts":[{"id":116974,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/12\/05\/senado-aprueba-a-unanimidad-modificacion-a-ley-organica-del-codigo-procesal-penal\/","url_meta":{"origin":93864,"position":0},"title":"Senado aprueba a unanimidad modificaci\u00f3n a Ley Org\u00e1nica del C\u00f3digo Procesal Penal","author":"Nelson Feliz","date":"5 de diciembre de 2025","format":false,"excerpt":"La pieza fue conocida en sesi\u00f3n extraordinaria y aprobada a unanimidad por la totalidad de 28 asamble\u00edstas presentes. El Senado de la Rep\u00fablica aprob\u00f3 en \u00fanica lectura las modificaciones realizadas al Proyecto de Ley Org\u00e1nica del C\u00f3digo Procesal Penal, remitido por la C\u00e1mara de Diputados. La normativa legislativa fue sometida\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/senado-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/senado-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/senado-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/12\/senado-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":103946,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/20\/presidente-de-fedomu-valora-como-positiva-aprobacion-de-proyecto-que-modifica-ley-225-20\/","url_meta":{"origin":93864,"position":1},"title":"Presidente de Fedomu valora como positiva aprobaci\u00f3n de proyecto que modifica Ley 225-20","author":"Nelson Feliz","date":"20 de julio de 2025","format":false,"excerpt":"N\u00fa\u00f1ez pidi\u00f3 al Senado que tambi\u00e9n apruebe el proyecto para que sea promulgado por el Poder Ejecutivo. El presidente de la Federaci\u00f3n Dominicana de Municipios (Fedomu) y alcalde de Saman\u00e1, Nelson N\u00fa\u00f1ez, valor\u00f3 como positiva la aprobaci\u00f3n en dos lecturas consecutivas, en la C\u00e1mara de Diputados, el proyecto de modificaci\u00f3n\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Nelson N\u00fa\u00f1ez","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Nelson-Nunez.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Nelson-Nunez.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Nelson-Nunez.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Nelson-Nunez.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":94717,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/04\/camara-alta-trabajara-para-aprobar-modificacion-al-codigo-penal\/","url_meta":{"origin":93864,"position":2},"title":"C\u00e1mara Alta trabajar\u00e1 para aprobar modificaci\u00f3n al C\u00f3digo Penal","author":"Nelson Feliz","date":"4 de marzo de 2025","format":false,"excerpt":"Durante su participaci\u00f3n en el programa Despierta con CDN, el presidente del Senado asegur\u00f3 que el poder legislativo tiene esa deuda con el pa\u00eds. Por Elvis Castro Hern\u00e1ndez El presidente del Senado, Ricardo de los Santos, destac\u00f3 el proyecto de modificaci\u00f3n al C\u00f3digo Penal dominicano, como la pieza legislativa macro\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Ricardo de los Santos","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Ricardo-de-los-Santos2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Ricardo-de-los-Santos2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Ricardo-de-los-Santos2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Ricardo-de-los-Santos2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":103690,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/17\/victor-daza-valora-como-positiva-la-modificacion-ley-225-20-aprobada-en-camara-de-diputados\/","url_meta":{"origin":93864,"position":3},"title":"V\u00edctor D\u00b4Aza valora como positiva la modificaci\u00f3n Ley 225-20 aprobada en C\u00e1mara de Diputados","author":"Nelson Feliz","date":"17 de julio de 2025","format":false,"excerpt":"El presidente de la Liga Municipal Dominicana (LMD), V\u00edctor D\u00b4Aza, valor\u00f3 como positiva la aprobaci\u00f3n en segunda lectura del proyecto de ley que modifica la Ley 225-20 de Gesti\u00f3n Integral y Coprocesamiento de los Residuos S\u00f3lidos. D\u00b4Aza explic\u00f3 que, ante la necesidad de los gobiernos locales de contar con m\u00e1s\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Victor-D%C2%B4Aza.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Victor-D%C2%B4Aza.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Victor-D%C2%B4Aza.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/07\/Victor-D%C2%B4Aza.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":120713,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/01\/27\/senado-aprobo-197-iniciativas-legislativas-en-segunda-legislatura-ordinaria-2025-2026\/","url_meta":{"origin":93864,"position":4},"title":"Senado aprob\u00f3 197 iniciativas legislativas en segunda Legislatura Ordinaria 2025-2026","author":"Nelson Feliz","date":"27 de enero de 2026","format":false,"excerpt":"Entre las iniciativas aprobadas se destacan la Ley org\u00e1nica que instituye el C\u00f3digo Procesal Penal, Ley org\u00e1nica que aprueba el C\u00f3digo Trabajo, as\u00ed como la Ley que crea el Colegio de Contadores P\u00fablicos Autorizados de la Rep\u00fablica Dominicana, entre otras de gran importancia para el pa\u00eds. El Senado de la\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260127-WA0141.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260127-WA0141.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260127-WA0141.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260127-WA0141.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260127-WA0141.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":95605,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/16\/circe-almanzar-respalda-la-modificacion-a-la-ley-de-residuos-solidos-para-impulsar-la-economia-circular-en-rd\/","url_meta":{"origin":93864,"position":5},"title":"Circe Alm\u00e1nzar respalda la modificaci\u00f3n a la Ley de Residuos S\u00f3lidos para impulsar la econom\u00eda circular en RD","author":"Nelson Feliz","date":"16 de marzo de 2025","format":false,"excerpt":"La exvicepresidenta de la Asociaci\u00f3n de Industrias y consultora privada, Circe Alm\u00e1nzar afirma que la modificaci\u00f3n a la Ley 225-20 de Gesti\u00f3n Integral y Cooprocesamiento de los Residuos S\u00f3lidos, ser\u00e1 un paso trascendental para el desarrollo de los municipios y del pa\u00eds. Alm\u00e1nzar sostiene que la discusi\u00f3n para este proyecto\u2026","rel":"","context":"En \u00abECONOM\u00cdA\u00bb","block_context":{"text":"ECONOM\u00cdA","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/economia\/"},"img":{"alt_text":"Circe Alm\u00e1nzar","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Circe_Almanzar_1-removebg-preview.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Circe_Almanzar_1-removebg-preview.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Circe_Almanzar_1-removebg-preview.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/Ricardo-De-Los-Santos.jpg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/93864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=93864"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/93864\/revisions"}],"predecessor-version":[{"id":93866,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/93864\/revisions\/93866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/93865"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=93864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=93864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=93864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}