{"id":95377,"date":"2025-03-13T07:42:13","date_gmt":"2025-03-13T11:42:13","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=95377"},"modified":"2025-03-13T07:42:15","modified_gmt":"2025-03-13T11:42:15","slug":"francisco-cumple-12-anos-como-papa-en-el-hospital-aunque-su-estado-mejora","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/13\/francisco-cumple-12-anos-como-papa-en-el-hospital-aunque-su-estado-mejora\/","title":{"rendered":"Francisco cumple 12 a\u00f1os como papa en el hospital, aunque su estado mejora"},"content":{"rendered":"\n<p>ROMA (AP) \u2014 El papa Francisco celebr\u00f3 el 12mo aniversario de su papado el jueves con reportes m\u00e9dicos cada vez m\u00e1s positivos, cuatro semanas despu\u00e9s de su hospitalizaci\u00f3n por neumon\u00eda bilateral.<\/p>\n\n\n\n<p>El papa pas\u00f3 otra noche tranquila, seg\u00fan inform\u00f3 el Vaticano en su breve comunicado matutino.<\/p>\n\n\n\n<p>Una radiograf\u00eda de t\u00f3rax confirm\u00f3 mejoras, indic\u00f3 el Vaticano el mi\u00e9rcoles, solo dos d\u00edas despu\u00e9s de que los m\u00e9dicos declararan que ya no se encuentra en peligro inminente de muerte. <\/p>\n\n\n\n<p>El \u00faltimo bolet\u00edn m\u00e9dico se\u00f1al\u00f3 que la condici\u00f3n del papa de 88 a\u00f1os se manten\u00eda estable, pero indicaba un cuadro complejo considerando su fragilidad general.<\/p>\n\n\n\n<p>La Santa Sede no ha dicho c\u00f3mo se podr\u00eda conmemorar el aniversario de su elecci\u00f3n como el 266to papa. Es un d\u00eda festivo en el Vaticano y se han planeado misas en su honor en las iglesias de Roma. No se emitir\u00e1n boletines m\u00e9dicos.<\/p>\n\n\n\n<p>Francisco sigui\u00f3 el mi\u00e9rcoles de manera remota un retiro espiritual de Cuaresma que ha sido un pilar de su papado. Contin\u00faa recibiendo altos flujos de ox\u00edgeno a trav\u00e9s de tubos nasales durante el d\u00eda y una m\u00e1scara de ox\u00edgeno no invasiva para ayudar a su descanso por la noche.<\/p>\n\n\n\n<p>El excardenal Jorge Mario Bergoglio fue elegido en la quinta votaci\u00f3n del c\u00f3nclave de 2013, que se convoc\u00f3 tras la renuncia del papa Benedicto XVI.<\/p>\n\n\n\n<p>Aunque Francisco ha elogiado la humildad de Benedicto al renunciar y ha dicho que podr\u00eda seguir sus pasos, m\u00e1s recientemente ha afirmado que el papado es un trabajo de por vida.<\/p>\n\n\n\n<p>Otro hito llegar\u00e1 el viernes, cuando Francisco sume cuatro semanas de hospitalizaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA (AP) \u2014 El papa Francisco celebr\u00f3 el 12mo aniversario de su papado el jueves con reportes m\u00e9dicos cada vez m\u00e1s positivos, cuatro semanas despu\u00e9s de su hospitalizaci\u00f3n por neumon\u00eda&hellip;<\/p>\n","protected":false},"author":10,"featured_media":95378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16289],"tags":[3314],"class_list":["post-95377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","tag-el-papa-francisco"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/casa-san-pablo.png","jetpack-related-posts":[{"id":95113,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/10\/el-papa-sigue-desde-lejos-el-retiro-espiritual-del-vaticano-mientras-se-recupera-en-el-hospital\/","url_meta":{"origin":95377,"position":0},"title":"El papa sigue desde lejos el retiro espiritual del Vaticano mientras se recupera en el hospital","author":"Nelson Feliz","date":"10 de marzo de 2025","format":false,"excerpt":"POR NICOLE WINFIELD ROMA (AP) \u2014 El papa Francisco sigui\u00f3 por videoconferencia el retiro espiritual de una semana del Vaticano el lunes, mientras continuaba su recuperaci\u00f3n de una neumon\u00eda bilateral y miraba hacia el 12mo aniversario de su elecci\u00f3n en medio de preguntas sobre c\u00f3mo podr\u00eda ser el futuro de\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa-2.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":93895,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/02\/23\/el-papa-francisco-esta-consciente-y-recibe-oxigeno-tras-una-crisis-respiratoria\/","url_meta":{"origin":95377,"position":1},"title":"El papa Francisco est\u00e1 consciente y recibe ox\u00edgeno tras una crisis respiratoria","author":"Nelson Feliz","date":"23 de febrero de 2025","format":false,"excerpt":"POR NICOLE WINFIELD ROMA (AP) \u2014 El papa Francisco estaba consciente pero a\u00fan recib\u00eda \u201caltos flujos\u201d de ox\u00edgeno suplementario el domingo, tras pasar por una crisis respiratoria y transfusiones de sangre el d\u00eda anterior. El pont\u00edfice permanec\u00eda en estado cr\u00edtico debido a una complicada infecci\u00f3n pulmonar, inform\u00f3 el Vaticano el\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/papa-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/papa-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/papa-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/papa-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":94588,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/03\/el-papa-parece-estar-superando-un-contratiempo-en-su-recuperacion-de-la-neumonia\/","url_meta":{"origin":95377,"position":2},"title":"El papa parece estar superando un contratiempo en su recuperaci\u00f3n de la neumon\u00eda","author":"Nelson Feliz","date":"3 de marzo de 2025","format":false,"excerpt":"POR NICOLE WINFIELD ROMA (AP) \u2014 El papa Francisco se levant\u00f3 y estaba recibiendo terapia el lunes despu\u00e9s de aparentemente superar un contratiempo en su recuperaci\u00f3n de la neumon\u00eda. El Vaticano dijo que se encuentra estable, no requiere ventilaci\u00f3n mec\u00e1nica y no muestra signos de nueva infecci\u00f3n tras una crisis\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":95232,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/11\/francisco-participa-via-remota-en-un-retiro-espiritual-y-los-medicos-mejoran-su-pronostico\/","url_meta":{"origin":95377,"position":3},"title":"Francisco participa v\u00eda remota en un retiro espiritual y los m\u00e9dicos mejoran su pron\u00f3stico","author":"Nelson Feliz","date":"11 de marzo de 2025","format":false,"excerpt":"POR NICOLE WINFIELD ROMA (AP) \u2014 Francisco particip\u00f3 de manera remota en un retiro espiritual del Vaticano el martes despu\u00e9s de recibir buenas noticias de sus doctores: mejoraron su pron\u00f3stico y dicen que ya no est\u00e1 en peligro inminente de muerte como resultado de la neumon\u00eda bilateral que lo ha\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa-3.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa-3.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa-3.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/papa-3.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":52239,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/06\/08\/el-vaticano-papa-francisco-en-buenas-condiciones-tras-estar-hospitalizado-por-cirugia\/","url_meta":{"origin":95377,"position":4},"title":"El Vaticano: Papa Francisco en &#8216;buenas condiciones&#8217; tras estar hospitalizado por cirug\u00eda","author":"prenxa100","date":"8 de junio de 2023","format":false,"excerpt":"El Papa Francisco pas\u00f3 su primera noche en el hospital Genelli de Roma tras ser operado por una hernia abdominal durante la tarde del mi\u00e9rcoles. D. RODR\u00cdGUEZ El Vaticano, REUTERS | El Papa Francisco se encontraba en buenas condiciones generales el jueves por la ma\u00f1ana despu\u00e9s de su primera noche\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":95944,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/23\/el-papa-francisco-abandona-el-hospital-y-regresa-al-vaticano-38-dias-despues\/","url_meta":{"origin":95377,"position":5},"title":"El papa Francisco abandona el hospital y regresa al Vaticano 38 d\u00edas despu\u00e9s","author":"Nelson Feliz","date":"23 de marzo de 2025","format":false,"excerpt":"\"Agradezco a todos\", dijo ante la multitud que abarrotaba desde una hora antes las puertas del centro Roma, EFE- El papa Francisco ha abandonado este domingo el Policl\u00ednico Gemelli de Roma, donde ha permanecido 38 d\u00edas ingresado por una infecci\u00f3n respiratoria, y se dirige ya de regreso a su residencia\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"El papa Francisco","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/El-papa-Francisco.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/El-papa-Francisco.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/El-papa-Francisco.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/El-papa-Francisco.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=95377"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95377\/revisions"}],"predecessor-version":[{"id":95379,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95377\/revisions\/95379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/95378"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=95377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=95377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=95377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}