{"id":96372,"date":"2025-03-30T11:44:46","date_gmt":"2025-03-30T15:44:46","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=96372"},"modified":"2025-03-30T11:44:50","modified_gmt":"2025-03-30T15:44:50","slug":"presidente-y-vicepresidenta-encabezan-actos-por-el-181-aniversario-de-la-batalla-de-santiago","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/30\/presidente-y-vicepresidenta-encabezan-actos-por-el-181-aniversario-de-la-batalla-de-santiago\/","title":{"rendered":"Presidente y vicepresidenta encabezan actos por el 181 aniversario de la Batalla de Santiago"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La jornada inici\u00f3 con un tedeum en la Catedral Santiago Ap\u00f3stol, donde estuvo presente la vicepresidenta en representaci\u00f3n del Gobierno.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente Luis Abinader y la vicepresidenta Raquel Pe\u00f1a encabezan este domingo los actos conmemorativos por el 181 aniversario de la Batalla del 30 de marzo de 1844 en Santiago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada inici\u00f3 con un tedeum en la Catedral Santiago Ap\u00f3stol, donde estuvo presente la vicepresidenta en representaci\u00f3n del Gobierno, y continu\u00f3 con un desfile c\u00edvico-militar, despu\u00e9s de las 10:00 a.m., el que encabez\u00f3 el presidente Abinader.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su homil\u00eda, monse\u00f1or H\u00e9ctor Rafael Rodr\u00edguez destac\u00f3 la importancia de la libertad y la dignidad nacional, recordando el sacrificio de los patriotas dominicanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Nuestra historia nos recuerda el valor de quienes defendieron la libertad, no la esclavitud; la dignidad, no la indignidad de nuestra naci\u00f3n, inspirados en los ideales de Duarte&#8221;, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, el prelado resalt\u00f3 que los patriotas que lucharon en la Batalla de Santiago lo hicieron motivados por ideales de justicia y bien com\u00fan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;No les movi\u00f3 ver sangre ni ver semejantes muertos, sino la libertad, la justicia y la entrega por la patria&#8221;, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llamado a la unidad y a la justicia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El arzobispo tambi\u00e9n enfatiz\u00f3 la necesidad de vivir para la libertad y no para la esclavitud, citando la primera lectura de la liturgia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;El Se\u00f1or libera a los oprimidos y nos env\u00eda a dar libertad a los cautivos&#8221;, afirm\u00f3, al tiempo que compar\u00f3 el contexto de la Rep\u00fablica Dominicana de 1844 con la del presente. &#8220;Gracias a Dios, hemos avanzado como naci\u00f3n. Falta mucho, hay desaf\u00edos, pero seguimos caminando&#8221;, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su discurso, Rodr\u00edguez resalt\u00f3 los avances en transparencia y rendici\u00f3n de cuentas, as\u00ed como en la lucha contra la corrupci\u00f3n, pero tambi\u00e9n llam\u00f3 la atenci\u00f3n sobre problem\u00e1ticas actuales como la migraci\u00f3n, los accidentes de tr\u00e1nsito y la crisis medioambiental. &#8220;Estos son desaf\u00edos que enfrentamos como pa\u00eds y que requieren de nuestra acci\u00f3n conjunta&#8221;, subray\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actos c\u00edvico-militares y participaci\u00f3n del presidente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego del tedeum, los actos conmemorativos continuaron con el desfile c\u00edvico-militar, programado para despu\u00e9s de las 10:00 a.m., encabezado por el presidente Abinader junto a la vicepresidenta Pe\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La celebraci\u00f3n incluy\u00f3 la participaci\u00f3n de diferentes cuerpos castrenses y estudiantes, rindiendo homenaje a los h\u00e9roes de la Batalla de Santiago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre la Batalla del 30 de marzo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este enfrentamiento, considerado clave en la consolidaci\u00f3n de la Independencia Nacional, tuvo lugar en 1844 cuando tropas dominicanas, bajo el mando del general Jos\u00e9 Mar\u00eda Imbert, resistieron y derrotaron a las fuerzas haitianas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La victoria en Santiago sell\u00f3 el proceso independentista en la regi\u00f3n norte del pa\u00eds y fortaleci\u00f3 la determinaci\u00f3n de los criollos de mantener su soberan\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jornada inici\u00f3 con un tedeum en la Catedral Santiago Ap\u00f3stol, donde estuvo presente la vicepresidenta en representaci\u00f3n del Gobierno. El presidente Luis Abinader y la vicepresidenta Raquel Pe\u00f1a encabezan&hellip;<\/p>\n","protected":false},"author":2,"featured_media":96373,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35,25],"tags":[17320,11276,18505,935,2874],"class_list":["post-96372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada","tag-181-aniversario","tag-actos","tag-batalla-de-santiago","tag-presidente","tag-vicepresidenta"],"jetpack-related-posts":[{"id":87880,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/08\/18\/abinader-y-raquel-pena-encabezan-tedeum-por-161-aniversario-restauracion-en-santiago\/","url_meta":{"origin":96372,"position":0},"title":"Abinader y Raquel Pe\u00f1a encabezan tedeum por 161 aniversario Restauraci\u00f3n en Santiago","author":"Nelson Feliz","date":"18 de agosto de 2024","format":false,"excerpt":"Mandatarios tambi\u00e9n encabezaron el develamiento tarja hist\u00f3rica conmemorativa al primer cementerio de Santiago. El presidente Luis Abinader y la vicepresidenta Raquel Pe\u00f1a encabezaron este domingo en esta provincia un tedeum de acci\u00f3n de gracias por el 161 aniversario de la gesta restauradora y por el inicio de los cuatro a\u00f1os\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"El presidente Luis Abinader y la vicepresidenta Raquel Pe\u00f1a","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Abinader-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Abinader-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Abinader-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/08\/Abinader-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":80245,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/04\/05\/presidente-abinader-agotara-agenda-de-trabajo-en-provincias-santiago-y-la-vega-este-fin-de-semana\/","url_meta":{"origin":96372,"position":1},"title":"Presidente Abinader agotar\u00e1 agenda de trabajo en provincias Santiago y La Vega este fin de semana","author":"BIMARY DE JES\u00daS Matos","date":"5 de abril de 2024","format":false,"excerpt":"Entre las actividades se encuentran el Tedeum y el desfile c\u00edvico-militar con motivo del 180 aniversario de la Batalla del 30 de Marzo Santo Domingo. - El presidente Luis Abinader se trasladar\u00e1 a las provincias de Santiago y La Vega durante este s\u00e1bado y domingo, en las cuales participar\u00e1 en\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/IMG-20240405-WA0037.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/IMG-20240405-WA0037.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/IMG-20240405-WA0037.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/IMG-20240405-WA0037.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/IMG-20240405-WA0037.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/04\/IMG-20240405-WA0037.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":94304,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/02\/27\/autoridades-de-spm-participan-en-el-181-aniversario-de-la-independencia-nacional\/","url_meta":{"origin":96372,"position":2},"title":"Autoridades de SPM participan en el 181 aniversario de la Independencia Nacional","author":"Nelson Feliz","date":"27 de febrero de 2025","format":false,"excerpt":"La gobernadora civil de San Pedro de Macor\u00eds, Yovanis Baltazar junto a autoridades municipales y provinciales, encabez\u00f3 los actos conmemorativos y de celebraci\u00f3n del 181 aniversario de la Independencia Nacional Dominicana. Los actos iniciaron a partir de las 8:00 de la ma\u00f1ana con una eucarist\u00eda en la catedral San Pedro\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/autoridades-de-spm-participan-en-el-181-aniversario-de-la-independencia-nacional.webp?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":96369,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/29\/presidente-abinader-encabezara-desfile-civico-militar-por-181-aniversario-de-la-batalla-del-30-de-marzo\/","url_meta":{"origin":96372,"position":3},"title":"Presidente Abinader encabezar\u00e1 desfile c\u00edvico-militar por 181 aniversario de la Batalla del 30 de Marzo","author":"Nelson Feliz","date":"29 de marzo de 2025","format":false,"excerpt":"Participar\u00e1 en inauguraci\u00f3n AC Hotel by Marriot El presidente Luis Abinader encabezar\u00e1 este domingo en la ciudad de Santiago el desfile c\u00edvico-militar en conmemoraci\u00f3n al 181 aniversario de la Batalla del 30 de Marzo. Iniciando a las 11 de la ma\u00f1ana, estudiantes, polic\u00edas y militares desfilar\u00e1n por la Avenida Las\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Luis-Abinader-6.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Luis-Abinader-6.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Luis-Abinader-6.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":93790,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/02\/20\/abinader-encabeza-homenaje-a-la-bandera-nacional-en-el-181-aniversario-de-la-independencia\/","url_meta":{"origin":96372,"position":4},"title":"Abinader encabeza homenaje a la Bandera Nacional en el 181 aniversario de la Independencia","author":"Nelson Feliz","date":"20 de febrero de 2025","format":false,"excerpt":"El presidente de la Rep\u00fablica, Luis Abinader, encabez\u00f3 este jueves un homenaje a la Bandera Nacional en conmemoraci\u00f3n del 181 aniversario de la Independencia, dentro del marco del Mes de la Patria 2025. El acto, celebrado en las escalinatas del Palacio Nacional, cont\u00f3 con la presencia de la vicepresidenta Raquel\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/bandera.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/bandera.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/bandera.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/02\/bandera.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":113756,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/11\/05\/abinader-encabezara-actos-por-el-181-o-aniversario-de-la-constitucion-en-san-cristobal\/","url_meta":{"origin":96372,"position":5},"title":"Abinader encabezar\u00e1 actos por el 181.\u00ba aniversario de la Constituci\u00f3n en San Crist\u00f3bal","author":"Nelson Feliz","date":"5 de noviembre de 2025","format":false,"excerpt":"Tambi\u00e9n entregar\u00e1 t\u00edtulos de propiedad en el sector de Villa Fundaci\u00f3n, que beneficiar\u00e1 a miles de familias. El presidente Luis Abinader encabezar\u00e1 este jueves los actos conmemorativos por el 181.\u00ba aniversario de la Constituci\u00f3n de la Rep\u00fablica Dominicana, en la provincia de San Crist\u00f3bal. La jornada del mandatario iniciar\u00e1 a\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Luis Abinader","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Luis-Abinader-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Luis-Abinader-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Luis-Abinader-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Luis-Abinader-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/11\/Luis-Abinader-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/La-jornada-de-conmemoracion-de-la-Batalla-de-Santiago.jpg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/96372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=96372"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/96372\/revisions"}],"predecessor-version":[{"id":96374,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/96372\/revisions\/96374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/96373"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=96372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=96372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=96372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}