{"id":97514,"date":"2025-04-22T10:49:53","date_gmt":"2025-04-22T14:49:53","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=97514"},"modified":"2025-04-22T10:49:55","modified_gmt":"2025-04-22T14:49:55","slug":"intrant-inhabilita-mas-de-300-licencias-vencidas-en-operativo-semana-santa-2025","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/22\/intrant-inhabilita-mas-de-300-licencias-vencidas-en-operativo-semana-santa-2025\/","title":{"rendered":"INTRANT inhabilita m\u00e1s de 300 licencias vencidas en operativo Semana Santa 2025\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Durante el operativo se realizaron 7,727 inspecciones vehiculares, 196 pruebas de dopaje y 532 de alcohol<\/strong><br>\u00a0<br>El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (Intrant), inhabilit\u00f3 a 302 conductores del transporte p\u00fablico urbano e interurbano, tras detectar que circulaban con licencias vencidas, extraviadas o con categor\u00edas que no corresponden al tipo de veh\u00edculo que operaban.<br>\u00a0<br>Los resultados se obtuvieron tras la realizaci\u00f3n de 7,727 inspecciones t\u00e9cnicas visuales a nivel nacional, como parte del operativo \u201cConciencia por la Vida: Semana Santa 2025\u201d, con el prop\u00f3sito de garantizar la seguridad vial y prevenir accidentes de tr\u00e1nsito durante el asueto.<br>\u00a0<br>Las inspecciones realizadas por el Intrant se llevaron a cabo en 116 terminales de autob\u00fas, microb\u00fas, minib\u00fas, carros y motocicletas, donde tambi\u00e9n se realizaron pruebas toxicol\u00f3gicas a los conductores, resultando negativas 196 pruebas de dopaje y 532 pruebas de alcohol.<br>\u00a0<br>Entre las fallas y omisiones identificadas se encontraron: 63 veh\u00edculos con seguros vencidos, 278 con luces LED o tuercas afiladas en neum\u00e1ticos, y decenas sin equipos b\u00e1sicos como botiqu\u00edn, tri\u00e1ngulo o extintor.<br>\u00a0<br>205 unidades carec\u00edan de botiqu\u00edn de primeros auxilios, 214 no contaban con tri\u00e1ngulo de emergencia y 143 no ten\u00edan extintor.<br>\u00a0<br>En cuanto a los da\u00f1os detectados, se orden\u00f3 la reparaci\u00f3n o sustituci\u00f3n de 620 gomas, 1,116 luces da\u00f1adas o en mal estado, 1,046 cristales rotos, as\u00ed como de 160 retrovisores, 176 limpiavidrios, 188 bumpers, 146 placas alteradas y 106 veh\u00edculos identificados como no aptos para circular.<br>\u00a0<br>Durante el asueto, se emiti\u00f3 20,648 permisos especiales para el transporte de carga, limitados a productos perecederos y combustibles.<br>\u00a0<br>El Intrant revel\u00f3 que este 2025 tuvo un impacto significativo, con el incremento de las inspecciones en un 30% y un 33% en las terminales del transporte en comparaci\u00f3n con el a\u00f1o 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el operativo se realizaron 7,727 inspecciones vehiculares, 196 pruebas de dopaje y 532 de alcohol\u00a0El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (Intrant), inhabilit\u00f3 a 302 conductores del transporte&hellip;<\/p>\n","protected":false},"author":10,"featured_media":97515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35,25],"tags":[18977,349,18978,3485,18798],"class_list":["post-97514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada","tag-inhabilita","tag-intrant","tag-licencias-vencidas","tag-operativo","tag-semana-santa-2025"],"jetpack-related-posts":[{"id":97209,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/17\/intrant-realizara-7000-inspecciones-vehiculares-para-garantizar-seguridad-vial-durante-semana-santa-2025\/","url_meta":{"origin":97514,"position":0},"title":"INTRANT realizar\u00e1 7,000 inspecciones vehiculares para garantizar seguridad vial durante Semana Santa 2025","author":"Nelson Feliz","date":"17 de abril de 2025","format":false,"excerpt":"A estas jornadas se incorporar\u00e1 pruebas de dopaje y alcoholemia, as\u00ed como al sector de motociclistas. El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (Intrant), impactar\u00e1 siete mil unidades y sus choferes de autobuses de transporte urbano e interurbano con sus operativos de inspecci\u00f3n t\u00e9cnica visual, con el prop\u00f3sito de\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/intrant-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/intrant-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/intrant-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/intrant-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":79785,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/03\/31\/digesett-retiene-cientos-de-vehiculos-por-infracciones-durante-operativos-de-semana-santa\/","url_meta":{"origin":97514,"position":1},"title":"Digesett retiene cientos de veh\u00edculos por infracciones durante operativos de Semana Santa","author":"Nelson Feliz","date":"31 de marzo de 2024","format":false,"excerpt":"Las autoridades de la Digesett llevaron a cabo un amplio operativo de fiscalizaci\u00f3n durante los d\u00edas jueves, y s\u00e1bado viernes santo, resultando con la retenci\u00f3n de miles de veh\u00edculos y la inspecci\u00f3n de conductores por diversas infracciones a la ley de tr\u00e1nsito, en especial a los motociclistas. Seg\u00fan detalla el\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Digesett","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/03\/Digesett-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":126783,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/04\/05\/intrant-evita-accidentes-detecta-3900-fallas-en-autobuses\/","url_meta":{"origin":97514,"position":2},"title":"INTRANT evita accidentes: detecta 3,900 fallas en autobuses","author":"Nelson Feliz","date":"5 de abril de 2026","format":false,"excerpt":"Como parte del operativo \u201cConciencia por la Vida: Semana Santa 2026\u201d, el Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (INTRANT) ejecut\u00f3 un amplio despliegue de inspecciones t\u00e9cnicas visuales en el transporte p\u00fablico de pasajeros, alcanzando un total de 8,084 unidades inspeccionadas en m\u00e1s de 40 terminales a nivel nacional. Estas\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"INTRANT","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-05-at-4.18.22-PM.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-05-at-4.18.22-PM.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-05-at-4.18.22-PM.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-05-at-4.18.22-PM.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":120296,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/01\/22\/intrant-inspecciona-tecnicamente-mas-de-553-unidades-de-transporte-interurbano-durante-el-operativo-altagraciano-2026\/","url_meta":{"origin":97514,"position":3},"title":"INTRANT inspecciona t\u00e9cnicamente m\u00e1s de 553 unidades de transporte interurbano durante el Operativo Altagraciano 2026","author":"Nelson Feliz","date":"22 de enero de 2026","format":false,"excerpt":"_M\u00e1s de 200 fallas t\u00e9cnicas detectadas y 9 licencias irregulares retenidas durante despliegue preventivo nacional._ El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (INTRANT) inform\u00f3 que, como parte del dispositivo \u201cConciencia por la Vida: Operativo Altagraciano 2026\u201d, coordinado por el Centro de Operaciones de Emergencias (COE), fueron inspeccionadas 553 unidades\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260122-WA0663.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260122-WA0663.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260122-WA0663.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260122-WA0663.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260122-WA0663.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/01\/IMG-20260122-WA0663.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":132720,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/06\/05\/intrant-despliega-historico-operativo-en-paradas-de-motocicletas\/","url_meta":{"origin":97514,"position":4},"title":"INTRANT despliega hist\u00f3rico operativo en paradas de motocicletas","author":"Nelson Feliz","date":"5 de junio de 2026","format":false,"excerpt":"Las intervenciones han impactado 29 paradas y permitido la retenci\u00f3n de 46 motocicletas como parte de las acciones para fortalecer la seguridad vial, verificar documentaci\u00f3n y ordenar el transporte en motocicletas. Santo Domingo. \u2013 El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (INTRANT), en coordinaci\u00f3n con la Polic\u00eda Nacional, la\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"INTRANT","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/INTRANT-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/INTRANT-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/INTRANT-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/06\/INTRANT-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":125909,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/03\/27\/intrant-realizara-mas-de-8000-inspecciones-vehiculares-durante-operativo-semana-santa-conciencia-por-la-vida-2026\/","url_meta":{"origin":97514,"position":5},"title":"INTRANT realizar\u00e1 m\u00e1s de 8,000 inspecciones vehiculares durante operativo \u201cSemana Santa Conciencia por la Vida 2026&#8243;","author":"Nelson Feliz","date":"27 de marzo de 2026","format":false,"excerpt":"El Instituto Nacional de Tr\u00e1nsito y Transporte Terrestre (INTRANT) realizar\u00e1 m\u00e1s de 8,000 inspecciones vehiculares durante el operativo \u201cSemana Santa Conciencia por la Vida 2026\u201d, que se desarrollar\u00e1 del 30 de marzo al 2 de abril, como parte de las acciones preventivas para reducir riesgos en las v\u00edas y salvar\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/IMG-20260327-WA0421.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/IMG-20260327-WA0421.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/IMG-20260327-WA0421.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/IMG-20260327-WA0421.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/IMG-20260327-WA0421.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/03\/IMG-20260327-WA0421.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/intrant-1-1.jpg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=97514"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97514\/revisions"}],"predecessor-version":[{"id":97516,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97514\/revisions\/97516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/97515"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=97514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=97514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=97514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}