{"id":97847,"date":"2025-04-25T12:05:47","date_gmt":"2025-04-25T16:05:47","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=97847"},"modified":"2025-04-28T12:08:54","modified_gmt":"2025-04-28T16:08:54","slug":"eted-dara-mantenimiento-en-la-linea-69-kv-boca-chica-megapuerto","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/25\/eted-dara-mantenimiento-en-la-linea-69-kv-boca-chica-megapuerto\/","title":{"rendered":"ETED dar\u00e1 mantenimiento en la l\u00ednea 69 kV Boca Chica \u2013 Megapuerto"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Empresa de Transmisi\u00f3n El\u00e9ctrica Dominicana (ETED) informa que, sustituir\u00e1 cable de guarda por fibra \u00f3ptica en la l\u00ednea 69 kV Boca Chica \u2013 Megapuerto, este s\u00e1bado 26 de abril, de 9:00 a.m. a 4:00 p.m.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por estos trabajos, se afectar\u00e1 el servicio en La Caleta perteneciente al Gran Santo Domingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por seguridad se requerir\u00e1n los UT\u00b4s: 21367, 21345, 21664, 21645 y 21607, los cuales afectar\u00e1n de manera parcial La Caleta, Boca Chica, Cancela, Los Frailes 2do, Aguas Locas, La Ure\u00f1a perteneciente al Gran Santo Domingo, tambi\u00e9n las empresas: Parque Cibern\u00e9tico, Zona Franca Multinodal Caucedo, Cartones del Caribe y Zona Franca Las Am\u00e9ricas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ETED pide disculpas por los inconvenientes que pueda causar y apela a la comprensi\u00f3n de los ciudadanos en las zonas afectadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas acciones son parte del compromiso de la empresa de garantizar un servicio de transporte de energ\u00eda en alta tensi\u00f3n estable, eficiente y de calidad que d\u00e9 respuesta a las necesidades de la ciudadan\u00eda, acorde a los mandatos del Gobierno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Empresa de Transmisi\u00f3n El\u00e9ctrica Dominicana (ETED) informa que, sustituir\u00e1 cable de guarda por fibra \u00f3ptica en la l\u00ednea 69 kV Boca Chica \u2013 Megapuerto, este s\u00e1bado 26 de abril,&hellip;<\/p>\n","protected":false},"author":10,"featured_media":97848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[35,25],"tags":[2703,5134,16636,5135,7570],"class_list":["post-97847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-portada","tag-boca-chica","tag-eted","tag-linea-69-kv","tag-mantenimiento","tag-megapuerto"],"jetpack-related-posts":[{"id":60563,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/15\/eted-trabajara-en-subestacion-69-kv-boca-chica-megapuerto-este-sabado\/","url_meta":{"origin":97847,"position":0},"title":"ETED trabajar\u00e1 en subestaci\u00f3n 69 kV Boca Chica- Megapuerto este s\u00e1bado","author":"Nelson Feliz","date":"15 de septiembre de 2023","format":false,"excerpt":"Por Martin Restituyo La Empresa de Transmisi\u00f3n El\u00e9ctrica Dominicana (ETED) informa que, este s\u00e1bado 16 de septiembre, estar\u00e1 dando mantenimiento preventivo al campo de l\u00ednea de la subestaci\u00f3n 69 kV Boca Chica- Megapuerto, como parte de los mantenimientos programados para esta semana.\u00a0 Los trabajos se efectuar\u00e1n de 9:00 a.m. a\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"LT Boca Chica- Megapuerto","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/LT-Boca-Chica-Megapuerto.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/LT-Boca-Chica-Megapuerto.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/LT-Boca-Chica-Megapuerto.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/LT-Boca-Chica-Megapuerto.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":130104,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/05\/10\/eted-desarrolla-jornadas-tecnicas-en-distintas-provincias-del-pais\/","url_meta":{"origin":97847,"position":1},"title":"ETED desarrolla jornadas t\u00e9cnicas en distintas provincias del pa\u00eds","author":"Nelson Feliz","date":"10 de mayo de 2026","format":false,"excerpt":"La Empresa de Transmisi\u00f3n El\u00e9ctrica Dominicana (ETED) informa que continuar\u00e1 desarrollando trabajos programados de mantenimiento preventivo, adecuaciones t\u00e9cnicas y reemplazo de estructuras en distintas l\u00edneas y subestaciones del pa\u00eds, como parte de las acciones orientadas a fortalecer la estabilidad, seguridad y eficiencia del sistema el\u00e9ctrico nacional. Este lunes 11 de\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/ETED.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/ETED.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/ETED.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/05\/ETED.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":104113,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/07\/21\/eted-dara-mantenimiento-este-martes-en-linea-de-transmision-y-subestacion-electrica\/","url_meta":{"origin":97847,"position":2},"title":"ETED dar\u00e1 mantenimiento este martes en l\u00ednea de transmisi\u00f3n y subestaci\u00f3n el\u00e9ctrica","author":"Nelson Feliz","date":"21 de julio de 2025","format":false,"excerpt":"La Empresa de Transmisi\u00f3n El\u00e9ctrica Dominicana (ETED) inform\u00f3 que este martes realizar\u00e1 trabajos programados de mantenimiento en la l\u00ednea de transmisi\u00f3n 69 kV Pimentel \u2013 San Francisco de Macor\u00eds y en la subestaci\u00f3n 69 kV Boca Chica \u2013 SPM, como parte de su compromiso con el fortalecimiento del servicio de\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"ETED","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/ETED-4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/ETED-4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/ETED-4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/10\/ETED-4.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":57028,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/08\/07\/brigadas-de-eted-trabajaran-este-martes-en-mantenimiento-de-subestaciones-y-lineas-de-distintas-zonas-del-pais\/","url_meta":{"origin":97847,"position":3},"title":"Brigadas de ETED trabajar\u00e1n este martes en mantenimiento de subestaciones y l\u00edneas de distintas zonas del pa\u00eds\u00a0","author":"Nelson Feliz","date":"7 de agosto de 2023","format":false,"excerpt":"Por Martin Restituyo La Empresa de Transmisi\u00f3n El\u00e9ctrica Dominicana (ETED) informa que, este martes, 08 de agosto, las brigadas de mantenimiento realizar\u00e1n trabajos en las subestaciones 138 kV R\u00edo San Juan \u2013 Barra, 69 kV Boca Chica - SPM I y, en la l\u00ednea 69 kV Duverg\u00e9 - Las Damas,\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"l\u00ednea de la subestaci\u00f3n","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Linea-de-Transmision-345-Kv-01.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Linea-de-Transmision-345-Kv-01.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Linea-de-Transmision-345-Kv-01.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/08\/Linea-de-Transmision-345-Kv-01.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":60218,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/11\/eted-dara-mantenimiento-en-la-subestacion-69-kv-villa-duarte-invivienda-y-palamara-inca\/","url_meta":{"origin":97847,"position":4},"title":"ETED dar\u00e1 mantenimiento en la subestaci\u00f3n 69 kV Villa Duarte \u2013 Invivienda y Palamara \u2013 INCA","author":"Nelson Feliz","date":"11 de septiembre de 2023","format":false,"excerpt":"Por Martin Restituyo La Empresa de Transmisi\u00f3n El\u00e9ctrica Dominicana (ETED) informa que, este martes, 12 de septiembre, dar\u00e1 mantenimiento preventivo al campo de l\u00ednea en la subestaci\u00f3n 69 kV Villa Duarte \u2013 Invivienda, como parte de los trabajos programados esta semana para optimizar la calidad de las infraestructuras en el\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"Redes El\u00e9ctrica","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Redes-Electrica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Redes-Electrica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Redes-Electrica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/Redes-Electrica.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":60173,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/09\/11\/eted-dara-mantenimiento-en-subestacion-y-linea-69-kv-este-martes\/","url_meta":{"origin":97847,"position":5},"title":"ETED dar\u00e1 mantenimiento en subestaci\u00f3n y l\u00ednea 69 kV este martes\u00a0\u00a0","author":"Nelson Feliz","date":"11 de septiembre de 2023","format":false,"excerpt":"Por Martin Restituyo La Empresa de Transmisi\u00f3n El\u00e9ctrica Dominicana (ETED) informa que, este martes 12 de septiembre, realizar\u00e1 sustituci\u00f3n de estructuras en malas condiciones en la l\u00ednea 69 kV Palamara \u2013 INCA y mantenimiento preventivo al campo de l\u00ednea en la subestaci\u00f3n 69 kV Villa Duarte \u2013 Invivienda, como parte\u2026","rel":"","context":"En \u00abNACIONALES\u00bb","block_context":{"text":"NACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/nacionales\/"},"img":{"alt_text":"ETED","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/ETED.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/ETED.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/ETED.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/09\/ETED.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/eted.jpg","_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=97847"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97847\/revisions"}],"predecessor-version":[{"id":97849,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97847\/revisions\/97849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/97848"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=97847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=97847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=97847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}