{"id":97871,"date":"2025-04-29T07:50:08","date_gmt":"2025-04-29T11:50:08","guid":{"rendered":"https:\/\/lasprimeras.com.do\/?p=97871"},"modified":"2025-04-29T07:50:08","modified_gmt":"2025-04-29T11:50:08","slug":"el-lider-conservador-de-canada-pierde-su-escano-en-el-parlamento-en-una-derrota-electoral","status":"publish","type":"post","link":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/29\/el-lider-conservador-de-canada-pierde-su-escano-en-el-parlamento-en-una-derrota-electoral\/","title":{"rendered":"El l\u00edder conservador de Canad\u00e1 pierde su esca\u00f1o en el Parlamento en una derrota electoral"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">POR ROB GILLIES<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TORONTO (AP) \u2014 El l\u00edder del Partido Conservador de Canad\u00e1, Pierre Poilievre, fue expulsado de su propio esca\u00f1o en el Parlamento mientras, que el Partido Liberal del primer ministro Mark Carney gan\u00f3 las elecciones federales de Canad\u00e1, seg\u00fan estimaciones publicadas el lunes por la Canadian Broadcasting Corporation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La p\u00e9rdida de su esca\u00f1o por su distrito de Ottawa durante las elecciones del lunes culmin\u00f3 un sorprendente declive en la fortuna de Poilievre, quien hace solo unos meses parec\u00eda ser el favorito para convertirse en el pr\u00f3ximo primer ministro de Canad\u00e1 y llevar a los conservadores de regreso al poder por primera vez en una d\u00e9cada antes de que la guerra comercial del presidente estadounidense Donald Trump con Canad\u00e1 y las sugerencias de que deber\u00eda convertirse en el estado 51 indignaran a los votantes y trastocaran la elecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poilievre, un pol\u00edtico de carrera, hizo campa\u00f1a con la misma actitud fanfarrona que Trump, incluso adoptando el lema \u201cCanad\u00e1 primero\u201d, inspirado en \u201cEstados Unidos Primero\u201d del mandatario estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero sus similitudes con Trump podr\u00edan haberle costado a \u00e9l y a su partido las elecciones del lunes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s del cierre de las urnas, se pronosticaba que los progresistas ganar\u00edan m\u00e1s esca\u00f1os que el Partido Conservador en el Parlamento de 343 bancas, aunque de momento se desconoce si obtendr\u00edan una mayor\u00eda absoluta \u2014al menos 172\u2014, o si necesitar\u00edan depender de uno o m\u00e1s partidos menores para formar un gobierno y poder aprobar proyectos de ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los progresistas parec\u00edan encaminarse a una derrota aplastante hasta que el presidente estadounidense comenz\u00f3 a atacar la econom\u00eda de Canad\u00e1 y amenazar su soberan\u00eda, insinuando que deber\u00eda convertirse en el estado 51 de Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las acciones de Trump enfurecieron a los canadienses y avivaron un incremento del nacionalismo que ayud\u00f3 a los progresistas a cambiar el discurso de la campa\u00f1a electoral y ganar un cuarto mandato consecutivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un discurso de victoria ante sus seguidores en Ottawa, Carney destac\u00f3 la importancia de la unidad canadiense frente a las amenazas de Washington.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n dijo que el sistema mutuamente beneficioso que Canad\u00e1 y Estados Unidos hab\u00edan compartido desde la II Guerra Mundial hab\u00eda terminado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos superando el shock de la traici\u00f3n estadounidense, pero nunca debemos olvidar las lecciones\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComo llevo advirtiendo durante meses, Estados Unidos quiere nuestra tierra, nuestros recursos, nuestra agua, nuestro pa\u00eds\u201d, dijo Carney. \u201cEstas no son amenazas vac\u00edas. El presidente Trump est\u00e1 tratando de quebrarnos para que Estados Unidos pueda poseernos. Eso nunca\u2026 jam\u00e1s suceder\u00e1. Pero tambi\u00e9n debemos reconocer la realidad de que nuestro mundo ha cambiado fundamentalmente\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POR ROB GILLIES TORONTO (AP) \u2014 El l\u00edder del Partido Conservador de Canad\u00e1, Pierre Poilievre, fue expulsado de su propio esca\u00f1o en el Parlamento mientras, que el Partido Liberal del&hellip;<\/p>\n","protected":false},"author":10,"featured_media":97872,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16289],"tags":[3169,19102,976,19101],"class_list":["post-97871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","tag-canada-3","tag-derrota-electoral","tag-parlamento","tag-pierre-poilievre"],"jetpack_featured_media_url":"https:\/\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/Pierre-Poilievre.jpg","jetpack-related-posts":[{"id":127427,"url":"https:\/\/lasprimeras.com.do\/index.php\/2026\/04\/12\/orban-reconoce-su-derrota-electoral-en-hungria-y-felicita-al-opositor-magyar-por-su-victoria\/","url_meta":{"origin":97871,"position":0},"title":"Orb\u00e1n reconoce su derrota electoral en Hungr\u00eda y felicita al opositor Magyar por su victoria","author":"Nelson Feliz","date":"12 de abril de 2026","format":false,"excerpt":"El ultranacionalista Viktor Orb\u00e1n gobern\u00f3 el pa\u00eds centroeuropeo desde 2010 con mayor\u00eda absoluta Budapest,EFE-El primer ministro de Hungr\u00eda, el ultranacionalista Viktor Orb\u00e1n, reconoci\u00f3 este domingo su derrota en las elecciones legislativas y felicit\u00f3 por la victoria a su rival, el opositor conservador P\u00e9ter Magyar. \"Para nosotros el resultado es doloroso\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/Viktor-Orban-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/Viktor-Orban-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/Viktor-Orban-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2026\/04\/Viktor-Orban-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":84536,"url":"https:\/\/lasprimeras.com.do\/index.php\/2024\/06\/10\/los-triunfos-electorales-de-la-extrema-derecha-lleva-a-macron-a-convocar-elecciones-anticipadas\/","url_meta":{"origin":97871,"position":1},"title":"Los triunfos electorales de la extrema derecha lleva a Macron a convocar elecciones anticipadas","author":"Nelson Feliz","date":"10 de junio de 2024","format":false,"excerpt":"POR RAF CASERT, LORNE COOK Y SAMUEL PETREQUIN BRUSELAS (AP) \u2014 Los partidos de extrema derecha sacudieron a las potencias tradicionales de la Uni\u00f3n Europea con importantes ganancias en esca\u00f1os parlamentarios, propin\u00e1ndole una derrota especialmente humillante al presidente franc\u00e9s Emmanuel Macron , quien convoc\u00f3 a elecciones legislativas anticipadas. Algunas papeletas\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Giorgia-Meloni.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Giorgia-Meloni.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Giorgia-Meloni.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2024\/06\/Giorgia-Meloni.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":97178,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/04\/17\/carney-dice-que-trump-es-el-tema-central-en-las-elecciones-de-canada-conservadores-piden-un-cambio\/","url_meta":{"origin":97871,"position":2},"title":"Carney dice que Trump es el tema central en las elecciones de Canad\u00e1; conservadores piden un cambio","author":"Nelson Feliz","date":"17 de abril de 2025","format":false,"excerpt":"POR ROB GILLIES TORONTO (AP) \u2014 El primer ministro de Canad\u00e1 Mark Carney declar\u00f3 el mi\u00e9rcoles que la cuesti\u00f3n central durante las elecciones nacionales ser\u00e1 decidir qui\u00e9n es la mejor opci\u00f3n para lidiar con el presidente de Estados Unidos, Donald Trump, mientras que su rival conservador argument\u00f3 que Carney no\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/MANDA.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/MANDA.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/MANDA.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/04\/MANDA.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":98267,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/05\/06\/la-candidatura-del-canciller-de-alemania-fracasa-en-el-parlamento-en-una-derrota-inesperada\/","url_meta":{"origin":97871,"position":3},"title":"La candidatura del canciller de Alemania fracasa en el parlamento en una derrota inesperada","author":"Nelson Feliz","date":"6 de mayo de 2025","format":false,"excerpt":"POR STEFANIE DAZIO BERL\u00cdN (AP) \u2014 En un hecho hist\u00f3rico, la candidatura del l\u00edder conservador Friedrich Merz para convertirse en el d\u00e9cimo canciller de Alemania desde la II Guerra Mundial fracas\u00f3 el martes en la primera ronda de votaci\u00f3n en el parlamento por seis votos, una sorprendente derrota ya que\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Friedrich-Merz.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Friedrich-Merz.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Friedrich-Merz.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/05\/Friedrich-Merz.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":95091,"url":"https:\/\/lasprimeras.com.do\/index.php\/2025\/03\/09\/canada-tiene-nuevo-primer-ministro\/","url_meta":{"origin":97871,"position":4},"title":"Canad\u00e1 tiene nuevo primer ministro","author":"Nelson Feliz","date":"9 de marzo de 2025","format":false,"excerpt":"Mark Carney se convertir\u00e1 en el pr\u00f3ximo primer ministro canadiense tras ser elegido como nuevo l\u00edder del Partido Liberal, la formaci\u00f3n gobernante. El exjefe del Banco de Canad\u00e1 y del Banco de Inglaterra, Mark Carney, se convertir\u00e1 en el pr\u00f3ximo primer ministro canadiense luego de que los liberales, que est\u00e1n\u2026","rel":"","context":"En \u00abINTERNACIONALES\u00bb","block_context":{"text":"INTERNACIONALES","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/internacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Mark-Carney.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Mark-Carney.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Mark-Carney.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2025\/03\/Mark-Carney.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":55646,"url":"https:\/\/lasprimeras.com.do\/index.php\/2023\/07\/24\/sorpresa-electoral-en-espana-el-partido-socialista-resiste-y-la-derecha-no-tiene-mayoria-para-gobernar\/","url_meta":{"origin":97871,"position":5},"title":"Sorpresa electoral en Espa\u00f1a: El Partido Socialista resiste y la derecha no tiene mayor\u00eda para gobernar","author":"Nelson Feliz","date":"24 de julio de 2023","format":false,"excerpt":"Seg\u00fan estos resultados cabr\u00eda la posibilidad de reeditar un Gobierno de coalici\u00f3n progresista entre el Partido Socialista de Pedro S\u00e1nchez y Sumar. Con casi el 97 % de los votos escrutados, el Partido Popular es la formaci\u00f3n que consigue m\u00e1s diputados, mientras que el Partido Socialista pr\u00e1cticamente le iguala en\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/lasprimeras.com.do\/index.php\/category\/sin-categoria\/"},"img":{"alt_text":"Elecciones","src":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Elecciones.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Elecciones.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Elecciones.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Elecciones.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lasprimeras.com.do\/wp-content\/uploads\/2023\/07\/Elecciones.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=97871"}],"version-history":[{"count":1,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97871\/revisions"}],"predecessor-version":[{"id":97873,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97871\/revisions\/97873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media\/97872"}],"wp:attachment":[{"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=97871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=97871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasprimeras.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=97871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}